{"id":46739,"date":"2019-08-30T16:02:58","date_gmt":"2019-08-30T14:02:58","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=46739"},"modified":"2021-05-11T17:01:57","modified_gmt":"2021-05-11T15:01:57","slug":"top-14-nos-pronostics-pour-la-2eme-journee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/","title":{"rendered":"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Le deuxi\u00e8me acte du Top 14 d\u00e9bute ce samedi, avec des affiches d\u00e9j\u00e0 prometteuses ! Retrouvez nos pronostics pour cette deuxi\u00e8me journ\u00e9e de la saison 2019-2020.<br \/>\n<\/em><\/strong><\/p>\n<h1 style=\"text-align: justify;\">Aviron Bayonnais &#8211; ASM Clermont : samedi 31 ao\u00fbt, 15h30<\/h1>\n<p style=\"text-align: justify;\">Vainqueur surprise au Racing 92, Bayonne a parfaitement r\u00e9ussi son retour dans l&rsquo;\u00e9lite. Quant aux Clermontois, ils n&rsquo;ont pas fait de d\u00e9tails face aux Rochelais. Deux \u00e9quipes en confiance donc, mais pour leur premier match \u00e0 domicile, les Bayonnais devraient \u00eatre transcend\u00e9s. <strong>Victoire de l&rsquo;Aviron<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 114.935%; text-align: left; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">\u00a0 Samedi 31 ao\u00fbt, 15h30<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 35%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 29%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle;\"><strong>Aviron Bayonnais &#8211; ASM Clermont<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729302?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 2.40<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729302?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 20<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729302?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.55<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h1 style=\"text-align: justify;\">SU Agen &#8211; CA Brive : samedi 31 ao\u00fbt, 18h00<\/h1>\n<p style=\"text-align: justify;\">S\u00e8chement battus \u00e0 domicile par Toulon, les Agenais ont une chance de se rattraper imm\u00e9diatement face au promu briviste. Les Coujoux, qui ont chut\u00e9 lors de la premi\u00e8re journ\u00e9e \u00e0 Pau, ne sont pas vernis avec deux d\u00e9placements pour leur retour en Top 14. <strong>On mise sur une victoire d&rsquo;Agen<\/strong>.<\/p>\n<table style=\"width: 100%; border-color: #ededed;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 114.935%; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 31 ao\u00fbt, 18h00<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 35%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 29%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle;\"><strong>SU Agen &#8211; CA Brive<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729300?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.35<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729300?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 25<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729300?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 3.00<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h1 style=\"text-align: justify;\">Montpellier &#8211; Section Paloise : samedi 31 ao\u00fbt, 18h00<\/h1>\n<p style=\"text-align: justify;\">Battu d&rsquo;un rien \u00e0 Castres, le MHR s&rsquo;est malgr\u00e9 tout de m\u00eame montr\u00e9 rassurant sur son \u00e9tat de forme. Face \u00e0 eux, des Palois qui ne sont pas tomb\u00e9s dans le pi\u00e8ge briviste. Mais les Cistes devraient prendre la mesure des B\u00e9arnais \u00e0 domicile. <strong>Victoire de Montpellier<\/strong>.<\/p>\n<table style=\"width: 100%; border-color: #ededed;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 114.935%; text-align: left; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 31 ao\u00fbt, 18h00<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 35%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 29%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; width: 114.935%;\"><strong>Montpellier &#8211; Section Paloise<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 10%;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729304?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.07<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 35%;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729304?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 35<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 29%;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729304?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 7.00<\/span><span style=\"font-size: 10px\"><\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h1 style=\"text-align: justify;\">Stade Rochelais &#8211; Stade Fran\u00e7ais : samedi 31 ao\u00fbt, 18h00<\/h1>\n<p style=\"text-align: justify;\">Battu \u00e0 Clermont, le Stade Rochelais doit se reprendre \u00e0 Deflandre, face \u00e0 une \u00e9quipe parisienne qui a \u00e9t\u00e9 s\u00e8chement battue lors de la 1\u00e8re journ\u00e9e. Les Maritimes partiront avec une longueur d&rsquo;avance devant leur public. <strong>Succ\u00e8s rochelais<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 114.935%; text-align: left; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 31 ao\u00fbt, 18h00<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 35%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 29%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; width: 114.935%;\"><strong>Stade Rochelais &#8211; Stade Fran\u00e7ais<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 10%;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729310?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.09<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 35%;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729310?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 30<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 29%;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729310?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 6.00<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h1 style=\"text-align: justify;\">UBB &#8211; RC Toulon : samedi 31 ao\u00fbt, 20h45<\/h1>\n<p style=\"text-align: justify;\">Tombeurs du champion toulousain, les Girondins ont bien entam\u00e9 le championnat. Face \u00e0 eux, Toulon a r\u00e9ussi \u00e0 s&rsquo;imposer \u00e0 l&rsquo;ext\u00e9rieur, sur la pelouse d&rsquo;Agen. Difficile de pronostiquer une issue pour cette rencontre, mais les Varois ont montr\u00e9 une sacr\u00e9e force de frappe le week-end pass\u00e9. <strong>Victoire toulonnaise<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 114.935%; text-align: left; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 31 ao\u00fbt, 20h45<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 35%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 29%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; vertical-align: middle; border-color: #ededed;\"><strong>UBB &#8211; RC Toulon<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; vertical-align: middle; border-color: #ededed;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729306?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.40<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; vertical-align: middle; border-color: #ededed;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729306?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 25<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; vertical-align: middle; border-color: #ededed;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/dicodusport.fr\/blog\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 2.75<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h1 style=\"text-align: justify;\">Racing 92 &#8211; Castres Olympique : dimanche 1er septembre, 12h30<\/h1>\n<p style=\"text-align: justify;\">Surpris \u00e0 domicile par Bayonne, les Racingmen doivent imm\u00e9diatement rectifier le tir ce dimanche, dans leur antre. Face \u00e0 eux, le CO a souffert pour s&rsquo;imposer d&rsquo;un rien face \u00e0 Montpellier dans le Tarn. Si la confiance est du c\u00f4t\u00e9 de Castres, l&rsquo;urgence, d\u00e9j\u00e0, se trouve chez les <em>Ciel &amp; Blanc<\/em>. <strong>Victoire du Racing 92<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 114.935%; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">Dimanche 1er septembre, 12h30<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 35%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 29%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 114.935%; text-align: justify;\"><strong>Racing 92 &#8211; Castres Olympique<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 10%; text-align: justify;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729308?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.35<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 35%; text-align: justify;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729308?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 25<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; width: 29%; text-align: justify;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729308?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 2.85<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h1 style=\"text-align: justify;\">LOU &#8211; Stade Toulousain : dimanche 1er septembre, 17h05<\/h1>\n<p style=\"text-align: justify;\">Large vainqueur du Stade Fran\u00e7ais, Lyon a une deuxi\u00e8me occasion de briller \u00e0 domicile face \u00e0 un Toulouse battu en Gironde. Les champions en titre, sans \u00eatre mauvais face \u00e0 l&rsquo;UBB, vont devoir trouver les ressources pour passer sans trop de d\u00e9g\u00e2ts la p\u00e9riode de la Coupe du monde. Mais ce ne sera pas pour ce deuxi\u00e8me d\u00e9placement cons\u00e9cutif. <strong>Victoire du LOU<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 114.935%; text-align: left; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">Dimanche 1er septembre, 17h05<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 35%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 29%; text-align: center; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle;\"><strong>LOU &#8211; Stade Toulousain<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729312?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.25<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729312?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 25<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/18729312?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 3.75<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre\u00a0<a href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a>.<\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le deuxi\u00e8me acte du Top 14 d\u00e9bute ce samedi, avec des affiches d\u00e9j\u00e0 prometteuses ! Retrouvez nos pronostics pour cette deuxi\u00e8me journ\u00e9e de la saison 2019-2020.<\/p>\n","protected":false},"author":4,"featured_media":46832,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2303],"tags":[4949,13,111],"class_list":["post-46739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby","tag-pronostics","tag-rugby","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e<\/title>\n<meta name=\"description\" content=\"Le 2\u00e8me acte du Top 14 d\u00e9bute ce samedi, avec des affiches d\u00e9j\u00e0 prometteuses ! Retrouvez nos pronostics pour cette deuxi\u00e8me journ\u00e9e de la saison 2019-2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Le 2\u00e8me acte du Top 14 d\u00e9bute ce samedi, avec des affiches d\u00e9j\u00e0 prometteuses ! Retrouvez nos pronostics pour cette deuxi\u00e8me journ\u00e9e de la saison 2019-2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-30T14:02:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T15:01:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e\",\"datePublished\":\"2019-08-30T14:02:58+00:00\",\"dateModified\":\"2021-05-11T15:01:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/\"},\"wordCount\":1006,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png\",\"keywords\":[\"Pronostics\",\"Rugby\",\"Top 14\"],\"articleSection\":[\"Rugby\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/\",\"name\":\"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png\",\"datePublished\":\"2019-08-30T14:02:58+00:00\",\"dateModified\":\"2021-05-11T15:01:57+00:00\",\"description\":\"Le 2\u00e8me acte du Top 14 d\u00e9bute ce samedi, avec des affiches d\u00e9j\u00e0 prometteuses ! Retrouvez nos pronostics pour cette deuxi\u00e8me journ\u00e9e de la saison 2019-2020.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e","description":"Le 2\u00e8me acte du Top 14 d\u00e9bute ce samedi, avec des affiches d\u00e9j\u00e0 prometteuses ! Retrouvez nos pronostics pour cette deuxi\u00e8me journ\u00e9e de la saison 2019-2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e","og_description":"Le 2\u00e8me acte du Top 14 d\u00e9bute ce samedi, avec des affiches d\u00e9j\u00e0 prometteuses ! Retrouvez nos pronostics pour cette deuxi\u00e8me journ\u00e9e de la saison 2019-2020.","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2019-08-30T14:02:58+00:00","article_modified_time":"2021-05-11T15:01:57+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e","datePublished":"2019-08-30T14:02:58+00:00","dateModified":"2021-05-11T15:01:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/"},"wordCount":1006,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png","keywords":["Pronostics","Rugby","Top 14"],"articleSection":["Rugby"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/","name":"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png","datePublished":"2019-08-30T14:02:58+00:00","dateModified":"2021-05-11T15:01:57+00:00","description":"Le 2\u00e8me acte du Top 14 d\u00e9bute ce samedi, avec des affiches d\u00e9j\u00e0 prometteuses ! Retrouvez nos pronostics pour cette deuxi\u00e8me journ\u00e9e de la saison 2019-2020.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Pronostics-2\u00e8me-journ\u00e9e-Top-14-2019-20201.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-nos-pronostics-pour-la-2eme-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 : nos pronostics pour la 2\u00e8me journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/46739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=46739"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/46739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/46832"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=46739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=46739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=46739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}