{"id":467556,"date":"2024-02-29T09:05:16","date_gmt":"2024-02-29T08:05:16","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=467556&#038;preview=true&#038;preview_id=467556"},"modified":"2024-02-29T14:50:05","modified_gmt":"2024-02-29T13:50:05","slug":"hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/","title":{"rendered":"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL"},"content":{"rendered":"<p align=\"justify\"><strong><em>HOCKEY SUR GLACE \u2013 Cette nuit, malgr\u00e9 la d\u00e9faite de New York, Chlo\u00e9 Aurard a d\u00e9bloqu\u00e9 son compteur buts en inscrivant sa premi\u00e8re r\u00e9alisation de la saison pour sa treizi\u00e8me sortie.<\/em><\/strong><\/p>\n<p align=\"justify\">Enfin, il est l\u00e0 ! Pr\u00e8s de deux mois apr\u00e8s le lancement en grandes pompes de la premi\u00e8re saison de l&rsquo;histoire de la <strong>PWHL<\/strong>, <strong>Chlo\u00e9 Aurard<\/strong> a trouv\u00e9 le chemin des filets la nuit derni\u00e8re. En d\u00e9placement \u00e0 Ottawa, <strong>New York<\/strong> s&rsquo;est pourtant inclin\u00e9 (2-4) dans un match entre les deux pires bilans de la ligue, et se retrouve d\u00e9sormais dernier, mais \u00e0 seulement deux points de la 4e place synonyme de playoffs.<\/p>\n<p align=\"justify\">Alors que son \u00e9quipe \u00e9tait men\u00e9e 2-0, <strong>Chlo\u00e9 Aurard<\/strong> a b\u00e9n\u00e9fici\u00e9 d&rsquo;un coup du sort. En effet, Ottawa avait la possession dans sa zone d\u00e9fensive, mais une joueuse canadienne va exploser sa crosse en tentant une passe, tout ce qu&rsquo;il y a de plus lambda. Plac\u00e9e seule face au filet, la Tricolore n&rsquo;a eu qu&rsquo;\u00e0 profiter de l&rsquo;offrande pour ajuster la gardienne adverse, relan\u00e7ant alors les siennes en cours de deuxi\u00e8me tiers.<\/p>\n<p align=\"justify\">Aux c\u00f4t\u00e9s d&rsquo;une multitude d&rsquo;internationales am\u00e9ricaines et canadiennes, Aurard a des responsabilit\u00e9s restreintes par rapport \u00e0 ce qu&rsquo;elle conna\u00eet en \u00c9quipe de France, ou \u00e0 ce qu&rsquo;elle a connu du c\u00f4t\u00e9 de Northeastern en NCAA. Malgr\u00e9 tout, elle cumule <strong>5 points, dont 1 but, en 13 matchs<\/strong>, et a su se rendre indispensable par son travail de l&rsquo;ombre, notamment d\u00e9fensivement. Avec encore une dizaine de rencontres \u00e0 disputer, la Tricolore et son \u00e9quipe ont encore largement le temps de renverser la tendance pour aller chercher une place dans le Top 4, et prolonger cette premi\u00e8re saison au-del\u00e0 de la r\u00e9guli\u00e8re.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Taking one more look at Chloe&rsquo;s first PWHL New York goal \ud83d\udc40 <a href=\"https:\/\/t.co\/13jBoJkB0o\">pic.twitter.com\/13jBoJkB0o<\/a><\/p>\n<p>\u2014 PWHL New York (@PWHL_NewYork) <a href=\"https:\/\/twitter.com\/PWHL_NewYork\/status\/1763014524431417546?ref_src=twsrc%5Etfw\">February 29, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOCKEY SUR GLACE \u2013 Cette nuit, malgr\u00e9 la d\u00e9faite de New York, Chlo\u00e9 Aurard a d\u00e9bloqu\u00e9 son compteur buts en inscrivant sa premi\u00e8re r\u00e9alisation de la saison pour sa treizi\u00e8me sortie.<\/p>\n","protected":false},"author":55,"featured_media":219879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10575],"tags":[16878,21172,838],"class_list":["post-467556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hockey-sur-glace","tag-breve","tag-chloe-aurard","tag-hockey-sur-glace"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL<\/title>\n<meta name=\"description\" content=\"HOCKEY SUR GLACE - Chlo\u00e9 Aurard (New York) a inscrit la nuit derni\u00e8re le premier but de sa carri\u00e8re en PWHL.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL\" \/>\n<meta property=\"og:description\" content=\"HOCKEY SUR GLACE - Chlo\u00e9 Aurard (New York) a inscrit la nuit derni\u00e8re le premier but de sa carri\u00e8re en PWHL.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-29T08:05:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-29T13:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL\",\"datePublished\":\"2024-02-29T08:05:16+00:00\",\"dateModified\":\"2024-02-29T13:50:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/\"},\"wordCount\":338,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png\",\"keywords\":[\"br\u00e8ve\",\"Chlo\u00e9 Aurard\",\"hockey sur glace\"],\"articleSection\":[\"Hockey sur glace\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/\",\"name\":\"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png\",\"datePublished\":\"2024-02-29T08:05:16+00:00\",\"dateModified\":\"2024-02-29T13:50:05+00:00\",\"description\":\"HOCKEY SUR GLACE - Chlo\u00e9 Aurard (New York) a inscrit la nuit derni\u00e8re le premier but de sa carri\u00e8re en PWHL.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png\",\"width\":800,\"height\":445,\"caption\":\"Hockey Mondial D1A 2022 Chlo\u00e9 Aurard et les Bleues \u00e0 60 minutes de l'extase\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL","description":"HOCKEY SUR GLACE - Chlo\u00e9 Aurard (New York) a inscrit la nuit derni\u00e8re le premier but de sa carri\u00e8re en PWHL.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/","og_locale":"fr_FR","og_type":"article","og_title":"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL","og_description":"HOCKEY SUR GLACE - Chlo\u00e9 Aurard (New York) a inscrit la nuit derni\u00e8re le premier but de sa carri\u00e8re en PWHL.","og_url":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-02-29T08:05:16+00:00","article_modified_time":"2024-02-29T13:50:05+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL","datePublished":"2024-02-29T08:05:16+00:00","dateModified":"2024-02-29T13:50:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/"},"wordCount":338,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png","keywords":["br\u00e8ve","Chlo\u00e9 Aurard","hockey sur glace"],"articleSection":["Hockey sur glace"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/","url":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/","name":"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png","datePublished":"2024-02-29T08:05:16+00:00","dateModified":"2024-02-29T13:50:05+00:00","description":"HOCKEY SUR GLACE - Chlo\u00e9 Aurard (New York) a inscrit la nuit derni\u00e8re le premier but de sa carri\u00e8re en PWHL.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Hockey-Mondial-D1A-2022-Chloe-Aurard-et-les-Bleues-a-60-minutes-de-lextase.png","width":800,"height":445,"caption":"Hockey Mondial D1A 2022 Chlo\u00e9 Aurard et les Bleues \u00e0 60 minutes de l'extase"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/hockey-sur-glace-chloe-aurard-inscrit-son-premier-but-en-pwhl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Hockey sur glace : Chlo\u00e9 Aurard inscrit son premier but en PWHL"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/467556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=467556"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/467556\/revisions"}],"predecessor-version":[{"id":467625,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/467556\/revisions\/467625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/219879"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=467556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=467556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=467556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}