{"id":469822,"date":"2024-03-07T07:58:57","date_gmt":"2024-03-07T06:58:57","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=469822&#038;preview=true&#038;preview_id=469822"},"modified":"2024-03-07T07:59:25","modified_gmt":"2024-03-07T06:59:25","slug":"championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/","title":{"rendered":"Championnats d&rsquo;Europe Escrime fauteuil : Le sabre masculin et l&rsquo;\u00e9p\u00e9e f\u00e9minine en argent"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>CHAMPIONNATS D&rsquo;EUROPE ESCRIME FAUTEUIL 2024 \u2013 Le deuxi\u00e8me jour de comp\u00e9tition a vu les deux \u00e9quipes tricolores en lice (sabre masculin et \u00e9p\u00e9e f\u00e9minine) d\u00e9crocher la m\u00e9daille d&rsquo;argent.<\/b><\/em><\/p>\n<p style=\"text-align: justify;\">Au lendemain de <a href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-fleurettiste-maxime-valet-se-pare-de-bronze\/\">la premi\u00e8re m\u00e9daille de bronze obtenue par Maxime Valet<\/a>, l&rsquo;\u00c9quipe de France avan\u00e7ait mercredi avec de gros espoirs \u00e0 la <strong>Halle Georges Carpentier<\/strong>. En effet, les tournois de sabre masculin et d&rsquo;\u00e9p\u00e9e f\u00e9minine \u00e9taient au programme, avec la r\u00e9elle possibilit\u00e9 de d\u00e9crocher un premier titre. Cependant, cela ne s&rsquo;est pas concr\u00e9tis\u00e9 malgr\u00e9 deux finales. Le sabre masculin emmen\u00e9 par <strong>Maxime Valet<\/strong>, <strong>Ludovic Lemoine<\/strong>, <strong>Moez El Assine<\/strong> et <strong>Serge Robin<\/strong> a chut\u00e9 face \u00e0 la surprenante Ukraine. Seulement t\u00eate de s\u00e9rie num\u00e9ro 4, cette derni\u00e8re s&rsquo;est offerte les deux grands favoris, l&rsquo;Italie, et donc la France.<\/p>\n<p style=\"text-align: justify;\">En ce qui concerne l&rsquo;\u00e9p\u00e9e f\u00e9minine, <strong>Cl\u00e9mence Delavoipi\u00e8re<\/strong>, <strong>C\u00e9cile Demaud<\/strong>, <strong>Sophie Sablon<\/strong> et <strong>Brianna Vide<\/strong> ont connu un sort similaire. Dans un tournoi r\u00e9duit (cinq \u00e9quipes), l&rsquo;\u00c9quipe de France a remport\u00e9 une demi-finale accroch\u00e9e face \u00e0 la Hongrie avant de s&rsquo;incliner face \u00e0 la Pologne, la faute notamment \u00e0 un cinglant 10-0 conc\u00e9d\u00e9 pour entamer le match. Malgr\u00e9 une pointe d&rsquo;amertume, les deux collectifs tricolores quittent la journ\u00e9e avec chacun une m\u00e9daille d&rsquo;or autour du cou. Jeudi, les \u00e9preuves individuelles feront leur retour au programme.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">VICE-CHAMPIONS D\u2019EUROPE \ud83e\udd48<\/p>\n<p>En Ekip, nos Fran\u00e7ais s\u2019offrent la m\u00e9daille d\u2019argent au sabre en escrime fauteuil par \u00e9quipes<\/p>\n<p>\u2014 Equipe France (@EquipeFRA) <a href=\"https:\/\/twitter.com\/EquipeFRA\/status\/1765431834916032651?ref_src=twsrc%5Etfw\">March 6, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE ESCRIME FAUTEUIL 2024 \u2013 Le deuxi\u00e8me jour de comp\u00e9tition a vu les deux \u00e9quipes tricolores en lice (sabre masculin et \u00e9p\u00e9e f\u00e9minine) d\u00e9crocher la m\u00e9daille d&rsquo;argent.<\/p>\n","protected":false},"author":55,"featured_media":469853,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9251,5753],"tags":[16878,38228,31073],"class_list":["post-469822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escrime","category-handisport","tag-breve","tag-championnats-deurope-escrime-fauteuil","tag-escrime-fauteuil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Championnats d&#039;Europe Escrime fauteuil : Le sabre masculin et l&#039;\u00e9p\u00e9e f\u00e9minine en argent<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS D&#039;EUROPE ESCRIME FAUTEUIL 2024 \u2013 L&#039;\u00e9p\u00e9e f\u00e9minine et le sabre masculin ont d\u00e9croch\u00e9 l&#039;argent ce mercredi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Championnats d&#039;Europe Escrime fauteuil : Le sabre masculin et l&#039;\u00e9p\u00e9e f\u00e9minine en argent\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS D&#039;EUROPE ESCRIME FAUTEUIL 2024 \u2013 L&#039;\u00e9p\u00e9e f\u00e9minine et le sabre masculin ont d\u00e9croch\u00e9 l&#039;argent ce mercredi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T06:58:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T06:59:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Championnats d&#039;Europe Escrime fauteuil : Le sabre masculin et l&#039;\u00e9p\u00e9e f\u00e9minine en argent\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Championnats d&rsquo;Europe Escrime fauteuil : Le sabre masculin et l&rsquo;\u00e9p\u00e9e f\u00e9minine en argent\",\"datePublished\":\"2024-03-07T06:58:57+00:00\",\"dateModified\":\"2024-03-07T06:59:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/\"},\"wordCount\":285,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png\",\"keywords\":[\"br\u00e8ve\",\"Championnats d'Europe escrime fauteuil\",\"escrime fauteuil\"],\"articleSection\":[\"Escrime\",\"Handisport\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/\",\"name\":\"Championnats d'Europe Escrime fauteuil : Le sabre masculin et l'\u00e9p\u00e9e f\u00e9minine en argent\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png\",\"datePublished\":\"2024-03-07T06:58:57+00:00\",\"dateModified\":\"2024-03-07T06:59:25+00:00\",\"description\":\"CHAMPIONNATS D'EUROPE ESCRIME FAUTEUIL 2024 \u2013 L'\u00e9p\u00e9e f\u00e9minine et le sabre masculin ont d\u00e9croch\u00e9 l'argent ce mercredi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png\",\"width\":1200,\"height\":674,\"caption\":\"Championnats d'Europe Escrime fauteuil Le sabre masculin et l'\u00e9p\u00e9e f\u00e9minine en argent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Championnats d&rsquo;Europe Escrime fauteuil : Le sabre masculin et l&rsquo;\u00e9p\u00e9e f\u00e9minine en argent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Championnats d'Europe Escrime fauteuil : Le sabre masculin et l'\u00e9p\u00e9e f\u00e9minine en argent","description":"CHAMPIONNATS D'EUROPE ESCRIME FAUTEUIL 2024 \u2013 L'\u00e9p\u00e9e f\u00e9minine et le sabre masculin ont d\u00e9croch\u00e9 l'argent ce mercredi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/","og_locale":"fr_FR","og_type":"article","og_title":"Championnats d'Europe Escrime fauteuil : Le sabre masculin et l'\u00e9p\u00e9e f\u00e9minine en argent","og_description":"CHAMPIONNATS D'EUROPE ESCRIME FAUTEUIL 2024 \u2013 L'\u00e9p\u00e9e f\u00e9minine et le sabre masculin ont d\u00e9croch\u00e9 l'argent ce mercredi.","og_url":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-03-07T06:58:57+00:00","article_modified_time":"2024-03-07T06:59:25+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Championnats d'Europe Escrime fauteuil : Le sabre masculin et l'\u00e9p\u00e9e f\u00e9minine en argent","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Championnats d&rsquo;Europe Escrime fauteuil : Le sabre masculin et l&rsquo;\u00e9p\u00e9e f\u00e9minine en argent","datePublished":"2024-03-07T06:58:57+00:00","dateModified":"2024-03-07T06:59:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/"},"wordCount":285,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png","keywords":["br\u00e8ve","Championnats d'Europe escrime fauteuil","escrime fauteuil"],"articleSection":["Escrime","Handisport"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/","url":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/","name":"Championnats d'Europe Escrime fauteuil : Le sabre masculin et l'\u00e9p\u00e9e f\u00e9minine en argent","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png","datePublished":"2024-03-07T06:58:57+00:00","dateModified":"2024-03-07T06:59:25+00:00","description":"CHAMPIONNATS D'EUROPE ESCRIME FAUTEUIL 2024 \u2013 L'\u00e9p\u00e9e f\u00e9minine et le sabre masculin ont d\u00e9croch\u00e9 l'argent ce mercredi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Championnats-dEurope-Escrime-fauteuil-Le-sabre-masculin-et-lepee-feminine-en-argent.png","width":1200,"height":674,"caption":"Championnats d'Europe Escrime fauteuil Le sabre masculin et l'\u00e9p\u00e9e f\u00e9minine en argent"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-escrime-fauteuil-le-sabre-masculin-et-lepee-feminine-en-argent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Championnats d&rsquo;Europe Escrime fauteuil : Le sabre masculin et l&rsquo;\u00e9p\u00e9e f\u00e9minine en argent"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/469822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=469822"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/469822\/revisions"}],"predecessor-version":[{"id":469834,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/469822\/revisions\/469834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/469853"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=469822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=469822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=469822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}