{"id":471276,"date":"2024-03-15T10:00:34","date_gmt":"2024-03-15T09:00:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=471276&#038;preview=true&#038;preview_id=471276"},"modified":"2024-03-14T22:05:49","modified_gmt":"2024-03-14T21:05:49","slug":"pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/","title":{"rendered":"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>JEUX OLYMPIQUES ET PARALYMPIQUES DE PARIS 2024 \u2013 Pr\u00e9sent dans les tribunes de la halle George Carpentier, samedi, pour assister aux championnats d\u2019Europe d\u2019escrime, Pierre Rabadan, l\u2019adjoint au sport \u00e0 la mairie de Paris, s\u2019est entretenu avec Dicodusport. Il est revenu sur le nombre important de comp\u00e9titions que la ville accueille, la place du handicap dans le sport et la pr\u00e9sence des athl\u00e8tes ukrainiens aux Jeux Olympiques et Paralympiques. <\/em><\/strong><\/p>\n<h3 style=\"text-align: justify;\"><strong>Pourquoi \u00eates-vous venu assister \u00e0 la comp\u00e9tition ?<\/strong><\/h3>\n<p style=\"text-align: justify;\">J&rsquo;essaie d&rsquo;aller sur la plupart des \u00e9v\u00e9nements qui se d\u00e9roulent \u00e0 Paris, m\u00eame s&rsquo;il y en a beaucoup. C\u2019est dur de tous les faire, entre les \u00e9v\u00e9nements r\u00e9currents et ceux qui sont exceptionnels comme ces championnats d&rsquo;Europe d\u2019escrime fauteuil. La ville de Paris est partenaire et co-organisatrice avec la F\u00e9d\u00e9ration Fran\u00e7aise Handisport. Beaucoup de sujets nous attendent dans les mois \u00e0 venir, donc j&rsquo;en profite pour voir les \u00e9preuves et discuter avec les \u00e9quipes organisatrices, voir si tout se passait bien et observer les performances des athl\u00e8tes.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Quels ont \u00e9t\u00e9 les retours ?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Je crois que tout le monde est plut\u00f4t content de l&rsquo;organisation, du lieu et du public qui est venu tout au long de la semaine. C&rsquo;\u00e9taient quasiment au-dessus des esp\u00e9rances en termes de billetterie. Le lieu s&rsquo;y pr\u00eate bien. On fait beaucoup d&rsquo;\u00e9v\u00e9nements ici \u00e0 Carpentier, de nature et de sports diff\u00e9rents. Mais on peut toujours s&rsquo;am\u00e9liorer, donc il faut voir ce qui peut encore l&rsquo;\u00eatre.<\/p>\n<h3 style=\"text-align: justify;\"><strong>La halle George Carpentier a re\u00e7u le rugby fauteuil \u00e0 l\u2019automne 2023. D\u00e9sormais, elle a re\u00e7u l\u2019escrime fauteuil. Est-ce une salle particuli\u00e8rement adapt\u00e9e aux comp\u00e9titions handisport ?<\/strong><\/h3>\n<p style=\"text-align: justify;\">C&rsquo;est une salle assez polyvalente. D\u2019abord, le Paris Basket a jou\u00e9 pendant 2\/3 ans ici (dor\u00e9navant, le club parisien \u00e9volue dans l\u2019Adidas Arena, au nord de Paris). Elle est assez modulable avec une grande surface d&rsquo;exploitation et des tribunes qui ne sont pas sur un calibrage tr\u00e8s \u00e9lev\u00e9. On peut monter jusqu&rsquo;\u00e0 4 000, mais elles sont r\u00e9tractables, donc c&rsquo;est pratique pour des \u00e9v\u00e9nements qui ne peuvent pas remplir l\u2019Accor Arena (Bercy) ou l&rsquo;Adidas Arena, \u00e0 la Porte de la Chapelle. Sur des \u00e9v\u00e9nements de 2 000 \u00e0 5 000 personnes, elle est vraiment tr\u00e8s adapt\u00e9e. Cette halle a plusieurs ann\u00e9es, mais elle a \u00e9t\u00e9 r\u00e9nov\u00e9e et on essaye de rendre la plus fonctionnelle possible. Ce n\u2019est pas du dernier-cri, mais elle r\u00e9pond \u00e0 beaucoup d&rsquo;exigences et notamment celles des \u00e9v\u00e9nements internationaux.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/sebastien-barrois-il-faut-arreter-de-ne-pas-avoir-confiance-en-nos-capacites-et-y-croire\/\" class=\"vlp-link\" title=\"S\u00e9bastien Barrois : \u00ab Il faut arr\u00eater de ne pas avoir confiance en nos capacit\u00e9s et y croire \u00bb\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Sebastien-Barrois-Il-faut-arreter-de-ne-pas-avoir-confiance-en-nos-capacites-et-y-croire-.png\" class=\"attachment-800x445 size-800x445\" alt=\"S\u00e9bastien Barrois \u00ab Il faut arr\u00eater de ne pas avoir confiance en nos capacit\u00e9s et y croire \u00bb\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Sebastien-Barrois-Il-faut-arreter-de-ne-pas-avoir-confiance-en-nos-capacites-et-y-croire-.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Sebastien-Barrois-Il-faut-arreter-de-ne-pas-avoir-confiance-en-nos-capacites-et-y-croire--300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Sebastien-Barrois-Il-faut-arreter-de-ne-pas-avoir-confiance-en-nos-capacites-et-y-croire--1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Sebastien-Barrois-Il-faut-arreter-de-ne-pas-avoir-confiance-en-nos-capacites-et-y-croire--768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">S\u00e9bastien Barrois : \u00ab Il faut arr\u00eater de ne pas avoir confiance en nos capacit\u00e9s et y croire \u00bb<\/div><div class=\"vlp-block-1 vlp-link-summary\">Apr\u00e8s les championnats d'Europe d'escrime fauteuil, S\u00e9bastien Barrois est revenu sur les r\u00e9sultats de l'\u00e9quipe de France sur la comp\u00e9tition.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h3 style=\"text-align: justify;\"><strong>La semaine pass\u00e9e, l\u2019Adidas Arena a re\u00e7u les Internationaux de France de badminton. Sans cette nouvelle salle, cela aurait \u00e9t\u00e9 impossible d\u2019avoir ces deux \u00e9v\u00e9nements en parall\u00e8le.<\/strong><\/h3>\n<p style=\"text-align: justify;\">Bien s\u00fbr, c&rsquo;est une option suppl\u00e9mentaire. On a d\u00e9j\u00e0 fait Halle Carpentier et Accor Arena. Mais c&rsquo;est vrai que c&rsquo;est une compl\u00e9mentarit\u00e9 diff\u00e9rente. Peut-\u00eatre qu&rsquo;un jour, on aura l\u2019Accor Arena, l&rsquo;Adidas Arena et la Halle Carpentier en m\u00eame temps. Et Roland-Garros, le Parc des Princes, le stade Jean Bouin et Charl\u00e9ty en m\u00eame temps (rires). On peut s&rsquo;appuyer sur ce maillage-l\u00e0. Il est important, mais il est aussi compl\u00e9mentaire. On essaie de faire en sorte que la ville de Paris reste un lieu attractif pour le sport et pour les comp\u00e9titions internationales.<\/p>\n<p style=\"text-align: justify;\">Avant d&rsquo;accueillir les Jeux, on a accueilli une vingtaine de grands \u00e9v\u00e9nements sportifs internationaux (GESI), dans l&rsquo;optique de montrer qu&rsquo;on a d\u00e9velopp\u00e9 une certaine expertise. La France, et Paris, va continuer de se positionner pour accueillir ces grands \u00e9v\u00e9nements sportifs internationaux. \u00c9videmment, la plus belle vitrine seront les Jeux Olympiques et Paralympiques qui arrivent en 2024, mais c&rsquo;est notre volont\u00e9 collective de faire de Paris une place forte du sport mondial et de continuer \u00e0 l&rsquo;\u00eatre \u00e0 l&rsquo;avenir.<\/p>\n<h3 style=\"text-align: justify;\"><strong>La ville de Paris accueille \u00e9galement des grands \u00e9v\u00e9nements sportifs handisport, comme les championnats du monde de para-athl\u00e9tisme l\u2019\u00e9t\u00e9 dernier. Est-ce que la ville souhaite multiplier leur organisation ?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Bien s\u00fbr. Mais quand je parle du sport, j&rsquo;inclus le handisport. Pour moi, \u00e7a fait partie int\u00e9grante de la r\u00e9flexion et de la strat\u00e9gie. Quand je vous dis qu&rsquo;on veut \u00eatre une terre d\u2019\u00e9v\u00e9nements sportifs, cela inclut bien s\u00fbr tout ce qui concerne le handisport. J&rsquo;en parlais tout \u00e0 l&rsquo;heure avec un membre de la F\u00e9d\u00e9ration handisport : entre 10 et 15% de la population mondiale est atteinte d\u2019un handicap, donc il faut que 10 \u00e0 15 %, voire plus, des \u00e9v\u00e9nements qu&rsquo;on accueille chez nous, soit du handisport.<\/p>\n<p style=\"text-align: justify;\">Cela permet de cr\u00e9er des vocations. Dans le cadre du programme d\u2019h\u00e9ritage des Jeux, on a souhait\u00e9 avoir 40 sections de parasports \u00e0 Paris en 2024. On va atteindre cet objectif alors qu\u2019on \u00e9tait \u00e0 7 ou 8 en 2018. C&rsquo;est la premi\u00e8re fois que la ville accueille les <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/jeux-paralympiques-paris-2024\/\">Jeux Paralympiques<\/a> et j&rsquo;esp\u00e8re que \u00e7a sera le plus grand succ\u00e8s possible. On lui a donn\u00e9 la m\u00eame ambition que les Jeux Olympiques, pour que les personnes en situation de handicap qui veulent pratiquer du sport puissent trouver un club \u00e0 Paris.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Vous parliez du public. Il y a eu beaucoup d&rsquo;enfants et de familles. Est-ce que cela peut permettre d\u2019\u00eatre un acc\u00e9l\u00e9rateur dans le changement des mentalit\u00e9s vis-\u00e0-vis du handicap ?<\/strong><\/h3>\n<p style=\"text-align: justify;\">C&rsquo;est souvent comme cela que les changements et les r\u00e9volutions arrivent. Avoir des familles, des enfants et des femmes qui viennent parce qu&rsquo;elles sont parfois plus porteuses d&rsquo;\u00e9volution que les hommes qui sont parfois plus conservateurs, \u00e7a am\u00e8ne ces avanc\u00e9es-l\u00e0. C&rsquo;est un tr\u00e8s bon signal, mais il faut travailler sur l&rsquo;ensemble de la population. Ce qui, hier, \u00e9tait une exception, devient aujourd\u2019hui quelque chose de normal et demain ce devra \u00eatre une obligation. \u00c7a passe par un changement des mentalit\u00e9s qui est en train de s&rsquo;op\u00e9rer. Et j\u2019esp\u00e8re que les Jeux Paralympiques vont aider.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Voir que les athl\u00e8tes ukrainiens \u00e9taient pr\u00e9sents vous rassure-t-il pour les Jeux ?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Je les ai vus avec beaucoup de joie et de fiert\u00e9. Je suis content de voir que malgr\u00e9 l&rsquo;\u00e9preuve que le pays traverse et la guerre qui lui est faite, certains d&rsquo;entre eux peuvent avoir des sas et, peut-\u00eatre, donner de l&rsquo;espoir ainsi que des petits moments de joie \u00e0 la population qui est dans la difficult\u00e9. Pour moi, c&rsquo;est toujours extr\u00eamement important de voir \u00e7a. De par mes fonctions, j&rsquo;ai eu l&rsquo;occasion de parler de ces sujets avec le CIO, le comit\u00e9 d\u2019organisation et les d\u00e9l\u00e9gations ukrainiennes. J&rsquo;ai r\u00e9cemment re\u00e7u mon homologue de la ville de Kiev et on a beaucoup parl\u00e9 de ces sujets compliqu\u00e9s de diplomatie internationale, dans lequel le sport a un r\u00f4le \u00e0 jouer, m\u00eame si ce n\u2019est pas ce qui fait arr\u00eater la guerre. La ville de Paris souhaitait s\u2019aligner sur la position des athl\u00e8tes ukrainiens. J&rsquo;esp\u00e8re et je sais qu&rsquo;ils viendront \u00e0 Paris. C&rsquo;\u00e9tait \u00e0 notre souhait le plus fort. On verra les conditions avec les athl\u00e8tes russes. C&rsquo;est un autre enjeu et si c&rsquo;est le cas, ce ne seront pas des athl\u00e8tes russes, mais des athl\u00e8tes qui appartiennent \u00e0 un pays et qui ne concourront pas pour la Russie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pierre Rabadan, l\u2019adjoint au sport \u00e0 la mairie de Paris, s\u2019est entretenu avec Dicodusport. Il est revenu sur le nombre important de comp\u00e9titions que la ville accueille.<\/p>\n","protected":false},"author":80,"featured_media":471932,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[21286,8436],"tags":[16878,1004],"class_list":["post-471276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeux-paralympiques-paris-2024","category-jo-paris-2024","tag-breve","tag-paris-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb<\/title>\n<meta name=\"description\" content=\"Pierre Rabadan, l\u2019adjoint au sport \u00e0 la mairie de Paris, s\u2019est entretenu avec Dicodusport. Il est revenu sur le nombre important de comp\u00e9titions que la ville accueille.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb\" \/>\n<meta property=\"og:description\" content=\"Pierre Rabadan, l\u2019adjoint au sport \u00e0 la mairie de Paris, s\u2019est entretenu avec Dicodusport. Il est revenu sur le nombre important de comp\u00e9titions que la ville accueille.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-15T09:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Killian Tanguy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sport_ktanguy\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/\"},\"author\":{\"name\":\"Killian Tanguy\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/ff2feeb71ea78ad31eeb3390ffe96b46\"},\"headline\":\"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb\",\"datePublished\":\"2024-03-15T09:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/\"},\"wordCount\":1386,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png\",\"keywords\":[\"br\u00e8ve\",\"Paris 2024\"],\"articleSection\":[\"Jeux Paralympiques de Paris 2024\",\"JO Paris 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/\",\"name\":\"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png\",\"datePublished\":\"2024-03-15T09:00:34+00:00\",\"description\":\"Pierre Rabadan, l\u2019adjoint au sport \u00e0 la mairie de Paris, s\u2019est entretenu avec Dicodusport. Il est revenu sur le nombre important de comp\u00e9titions que la ville accueille.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png\",\"width\":1200,\"height\":674,\"caption\":\"Pierre Rabadan \u00ab Faire de Paris une place forte du sport mondial \u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/ff2feeb71ea78ad31eeb3390ffe96b46\",\"name\":\"Killian Tanguy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"caption\":\"Killian Tanguy\"},\"description\":\"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.\",\"sameAs\":[\"https:\\\/\\\/killiantanguy.wixsite.com\\\/monsite\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100009753662352\",\"https:\\\/\\\/www.instagram.com\\\/sport.killiantanguy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/killiantanguy\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sport_ktanguy\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRfZkHKJL0wK7wvnJjCry-Q\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/killian-tanguy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb","description":"Pierre Rabadan, l\u2019adjoint au sport \u00e0 la mairie de Paris, s\u2019est entretenu avec Dicodusport. Il est revenu sur le nombre important de comp\u00e9titions que la ville accueille.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/","og_locale":"fr_FR","og_type":"article","og_title":"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb","og_description":"Pierre Rabadan, l\u2019adjoint au sport \u00e0 la mairie de Paris, s\u2019est entretenu avec Dicodusport. Il est revenu sur le nombre important de comp\u00e9titions que la ville accueille.","og_url":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/profile.php?id=100009753662352","article_published_time":"2024-03-15T09:00:34+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png","type":"image\/png"}],"author":"Killian Tanguy","twitter_card":"summary_large_image","twitter_title":"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb","twitter_creator":"@https:\/\/twitter.com\/sport_ktanguy","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/"},"author":{"name":"Killian Tanguy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46"},"headline":"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb","datePublished":"2024-03-15T09:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/"},"wordCount":1386,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png","keywords":["br\u00e8ve","Paris 2024"],"articleSection":["Jeux Paralympiques de Paris 2024","JO Paris 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/","url":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/","name":"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png","datePublished":"2024-03-15T09:00:34+00:00","description":"Pierre Rabadan, l\u2019adjoint au sport \u00e0 la mairie de Paris, s\u2019est entretenu avec Dicodusport. Il est revenu sur le nombre important de comp\u00e9titions que la ville accueille.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Pierre-Rabadan-Faire-de-Paris-une-place-forte-du-sport-mondial-.png","width":1200,"height":674,"caption":"Pierre Rabadan \u00ab Faire de Paris une place forte du sport mondial \u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pierre-rabadan-faire-de-paris-une-place-forte-du-sport-mondial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pierre Rabadan : \u00ab Faire de Paris une place forte du sport mondial \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46","name":"Killian Tanguy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","caption":"Killian Tanguy"},"description":"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.","sameAs":["https:\/\/killiantanguy.wixsite.com\/monsite","https:\/\/www.facebook.com\/profile.php?id=100009753662352","https:\/\/www.instagram.com\/sport.killiantanguy\/","https:\/\/www.linkedin.com\/in\/killiantanguy\/","https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy","https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q"],"url":"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/471276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=471276"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/471276\/revisions"}],"predecessor-version":[{"id":471934,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/471276\/revisions\/471934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/471932"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=471276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=471276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=471276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}