{"id":472897,"date":"2024-03-17T19:34:22","date_gmt":"2024-03-17T18:34:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=472897&#038;preview=true&#038;preview_id=472897"},"modified":"2024-03-17T20:41:39","modified_gmt":"2024-03-17T19:41:39","slug":"ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/","title":{"rendered":"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><b>LIGUE EUROP\u00c9ENNE DE HANDBALL &#8211; Dans ce match aller des quarts de finale, les Neptunes de Nantes se sont d\u00e9faites des Norv\u00e9giennes de Sola (31-27) dans leur salle. Cela leur donne un avantage non n\u00e9gligeable avant le match retour.<\/b><\/i><\/p>\n<h2 style=\"text-align: justify;\">Le double visage de Nantes<\/h2>\n<p style=\"text-align: justify;\">Parti avec la casquette de favori, Nantes d\u00e9bute mal son match. La tactique semble ne pas fonctionner et Sola est imp\u00e9rial sur ses ballons (0-4, 3&rsquo;42). D\u00e8s lors, la coach des Nantais, <strong>Helle Thomsen<\/strong>, pose un temps mort pour faire r\u00e9agir son \u00e9quipe. Les attaques sont rapides, mais les Nantaises se font contrer trop facilement. En r\u00e9action, les Neptunes vont faire davantage circuler le ballon et moins se jeter vers le but de <strong>Rikke Grandlund<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En un quart d&rsquo;heure, le retard accumul\u00e9 s&rsquo;est r\u00e9sorb\u00e9 et la possession de balle est largement pour les Nantaises. Seul point noir, les buts encaiss\u00e9s rapidement (7-7, 15&prime;). Mais <strong>Floriane Andr\u00e9<\/strong> ne manque pas de s&rsquo;interposer sur les tirs norv\u00e9giens et m\u00e8ne toute son \u00e9quipe vers un \u00e9cart qui commence \u00e0 croitre en fin de p\u00e9riode (13-10, 25&prime;). En fin de p\u00e9riode, les visiteuses montrent qu&rsquo;elles sont au niveau du match, elles reviennent \u00e0 un but d&rsquo;\u00e9cart (16-15, 30&prime;).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">The only one who can stop Sola HK \ud835\udc05\ud835\udc25\ud835\udc28\ud835\udc2b\ud835\udc22\ud835\udc1a\ud835\udc27\ud835\udc1e \ud835\udc00\ud835\udc27\ud835\udc1d\ud835\udc2b\ud835\udc1e \ud83c\udf1f<a href=\"https:\/\/twitter.com\/hashtag\/ehfel?src=hash&amp;ref_src=twsrc%5Etfw\">#ehfel<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/elw?src=hash&amp;ref_src=twsrc%5Etfw\">#elw<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/allin?src=hash&amp;ref_src=twsrc%5Etfw\">#allin<\/a> <a href=\"https:\/\/t.co\/1K6T9CxXAW\">pic.twitter.com\/1K6T9CxXAW<\/a><\/p>\n<p>\u2014 EHF European League (@ehfel_official) <a href=\"https:\/\/twitter.com\/ehfel_official\/status\/1769412528361091484?ref_src=twsrc%5Etfw\">March 17, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">La solidit\u00e9 du collectif nantais<\/h2>\n<p style=\"text-align: justify;\">Au retour des vestiaires, la strat\u00e9gie des Nantaises commence \u00e0 payer de plus en plus, en privant les visiteuses de leur jeu, tout en faisant bien tourner le ballon. Bien aid\u00e9es par <strong>Tamara Horacek<\/strong> et<strong> Lena Grandveau<\/strong>, les Neptunes prennent de l&rsquo;avance (26-21, 15&prime;). <strong>Jessica Ryde<\/strong>, la gardienne des Neptunes en seconde p\u00e9riode, participe \u00e0 l&rsquo;effort en sortant plusieurs ballons. L&rsquo;avance se stabilise, Nantes n&rsquo;a plus \u00e0 forcer pour faire le jeu et en profite pour offrir quelques belles actions (30-25, 24&prime;). Les Neptunes de Nantes n&rsquo;ont plus qu&rsquo;\u00e0 g\u00e9rer leur fin de rencontre pour s&rsquo;accorder une victoire nette qui offre un bon avantage pour le match retour pr\u00e9vu la semaine prochaine en Norv\u00e8ge.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Great game we watched \ud83d\udc40in Nantes, <a href=\"https:\/\/twitter.com\/neptunesnantes?ref_src=twsrc%5Etfw\">@neptunesnantes<\/a> \ud83d\udd31 got the win and will fly to Norway \ud83c\uddf3\ud83c\uddf4with 4 goals ahead.<a href=\"https:\/\/twitter.com\/hashtag\/ehfel?src=hash&amp;ref_src=twsrc%5Etfw\">#ehfel<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/elw?src=hash&amp;ref_src=twsrc%5Etfw\">#elw<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/allin?src=hash&amp;ref_src=twsrc%5Etfw\">#allin<\/a> <a href=\"https:\/\/t.co\/Lax5JReQDl\">pic.twitter.com\/Lax5JReQDl<\/a><\/p>\n<p>\u2014 EHF European League (@ehfel_official) <a href=\"https:\/\/twitter.com\/ehfel_official\/status\/1769432455583322237?ref_src=twsrc%5Etfw\">March 17, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE EUROP\u00c9ENNE DE HANDBALL &#8211; Dans ce match aller des quarts de finale, les Neptunes de Nantes se sont d\u00e9faites des Norv\u00e9giennes de Sola (31-27) dans leur salle. Cela leur donne un avantage non n\u00e9gligeable avant le match retour.<\/p>\n","protected":false},"author":77,"featured_media":472924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2304],"tags":[16878,29822,29824],"class_list":["post-472897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handball","tag-breve","tag-european-league-handball","tag-neptunes-de-nantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification<\/title>\n<meta name=\"description\" content=\"LIGUE EUROP\u00c9ENNE DE HANDBALL - Dans ce match aller des quarts de finale, les Neptunes de Nantes se sont d\u00e9faites des Norv\u00e9giennes de Sola (31-27).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification\" \/>\n<meta property=\"og:description\" content=\"LIGUE EUROP\u00c9ENNE DE HANDBALL - Dans ce match aller des quarts de finale, les Neptunes de Nantes se sont d\u00e9faites des Norv\u00e9giennes de Sola (31-27).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-17T18:34:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-17T19:41:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gauthier Santenac\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/\"},\"author\":{\"name\":\"Gauthier Santenac\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/8dc834d4675ed3b1b0d3c7ac46cf393d\"},\"headline\":\"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification\",\"datePublished\":\"2024-03-17T18:34:22+00:00\",\"dateModified\":\"2024-03-17T19:41:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png\",\"keywords\":[\"br\u00e8ve\",\"european league handball\",\"Neptunes de Nantes\"],\"articleSection\":[\"Handball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/\",\"name\":\"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png\",\"datePublished\":\"2024-03-17T18:34:22+00:00\",\"dateModified\":\"2024-03-17T19:41:39+00:00\",\"description\":\"LIGUE EUROP\u00c9ENNE DE HANDBALL - Dans ce match aller des quarts de finale, les Neptunes de Nantes se sont d\u00e9faites des Norv\u00e9giennes de Sola (31-27).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png\",\"width\":1200,\"height\":674,\"caption\":\"Ligue europ\u00e9enne de handball (F) Nantes prend une option pour la qualification\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/8dc834d4675ed3b1b0d3c7ac46cf393d\",\"name\":\"Gauthier Santenac\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"caption\":\"Gauthier Santenac\"},\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/gauthier-santenac\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification","description":"LIGUE EUROP\u00c9ENNE DE HANDBALL - Dans ce match aller des quarts de finale, les Neptunes de Nantes se sont d\u00e9faites des Norv\u00e9giennes de Sola (31-27).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification","og_description":"LIGUE EUROP\u00c9ENNE DE HANDBALL - Dans ce match aller des quarts de finale, les Neptunes de Nantes se sont d\u00e9faites des Norv\u00e9giennes de Sola (31-27).","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-03-17T18:34:22+00:00","article_modified_time":"2024-03-17T19:41:39+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png","type":"image\/png"}],"author":"Gauthier Santenac","twitter_card":"summary_large_image","twitter_title":"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/"},"author":{"name":"Gauthier Santenac","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8dc834d4675ed3b1b0d3c7ac46cf393d"},"headline":"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification","datePublished":"2024-03-17T18:34:22+00:00","dateModified":"2024-03-17T19:41:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png","keywords":["br\u00e8ve","european league handball","Neptunes de Nantes"],"articleSection":["Handball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/","name":"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png","datePublished":"2024-03-17T18:34:22+00:00","dateModified":"2024-03-17T19:41:39+00:00","description":"LIGUE EUROP\u00c9ENNE DE HANDBALL - Dans ce match aller des quarts de finale, les Neptunes de Nantes se sont d\u00e9faites des Norv\u00e9giennes de Sola (31-27).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Ligue-europeenne-de-handball-F-Nantes-prend-une-option-pour-la-qualification.png","width":1200,"height":674,"caption":"Ligue europ\u00e9enne de handball (F) Nantes prend une option pour la qualification"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europeenne-de-handball-f-nantes-prend-une-option-pour-la-qualification\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue europ\u00e9enne de handball (F) : Nantes prend une option pour la qualification"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8dc834d4675ed3b1b0d3c7ac46cf393d","name":"Gauthier Santenac","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","caption":"Gauthier Santenac"},"url":"https:\/\/dicodusport.fr\/blog\/author\/gauthier-santenac\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/472897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=472897"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/472897\/revisions"}],"predecessor-version":[{"id":472949,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/472897\/revisions\/472949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/472924"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=472897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=472897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=472897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}