{"id":472981,"date":"2024-03-17T23:01:41","date_gmt":"2024-03-17T22:01:41","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=472981&#038;preview=true&#038;preview_id=472981"},"modified":"2024-03-17T23:42:27","modified_gmt":"2024-03-17T22:42:27","slug":"la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/","title":{"rendered":"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>RUGBY EUROPE CHAMPIONSHIP 2024 &#8211; En patronne, la G\u00e9orgie a d\u00e9croch\u00e9 un septi\u00e8me succ\u00e8s cons\u00e9cutif dans le Rugby Europe Championship, en surclassant le Portugal en finale ce dimanche (36-10).<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet<\/strong>\u00a0:\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-rugby-europe-championship-2024\/\"><strong>Les r\u00e9sultats du Rugby Europe Championship 2024<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>G\u00e9orgie &#8211; Portugal<\/strong>, c&rsquo;est le remake de la finale du Rugby Europe Championship 2023, <a href=\"https:\/\/dicodusport.fr\/blog\/rugby-europe-championship-2023-la-georgie-sacree-pour-la-6eme-fois-de-suite\/\">remport\u00e9e par <em>los Lelos<\/em> (38-11)<\/a>, il y a tout juste un an. C&rsquo;est aussi le remake de la rencontre opposant G\u00e9orgiens et Portugais lors de la phase de poules de la derni\u00e8re Coupe du monde, d\u00e9bouchant sur <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-georgie-arrache-le-nul-contre-le-portugal-dans-un-match-spectaculaire\/\">un match nul (18-18<\/a>). Autant dire que cette finale du <strong>REC 2024<\/strong> s&rsquo;annon\u00e7ait serr\u00e9e. Du moins, sur le papier.<\/p>\n<h2 style=\"text-align: justify;\">La G\u00e9orgie tout en ma\u00eetrise<\/h2>\n<p style=\"text-align: justify;\">Car sur le terrain, la <strong>G\u00e9orgie<\/strong> marque le <strong>Portugal<\/strong> au fer rouge. Plus puissants, les joueurs du Caucase investissent les 22 m\u00e8tres portugais. Une domination qui se traduit par quatre p\u00e9nalit\u00e9s enquill\u00e9es de <strong>Luka Matkava<\/strong>, l&rsquo;ouvreur de <strong>Black Lion<\/strong>. En face, <strong>Hugo Camacho<\/strong> (Aviron Bayonnais) permet aux <strong>Lobos<\/strong> de ne pas rentrer fanny au vestiaire. Score \u00e0 la pause, 12-3<strong> G\u00e9orgie<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Mais, apr\u00e8s la pause, la <strong>G\u00e9orgie<\/strong> passe la surmultipli\u00e9e. L&rsquo;ailier <strong>Akaki Tabutsadze<\/strong> s&rsquo;offre un doubl\u00e9 (42&prime; et 63&prime;). Le talonneur du MHR, <strong>Vano Karkadze<\/strong>, y va aussi de son essai (49&prime;), tout comme le demi de m\u00eal\u00e9e aurillacois, tout juste entr\u00e9 en jeu, <b>Mikheil Alania<\/b> (68&prime;). L&rsquo;essai de <strong>Rodrigo Marta<\/strong> en toute fin de rencontre pour le Portugal ne changera rien. Succ\u00e8s des G\u00e9orgiens <strong>(36-10)<\/strong>, et septi\u00e8me sacre cons\u00e9cutif pour <em>los Lelos<\/em> dans la comp\u00e9tition. Les Portugais, eux, ont \u00e9t\u00e9 trop maladroits et indisciplin\u00e9s tout au long de la rencontre pour esp\u00e9rer l&#8217;emporter.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">For the SEVENTH successive time, <a href=\"https:\/\/twitter.com\/GeorgianRugby?ref_src=twsrc%5Etfw\">@GeorgianRugby<\/a> are <a href=\"https:\/\/twitter.com\/rugby_europe?ref_src=twsrc%5Etfw\">@rugby_europe<\/a> Champions \ud83c\udfc6<a href=\"https:\/\/twitter.com\/hashtag\/GEOvPOR?src=hash&amp;ref_src=twsrc%5Etfw\">#GEOvPOR<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/REC24?src=hash&amp;ref_src=twsrc%5Etfw\">#REC24<\/a> <a href=\"https:\/\/t.co\/OFg74e3EjF\">pic.twitter.com\/OFg74e3EjF<\/a><\/p>\n<p>\u2014 World Rugby (@WorldRugby) <a href=\"https:\/\/twitter.com\/WorldRugby\/status\/1769484286959276284?ref_src=twsrc%5Etfw\">March 17, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY EUROPE CHAMPIONSHIP 2024 &#8211; En patronne, la G\u00e9orgie a d\u00e9croch\u00e9 un septi\u00e8me succ\u00e8s cons\u00e9cutif dans le Rugby Europe Championship, en surclassant le Portugal en finale ce dimanche (36-10).<\/p>\n","protected":false},"author":4,"featured_media":473019,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129],"tags":[16878,7020,89,29619],"class_list":["post-472981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-breve","tag-georgie","tag-portugal","tag-rugby-europe-championship"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif<\/title>\n<meta name=\"description\" content=\"La G\u00e9orgie a d\u00e9croch\u00e9 un septi\u00e8me succ\u00e8s cons\u00e9cutif dans le Rugby Europe Championship, en surclassant le Portugal en finale ce dimanche (36-10).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif\" \/>\n<meta property=\"og:description\" content=\"La G\u00e9orgie a d\u00e9croch\u00e9 un septi\u00e8me succ\u00e8s cons\u00e9cutif dans le Rugby Europe Championship, en surclassant le Portugal en finale ce dimanche (36-10).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-17T22:01:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-17T22:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif\",\"datePublished\":\"2024-03-17T22:01:41+00:00\",\"dateModified\":\"2024-03-17T22:42:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png\",\"keywords\":[\"br\u00e8ve\",\"G\u00e9orgie\",\"Portugal\",\"Rugby Europe Championship\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/\",\"name\":\"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png\",\"datePublished\":\"2024-03-17T22:01:41+00:00\",\"dateModified\":\"2024-03-17T22:42:27+00:00\",\"description\":\"La G\u00e9orgie a d\u00e9croch\u00e9 un septi\u00e8me succ\u00e8s cons\u00e9cutif dans le Rugby Europe Championship, en surclassant le Portugal en finale ce dimanche (36-10).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png\",\"width\":1200,\"height\":674,\"caption\":\"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif (1)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif","description":"La G\u00e9orgie a d\u00e9croch\u00e9 un septi\u00e8me succ\u00e8s cons\u00e9cutif dans le Rugby Europe Championship, en surclassant le Portugal en finale ce dimanche (36-10).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/","og_locale":"fr_FR","og_type":"article","og_title":"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif","og_description":"La G\u00e9orgie a d\u00e9croch\u00e9 un septi\u00e8me succ\u00e8s cons\u00e9cutif dans le Rugby Europe Championship, en surclassant le Portugal en finale ce dimanche (36-10).","og_url":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2024-03-17T22:01:41+00:00","article_modified_time":"2024-03-17T22:42:27+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif","datePublished":"2024-03-17T22:01:41+00:00","dateModified":"2024-03-17T22:42:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png","keywords":["br\u00e8ve","G\u00e9orgie","Portugal","Rugby Europe Championship"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/","url":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/","name":"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png","datePublished":"2024-03-17T22:01:41+00:00","dateModified":"2024-03-17T22:42:27+00:00","description":"La G\u00e9orgie a d\u00e9croch\u00e9 un septi\u00e8me succ\u00e8s cons\u00e9cutif dans le Rugby Europe Championship, en surclassant le Portugal en finale ce dimanche (36-10).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/La-Georgie-remporte-un-7eme-Rugby-Europe-Championship-consecutif-1.png","width":1200,"height":674,"caption":"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif (1)"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/la-georgie-remporte-un-7eme-rugby-europe-championship-consecutif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"La G\u00e9orgie remporte un 7\u00e8me Rugby Europe Championship cons\u00e9cutif"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/472981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=472981"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/472981\/revisions"}],"predecessor-version":[{"id":473012,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/472981\/revisions\/473012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/473019"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=472981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=472981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=472981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}