{"id":473407,"date":"2024-03-20T16:32:25","date_gmt":"2024-03-20T15:32:25","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=473407&#038;preview=true&#038;preview_id=473407"},"modified":"2024-03-20T16:42:53","modified_gmt":"2024-03-20T15:42:53","slug":"tour-de-catalogne-2024-classement-3eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/","title":{"rendered":"Tour de Catalogne 2024 &#8211; Classement 3\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>TOUR DE CATALOGNE 2024 &#8211; D\u00e9couvrez le classement de la 3\u00e8me \u00e9tape (top 20) du Tour de Catalogne 2024, disput\u00e9e ce mercredi 20 mars<\/strong><\/em><em><strong> 2024 entre <span class=\"red\">Sant Joan de les Abadesses et <\/span><span class=\"red\">Port Ain\u00e9 <\/span><span class=\"red fw400\">(176.7 km)<\/span>. La course catalane est inscrite au <a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-calendrier-world-tour-2024\/\">calendrier World Tour<\/a>.<\/strong><\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-parcours-detaille-et-profils-des-etapes\/\">Tour de Catalogne 2024 : Parcours d\u00e9taill\u00e9 et profils des \u00e9tapes<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-general\/\">Tour de Catalogne 2024\u00a0&#8211; Classement g\u00e9n\u00e9ral<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Classement 3\u00e8me \u00e9tape Tour de Catalogne 2024 &#8211; Mercredi 20 mars<\/h2>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf8\ud83c\uddee TADEJ POGACAR<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UAE TEAM EMIRATES<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>4h34m25s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">\ud83c\uddea\ud83c\uddf8<\/strong> MIKEL LANDA<br \/>\n<\/strong><span style=\"font-size: 0.8em\">SOUDAL &#8211; QUICK STEP<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 48s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9<\/strong><\/span> ANTONIO TIBERI<\/strong><br \/>\n<span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">BAHRAIN VICTORIOUS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m03s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">\ud83c\uddf3\ud83c\uddf1 WOUT POELS<\/strong><br \/>\n<span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">BAHRAIN VICTORIOUS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m03s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\uddf8 SEPP KUSS<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">TEAM VISMA | LEASE A BIKE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m03s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong style=\"font-size: 14.4px\">\ud83c\uddf7\ud83c\uddfa ALEKSANDR VLASOV<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">BORA &#8211; HANSGROHE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m10s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">\ud83c\uddea\ud83c\uddf8<\/strong> CRISTIAN RODRIGUEZ<br \/>\n<\/strong><span style=\"font-size: 0.8em\">ARK\u00c9A B&amp;B HOTELS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m10s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde6\ud83c\uddfa CHRIS HARPER<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM JAYCO ALULA<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m10s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7<\/strong> LENNY MARTINEZ<br \/>\n<\/strong><span style=\"font-size: 0.8em\">GROUPAMA &#8211; FDJ<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m10s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">\ud83c\uddea\ud83c\uddf8<\/strong> ENRIC MAS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MOVISTAR<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m10s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf3\ud83c\uddff GEORGE BENNETT<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ISRAEL &#8211; PREMIER TECH<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m20s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde7\ud83c\uddea<\/strong><\/span> CIAN UIJTDEBROEKS<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">TEAM VISMA | LEASE A BIKE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m20s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde7\ud83c\uddea LAURENS DE PLUS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">INEOS GRENADIERS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m25s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 LORENZO FORTUNATO<br \/>\n<\/strong><span style=\"font-size: 0.8em\">ASTANA QAZAQSTAN TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m38s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">\ud83c\udde8\ud83c\uddf4<\/strong> EGAN BERNAL<\/strong><br \/>\n<span style=\"font-size: 0.8em\">INEOS GRENADIERS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m38s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">\ud83c\udde8\ud83c\uddf4<\/strong> EINER RUBIO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MOVISTAR<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m44s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf5\ud83c\uddf9 JOAO ALMEIDA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UAE TEAM EMIRATES<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m46s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\uddf8<\/strong> MATTHEW RICCITELLO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ISRAEL &#8211; PREMIER TECH<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m52s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">\ud83c\udde8\ud83c\uddf4<\/strong> ESTEBAN CHAVES<\/strong><br \/>\n<span style=\"font-size: 0.8em\">EF EDUCATION EASYPOST<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 2m11s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">\ud83c\uddea\ud83c\uddf8<\/strong> CARLOS VERONA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">LIDL &#8211; TREK<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 2m16s<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.procyclingstats.com\/race\/volta-a-catalunya\/2024\/stage-3\"><strong>Le classement complet de la 3\u00e8me \u00e9tape<\/strong><\/a><strong><br \/>\n<\/strong><\/li>\n<\/ul>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-les-10-coureurs-les-mieux-payes-du-peloton-en-2024\/\" class=\"vlp-link\" title=\"Cyclisme : Les 10 coureurs les mieux pay\u00e9s du peloton en 2024\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Cyclisme-Les-10-coureurs-les-mieux-payes-du-peloton-en-2024.png\" class=\"attachment-800x445 size-800x445\" alt=\"Cyclisme Les 10 coureurs les mieux pay\u00e9s du peloton en 2024\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Cyclisme-Les-10-coureurs-les-mieux-payes-du-peloton-en-2024.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Cyclisme-Les-10-coureurs-les-mieux-payes-du-peloton-en-2024-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Cyclisme-Les-10-coureurs-les-mieux-payes-du-peloton-en-2024-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Cyclisme-Les-10-coureurs-les-mieux-payes-du-peloton-en-2024-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Cyclisme : Les 10 coureurs les mieux pay\u00e9s du peloton en 2024<\/div><div class=\"vlp-block-1 vlp-link-summary\">CYCLISME SUR ROUTE 2024 - R\u00e9cemment, la Gazzetta dello Sport a d\u00e9voil\u00e9 les salaires annuels des 10 cyclistes les mieux pay\u00e9s en 2024.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TOUR DE CATALOGNE 2024 &#8211; D\u00e9couvrez le classement de la 3\u00e8me\u00a0\u00e9tape (top 20) du Tour de Catalogne 2024, disput\u00e9e ce mercredi 20 mars 2024.<\/p>\n","protected":false},"author":4,"featured_media":473409,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46994],"tags":[16878,7488],"class_list":["post-473407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-breve","tag-tour-de-catalogne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"TOUR DE CATALOGNE 2024 - D\u00e9couvrez le classement de la 3\u00e8me\u00a0\u00e9tape (top 20) du Tour de Catalogne 2024, disput\u00e9e ce mercredi 20 mars 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"TOUR DE CATALOGNE 2024 - D\u00e9couvrez le classement de la 3\u00e8me\u00a0\u00e9tape (top 20) du Tour de Catalogne 2024, disput\u00e9e ce mercredi 20 mars 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T15:32:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T15:42:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tour de Catalogne 2024 &#8211; Classement 3\u00e8me \u00e9tape\",\"datePublished\":\"2024-03-20T15:32:25+00:00\",\"dateModified\":\"2024-03-20T15:42:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png\",\"keywords\":[\"br\u00e8ve\",\"Tour de Catalogne\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/\",\"name\":\"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png\",\"datePublished\":\"2024-03-20T15:32:25+00:00\",\"dateModified\":\"2024-03-20T15:42:53+00:00\",\"description\":\"TOUR DE CATALOGNE 2024 - D\u00e9couvrez le classement de la 3\u00e8me\u00a0\u00e9tape (top 20) du Tour de Catalogne 2024, disput\u00e9e ce mercredi 20 mars 2024.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png\",\"width\":1200,\"height\":674,\"caption\":\"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de Catalogne 2024 &#8211; Classement 3\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape","description":"TOUR DE CATALOGNE 2024 - D\u00e9couvrez le classement de la 3\u00e8me\u00a0\u00e9tape (top 20) du Tour de Catalogne 2024, disput\u00e9e ce mercredi 20 mars 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape","og_description":"TOUR DE CATALOGNE 2024 - D\u00e9couvrez le classement de la 3\u00e8me\u00a0\u00e9tape (top 20) du Tour de Catalogne 2024, disput\u00e9e ce mercredi 20 mars 2024.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2024-03-20T15:32:25+00:00","article_modified_time":"2024-03-20T15:42:53+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tour de Catalogne 2024 &#8211; Classement 3\u00e8me \u00e9tape","datePublished":"2024-03-20T15:32:25+00:00","dateModified":"2024-03-20T15:42:53+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png","keywords":["br\u00e8ve","Tour de Catalogne"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/","name":"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png","datePublished":"2024-03-20T15:32:25+00:00","dateModified":"2024-03-20T15:42:53+00:00","description":"TOUR DE CATALOGNE 2024 - D\u00e9couvrez le classement de la 3\u00e8me\u00a0\u00e9tape (top 20) du Tour de Catalogne 2024, disput\u00e9e ce mercredi 20 mars 2024.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/03\/Tour-de-Catalogne-2024-Classement-3eme-etape.png","width":1200,"height":674,"caption":"Tour de Catalogne 2024 - Classement 3\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2024-classement-3eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de Catalogne 2024 &#8211; Classement 3\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/473407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=473407"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/473407\/revisions"}],"predecessor-version":[{"id":473439,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/473407\/revisions\/473439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/473409"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=473407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=473407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=473407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}