{"id":481663,"date":"2024-04-26T22:14:19","date_gmt":"2024-04-26T20:14:19","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=481663&#038;preview=true&#038;preview_id=481663"},"modified":"2024-04-26T22:56:25","modified_gmt":"2024-04-26T20:56:25","slug":"volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/","title":{"rendered":"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE A F\u00c9MININE DE VOLLEY &#8211; Nantes a bien d\u00e9but\u00e9, mais la machine s&rsquo;est enray\u00e9e apr\u00e8s une manche et demie, et les Mariannes ont renvers\u00e9 la situation pour aller chercher le titre.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Ce soir, on allait savoir qui allait succ\u00e9der au Vol\u00e9ro Le Cannet au palmar\u00e8s de la Ligue A f\u00e9minine de volley. Mardi, lors de la finale aller, les Mariannes de Levallois Paris Saint-Cloud avaient fait leur part de travail <a href=\"https:\/\/dicodusport.fr\/blog\/volley-levallois-paris-saint-cloud-etrille-nantes-en-finale-aller-de-ligue-a-feminine\/\">et remport\u00e9 la premi\u00e8re manche<\/a>, pouvant se d\u00e9placer l&rsquo;esprit libre. Plus d&rsquo;alternative donc pour les Neptunes de Nantes : il fallait gagner, quelque soit le score, pour arracher un <em>Golden Set<\/em> dans la foul\u00e9e.<\/p>\n<h2 style=\"text-align: justify;\">Les Mariannes renversent tout<\/h2>\n<p style=\"text-align: justify;\">Une mission \u00e0 la hauteur des laur\u00e9ates de la Coupe de France, qui ne font preuve d&rsquo;aucune prudence, et creusent les premi\u00e8res un vrai \u00e9cart, provoquant un premier temps mort rapide. Mais ce petit \u00e9cart sera crucial au final, les Mariannes ayant des occasions d&rsquo;effectuer un rapproch\u00e9 sans y parvenir, avant de l\u00e2cher le set devant la puissance du block nantais. La salle est en d\u00e9lire, mais change d&rsquo;ambiance ensuite. Alors que les Mariannes \u00e9taient bien parties, elles encaissent un terrible <strong>8-1<\/strong> qui laisse \u00e0 penser que les Neptunes peuvent enfoncer le clou, puisque menant <strong>18-12<\/strong>, mais la puissance des Franciliennes fait payer cher les impr\u00e9cisions locales, et les visiteuses parviennent \u00e0 arracher la deuxi\u00e8me manche et relancer la rencontre.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udc01\ud835\udc1a\ud835\udc25\ud835\udc25\ud835\udc1e \ud835\udc1d\ud835\udc1e \ud835\udc2c\ud835\udc1e\ud835\udc2d \ud83c\udfd0<a href=\"https:\/\/twitter.com\/neptunesnantes?ref_src=twsrc%5Etfw\">@neptunesnantes<\/a> \ud83d\udd35 24 &#8211; 26 \ud83d\udfe3 <a href=\"https:\/\/twitter.com\/lesmariannes75?ref_src=twsrc%5Etfw\">@lesmariannes75<\/a><\/p>\n<p>Le direct \ud83d\udcfa\ud83d\udc49<a href=\"https:\/\/t.co\/0YVlsETjat\">https:\/\/t.co\/0YVlsETjat<\/a><a href=\"https:\/\/twitter.com\/hashtag\/playoffs?src=hash&amp;ref_src=twsrc%5Etfw\">#playoffs<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/volleyLAF?src=hash&amp;ref_src=twsrc%5Etfw\">#volleyLAF<\/a> <a href=\"https:\/\/t.co\/M2L2pKs9gp\">pic.twitter.com\/M2L2pKs9gp<\/a><\/p>\n<p>\u2014 LNV (@LNVofficiel) <a href=\"https:\/\/twitter.com\/LNVofficiel\/status\/1783935848213266549?ref_src=twsrc%5Etfw\">April 26, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">On ne croyait pas si bien dire, puisque les Mariannes profitent de l&rsquo;\u00e9lan et se d\u00e9tachent irr\u00e9sistiblement dans le troisi\u00e8me set. Port\u00e9es par une<strong> Bianca Cugno<\/strong> incroyable d&rsquo;efficacit\u00e9 en attaque (31 points !), elles font taire le complexe Mangin-Beaulieu et prennent la troisi\u00e8me manche. Il n&rsquo;en manque qu&rsquo;une, mais la partie semble avoir d\u00e9finitivement tourn\u00e9. Les visiteuses d\u00e9roulent leur volley, sont trop fortes au contre, et la partie semble pli\u00e9e, jusqu&rsquo;au baroud d&rsquo;honneur des Neptunes, qui l\u00e2chent toutes leurs forces. Cons\u00e9quence, elles exploitent la nervosit\u00e9 adverse, collent un <strong>4-0<\/strong>, se procurent m\u00eame une balle de tie-break.<\/p>\n<p style=\"text-align: justify;\">Les Mariannes ne craquent pas, et le block fait le travail pour encha\u00eener les trois derniers points et aller chercher la victoire <strong>19-25, 26-24, 25-17, 26-24<\/strong>.\u00a0Seulement un an apr\u00e8s la fusion de Levallois et du Stade Fran\u00e7ais Paris Saint-Cloud, les Mariannes sont championnes de France !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE A F\u00c9MININE DE VOLLEY &#8211; Nantes a bien d\u00e9but\u00e9, mais la machine s&rsquo;est enray\u00e9e apr\u00e8s une manche et demie, et les Mariannes ont renvers\u00e9 la situation pour aller chercher le titre.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":481711,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8369],"tags":[16878,38959,6576,29824],"class_list":["post-481663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volley-ball","tag-breve","tag-levallois-paris-saint-cloud-volley","tag-ligue-a-feminine","tag-neptunes-de-nantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !<\/title>\n<meta name=\"description\" content=\"LIGUE A F\u00c9MININE DE VOLLEY - Nantes a bien d\u00e9but\u00e9, mais la machine s&#039;est enray\u00e9e apr\u00e8s une manche et demie, et les Mariannes ont renvers\u00e9 la situation pour aller chercher le titre.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !\" \/>\n<meta property=\"og:description\" content=\"LIGUE A F\u00c9MININE DE VOLLEY - Nantes a bien d\u00e9but\u00e9, mais la machine s&#039;est enray\u00e9e apr\u00e8s une manche et demie, et les Mariannes ont renvers\u00e9 la situation pour aller chercher le titre.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T20:14:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T20:56:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !\",\"datePublished\":\"2024-04-26T20:14:19+00:00\",\"dateModified\":\"2024-04-26T20:56:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png\",\"keywords\":[\"br\u00e8ve\",\"Levallois Paris Saint-Cloud Volley\",\"Ligue A f\u00e9minine\",\"Neptunes de Nantes\"],\"articleSection\":[\"Volley-Ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/\",\"name\":\"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png\",\"datePublished\":\"2024-04-26T20:14:19+00:00\",\"dateModified\":\"2024-04-26T20:56:25+00:00\",\"description\":\"LIGUE A F\u00c9MININE DE VOLLEY - Nantes a bien d\u00e9but\u00e9, mais la machine s'est enray\u00e9e apr\u00e8s une manche et demie, et les Mariannes ont renvers\u00e9 la situation pour aller chercher le titre.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png\",\"width\":1200,\"height\":674,\"caption\":\"Volley Les Mariannes de Levallois Paris Saint-Cloud championnes de France !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !","description":"LIGUE A F\u00c9MININE DE VOLLEY - Nantes a bien d\u00e9but\u00e9, mais la machine s'est enray\u00e9e apr\u00e8s une manche et demie, et les Mariannes ont renvers\u00e9 la situation pour aller chercher le titre.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/","og_locale":"fr_FR","og_type":"article","og_title":"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !","og_description":"LIGUE A F\u00c9MININE DE VOLLEY - Nantes a bien d\u00e9but\u00e9, mais la machine s'est enray\u00e9e apr\u00e8s une manche et demie, et les Mariannes ont renvers\u00e9 la situation pour aller chercher le titre.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2024-04-26T20:14:19+00:00","article_modified_time":"2024-04-26T20:56:25+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !","datePublished":"2024-04-26T20:14:19+00:00","dateModified":"2024-04-26T20:56:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png","keywords":["br\u00e8ve","Levallois Paris Saint-Cloud Volley","Ligue A f\u00e9minine","Neptunes de Nantes"],"articleSection":["Volley-Ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/","url":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/","name":"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png","datePublished":"2024-04-26T20:14:19+00:00","dateModified":"2024-04-26T20:56:25+00:00","description":"LIGUE A F\u00c9MININE DE VOLLEY - Nantes a bien d\u00e9but\u00e9, mais la machine s'est enray\u00e9e apr\u00e8s une manche et demie, et les Mariannes ont renvers\u00e9 la situation pour aller chercher le titre.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Volley-Les-Mariannes-de-Levallois-Paris-Saint-Cloud-championnes-de-France-.png","width":1200,"height":674,"caption":"Volley Les Mariannes de Levallois Paris Saint-Cloud championnes de France !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Volley : Les Mariannes de Levallois Paris Saint-Cloud championnes de France !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/481663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=481663"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/481663\/revisions"}],"predecessor-version":[{"id":481731,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/481663\/revisions\/481731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/481711"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=481663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=481663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=481663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}