{"id":482165,"date":"2024-04-28T17:55:01","date_gmt":"2024-04-28T15:55:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=482165&#038;preview=true&#038;preview_id=482165"},"modified":"2024-04-28T22:29:08","modified_gmt":"2024-04-28T20:29:08","slug":"championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/","title":{"rendered":"Championnats d&rsquo;Europe de Boxe : Billal Bennama s&rsquo;incline en finale et se pare d&rsquo;argent"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS D&rsquo;EUROPE DE BOXE &#8211; Ce dimanche, Billal Bennama a d\u00e9croch\u00e9 la m\u00e9daille d&rsquo;argent dans la cat\u00e9gorie -54kg suite \u00e0 sa d\u00e9faite en finale face \u00e0 Dmitrii Dvali. Il obtient au passage la troisi\u00e8me breloque tricolore \u00e0 Belgrade (Serbie).<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Dernier repr\u00e9sentant tricolore en lice, <strong>Billal Bennama<\/strong> \u00e9tait \u00e9galement le seul \u00e0 \u00eatre parvenu \u00e0 se hisser en finale. Plus t\u00f4t dans la semaine, <strong>Yojerlin C\u00e9sar<\/strong> et<strong> Samuel Kistohurry<\/strong> avaient toutefois ouvert le palmar\u00e8s des Bleus en se hissant jusqu&rsquo;en demi-finales, pour assurer une m\u00e9daille de bronze.<\/p>\n<h2>Un combat resserr\u00e9 qui bascule en faveur de Dvali<\/h2>\n<p style=\"text-align: justify;\">Dans la cat\u00e9gorie -54 kg, <strong>Billal Bennama<\/strong> avait l&rsquo;occasion d&rsquo;\u00e9crire de nouveau l&rsquo;histoire. Il y a deux ans, \u00e0 Erevan, il avait d\u00e9j\u00e0 frapp\u00e9 fort en mettant fin \u00e0 22 ans de disette pour les boxeurs tricolores en raflant le titre europ\u00e9en. Auteur d&rsquo;un parcours parfait jusque-l\u00e0, il avait ainsi l&rsquo;opportunit\u00e9 de faire la passe de deux ce dimanche. En finale, il faisait ainsi face au jeune russe de 23 ans, <strong>Dmitrii Dvali<\/strong>. Ce dernier lance les hostilit\u00e9s en se montrant tr\u00e8s agressif, mais cela ne d\u00e9stabilise pas le Tricolore. Bien en place, il d\u00e9fend parfaitement et place des premiers contres \u00e9clairs pour reprendre l&rsquo;ascendant. Il distille ainsi quelques coups bien plac\u00e9s mais son adversaire ne l\u00e2che pas prise et place notamment deux solides crochets du droit en fin de premier round.<\/p>\n<p style=\"text-align: justify;\">Bennama va alors d\u00e9cider d&rsquo;acc\u00e9l\u00e9rer le rythme pour la seconde reprise. Plus offensif et pr\u00e9cis, il d\u00e9roule face \u00e0 un Russe qui se contente de maintenir sa garde avant tout, mais se montre impactant dans ses contres. L&rsquo;ultime reprise part sur un \u00e9change d&rsquo;uppercuts et une intensit\u00e9 \u00e9norme. Les deux combattants restent proches et s&rsquo;\u00e9changent des coups durs. La fatigue se ressent et la pr\u00e9cision en p\u00e2tit. Le combat est \u00e9quilibr\u00e9 mais finalement la d\u00e9cision des juges ira contre le Tricolore. <strong>Dmitrii Dvali<\/strong> d\u00e9croche donc la timbale.<strong> Billal Bennama<\/strong> doit se contenter de l&rsquo;argent, mais valide un deuxi\u00e8me podium europ\u00e9en cons\u00e9cutif et une troisi\u00e8me m\u00e9daille tricolore \u00e0 Belgrade cette semaine.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">M\u00e9daille d&rsquo;argent pour Billal Bennama \u00e0 l&rsquo;Euro de boxe \u00e0 Belgrade. Il est battu par le Russe Dvali en finale des 54 kilos. <a href=\"https:\/\/t.co\/gVTjyQagZ5\">pic.twitter.com\/gVTjyQagZ5<\/a><\/p>\n<p>\u2014 Morgan Maury (@MorganMauryRMC) <a href=\"https:\/\/twitter.com\/MorganMauryRMC\/status\/1784611601112330283?ref_src=twsrc%5Etfw\">April 28, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE DE BOXE &#8211; Ce dimanche, Billal Bennama a d\u00e9croch\u00e9 la m\u00e9daille d&rsquo;argent dans la cat\u00e9gorie -54kg suite \u00e0 sa d\u00e9faite en finale face \u00e0 Dmitrii Dvali. Il obtient au passage la troisi\u00e8me breloque tricolore \u00e0 Belgrade (Serbie).<\/p>\n","protected":false},"author":55,"featured_media":482199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8672],"tags":[23830,622,16878],"class_list":["post-482165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-billal-bennama","tag-boxe","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Championnats d&#039;Europe de Boxe : Billal Bennama s&#039;incline en finale et se pare d&#039;argent<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS D&#039;EUROPE DE BOXE - Billal Bennama a d\u00e9croch\u00e9 la m\u00e9daille d&#039;argent ce dimanche \u00e0 Belgrade (Serbie).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Championnats d&#039;Europe de Boxe : Billal Bennama s&#039;incline en finale et se pare d&#039;argent\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS D&#039;EUROPE DE BOXE - Billal Bennama a d\u00e9croch\u00e9 la m\u00e9daille d&#039;argent ce dimanche \u00e0 Belgrade (Serbie).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-28T15:55:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T20:29:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Boxe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Championnats d&#039;Europe de Boxe : Billal Bennama s&#039;incline en finale et se pare d&#039;argent\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Championnats d&rsquo;Europe de Boxe : Billal Bennama s&rsquo;incline en finale et se pare d&rsquo;argent\",\"datePublished\":\"2024-04-28T15:55:01+00:00\",\"dateModified\":\"2024-04-28T20:29:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/\"},\"wordCount\":421,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Boxe.png\",\"keywords\":[\"Billal Bennama\",\"boxe\",\"br\u00e8ve\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/\",\"name\":\"Championnats d'Europe de Boxe : Billal Bennama s'incline en finale et se pare d'argent\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Boxe.png\",\"datePublished\":\"2024-04-28T15:55:01+00:00\",\"dateModified\":\"2024-04-28T20:29:08+00:00\",\"description\":\"CHAMPIONNATS D'EUROPE DE BOXE - Billal Bennama a d\u00e9croch\u00e9 la m\u00e9daille d'argent ce dimanche \u00e0 Belgrade (Serbie).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Boxe.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Boxe.png\",\"width\":1200,\"height\":674,\"caption\":\"Championnats d'Europe de Boxe : Billal Bennama perd son titre et se pare d'argent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Championnats d&rsquo;Europe de Boxe : Billal Bennama s&rsquo;incline en finale et se pare d&rsquo;argent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Championnats d'Europe de Boxe : Billal Bennama s'incline en finale et se pare d'argent","description":"CHAMPIONNATS D'EUROPE DE BOXE - Billal Bennama a d\u00e9croch\u00e9 la m\u00e9daille d'argent ce dimanche \u00e0 Belgrade (Serbie).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/","og_locale":"fr_FR","og_type":"article","og_title":"Championnats d'Europe de Boxe : Billal Bennama s'incline en finale et se pare d'argent","og_description":"CHAMPIONNATS D'EUROPE DE BOXE - Billal Bennama a d\u00e9croch\u00e9 la m\u00e9daille d'argent ce dimanche \u00e0 Belgrade (Serbie).","og_url":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-04-28T15:55:01+00:00","article_modified_time":"2024-04-28T20:29:08+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Boxe.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Championnats d'Europe de Boxe : Billal Bennama s'incline en finale et se pare d'argent","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Championnats d&rsquo;Europe de Boxe : Billal Bennama s&rsquo;incline en finale et se pare d&rsquo;argent","datePublished":"2024-04-28T15:55:01+00:00","dateModified":"2024-04-28T20:29:08+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/"},"wordCount":421,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Boxe.png","keywords":["Billal Bennama","boxe","br\u00e8ve"],"articleSection":["Boxe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/","url":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/","name":"Championnats d'Europe de Boxe : Billal Bennama s'incline en finale et se pare d'argent","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Boxe.png","datePublished":"2024-04-28T15:55:01+00:00","dateModified":"2024-04-28T20:29:08+00:00","description":"CHAMPIONNATS D'EUROPE DE BOXE - Billal Bennama a d\u00e9croch\u00e9 la m\u00e9daille d'argent ce dimanche \u00e0 Belgrade (Serbie).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Boxe.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Boxe.png","width":1200,"height":674,"caption":"Championnats d'Europe de Boxe : Billal Bennama perd son titre et se pare d'argent"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-boxe-billal-bennama-sincline-en-finale-et-se-pare-dargent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Championnats d&rsquo;Europe de Boxe : Billal Bennama s&rsquo;incline en finale et se pare d&rsquo;argent"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/482165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=482165"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/482165\/revisions"}],"predecessor-version":[{"id":482262,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/482165\/revisions\/482262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/482199"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=482165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=482165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=482165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}