{"id":482312,"date":"2024-04-29T11:51:17","date_gmt":"2024-04-29T09:51:17","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=482312&#038;preview=true&#038;preview_id=482312"},"modified":"2024-04-29T12:09:06","modified_gmt":"2024-04-29T10:09:06","slug":"transferts-ben-youngs-pourrait-signer-en-top-14","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/","title":{"rendered":"Transferts : Ben Youngs pourrait signer en Top 14"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOP 14 2023-2024 &#8211; Selon le Midi Olympique, Ben Youngs (Leicester Tigers) int\u00e9resse plusieurs clubs de Top 14 pour la saison prochaine.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">De nombreux joueurs anglais vont poser leurs valises en France la saison prochaine, suite aux probl\u00e8mes financiers que rencontrent de nombreux clubs de Premiership. <strong>Billy Vunipola<\/strong>, qui vient de se faire remarquer pour <a href=\"https:\/\/rmcsport.bfmtv.com\/rugby\/rugby-l-international-anglais-billy-vunipola-arrete-avec-deux-coups-de-taser-dans-un-bar-a-majorque_AV-202404290330.html\">une histoire extra-sportive en Espagne<\/a>, a sign\u00e9 au MHR. <strong>Owen Farrell<\/strong> s&rsquo;est lui engag\u00e9 au Racing 92 alors que <strong>Manu Tuilagi<\/strong> arrive \u00e0 Bayonne.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-asm-clermont-julien-heriteau-a-une-nouvelle-piste-en-top-14\/\" target=\"_blank\" rel=\"noopener\">Transferts ASM Clermont : Julien H\u00e9riteau a une nouvelle piste en Top 14<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Ben Youngs pla\u00eet \u00e0 des clubs fran\u00e7ais<\/h2>\n<p style=\"text-align: justify;\">Cette liste est non exhaustive, puisqu&rsquo;ils seront nombreux \u00e0 traverser la Manche, et l&rsquo;exode n&rsquo;est peut-\u00eatre pas termin\u00e9. <strong>Ben<\/strong> <strong>Youngs <\/strong>(34 ans), demi de m\u00eal\u00e9e international anglais, est en fin de contrat avec les <strong>Leicester<\/strong> <strong>Tigers<\/strong>. Le club anglais n&rsquo;est pas certain de pouvoir le conserver pour pouvoir rester dans les clous du<em> salary cap<\/em> et \u00e9viter des sanctions.<\/p>\n<p style=\"text-align: justify;\">Par cons\u00e9quent, <strong>Ben Youngs<\/strong> a donc \u00e9t\u00e9 propos\u00e9 \u00e0 des clubs fran\u00e7ais, et son CV a retenu l&rsquo;attention de plusieurs recruteurs. Si les noms des \u00e9quipes int\u00e9ress\u00e9es n&rsquo;ont pas filtr\u00e9, l&rsquo;homme au 127 s\u00e9lections avec le XV de la Rose pourrait bien poser ses valises dans l&rsquo;Hexagone dans quelques mois. Il a pour le moment port\u00e9 les couleurs d&rsquo;un seul club dans sa carri\u00e8re.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La Folie Top 14 en Une du Midi Olympique !<\/p>\n<p>Retrouvez le journal ici &gt; <a href=\"https:\/\/t.co\/cIlUIU6j6V\">https:\/\/t.co\/cIlUIU6j6V<\/a> <a href=\"https:\/\/t.co\/F1oC9oE3z1\">pic.twitter.com\/F1oC9oE3z1<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1784714858807558604?ref_src=twsrc%5Etfw\">April 28, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2023-2024 &#8211; Selon le Midi Olympique, Ben Youngs (Leicester Tigers) int\u00e9resse plusieurs clubs de Top 14 pour la saison prochaine.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":482314,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[51,16878,111],"class_list":["post-482312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-angleterre","tag-breve","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : Ben Youngs pourrait signer en Top 14<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2024 - Selon le Midi Olympique, Ben Youngs (Leicester Tigers) int\u00e9resse plusieurs clubs de Top 14 pour la saison prochaine.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Ben Youngs pourrait signer en Top 14\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2024 - Selon le Midi Olympique, Ben Youngs (Leicester Tigers) int\u00e9resse plusieurs clubs de Top 14 pour la saison prochaine.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T09:51:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-29T10:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Ben Youngs pourrait signer en Top 14\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Ben Youngs pourrait signer en Top 14\",\"datePublished\":\"2024-04-29T09:51:17+00:00\",\"dateModified\":\"2024-04-29T10:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/\"},\"wordCount\":274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png\",\"keywords\":[\"Angleterre\",\"br\u00e8ve\",\"Top 14\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/\",\"name\":\"Transferts : Ben Youngs pourrait signer en Top 14\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png\",\"datePublished\":\"2024-04-29T09:51:17+00:00\",\"dateModified\":\"2024-04-29T10:09:06+00:00\",\"description\":\"TOP 14 2023-2024 - Selon le Midi Olympique, Ben Youngs (Leicester Tigers) int\u00e9resse plusieurs clubs de Top 14 pour la saison prochaine.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Ben Youngs pourrait signer en Top 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Ben Youngs pourrait signer en Top 14","description":"TOP 14 2023-2024 - Selon le Midi Olympique, Ben Youngs (Leicester Tigers) int\u00e9resse plusieurs clubs de Top 14 pour la saison prochaine.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Ben Youngs pourrait signer en Top 14","og_description":"TOP 14 2023-2024 - Selon le Midi Olympique, Ben Youngs (Leicester Tigers) int\u00e9resse plusieurs clubs de Top 14 pour la saison prochaine.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-04-29T09:51:17+00:00","article_modified_time":"2024-04-29T10:09:06+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : Ben Youngs pourrait signer en Top 14","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Ben Youngs pourrait signer en Top 14","datePublished":"2024-04-29T09:51:17+00:00","dateModified":"2024-04-29T10:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/"},"wordCount":274,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png","keywords":["Angleterre","br\u00e8ve","Top 14"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/","name":"Transferts : Ben Youngs pourrait signer en Top 14","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png","datePublished":"2024-04-29T09:51:17+00:00","dateModified":"2024-04-29T10:09:06+00:00","description":"TOP 14 2023-2024 - Selon le Midi Olympique, Ben Youngs (Leicester Tigers) int\u00e9resse plusieurs clubs de Top 14 pour la saison prochaine.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/04\/Transferts-Ben-Youngs-pourrait-signer-en-Top-14.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-ben-youngs-pourrait-signer-en-top-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Ben Youngs pourrait signer en Top 14"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/482312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=482312"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/482312\/revisions"}],"predecessor-version":[{"id":482321,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/482312\/revisions\/482321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/482314"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=482312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=482312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=482312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}