{"id":483450,"date":"2024-05-04T17:07:11","date_gmt":"2024-05-04T15:07:11","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=483450&#038;preview=true&#038;preview_id=483450"},"modified":"2024-05-05T16:17:56","modified_gmt":"2024-05-05T14:17:56","slug":"euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/","title":{"rendered":"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS D&rsquo;EUROPE DE GYMNASTIQUE 2024 &#8211; Gr\u00e2ce \u00e0 deux superbes sauts, Coline Devillard r\u00e9alise l&rsquo;exploit de conserver sa couronne europ\u00e9enne au saut de cheval. Un podium partag\u00e9 avec une autre tricolore puisque Ming Gherardi van Eijken remporte la m\u00e9daille de bronze.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">C\u2019est fait pour <strong>Coline Devillard<\/strong> ! Un deuxi\u00e8me titre europ\u00e9en cons\u00e9cutif au saut de cheval, le troisi\u00e8me en tout. \u00c0 Rimini (Italie), la tricolore n\u2019a pas trembl\u00e9 sur sa discipline de pr\u00e9dilection.<\/p>\n<p style=\"text-align: justify;\">Avec deux superbes sauts, not\u00e9s respectivement 14.366 et 13.366, elle obtient la moyenne de 13.866 et remporte la m\u00e9daille d\u2019or. Celle qui a choisi de travailler sa course avec le champion du monde du 110m haies, <strong>Ladji Doucour\u00e9<\/strong>, partait avec les notes de difficult\u00e9 les plus \u00e9lev\u00e9es de cette finale.<\/p>\n<p style=\"text-align: justify;\">La deuxi\u00e8me concurrente qui poss\u00e9dait les notes de difficult\u00e9s les plus \u00e9lev\u00e9es, c&rsquo;est notre seconde fran\u00e7aise, <strong>Ming Gherardi Van Eijken<\/strong>. Premi\u00e8re \u00e0 s\u2019\u00e9lancer, elle obtient deux jolies notes (14.133 et 13.266), obtenant la moyenne de 13.699. Un score qui lui permet de s\u2019offrir la m\u00e9daille de bronze et de partager la Marseillaise avec sa co\u00e9quipi\u00e8re.<\/p>\n<p style=\"text-align: justify;\">La Bulgare <strong>Valentina Georgieva<\/strong> devient vice-championne d\u2019Europe avec le score final de 13.799.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">[GAF &#8211; CHAMPIONNAT D&rsquo;EUROPE \ud83d\udccd Rimini \ud83c\uddee\ud83c\uddf9]\n<p>Deux Fran\u00e7aises m\u00e9daill\u00e9es au saut : Coline Devillard conserve le titre europ\u00e9en\ud83e\udd47 et Ming Gherardi Van Eijken remporte le bronze \ud83e\udd49 dans sa premi\u00e8re finale europ\u00e9enne senior ! \ud83e\udd29\ud83c\uddeb\ud83c\uddf7<\/p>\n<p>\u2795 <a href=\"https:\/\/t.co\/t2bF2TXufc\">https:\/\/t.co\/t2bF2TXufc<\/a> <a href=\"https:\/\/t.co\/0FyIv0kCNe\">pic.twitter.com\/0FyIv0kCNe<\/a><\/p>\n<p>\u2014 F\u00e9d\u00e9ration Fran\u00e7aise de Gymnastique (@ffgymnastique) <a href=\"https:\/\/twitter.com\/ffgymnastique\/status\/1786771813864796211?ref_src=twsrc%5Etfw\">May 4, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE DE GYMNASTIQUE 2024 &#8211; Gr\u00e2ce \u00e0 deux superbes sauts, Coline Devillard r\u00e9alise l&rsquo;exploit de conserver sa couronne europ\u00e9enne au saut de cheval. Un podium partag\u00e9 avec une autre tricolore puisque Ming Gherardi van Eijken remporte la m\u00e9daille de bronze.\u00a0<\/p>\n","protected":false},"author":89,"featured_media":483730,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10429],"tags":[16878,12433,1595,391,24],"class_list":["post-483450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gymnastique","tag-breve","tag-championnats-deurope-de-gymnastique","tag-coline-devillard","tag-gymnastique","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze<\/title>\n<meta name=\"description\" content=\"Coline Devillard conserve sa couronne europ\u00e9enne au saut de cheval. Ming Gherardi van Eijken remporte la m\u00e9daille de bronze.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze\" \/>\n<meta property=\"og:description\" content=\"Coline Devillard conserve sa couronne europ\u00e9enne au saut de cheval. Ming Gherardi van Eijken remporte la m\u00e9daille de bronze.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-04T15:07:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-05T14:17:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Louka Lesueur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LNewsSF\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/\"},\"author\":{\"name\":\"Louka Lesueur\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a\"},\"headline\":\"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze\",\"datePublished\":\"2024-05-04T15:07:11+00:00\",\"dateModified\":\"2024-05-05T14:17:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/\"},\"wordCount\":283,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png\",\"keywords\":[\"br\u00e8ve\",\"Championnats d'Europe de gymnastique\",\"Coline Devillard\",\"gymnastique\",\"sport\"],\"articleSection\":[\"Gymnastique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/\",\"name\":\"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png\",\"datePublished\":\"2024-05-04T15:07:11+00:00\",\"dateModified\":\"2024-05-05T14:17:56+00:00\",\"description\":\"Coline Devillard conserve sa couronne europ\u00e9enne au saut de cheval. Ming Gherardi van Eijken remporte la m\u00e9daille de bronze.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png\",\"width\":1200,\"height\":674,\"caption\":\"Gymnastique artistique 2024 Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a\",\"name\":\"Louka Lesueur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg\",\"caption\":\"Louka Lesueur\"},\"description\":\"Passionn\u00e9 depuis tout petit par les exploits de Bolt, Fourcade, Riner, Lavillenie, Wilkinson, Hirscher. Les \u00e9motions provoqu\u00e9es par le sport ont berc\u00e9 mon enfance et continuent de le faire aujourd'hui. C'est ainsi qu'il m'est arriv\u00e9 de pleurer devant la d\u00e9faite des Bleus face aux Blacks en 2011, ou encore devant le titre olympique de Florent Manaudou \u00e0 Londres. Bien loin de ce milieu professionnel, j'ai os\u00e9 tenter ma chance pour rejoindre l'\u00e9quipe de r\u00e9daction de Dicodusport, et depuis septembre 2023, je tente de retransmettre au mieux les exploits des athl\u00e8tes, tous sports confondus. Grand chauvin, c'est bel et bien sur les sportifs tricolores que je pr\u00e9f\u00e8re \u00e9crire.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/LNewsSF\"],\"gender\":\"Homme\",\"worksFor\":\"Louka LESUEUR\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/louka-lesueur\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze","description":"Coline Devillard conserve sa couronne europ\u00e9enne au saut de cheval. Ming Gherardi van Eijken remporte la m\u00e9daille de bronze.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/","og_locale":"fr_FR","og_type":"article","og_title":"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze","og_description":"Coline Devillard conserve sa couronne europ\u00e9enne au saut de cheval. Ming Gherardi van Eijken remporte la m\u00e9daille de bronze.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-05-04T15:07:11+00:00","article_modified_time":"2024-05-05T14:17:56+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png","type":"image\/png"}],"author":"Louka Lesueur","twitter_card":"summary_large_image","twitter_title":"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze","twitter_creator":"@https:\/\/twitter.com\/LNewsSF","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/"},"author":{"name":"Louka Lesueur","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a"},"headline":"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze","datePublished":"2024-05-04T15:07:11+00:00","dateModified":"2024-05-05T14:17:56+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/"},"wordCount":283,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png","keywords":["br\u00e8ve","Championnats d'Europe de gymnastique","Coline Devillard","gymnastique","sport"],"articleSection":["Gymnastique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/","url":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/","name":"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png","datePublished":"2024-05-04T15:07:11+00:00","dateModified":"2024-05-05T14:17:56+00:00","description":"Coline Devillard conserve sa couronne europ\u00e9enne au saut de cheval. Ming Gherardi van Eijken remporte la m\u00e9daille de bronze.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Gymnastique-artistique-2024-Coline-Devillard-conserve-son-titre-europeen-au-saut-Ming-Gherardi-van-Eijken-en-bronze.png","width":1200,"height":674,"caption":"Gymnastique artistique 2024 Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euro-gym-2024-coline-devillard-conserve-son-titre-europeen-au-saut-ming-gherardi-van-eijken-en-bronze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Gymnastique artistique : Coline Devillard conserve son titre europ\u00e9en au saut, Ming Gherardi van Eijken en bronze"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a","name":"Louka Lesueur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","caption":"Louka Lesueur"},"description":"Passionn\u00e9 depuis tout petit par les exploits de Bolt, Fourcade, Riner, Lavillenie, Wilkinson, Hirscher. Les \u00e9motions provoqu\u00e9es par le sport ont berc\u00e9 mon enfance et continuent de le faire aujourd'hui. C'est ainsi qu'il m'est arriv\u00e9 de pleurer devant la d\u00e9faite des Bleus face aux Blacks en 2011, ou encore devant le titre olympique de Florent Manaudou \u00e0 Londres. Bien loin de ce milieu professionnel, j'ai os\u00e9 tenter ma chance pour rejoindre l'\u00e9quipe de r\u00e9daction de Dicodusport, et depuis septembre 2023, je tente de retransmettre au mieux les exploits des athl\u00e8tes, tous sports confondus. Grand chauvin, c'est bel et bien sur les sportifs tricolores que je pr\u00e9f\u00e8re \u00e9crire.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/LNewsSF"],"gender":"Homme","worksFor":"Louka LESUEUR","url":"https:\/\/dicodusport.fr\/blog\/author\/louka-lesueur\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/483450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=483450"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/483450\/revisions"}],"predecessor-version":[{"id":483571,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/483450\/revisions\/483571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/483730"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=483450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=483450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=483450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}