{"id":486210,"date":"2024-05-17T22:40:15","date_gmt":"2024-05-17T20:40:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=486210&#038;preview=true&#038;preview_id=486210"},"modified":"2024-05-17T23:16:54","modified_gmt":"2024-05-17T21:16:54","slug":"barrages-pro-d2-affiches-dates-et-horaires","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/","title":{"rendered":"Barrages Pro D2 : Affiches, dates et horaires"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>PRO D2 2023-2024 &#8211; Retrouvez les affiches, les dates et les horaires des barrages du championnat de France de Pro D2 2023-2024.<\/i><\/b><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/\">L&rsquo;actualit\u00e9 du rugby \u00e0 XV<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La <strong>phase finale de la <a href=\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2023-2024\/\">Pro D2<\/a><\/strong> d\u00e9bute ce jeudi 23 mai avec le premier barrage. Quatri\u00e8me de la phase r\u00e9guli\u00e8re, le <strong>FC Grenoble<\/strong> accueillera l&rsquo;<strong>US Dax<\/strong> le jeudi 23 mai (21h), le promu, grande surprise de cette saison de Pro D2. Le second barrage verra s&rsquo;opposer<strong> B\u00e9ziers<\/strong> (3\u00e8me) au <strong>CA Brive<\/strong> (6\u00e8me), vendredi 24 mai (21h). Les Brivistes ont arrach\u00e9 leur ticket pour les playoffs <a href=\"https:\/\/dicodusport.fr\/blog\/provence-rugby-1er-brive-arrache-un-top-6-rouen-en-nationale-derniere-soiree-folle-en-pro-d2\/\">\u00e0 l&rsquo;issue d&rsquo;une 30\u00e8me journ\u00e9e de folie<\/a> !<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">&#8211; BARRAGES &#8211;<\/span><\/h2>\n<table style=\"width: 800px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 800px; background-color: #052c47; height: 22px; text-align: center; vertical-align: middle;\" colspan=\"3\"><span style=\"color: #acc3e4;\"><strong>JEUDI 23 MAI 2024<\/strong><\/span><span style=\"color: #ffffff;\"><strong><br \/>\n<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 304px; text-align: center; height: 10px; vertical-align: middle;\">FC GRENOBLE<\/td>\n<td style=\"text-align: center; width: 192px; height: 10px; vertical-align: middle;\">21H00<br \/>\n<span style=\"font-size: 11.52px;\"><b><i>Canal+ Sport<\/i><\/b><\/span><\/td>\n<td style=\"text-align: center; height: 10px; width: 304px; vertical-align: middle;\">US DAX<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 800px; background-color: #052c47; height: 22px; text-align: center; vertical-align: middle;\" colspan=\"3\"><span style=\"color: #ffffff;\"><strong><span style=\"color: #acc3e4;\">VENDREDI 24 MAI 2024<\/span><\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td style=\"width: 304px; text-align: center; height: 10px; vertical-align: middle;\">AS B\u00c9ZIERS<\/td>\n<td style=\"text-align: center; width: 192px; height: 10px; vertical-align: middle;\">21H00<br \/>\n<span style=\"font-size: 11.52px;\"><b><i>Canal+ Sport<\/i><\/b><\/span><\/td>\n<td style=\"text-align: center; height: 10px; width: 304px; vertical-align: middle;\">CA BRIVE<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/phase-finale-pro-d2-tableau-complet-et-resultats\/\">Phase finale Pro D2 &#8211; Tableau complet et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>PRO D2 2023-2024 &#8211; Retrouvez les affiches, les dates et les horaires des barrages du championnat de France de Pro D2 2023-2024.<\/p>\n","protected":false},"author":4,"featured_media":486233,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129],"tags":[16878,1839],"class_list":["post-486210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-breve","tag-pro-d2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Barrages Pro D2 : Affiches, dates et horaires<\/title>\n<meta name=\"description\" content=\"PRO D2 2023-2024 - Retrouvez les affiches, les dates et les horaires des barrages du championnat de France de Pro D2 2023-2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barrages Pro D2 : Affiches, dates et horaires\" \/>\n<meta property=\"og:description\" content=\"PRO D2 2023-2024 - Retrouvez les affiches, les dates et les horaires des barrages du championnat de France de Pro D2 2023-2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-17T20:40:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-17T21:16:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Barrages Pro D2 : Affiches, dates et horaires\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Barrages Pro D2 : Affiches, dates et horaires\",\"datePublished\":\"2024-05-17T20:40:15+00:00\",\"dateModified\":\"2024-05-17T21:16:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/\"},\"wordCount\":151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png\",\"keywords\":[\"br\u00e8ve\",\"Pro D2\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/\",\"name\":\"Barrages Pro D2 : Affiches, dates et horaires\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png\",\"datePublished\":\"2024-05-17T20:40:15+00:00\",\"dateModified\":\"2024-05-17T21:16:54+00:00\",\"description\":\"PRO D2 2023-2024 - Retrouvez les affiches, les dates et les horaires des barrages du championnat de France de Pro D2 2023-2024.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png\",\"width\":1200,\"height\":674,\"caption\":\"Barrages Pro D2 Affiches, dates et horaires\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barrages Pro D2 : Affiches, dates et horaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Barrages Pro D2 : Affiches, dates et horaires","description":"PRO D2 2023-2024 - Retrouvez les affiches, les dates et les horaires des barrages du championnat de France de Pro D2 2023-2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Barrages Pro D2 : Affiches, dates et horaires","og_description":"PRO D2 2023-2024 - Retrouvez les affiches, les dates et les horaires des barrages du championnat de France de Pro D2 2023-2024.","og_url":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2024-05-17T20:40:15+00:00","article_modified_time":"2024-05-17T21:16:54+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Barrages Pro D2 : Affiches, dates et horaires","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Barrages Pro D2 : Affiches, dates et horaires","datePublished":"2024-05-17T20:40:15+00:00","dateModified":"2024-05-17T21:16:54+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/"},"wordCount":151,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png","keywords":["br\u00e8ve","Pro D2"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/","url":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/","name":"Barrages Pro D2 : Affiches, dates et horaires","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png","datePublished":"2024-05-17T20:40:15+00:00","dateModified":"2024-05-17T21:16:54+00:00","description":"PRO D2 2023-2024 - Retrouvez les affiches, les dates et les horaires des barrages du championnat de France de Pro D2 2023-2024.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Barrages-Pro-D2-Affiches-dates-et-horaires.png","width":1200,"height":674,"caption":"Barrages Pro D2 Affiches, dates et horaires"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/barrages-pro-d2-affiches-dates-et-horaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Barrages Pro D2 : Affiches, dates et horaires"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/486210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=486210"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/486210\/revisions"}],"predecessor-version":[{"id":486250,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/486210\/revisions\/486250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/486233"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=486210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=486210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=486210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}