{"id":486464,"date":"2024-05-18T20:31:17","date_gmt":"2024-05-18T18:31:17","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=486464&#038;preview=true&#038;preview_id=486464"},"modified":"2024-05-18T21:18:44","modified_gmt":"2024-05-18T19:18:44","slug":"coupe-de-france-handball-f-metz-handball-remporte-le-titre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/","title":{"rendered":"Coupe de France Handball (F) : Metz Handball remporte le titre"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE DE FRANCE DE HANDBALL F\u00c9MININE 2023-2024 &#8211; Metz Handball a domin\u00e9 la JDA Dijon en finale de la Coupe de France (29-20). Apr\u00e8s une premi\u00e8re mi-temps compliqu\u00e9e (15-14), les Messines ont \u00e9rig\u00e9 le rideau de fer dans le second acte. Et restent en course pour le tripl\u00e9 cette saison.<\/em><\/strong><\/p>\n<h2>La JDA Dijon a r\u00e9sist\u00e9 une mi-temps<\/h2>\n<p style=\"text-align: justify;\">Les Messines ne sont pas na\u00efves. Si Dijon n&rsquo;est pas une \u00e9quipe de l&rsquo;envergure de Metz, c&rsquo;\u00e9tait une \u00e9quipe europ\u00e9enne en d\u00e9but de saison. Et surtout une \u00e9quipe en plein progr\u00e8s ces derni\u00e8res ann\u00e9es. Il ne fallait pas s&rsquo;attendre \u00e0 un fleuve tranquille. Ce ne fut pas le cas, loin de l\u00e0 pour les Messines, dans ce premier acte. Avec un tout petit but d&rsquo;avance \u00e0 la pause et un score de 15-14. Avec une excellente <strong>Manuela Dos Reis<\/strong> dans les cages. L&rsquo;ancienne joueuse de Saint-Amand affichait plus de 35 % d&rsquo;arr\u00eat \u00e0 la 20e minute de jeu (7\/19). Et<strong> C\u00e9line Sivertsen<\/strong> a \u00e9t\u00e9 tr\u00e8s efficace avec ses six buts dans le premier acte.<\/p>\n<p style=\"text-align: justify;\">Mais le vrai m\u00e9rite de Dijon, dans ce premier acte, c&rsquo;est de n&rsquo;avoir rien l\u00e2ch\u00e9. \u00c0 plusieurs reprises, les Messine ont eu quatre buts d&rsquo;avance. Notamment quand, apr\u00e8s un d\u00e9but de match d\u00e9licat (1-3, 4e), elles ont acc\u00e9l\u00e9r\u00e9 consid\u00e9rablement (8-4, 12e). Mais \u00e0 chaque fois, les Dijonnaises ont recoll\u00e9. Et la d\u00e9fense messine a parfois \u00e9t\u00e9 m\u00e9connaissable. C&rsquo;est d&rsquo;ailleurs tr\u00e8s rare de les voir prendre 14 buts en une mi-temps, face \u00e0 une \u00e9quipe fran\u00e7aise. Cela provoquera un certain agacement d<strong>&lsquo;Hatadou Sako<\/strong>, la gardienne messine, \u00e0 la pause, au micro de <em>beIN SPORTS<\/em>. Un agacement qui n&rsquo;a pas d\u00fb se cantonner qu&rsquo;au micro de la journaliste<strong> Mary Patrux<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Mais Metz \u00e9rige le rideau de fer dans le second acte<\/h2>\n<p style=\"text-align: justify;\">Car, au retour des vestiaires, c&rsquo;est un autre match qui a commenc\u00e9. Et les Messines ont tout de suite mis la t\u00eate des Dijonnaises sous l&rsquo;eau. Avec un 4-0 et aucun but encaiss\u00e9 dans les cinq premi\u00e8res minutes du second acte (19-14, 36e). Les solutions faciles se sont \u00e9vapor\u00e9es et <strong>Hatadou Sako<\/strong> a verrouill\u00e9 ses cages (17 parades \u00e0 50 % d&rsquo;arr\u00eats \u00e0 trois minutes du terme du match). Le <strong>JDA Dijon<\/strong> ne marquera qu&rsquo;un petit but dans les onze premi\u00e8res minutes du second acte. Mais que Dijon se rassure, le CSM Bucarest, l&rsquo;une des meilleures \u00e9quipes europ\u00e9ennes, mais aussi Brest, sont pass\u00e9es \u00e0 la moulinette messine dans le second acte. Car quand les joueuses d&rsquo;<strong>Emmanuel Mayonnade<\/strong> acc\u00e9l\u00e8rent, difficile de leur r\u00e9sister.<\/p>\n<p style=\"text-align: justify;\">N\u00e9anmoins, Metz, m\u00eame en \u00e9tant mieux, a souffert de lacunes. Notamment dans son jeu plac\u00e9. Rendant des ballons aux Dijonnaises. Mais la d\u00e9fense messine est devenue trop forte et n&rsquo;encaissera que six buts en 2e mi-temps. On vous a dit, m\u00eame tarif que le CSM Bucarest. Si cela peut consoler des Dijonnaises qui n&rsquo;auront pourtant pas \u00e0 rougir de leur finale. Forc\u00e9ment, pour<strong> Dijon<\/strong>, le score d\u00e9file et devient lourd (23-17, 48e puis 26-18, 52e). La marche \u00e9tait un peu trop haute, mais la finale a quand m\u00eame tenu ses promesses.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udde1\ud835\udde2\ud835\udde8\ud835\udde6 \ud835\udde6\ud835\udde2\ud835\udde0\ud835\udde0\ud835\uddd8\ud835\udde6 \ud835\udde9\ud835\uddd4\ud835\udddc\ud835\udde1\ud835\udde4\ud835\udde8\ud835\uddd8\ud835\udde8\ud835\udde5\ud835\udde6 \ud835\uddd7\ud835\uddd8 \ud835\udddf\ud835\uddd4 \ud835\uddd6\ud835\udde2\ud835\udde8\ud835\udde3\ud835\uddd8 \ud835\uddd7\ud835\uddd8 \ud835\uddd9\ud835\udde5\ud835\uddd4\ud835\udde1\ud835\uddd6\ud835\uddd8 \ud83c\udfc6<\/p>\n<p>Apr\u00e8s 2022, 2023, ca sera 2\ufe0f\u20e30\ufe0f\u20e32\ufe0f\u20e34\ufe0f\u20e3 ! Metz remporte pour la troisi\u00e8me ann\u00e9e cons\u00e9cutive la comp\u00e9tition et un 1\ufe0f\u20e32\ufe0f\u20e3\u00e8me troph\u00e9e. \ud83e\udd29<a href=\"https:\/\/twitter.com\/hashtag\/MHBJDA?src=hash&amp;ref_src=twsrc%5Etfw\">#MHBJDA<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/FINALECDF?src=hash&amp;ref_src=twsrc%5Etfw\">#FINALECDF<\/a> <a href=\"https:\/\/t.co\/2buI0hJt0b\">pic.twitter.com\/2buI0hJt0b<\/a><\/p>\n<p>\u2014 Metz Handball (@MetzHandball) <a href=\"https:\/\/twitter.com\/MetzHandball\/status\/1791899856291745994?ref_src=twsrc%5Etfw\">May 18, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Metz Handball a domin\u00e9 la JDA Dijon en finale de la Coupe de France (29-20).<\/p>\n","protected":false},"author":83,"featured_media":486499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2304],"tags":[16878,405,19698,2449],"class_list":["post-486464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handball","tag-breve","tag-handball","tag-jda-dijon","tag-metz-handball"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coupe de France Handball (F) : Metz Handball remporte le titre<\/title>\n<meta name=\"description\" content=\"HANDBALL - Metz Handball a domin\u00e9 la JDA Dijon en finale de la Coupe de France (29-20), ce samedi soir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe de France Handball (F) : Metz Handball remporte le titre\" \/>\n<meta property=\"og:description\" content=\"HANDBALL - Metz Handball a domin\u00e9 la JDA Dijon en finale de la Coupe de France (29-20), ce samedi soir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-18T18:31:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-18T19:18:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe de France Handball (F) : Metz Handball remporte le titre\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Coupe de France Handball (F) : Metz Handball remporte le titre\",\"datePublished\":\"2024-05-18T18:31:17+00:00\",\"dateModified\":\"2024-05-18T19:18:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/\"},\"wordCount\":595,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png\",\"keywords\":[\"br\u00e8ve\",\"Handball\",\"JDA Dijon\",\"Metz Handball\"],\"articleSection\":[\"Handball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/\",\"name\":\"Coupe de France Handball (F) : Metz Handball remporte le titre\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png\",\"datePublished\":\"2024-05-18T18:31:17+00:00\",\"dateModified\":\"2024-05-18T19:18:44+00:00\",\"description\":\"HANDBALL - Metz Handball a domin\u00e9 la JDA Dijon en finale de la Coupe de France (29-20), ce samedi soir.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Coupe de France Handball (F) Metz Handball remporte le titre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe de France Handball (F) : Metz Handball remporte le titre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe de France Handball (F) : Metz Handball remporte le titre","description":"HANDBALL - Metz Handball a domin\u00e9 la JDA Dijon en finale de la Coupe de France (29-20), ce samedi soir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe de France Handball (F) : Metz Handball remporte le titre","og_description":"HANDBALL - Metz Handball a domin\u00e9 la JDA Dijon en finale de la Coupe de France (29-20), ce samedi soir.","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-05-18T18:31:17+00:00","article_modified_time":"2024-05-18T19:18:44+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Coupe de France Handball (F) : Metz Handball remporte le titre","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Coupe de France Handball (F) : Metz Handball remporte le titre","datePublished":"2024-05-18T18:31:17+00:00","dateModified":"2024-05-18T19:18:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/"},"wordCount":595,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png","keywords":["br\u00e8ve","Handball","JDA Dijon","Metz Handball"],"articleSection":["Handball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/","name":"Coupe de France Handball (F) : Metz Handball remporte le titre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png","datePublished":"2024-05-18T18:31:17+00:00","dateModified":"2024-05-18T19:18:44+00:00","description":"HANDBALL - Metz Handball a domin\u00e9 la JDA Dijon en finale de la Coupe de France (29-20), ce samedi soir.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Coupe-de-France-Handball-F-Metz-Handball-remporte-le-titre-1.png","width":1200,"height":674,"caption":"Coupe de France Handball (F) Metz Handball remporte le titre"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-de-france-handball-f-metz-handball-remporte-le-titre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe de France Handball (F) : Metz Handball remporte le titre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/486464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=486464"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/486464\/revisions"}],"predecessor-version":[{"id":486492,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/486464\/revisions\/486492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/486499"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=486464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=486464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=486464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}