{"id":487105,"date":"2024-05-22T19:06:27","date_gmt":"2024-05-22T17:06:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=487105&#038;preview=true&#038;preview_id=487105"},"modified":"2024-05-23T11:27:52","modified_gmt":"2024-05-23T09:27:52","slug":"pro-d2-lincroyable-parcours-de-dax-en-chiffres","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/","title":{"rendered":"Pro D2 : L&rsquo;incroyable parcours de Dax en chiffres"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>PRO D2 2023-2024 &#8211; Promu de Nationale, Dax s&rsquo;est invit\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale en barrages. Retour en chiffres sur sa performance.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2023-2024\/\">Classement de la Pro D2<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Celui qui aurait mis\u00e9 sur <strong>Dax<\/strong> en position de barragiste \u00e0 la fin de la saison aurait \u00e9t\u00e9 trait\u00e9 au mieux de gentil ben\u00eat, au pire de fou. Promus de Nationale, les Dacquois se sont pourtant invit\u00e9s au banquet des barragistes de la phase finale de Pro D2, en terminant 5e de la phase r\u00e9guli\u00e8re de la Pro D2. Un authentique exploit, quand on connait la difficult\u00e9 des clubs promus \u00e0 se maintenir \u00e0 ce niveau.<\/p>\n<p style=\"text-align: justify;\">Lors de la saison 2022-2023, Massy avait fait l&rsquo;ascenseur, tandis que Soyaux-Angoul\u00eame s&rsquo;\u00e9tait sauv\u00e9 \u00e0 moins de dix minutes du terme de ce championnat, au terme d&rsquo;un bonus d\u00e9fensif arrach\u00e9 sur la pelouse d&rsquo;Oyonnax. Du suspense, il y en a \u00e9galement eu pour l&rsquo;<strong>US Dax<\/strong>, dans cette derni\u00e8re journ\u00e9e, o\u00f9 elle a \u00e9t\u00e9 virtuellement 3e, en \u00e9tant devant au score \u00e0 Nevers. Finalement 5\u00e8mes, les joueurs de Dax se d\u00e9placent \u00e0 Grenoble, ce jeudi soir.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/phase-finale-pro-d2-tableau-complet-et-resultats\/\">Phase finale Pro D2 \u2013 Tableau complet et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">La saison r\u00e9guli\u00e8re de Dax en chiffres<\/h2>\n<h2 style=\"text-align: justify;\">5<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre de saisons pass\u00e9es en Nationale par Dax, avant sa remont\u00e9e en Pro D2, la saison pass\u00e9e.<\/p>\n<h2 style=\"text-align: justify;\">15<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre d&rsquo;ann\u00e9es o\u00f9 Dax n&rsquo;a pas \u00e9volu\u00e9 en Top 14. Sa derni\u00e8re apparition date de la saison 2008-2009. Une \u00e9ternit\u00e9 pour un des clubs embl\u00e9matiques du rugby fran\u00e7ais.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/pro-d2-grenoble-en-favori-des-barrages\/\">Pro D2 : Grenoble en favori des barrages ?<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">20<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre de points pris en d\u00e9placement par les Dacquois. Quatri\u00e8me \u00e9quipe de ce championnat hors des Landes. Pour quatre victoires, un nul (sur la pelouse du SAXV) et dix d\u00e9faites. Ils ont su construire leur accession aux barrages en d\u00e9placement.<\/p>\n<h2 style=\"text-align: justify;\">27<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre de franchissements de l&rsquo;ailier fidjien <strong>Jope Naseara<\/strong> (22 ans). C&rsquo;est le deuxi\u00e8me total du championnat. \u00c0 cela s&rsquo;ajoute dix essais marqu\u00e9s. Le tout en seulement 20 matchs jou\u00e9s. D\u00e9tonateur.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udddf\ud835\uddd4 \ud835\uddd6\ud835\udde2\ud835\udde0\ud835\udde3\ud835\udde2 \ud83d\udca5<\/p>\n<p>D\u00e9couvrez la composition dacquoise pour affronter le <a href=\"https:\/\/twitter.com\/FCGrugby?ref_src=twsrc%5Etfw\">@FCGrugby<\/a> pour le barrage de <a href=\"https:\/\/twitter.com\/rugbyprod2?ref_src=twsrc%5Etfw\">@rugbyprod2<\/a> !<a href=\"https:\/\/twitter.com\/hashtag\/dax?src=hash&amp;ref_src=twsrc%5Etfw\">#dax<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/compo?src=hash&amp;ref_src=twsrc%5Etfw\">#compo<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ProD2?src=hash&amp;ref_src=twsrc%5Etfw\">#ProD2<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/BarragesPROD2?src=hash&amp;ref_src=twsrc%5Etfw\">#BarragesPROD2<\/a> <a href=\"https:\/\/t.co\/3SsB5Y7IDf\">pic.twitter.com\/3SsB5Y7IDf<\/a><\/p>\n<p>\u2014 U.S.Dax Rugby Landes (@usdaxrugby) <a href=\"https:\/\/twitter.com\/usdaxrugby\/status\/1793319255573721198?ref_src=twsrc%5Etfw\">May 22, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">66 et 76<\/h2>\n<p style=\"text-align: justify;\">66, comme le nombre d&rsquo;essais marqu\u00e9s par de Dax cette saison. Le 12e total seulement de cette Pro D2. Ils en ont encaiss\u00e9 dix de plus (76). C&rsquo;est la seule \u00e9quipe du Top 6 \u00e0 avoir encaiss\u00e9 plus d&rsquo;essais qu&rsquo;elle en a marqu\u00e9s.<\/p>\n<h2 style=\"text-align: justify;\">77<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre de points de Dax \u00e0 l&rsquo;issue de la phase r\u00e9guli\u00e8re. Soit 2,56 points par match. Dont 27 sur les 10 derni\u00e8res rencontres (2.7 points par match). Et 57 sur les 20 derniers matchs. Apr\u00e8s un d\u00e9but de saison d\u00e9j\u00e0 correct, les Landais ont trouv\u00e9 leur rythme de croisi\u00e8re dans cette Pro D2.<\/p>\n<h2 style=\"text-align: justify;\">126<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre de ballons gratt\u00e9s par la d\u00e9fense de Dax cette saison. Le meilleur total de ce championnat de Pro D2. Dix-huit ballons de plus que Soyaux-Angoul\u00eame, le 2e de ce championnat dans ce secteur. Les Dacquois sont bien aid\u00e9s par les 21 ballons gratt\u00e9s par leur 3e ligne<strong> Jean-Baptiste Barr\u00e8re<\/strong>. 3\u1d49 total de la saison (il est aussi dans le top 10 des meilleurs plaqueurs de la saison). Mais aussi les douze ballons r\u00e9cup\u00e9r\u00e9s du talonneur <strong>Iban Hiriart-Urruty<\/strong>, \u00e9galement bien plac\u00e9 dans ce classement.<\/p>\n<h2 style=\"text-align: justify;\">272<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre d&rsquo;offloads (passe apr\u00e8s contact) r\u00e9alis\u00e9 par les Dacquois cette saison. C&rsquo;est le 3e total de ce championnat.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>PRO D2 2023-2024 &#8211; Promu de Nationale, Dax s&rsquo;est invit\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale en barrages. Retour en chiffres sur leur performance.<\/p>\n","protected":false},"author":83,"featured_media":487123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129],"tags":[2227,16878,1839,13,3666],"class_list":["post-487105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-biarritz-olympique","tag-breve","tag-pro-d2","tag-rugby","tag-us-dax"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pro D2 : L&#039;incroyable parcours de Dax en chiffres<\/title>\n<meta name=\"description\" content=\"PRO D2 2023-2024 - Promu de Nationale, Dax s&#039;est invit\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale en barrages. Retour en chiffres sur leur performance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pro D2 : L&#039;incroyable parcours de Dax en chiffres\" \/>\n<meta property=\"og:description\" content=\"PRO D2 2023-2024 - Promu de Nationale, Dax s&#039;est invit\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale en barrages. Retour en chiffres sur leur performance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-22T17:06:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T09:27:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pro D2 : L&#039;incroyable parcours de Dax en chiffres\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Pro D2 : L&rsquo;incroyable parcours de Dax en chiffres\",\"datePublished\":\"2024-05-22T17:06:27+00:00\",\"dateModified\":\"2024-05-23T09:27:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/\"},\"wordCount\":619,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png\",\"keywords\":[\"biarritz olympique\",\"br\u00e8ve\",\"Pro D2\",\"Rugby\",\"us dax\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/\",\"name\":\"Pro D2 : L'incroyable parcours de Dax en chiffres\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png\",\"datePublished\":\"2024-05-22T17:06:27+00:00\",\"dateModified\":\"2024-05-23T09:27:52+00:00\",\"description\":\"PRO D2 2023-2024 - Promu de Nationale, Dax s'est invit\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale en barrages. Retour en chiffres sur leur performance.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png\",\"width\":1200,\"height\":674,\"caption\":\"Pro D2 : L'incroyable parcours de Dax en chiffres\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro D2 : L&rsquo;incroyable parcours de Dax en chiffres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pro D2 : L'incroyable parcours de Dax en chiffres","description":"PRO D2 2023-2024 - Promu de Nationale, Dax s'est invit\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale en barrages. Retour en chiffres sur leur performance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/","og_locale":"fr_FR","og_type":"article","og_title":"Pro D2 : L'incroyable parcours de Dax en chiffres","og_description":"PRO D2 2023-2024 - Promu de Nationale, Dax s'est invit\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale en barrages. Retour en chiffres sur leur performance.","og_url":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-05-22T17:06:27+00:00","article_modified_time":"2024-05-23T09:27:52+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Pro D2 : L'incroyable parcours de Dax en chiffres","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Pro D2 : L&rsquo;incroyable parcours de Dax en chiffres","datePublished":"2024-05-22T17:06:27+00:00","dateModified":"2024-05-23T09:27:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/"},"wordCount":619,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png","keywords":["biarritz olympique","br\u00e8ve","Pro D2","Rugby","us dax"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/","url":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/","name":"Pro D2 : L'incroyable parcours de Dax en chiffres","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png","datePublished":"2024-05-22T17:06:27+00:00","dateModified":"2024-05-23T09:27:52+00:00","description":"PRO D2 2023-2024 - Promu de Nationale, Dax s'est invit\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale en barrages. Retour en chiffres sur leur performance.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Pro-D2-Lincroyable-parcours-de-Dax-en-chiffres.png","width":1200,"height":674,"caption":"Pro D2 : L'incroyable parcours de Dax en chiffres"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-lincroyable-parcours-de-dax-en-chiffres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pro D2 : L&rsquo;incroyable parcours de Dax en chiffres"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=487105"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487105\/revisions"}],"predecessor-version":[{"id":487183,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487105\/revisions\/487183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/487123"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=487105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=487105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=487105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}