{"id":487431,"date":"2024-06-10T13:53:43","date_gmt":"2024-06-10T11:53:43","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=487431&#038;preview=true&#038;preview_id=487431"},"modified":"2024-06-10T15:32:04","modified_gmt":"2024-06-10T13:32:04","slug":"enzo-djebali-la-france-est-en-retard-sur-le-recrutement","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/","title":{"rendered":"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FOOTBALL \u2013 En charge du recrutement au Red Star, au Stade de Reims et au FC Versailles, Enzo Djebali s\u2019occupe d\u00e9sormais de recruter des joueurs europ\u00e9ens pour le FC Dallas (MLS). Auteur du livre \u00ab\u00a0Recruteur\u00a0\u00bb (\u00e9ditions Solar), il confie les m\u00e9thodes et les secrets des scouts. Pour Dicodusport, il revient sur les principes du m\u00e9tier, analyse les recrutements de l\u2019OM et de OL dont les r\u00e9sultats ont \u00e9t\u00e9 oppos\u00e9s et aborde l\u2019avenir du football aux \u00c9tats-Unis. <\/em><\/strong><\/p>\n<h3 style=\"text-align: justify;\"><strong>Pourquoi le m\u00e9tier de recruteur est-il si peu connu ?<\/strong><\/h3>\n<p style=\"text-align: justify;\">C\u2019est un nouveau m\u00e9tier dans l\u2019importance du football, qui est apparu avec la mondialisation progressive du sport. Avant, les recruteurs \u00e9taient souvent les entra\u00eeneurs adjoints qui sillonnaient le pays et les \u00e9quipes, qui ne pouvaient b\u00e9n\u00e9ficier que de cinq joueurs \u00e9trangers. Aujourd\u2019hui, gr\u00e2ce \u00e0 l\u2019arr\u00eat Bosman et l\u2019accord de Cotonou, le champ des recherches s&rsquo;est consid\u00e9rablement \u00e9largi, ce qui a engendr\u00e9 un besoin de d\u00e9l\u00e9guer. Surtout que le mercato est devenu un business et des clubs survivent gr\u00e2ce aux transferts. C\u2019est pour cela que le m\u00e9tier de recruteur est inscrit dans le football moderne.<\/p>\n<p style=\"text-align: justify;\">Deuxi\u00e8me point, le recruteur est un des maillons de la cha\u00eene,\u00a0mais il ne prend pas la d\u00e9cision. Le projet sportif est \u00e9dit\u00e9 par le coach et par la direction sportive. Donc comme il ne d\u00e9cide pas, il doit se taire sur beaucoup d\u2019aspects et il se fait discret dans les m\u00e9dias.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Existe-t-il une semaine type\u00a0? <\/strong><\/h3>\n<p style=\"text-align: justify;\">Un scout n\u2019a pas de semaine type, car tout se fait en fonction du club et ses facteurs contraignants \u2013 la culture du club \u2013 et limitants \u2013 les lois, les salaires et les budgets du club, mais aussi le planning et le budget du scout.<\/p>\n<p style=\"text-align: justify;\">Sur une semaine, un scout doit voir son \u00e9quipe et en m\u00eame temps observer celle des autres clubs. Cela fait 3 ou 4 matchs par semaine avec des rapports \u00e0 rendre. Mais un scout est toujours dans la prospection. Faire des rapports, c&rsquo;est bien, mais il faut aussi statuer, car le mercato va vite. Tout ne se fait pas pendant la p\u00e9riode des transferts. Parfois, il se joue d\u00e8s novembre. Le timing est la notion la plus fondamentale pour un scout.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Le mercato a d\u00e9marr\u00e9 le lundi 10 \u00a0juin dernier en France. Est-ce le moment o\u00f9 le recruteur travaille le plus ? Ou pas forc\u00e9ment vu qu\u2019il n\u2019y a plus de match ?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Le travail d&rsquo;un scout est un marathon. Les semaines sont tr\u00e8s lancinantes, car il encha\u00eene les rapports. En revanche, le mercato est une succession de sprints. Sur certaines p\u00e9riodes, le recruteur r\u00e9vise des dossiers d\u00e9j\u00e0 vus, donc c\u2019est un travail peu \u00e9nergivore. Parfois, il faut prendre une d\u00e9cision rapidement, parce qu&rsquo;une opportunit\u00e9 se pr\u00e9sente et il doit encha\u00eener une quinzaine de matchs avec une grosse pression. Le c\u0153ur du travail d\u2019un recruteur n\u2019est pas le mercato, mais il y a de temps en temps du travail et il est oppressant.<\/p>\n<h3 style=\"text-align: justify;\"><strong>O\u00f9 se situe la France par rapport aux autres pays europ\u00e9ens\u00a0et notamment les anglo-saxons\u00a0? <\/strong><\/h3>\n<p style=\"text-align: justify;\">La France est en retard et je n\u2019ai pas peur de le dire. En France, on aime bien \u00eatre dans la discussion et dans l\u2019\u00e9motion. Tout ce qui est syst\u00e9mique ou protocolaire fait peur aux Fran\u00e7ais. Beaucoup de pr\u00e9sidents de clubs n\u2019ont pas encore d\u00e9l\u00e9gu\u00e9 leur pouvoir ou l\u2019ont fait de mani\u00e8re n\u00e9potique, ce qui court-circuite le processus de travail classique. En France, on aime bien donner la confiance et la reprendre, alors que dans les pays anglo-saxons, on te fait confiance. Si \u00e7a marche, tr\u00e8s bien, on continue ; si \u00e7a ne marche pas, tu es vir\u00e9. En France, on a du mal \u00e0 faire des choses avant-gardistes, car chacun craint pour sa place. C&rsquo;est la culture fran\u00e7aise et \u00e7a a du bon aussi.<\/p>\n<p style=\"text-align: justify;\">Par exemple, \u00eatre conservateur permet de cr\u00e9er des histoires comme Brest. Si le club avait chamboul\u00e9 tout le groupe, peut-\u00eatre que le r\u00e9sultat aurait \u00e9t\u00e9 pire que la saison d\u2019avant (14<sup>e<\/sup> en 2022-2023) alors que Brest termine 3e de Ligue 1. Si on veut que le monde du football fran\u00e7ais avance au niveau du fonctionnement du recrutement, il faut changer le sens politique du recrutement. Aujourd&rsquo;hui, les clubs qui r\u00e9ussissent sont ceux qui mettent \u00e0 niveau \u00e9gal le coach, la direction sportive et les recruteurs. Lorsque tout le monde se regarde d\u2019\u00e9gal \u00e0 \u00e9gal, et que la parole de chacun vaut un pour un, \u00e7a marche.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Wow ! \ud83e\udd29<br \/>\nQuelle incroyable surprise !<br \/>\nJuste avant de couvrir le Tournoi de Toulon, les premiers retours issus de mon \u00e9diteur montrent que RECRUTEUR est le livre le plus demand\u00e9 sur Amazon #1 !<br \/>\nMerci \u00e0 vous infiniment, peu de mots pour vous exprimer \u00e0 quel point c\u2019est incroyable <a href=\"https:\/\/t.co\/8TQXomb8Ud\">pic.twitter.com\/8TQXomb8Ud<\/a><\/p>\n<p>\u2014 Enzo Djebali (@EnzoDjebali) <a href=\"https:\/\/twitter.com\/EnzoDjebali\/status\/1797518623361360068?ref_src=twsrc%5Etfw\">June 3, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\"><strong>L\u2019\u00e9t\u00e9 dernier, l\u2019Olympique de Marseille a recrut\u00e9 de nombreux joueurs africains et en a pay\u00e9 les frais pendant la CAN. Est-ce la faute des dirigeants ou du recruteur ? <\/strong><\/h3>\n<p style=\"text-align: justify;\">Le probl\u00e8me est diff\u00e9rent et pour moi le probl\u00e8me n\u2019a pas \u00e9t\u00e9 le recrutement. L\u2019\u00e9quipe de Marseille a \u00e9t\u00e9 marqu\u00e9e en termes de style de jeu par la patte d\u2019Igor Tudor : un pressing tr\u00e8s haut, des bases \u00e0 3 et des joueurs qui r\u00e9p\u00e8tent \u00e9norm\u00e9ment les volumes de courses. C&rsquo;\u00e9tait une identit\u00e9 tr\u00e8s tranch\u00e9e. L\u2019erreur est d\u2019avoir amen\u00e9 Marcelino, un coach extr\u00eamement comp\u00e9tent et qui l&rsquo;a d\u00e9j\u00e0 prouv\u00e9, mais qui est un pur micro-tacticien. Il n&rsquo;aime pas imposer son jeu, mais il s&rsquo;adapte constamment \u00e0 l&rsquo;adversaire avec un bloc haut pour trouver les petites failles pour gagner 1-0 ou 2-1. \u00c7a ne colle pas \u00e0 la culture marseillaise et \u00e7a n\u2019allait pas avec le style de l&rsquo;effectif. Sur le papier, Marseille avait une bonne \u00e9quipe avec de bons joueurs, mais \u00e7a a plong\u00e9 l&rsquo;effectif dans une sous performance et dans le doute, car il y avait un manque de rep\u00e8res tactiques et techniques. Je pense que l\u2019excuse de la CAN est un peu surestim\u00e9e.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Au contraire, l\u2019OL a profit\u00e9 du mercato hivernal pour se redresser. Comment cela se passe-t-il pour le recruteur lors de la premi\u00e8re partie de saison\u00a0? <\/strong><\/h3>\n<p style=\"text-align: justify;\">D\u00e9j\u00e0, le recruteur le vit tr\u00e8s mal. Quand les joueurs performent, vous ne partagez pas la joie, car ce n&rsquo;est pas vous qui \u00eates sur le terrain, ni qui avez fait la composition. Par contre, lorsque les joueurs sous-performent, vous le prenez pour vous, votre tristesse et votre frustration se nourrissent de l&rsquo;int\u00e9rieur et elles ne cessent de gonfler. Un recruteur vit bien plus mal les mauvais r\u00e9sultats qu&rsquo;il ne vit bien les bons.<\/p>\n<p style=\"text-align: justify;\">En hiver, Lyon a termin\u00e9 son mercato d&rsquo;\u00e9t\u00e9. Le club a conserv\u00e9 une \u00e9quipe qui pouvait \u00eatre dominant sur la possession et dans la transition. Il y a eu des critiques sur le fait d\u2019avoir d\u00e9pens\u00e9 65 millions d\u2019euros, mais \u00e7a fait partie de leurs moyens. Lyon aurait pu les mettre pour des joueurs de niveau Ligue 1 et simplement jouer le maintien. Mais ce n\u2019est pas ce que le club a fait. Il a fait un mercato pour joueur l\u2019Europe, en pensant au long terme.<\/p>\n<h3 style=\"text-align: justify;\"><strong>D\u00e9sormais, vous travaillez pour le club de Dallas. Est-ce que le recrutement est diff\u00e9rent aux \u00c9tats-Unis ? <\/strong><\/h3>\n<p style=\"text-align: justify;\">En MLS <em>(Major League Soccer)<\/em>, le r\u00e8glement est tr\u00e8s am\u00e9ricain avec plein de lois sur les contrats. Cela n\u2019a rien \u00e0 voir avec le fonctionnement europ\u00e9en du fait de l\u2019absence d\u2019arr\u00eat Bosman ou d\u2019accord de Cotonou. En revanche, je retrouve beaucoup d\u2019aspects du monde anglo-saxon : on te consulte, on te met face \u00e0 tes responsabilit\u00e9s et on te prend pour ce que tu es. Il y a beaucoup de solidarit\u00e9, de volont\u00e9, d&rsquo;encouragement et de choses dont on n&rsquo;a pas forc\u00e9ment l&rsquo;habitude en France. Par exemple, on essaie de faire participer tout le monde afin d\u2019optimiser les qualit\u00e9s et les exp\u00e9riences de chacun.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Comment imagines-tu l\u2019avenir du football aux \u00c9tats-Unis avec notamment la coupe du monde en 2026\u00a0? <\/strong><\/h3>\n<p style=\"text-align: justify;\">La MLS <em>(Major League Soccer) <\/em>est un projet bien diff\u00e9rent de l&rsquo;Arabie saoudite ou des pays du Golfe. Dans les lois, elle incite \u00e0 recruter des jeunes joueurs avec le \u00ab\u00a0Young\u00a0Designated Players\u00a0\u00bb qui offre des bonus financiers lorsqu\u2019une \u00e9quipe prend un jeune <em>(moins de 24 ans)<\/em>. La MLS veut devenir une ligue comp\u00e9titive ainsi que former et exporter des jeunes joueurs. Le vrai concurrent de la MLS n&rsquo;est pas l&rsquo;Europe, mais le Mexique. Les \u00c9tats-Unis veulent devenir le premier pays du football en Am\u00e9rique, derri\u00e8re le Br\u00e9sil et l\u2019Argentine, o\u00f9 le football n&rsquo;est pas un sport, mais une religion. L&rsquo;objectif est plus continental et c&rsquo;est par l\u00e0 que les \u00c9tats-Unis deviendront une r\u00e9f\u00e9rence mondiale. \u00c0 l\u2019image d\u2019Andr\u00e9-Pierre Gignac qui est devenu une des l\u00e9gendes aux Tigres <em>(Mexique)<\/em>, \u00e0 l&rsquo;avenir, plusieurs jours europ\u00e9ens qui seront au top de leur forme pourront \u00e9crire des dynasties en MLS.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Donc pas forc\u00e9ment comme le font actuellement Lionel Messi (Inter Miami), Olivier Giroud ou Hugo Lloris (Los Angeles FC)\u00a0qui sont en fin de carri\u00e8re.<\/strong><\/h3>\n<p style=\"text-align: justify;\">Ce sont des exemples qui sont utiles pour l&rsquo;exposition. \u00c7a permet d&rsquo;amener la culture foot aux \u00c9tats-Unis. Actuellement, elle est compl\u00e8tement absente. Le pays ne conna\u00eet pas l&rsquo;histoire du football. C\u2019est gr\u00e2ce \u00e0 ces anciennes gloires que la culture va se construire. Les Am\u00e9ricains vont les voir jouer et d\u00e9couvrir leur histoire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recruteur, Enzo Djebali confie les m\u00e9thodes et les secrets des scouts. Les principes du m\u00e9tier avec une analyse sur l&rsquo;OM et l&rsquo;OL.<\/p>\n","protected":false},"author":80,"featured_media":491889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301],"tags":[16878,75],"class_list":["post-487431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-breve","tag-football"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb<\/title>\n<meta name=\"description\" content=\"Recruteur, Enzo Djebali confie les m\u00e9thodes et les secrets des scouts. Les principes du m\u00e9tier avec une analyse sur l&#039;OM et l&#039;OL.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb\" \/>\n<meta property=\"og:description\" content=\"Recruteur, Enzo Djebali confie les m\u00e9thodes et les secrets des scouts. Les principes du m\u00e9tier avec une analyse sur l&#039;OM et l&#039;OL.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T11:53:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T13:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Killian Tanguy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sport_ktanguy\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/\"},\"author\":{\"name\":\"Killian Tanguy\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/ff2feeb71ea78ad31eeb3390ffe96b46\"},\"headline\":\"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb\",\"datePublished\":\"2024-06-10T11:53:43+00:00\",\"dateModified\":\"2024-06-10T13:32:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/\"},\"wordCount\":1676,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png\",\"keywords\":[\"br\u00e8ve\",\"Football\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/\",\"name\":\"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png\",\"datePublished\":\"2024-06-10T11:53:43+00:00\",\"dateModified\":\"2024-06-10T13:32:04+00:00\",\"description\":\"Recruteur, Enzo Djebali confie les m\u00e9thodes et les secrets des scouts. Les principes du m\u00e9tier avec une analyse sur l'OM et l'OL.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png\",\"width\":1200,\"height\":674,\"caption\":\"Enzo Djebali \u00ab La France est en retard sur le recrutement \u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/ff2feeb71ea78ad31eeb3390ffe96b46\",\"name\":\"Killian Tanguy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"caption\":\"Killian Tanguy\"},\"description\":\"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.\",\"sameAs\":[\"https:\\\/\\\/killiantanguy.wixsite.com\\\/monsite\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100009753662352\",\"https:\\\/\\\/www.instagram.com\\\/sport.killiantanguy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/killiantanguy\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sport_ktanguy\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRfZkHKJL0wK7wvnJjCry-Q\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/killian-tanguy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb","description":"Recruteur, Enzo Djebali confie les m\u00e9thodes et les secrets des scouts. Les principes du m\u00e9tier avec une analyse sur l'OM et l'OL.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/","og_locale":"fr_FR","og_type":"article","og_title":"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb","og_description":"Recruteur, Enzo Djebali confie les m\u00e9thodes et les secrets des scouts. Les principes du m\u00e9tier avec une analyse sur l'OM et l'OL.","og_url":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/profile.php?id=100009753662352","article_published_time":"2024-06-10T11:53:43+00:00","article_modified_time":"2024-06-10T13:32:04+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png","type":"image\/png"}],"author":"Killian Tanguy","twitter_card":"summary_large_image","twitter_title":"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb","twitter_creator":"@https:\/\/twitter.com\/sport_ktanguy","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/"},"author":{"name":"Killian Tanguy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46"},"headline":"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb","datePublished":"2024-06-10T11:53:43+00:00","dateModified":"2024-06-10T13:32:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/"},"wordCount":1676,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png","keywords":["br\u00e8ve","Football"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/","url":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/","name":"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png","datePublished":"2024-06-10T11:53:43+00:00","dateModified":"2024-06-10T13:32:04+00:00","description":"Recruteur, Enzo Djebali confie les m\u00e9thodes et les secrets des scouts. Les principes du m\u00e9tier avec une analyse sur l'OM et l'OL.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Enzo-Djebali-La-France-est-en-retard-sur-le-recrutement-.png","width":1200,"height":674,"caption":"Enzo Djebali \u00ab La France est en retard sur le recrutement \u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/enzo-djebali-la-france-est-en-retard-sur-le-recrutement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Enzo Djebali : \u00ab La France est en retard sur le recrutement \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46","name":"Killian Tanguy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","caption":"Killian Tanguy"},"description":"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.","sameAs":["https:\/\/killiantanguy.wixsite.com\/monsite","https:\/\/www.facebook.com\/profile.php?id=100009753662352","https:\/\/www.instagram.com\/sport.killiantanguy\/","https:\/\/www.linkedin.com\/in\/killiantanguy\/","https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy","https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q"],"url":"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=487431"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487431\/revisions"}],"predecessor-version":[{"id":491895,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487431\/revisions\/491895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/491889"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=487431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=487431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=487431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}