{"id":487680,"date":"2024-05-24T09:15:16","date_gmt":"2024-05-24T07:15:16","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=487680&#038;preview=true&#038;preview_id=487680"},"modified":"2024-05-24T09:29:49","modified_gmt":"2024-05-24T07:29:49","slug":"transferts-toulouse-piula-faasalele-va-signer-en-pro-d2","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/","title":{"rendered":"Transferts Toulouse : Piula Faasalele va signer en Pro D2"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>RUGBY \u00c0 XV<\/em><\/strong><strong><em> &#8211; Selon le Midi Olympique, Piula Faasalele (Stade Toulousain) va s&rsquo;engager avec le Stade Ni\u00e7ois pour la saison 2024-2025.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/finale-nationale-le-stade-nicois-vient-a-bout-de-narbonne-et-accede-a-la-pro-d2\/\">Le <strong>Stade<\/strong> <strong>Ni\u00e7ois<\/strong> a v\u00e9cu un moment historique<\/a> il y a quelques jours, en remportant le championnat de Nationale, synonyme de mont\u00e9e en <strong>Pro<\/strong> <strong>D2<\/strong> pour la saison prochaine. Les Azur\u00e9ens sont venus \u00e0 bout de <strong>Narbonne<\/strong> pour valider leur ticket et doivent maintenant commencer \u00e0 pr\u00e9parer leur premi\u00e8re saison au deuxi\u00e8me \u00e9chelon du rugby fran\u00e7ais.<\/p>\n<h2 style=\"text-align: justify;\">Piula Faasalele tout proche de Nice<\/h2>\n<p style=\"text-align: justify;\">Les dirigeants du club ni\u00e7ois seraient tout proches de r\u00e9aliser un joli premier tr\u00e8s gros coup avec la signature du tr\u00e8s exp\u00e9riment\u00e9 <strong>Piula<\/strong> <strong>Faasalele<\/strong>. Revenu au <strong>Stade<\/strong> <strong>Toulousain<\/strong> cette saison comme joker <strong>Coupe du monde<\/strong>, il a finalement \u00e9t\u00e9 conserv\u00e9 jusqu&rsquo;\u00e0 la fin de la saison avec pas moins de 19 feuilles de matchs \u00e0 son actif.<\/p>\n<p style=\"text-align: justify;\">En fin de contrat, il ne sera pas conserv\u00e9 par les champions de France en titre et \u00e9tait en qu\u00eate d&rsquo;un nouveau challenge malgr\u00e9 ses 36 ans. Si <strong>Piula<\/strong> <strong>Faasalele<\/strong> n&rsquo;a pas encore sign\u00e9 son contrat avec le promu en <strong>Pro<\/strong> <strong>D2<\/strong>, un accord est imminent. Aussi pass\u00e9 par le <strong>Castres<\/strong> <strong>Olympique<\/strong>, le <strong>Stade<\/strong> <strong>Rochelais<\/strong> et l&rsquo;<strong>USAP<\/strong>, l&rsquo;international samoan va donc se lancer un nouveau challenge en <strong>France<\/strong>, o\u00f9 il a fait l&rsquo;int\u00e9gralit\u00e9 de sa carri\u00e8re professionnelle.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Tapis rouge en Une de Midi Olympique !<\/p>\n<p>Le journal est dispo &gt; <a href=\"https:\/\/t.co\/hO2HfN674U\">https:\/\/t.co\/hO2HfN674U<\/a> <a href=\"https:\/\/t.co\/tSsTxTO57w\">pic.twitter.com\/tSsTxTO57w<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1793755144682938789?ref_src=twsrc%5Etfw\">May 23, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY \u00c0 XV &#8211; Selon le Midi Olympique, Piula Faasalele (Stade Toulousain) va s&rsquo;engager avec le Stade Ni\u00e7ois pour la saison 2024-2025.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":487683,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,47050],"tags":[16878,460],"class_list":["post-487680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-breve","tag-nice"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Transferts Toulouse : Piula Faasalele va signer en Pro D2<\/title>\n<meta name=\"description\" content=\"RUGBY \u00c0 XV - Selon le Midi Olympique, Piula Faasalele (Stade Toulousain) va s&#039;engager avec le Stade Ni\u00e7ois pour la saison 2024-2025.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Toulouse : Piula Faasalele va signer en Pro D2\" \/>\n<meta property=\"og:description\" content=\"RUGBY \u00c0 XV - Selon le Midi Olympique, Piula Faasalele (Stade Toulousain) va s&#039;engager avec le Stade Ni\u00e7ois pour la saison 2024-2025.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-24T07:15:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-24T07:29:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Toulouse : Piula Faasalele va signer en Pro D2\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts Toulouse : Piula Faasalele va signer en Pro D2\",\"datePublished\":\"2024-05-24T07:15:16+00:00\",\"dateModified\":\"2024-05-24T07:29:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/\"},\"wordCount\":270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png\",\"keywords\":[\"br\u00e8ve\",\"Nice\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/\",\"name\":\"Transferts Toulouse : Piula Faasalele va signer en Pro D2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png\",\"datePublished\":\"2024-05-24T07:15:16+00:00\",\"dateModified\":\"2024-05-24T07:29:49+00:00\",\"description\":\"RUGBY \u00c0 XV - Selon le Midi Olympique, Piula Faasalele (Stade Toulousain) va s'engager avec le Stade Ni\u00e7ois pour la saison 2024-2025.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Toulouse : Piula Faasalele va signer en Pro D2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Toulouse : Piula Faasalele va signer en Pro D2","description":"RUGBY \u00c0 XV - Selon le Midi Olympique, Piula Faasalele (Stade Toulousain) va s'engager avec le Stade Ni\u00e7ois pour la saison 2024-2025.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Toulouse : Piula Faasalele va signer en Pro D2","og_description":"RUGBY \u00c0 XV - Selon le Midi Olympique, Piula Faasalele (Stade Toulousain) va s'engager avec le Stade Ni\u00e7ois pour la saison 2024-2025.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-05-24T07:15:16+00:00","article_modified_time":"2024-05-24T07:29:49+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts Toulouse : Piula Faasalele va signer en Pro D2","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts Toulouse : Piula Faasalele va signer en Pro D2","datePublished":"2024-05-24T07:15:16+00:00","dateModified":"2024-05-24T07:29:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/"},"wordCount":270,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png","keywords":["br\u00e8ve","Nice"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/","name":"Transferts Toulouse : Piula Faasalele va signer en Pro D2","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png","datePublished":"2024-05-24T07:15:16+00:00","dateModified":"2024-05-24T07:29:49+00:00","description":"RUGBY \u00c0 XV - Selon le Midi Olympique, Piula Faasalele (Stade Toulousain) va s'engager avec le Stade Ni\u00e7ois pour la saison 2024-2025.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Transferts-Toulouse-Piula-Faasalele-va-signer-en-Pro-D2.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-piula-faasalele-va-signer-en-pro-d2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Toulouse : Piula Faasalele va signer en Pro D2"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=487680"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487680\/revisions"}],"predecessor-version":[{"id":487689,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/487680\/revisions\/487689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/487683"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=487680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=487680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=487680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}