{"id":488761,"date":"2024-05-29T01:39:43","date_gmt":"2024-05-28T23:39:43","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=488761&#038;preview=true&#038;preview_id=488761"},"modified":"2024-05-29T01:39:43","modified_gmt":"2024-05-28T23:39:43","slug":"roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/","title":{"rendered":"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>ROLAND-GARROS 2024 &#8211; Voici le programme des principaux courts du mercredi 29 mai 2024 \u00e0 Roland-Garros.\u00a0<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi :\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-tableau-de-simple-hommes\/\">Le tableau de simple hommes de Roland-Garros<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi :\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-tableau-de-simple-dames\/\">Le tableau de simple dames de Roland-Garros<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Court Philippe-Chatrier (\u00e0 partir de 12h)<\/h2>\n<p style=\"text-align: justify;\">Sofia Kenin &#8211; <strong>Caroline Garcia<\/strong><br \/>\nJesper de Jong &#8211; Carlos Alcaraz<br \/>\nIga Swiatek &#8211; Naomi Osaka<br \/>\n<strong>20h15 :<\/strong> <strong>Richard Gasquet <\/strong>&#8211; Jannik Sinner<\/p>\n<h2 style=\"text-align: justify;\">Court Suzanne-Lenglen (\u00e0 partir de 11h)<\/h2>\n<p>Daniel Altmaier &#8211; Stefanos Tsitsipas<br \/>\nCamila Osorio &#8211; Ons Jabeur<br \/>\nAndrey Rublev &#8211; Pedro Martinez<br \/>\nCoco Gauff &#8211; Tamara Zidansek<\/p>\n<h2 style=\"text-align: justify;\">Court Simonne-Mathieu (\u00e0 partir de 11h)<\/h2>\n<p>Hubert Hurkacz &#8211; Brandon Nakashima<br \/>\nKaterina Siniakova &#8211; <strong>Chlo\u00e9 Paquet<\/strong><br \/>\nDanielle Collins &#8211; Olga Danilovic<br \/>\n<strong>Corentin Moutet <\/strong>&#8211; Alexander Shevchenko<\/p>\n<h2>Court n\u00b014 (\u00e0 partir de 11h)<\/h2>\n<p style=\"text-align: justify;\">Katie Volynets &#8211; Marketa Vondrousova<strong><br \/>\n<\/strong>Denis Shapovalov &#8211; Frances Tiafoe<strong><br \/>\n<\/strong>Donna Vekic &#8211; Marta Kostyuk<br \/>\n<strong>17h : <\/strong>Pavel Kotov &#8211; Stan Wawrinka<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b07 (\u00e0 partir de 11h)<\/h2>\n<p style=\"text-align: justify;\">Ben Shelton &#8211; Kei Nishikori<br \/>\nJelena Ostapenko &#8211; Clara Tauson<br \/>\nFabian Marozsan &#8211; Grigor Dimitrov<br \/>\nLiudmila Samsonova &#8211; Amanda Anisimova<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b06 (\u00e0 partir de 11h)<\/h2>\n<p style=\"text-align: justify;\"><strong>Alexandre M\u00fcller<\/strong> &#8211; Matteo Arnaldi<strong><br \/>\n<\/strong>Henri Squire &#8211; F\u00e9lix Auger-Aliassime<strong><br \/>\n<\/strong>Xinyu Wang &#8211; Viktoriya Tomova<br \/>\nCristina Bucsa &#8211; Elisabetta Cocciaretto<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b08 (\u00e0 partir de 11h)<\/h2>\n<p style=\"text-align: justify;\">Leylah Fernandez &#8211; Xiyu Wang<br \/>\nZizou Bergs &#8211; Maximilian Marterer<br \/>\nSchuurs\/Stefani &#8211; Begu\/Podoroska<br \/>\nStearns\/Zhang &#8211; Navarro\/Shnaider<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b09 (\u00e0 partir de 11h)<\/h2>\n<p>Jana Fett &#8211; Marie Bouzkova<br \/>\nSebastian Ofner &#8211; Sebastian Baez<br \/>\nHsieh\/Mertens &#8211; Aoyama\/Krunic<br \/>\n<strong>Droguet\/Mpetshi Perricard <\/strong>&#8211;<strong> Barr\u00e8re\/Pouille<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROLAND-GARROS 2024 &#8211; Voici le programme des principaux courts du mercredi 29 mai 2024 \u00e0 Roland-Garros.\u00a0<\/p>\n","protected":false},"author":12,"featured_media":488412,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47090],"tags":[16878,159],"class_list":["post-488761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roland-garros","tag-breve","tag-roland-garros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai<\/title>\n<meta name=\"description\" content=\"ROLAND-GARROS 2024 - Voici le programme des principaux courts du mercredi 29 mai 2024 \u00e0 Roland-Garros.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai\" \/>\n<meta property=\"og:description\" content=\"ROLAND-GARROS 2024 - Voici le programme des principaux courts du mercredi 29 mai 2024 \u00e0 Roland-Garros.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-28T23:39:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai\",\"datePublished\":\"2024-05-28T23:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/\"},\"wordCount\":245,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png\",\"keywords\":[\"br\u00e8ve\",\"Roland-Garros\"],\"articleSection\":[\"Roland-Garros\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/\",\"name\":\"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png\",\"datePublished\":\"2024-05-28T23:39:43+00:00\",\"description\":\"ROLAND-GARROS 2024 - Voici le programme des principaux courts du mercredi 29 mai 2024 \u00e0 Roland-Garros.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png\",\"width\":1200,\"height\":674,\"caption\":\"Roland-Garros 2024 : Gasquet, Alcaraz, Garcia, les r\u00e9sultats du dimanche 26 mai\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai","description":"ROLAND-GARROS 2024 - Voici le programme des principaux courts du mercredi 29 mai 2024 \u00e0 Roland-Garros.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/","og_locale":"fr_FR","og_type":"article","og_title":"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai","og_description":"ROLAND-GARROS 2024 - Voici le programme des principaux courts du mercredi 29 mai 2024 \u00e0 Roland-Garros.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-05-28T23:39:43+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai","datePublished":"2024-05-28T23:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/"},"wordCount":245,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png","keywords":["br\u00e8ve","Roland-Garros"],"articleSection":["Roland-Garros"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/","url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/","name":"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png","datePublished":"2024-05-28T23:39:43+00:00","description":"ROLAND-GARROS 2024 - Voici le programme des principaux courts du mercredi 29 mai 2024 \u00e0 Roland-Garros.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/05\/Roland-Garros-2024-Gasquet-Alcaraz-Garcia-les-resultats-du-dimanche-26-mai.png","width":1200,"height":674,"caption":"Roland-Garros 2024 : Gasquet, Alcaraz, Garcia, les r\u00e9sultats du dimanche 26 mai"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-le-programme-des-matchs-du-mercredi-29-mai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Roland-Garros 2024 : Le programme des matchs du mercredi 29 mai"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/488761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=488761"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/488761\/revisions"}],"predecessor-version":[{"id":488762,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/488761\/revisions\/488762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/488412"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=488761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=488761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=488761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}