{"id":490784,"date":"2024-06-07T16:28:27","date_gmt":"2024-06-07T14:28:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=490784&#038;preview=true&#038;preview_id=490784"},"modified":"2024-06-07T16:28:27","modified_gmt":"2024-06-07T14:28:27","slug":"euro-2024-la-serbie-une-premiere-dans-la-competition","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/","title":{"rendered":"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>CHAMPIONNAT D&rsquo;EUROPE DE FOOTBALL 2024 &#8211; Avant le d\u00e9but de la comp\u00e9tition, Dicodusport vous pr\u00e9sente les 24 \u00e9quipes engag\u00e9es. Focus aujourd\u2019hui sur la Serbie, qui s\u2019est qualifi\u00e9e pour la premi\u00e8re fois de son histoire en tant que pays ind\u00e9pendant.<\/strong><\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-de-football-calendrier-et-resultats\/\">Euro 2024 de Football : Calendrier et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Historique de la Serbie aux Championnats d&rsquo;Europe<\/h2>\n<p style=\"text-align: justify;\">Jamais \u00f4 grand jamais la Serbie n\u2019a vu son nom affich\u00e9 dans le tableau du 1<sup>er<\/sup> tour de l\u2019Euro. Membre de la Yougoslavie &#8211; qui regroupait notamment Serbes, Croates et Slov\u00e8nes &#8211; lors des Championnats d\u2019Europe 1960 et ce jusqu\u2019en 1992, elle a ensuite \u00e9t\u00e9 int\u00e9gr\u00e9e \u00e0 la R\u00e9publique f\u00e9d\u00e9rale de Yougoslavie, plus tard appel\u00e9e Serbie-et-Mont\u00e9n\u00e9gro. C\u2019est sous ces derni\u00e8res couleurs qu\u2019elle participe \u00e0 l\u2019Euro 2000. Ind\u00e9pendante depuis 2006, la Serbie n\u2019\u00e9tait pas parvenue \u00e0 se qualifier en 2008, ni en 2012. Pas plus de chance quatre et huit ans plus tard&#8230; Les Serbes vont donc conna\u00eetre leur premier Championnat d\u2019Europe depuis 24 ans, le premier en tant que pays ind\u00e9pendant.<\/p>\n<p style=\"text-align: justify;\">Aucune participation<\/p>\n<p style=\"text-align: justify;\"><strong>1960 \u2013 1992<\/strong>\u00a0: Finaliste de la premi\u00e8re \u00e9dition, la Yougoslavie retrouve ce stade de la comp\u00e9tition huit ans plus tard mais ne sera toujours pas sacr\u00e9e, tombant face \u00e0 l\u2019Italie. Dans le dernier carr\u00e9 en 1976, il n\u2019y aura pas de troisi\u00e8me finale, la Yougoslavie restait au pied du podium.<\/p>\n<p style=\"text-align: justify;\"><strong>1996 \u2013 2004<\/strong>\u00a0: Une seule participation sous la Serbie-et-Mont\u00e9n\u00e9gro. C\u2019\u00e9tait en 2000 pour un parcours jusqu\u2019en quarts de finale et une lourde d\u00e9faite face aux Pays-Bas (6-1).<\/p>\n<p style=\"text-align: justify;\"><strong>2008<\/strong>\u00a0: -, <strong>2012<\/strong>\u00a0: -, <strong>2016<\/strong>\u00a0: -, <strong>2020<\/strong>\u00a0: &#8211;<\/p>\n<h2 style=\"text-align: justify;\">Parcours en qualifications<\/h2>\n<p style=\"text-align: justify;\">2<sup>\u00e8me<\/sup> du groupe G avec 14 points en 8 matchs (4V, 2N,2D)<\/p>\n<p style=\"text-align: justify;\">SERBIE 2-0 Lituanie, Mont\u00e9n\u00e9gro 0-2 SERBIE, Bulgarie 1-1 SERBIE, SERBIE 1-2 Hongrie, Lituanie 1-3 SERBIE, Hongrie 2-1 SERBIE, SERBIE 3-1 Mont\u00e9n\u00e9gro, SERBIE 2-2 Bulgarie<\/p>\n<p style=\"text-align: justify;\">Elle a \u00e9t\u00e9 compliqu\u00e9e \u00e0 aller chercher cette premi\u00e8re qualification \u00e0 l\u2019Euro. Malgr\u00e9 un bon d\u00e9but de campagne, les Serbes ont d\u00fb attendre la toute derni\u00e8re journ\u00e9e pour d\u00e9crocher leur billet pour la comp\u00e9tition. Un nul arrach\u00e9 difficilement face \u00e0 la Bulgarie, bonne derni\u00e8re du groupe. Suffisant n\u00e9anmoins pour se positionner \u00e0 la seconde place devant le Mont\u00e9n\u00e9gro et commencer \u00e0 \u00e9crire l\u2019histoire de la nation.<\/p>\n<h2 style=\"text-align: justify;\">Groupe et XI type de la Serbie<\/h2>\n<p style=\"text-align: justify;\"><strong>Gardiens\u00a0:\u00a0<\/strong>Vanja Milinkovic-Savic (Torino\/ITA), Dorde Petrovic (Chelsea\/ANG), Predrag Rajkovic (Majorque\/ESP).<br \/>\n<strong><br \/>\nD\u00e9fenseurs\u00a0:\u00a0<\/strong>Strahinja Pavlovic (RB\u00a0Salzbourg\/AUT), Nikola Milenkovic (Fiorentina\/ITA), Srdjan Babic (Spartak Moscou\/RUS), Milos Veljkovic (Werder Br\u00eame\/ALL), Uros Spajic (\u00c9toile Rouge Belgrade\/SER), Nemanja Stojic (TSC Backa Topola\/SER).<\/p>\n<p>Milieux\u00a0:\u00a0Sasa Lukic (Fulham\/ANG), Nemanja Gudelj (S\u00e9ville\u00a0FC\/ESP), Nemanja Maksimovic (Getafe\/ESP), Ivan Ilic (Torino\/ITA), Srdjan Mijailovic (\u00c9toile Rouge Belgrade\/SER), Sergej Milinkovic-Savic (Al-Hilal\/ARS), Dusan Tadic (Fenerbah\u00e7e\/TUR), Lazar Samardzic (Udinese\/ITA), Veljko Birmancevic (Sparta Prague\/RTC), Filip Kostic (Juventus\/ITA), Andrija Zivkovic (PAOK Salonique\/GRE), Filip Mladenovic (Panathina\u00efkos\/GRE), Mijat Gacinovic (AEK Ath\u00e8nes\/GRE).<br \/>\n<strong><br \/>\nAttaquants\u00a0:\u00a0<\/strong>Aleksandar Mitrovic (Al-Hilal\/ARS), Dusan Vlahovic (Juventus\/ITA), Luka Jovic (AC\u00a0Milan\/ITA), Petar Ratkov (RB Salzbourg\/AUT).<\/p>\n<p style=\"text-align: justify;\"><u>XI type\u00a0<\/u>: V. Milinkovic-Savic, Pavlovic, Milenkovic, Veljkovic, Kostic, Ilic, S. Milinkovic-Savic, Zivkovic, Tadic, Mitrovic, Vlahovic<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83d\udccb\ud83c\uddf7\ud83c\uddf8 FINAL SQUAD FOR <a href=\"https:\/\/twitter.com\/hashtag\/EURO2024?src=hash&amp;ref_src=twsrc%5Etfw\">#EURO2024<\/a>. \ud83c\udfc6\ud83c\udde9\ud83c\uddea <a href=\"https:\/\/t.co\/A1QY3mLKZp\">pic.twitter.com\/A1QY3mLKZp<\/a><\/p>\n<p>\u2014 Fudbalski savez Srbije | FA of Serbia (@FSSrbije) <a href=\"https:\/\/twitter.com\/FSSrbije\/status\/1795349959824597404?ref_src=twsrc%5Etfw\">May 28, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les joueurs \u00e0 suivre<\/h2>\n<p style=\"text-align: justify;\">L\u2019\u00e9quipe sera men\u00e9e offensivement par <strong>Aleksandar Mitrovic<\/strong> et <strong>Dusan Vlahovic<\/strong>. Le premier a inscrit 5 buts lors des phases qualificatives, et devra rester sur cet \u00e9lan si la Serbie veut esp\u00e9rer passer le 1<sup>er<\/sup> tour. Le second passe actuellement de tr\u00e8s beaux jours sous le maillot turinois. Avec 16 buts inscrits en 33 matchs de s\u00e9rie A, il faudra aussi surveiller cette force serbe. La formation de <strong>Dragan Stojkovic<\/strong> ne poss\u00e8de aucune exp\u00e9rience dans cette comp\u00e9tition, mais ses joueurs, comme le v\u00e9t\u00e9ran <strong>Dusan<\/strong> <strong>Tadic<\/strong> ou <strong>Sergej Milinkovic-Savic<\/strong>, ne se laisseront pas impressionner par l\u2019enjeu de cet Euro.<\/p>\n<h2 style=\"text-align: justify;\">Calendrier du premier tour de la Serbie<\/h2>\n<p style=\"text-align: justify;\">16\/06 Serbie \u2013 Angleterre (21h, Gelsenkirchen \u2013 TF1)<\/p>\n<p style=\"text-align: justify;\">20\/06 <a href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-slovenie-de-retour-24-ans-apres-la-bande-a-zahovic\/\">Slov\u00e9nie<\/a> \u2013 Serbie (15h, Munich \u2013 cha\u00eene \u00e0 d\u00e9terminer)<\/p>\n<p style=\"text-align: justify;\">25\/06 <a href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-le-danemark-peut-il-recreer-l-exploit\/\">Danemark<\/a> \u2013 Serbie (21h, Munich \u2013 cha\u00eene \u00e0 d\u00e9terminer)<\/p>\n<h2 style=\"text-align: justify;\">Pronostic<\/h2>\n<p style=\"text-align: justify;\">Tout juste d\u00e9faite par l\u2019Autriche en match pr\u00e9paratoire, la Serbie ne partira pas confiante dans cet Euro. Oppos\u00e9e \u00e0 l\u2019Angleterre, au Danemark et \u00e0 la Slov\u00e9nie lors des rencontres du 1<sup>er<\/sup> tour, la nation peut-elle continuer d\u2019\u00e9crire son histoire ? Les fr\u00e8res <strong>Milinkovic-Savic<\/strong> peuvent-ils r\u00eaver plus grand\u00a0ensemble ? Tr\u00e8s peu probable. D\u00e9j\u00e0 qualifi\u00e9s de peu dans un groupe relativement faible, les Serbes, sans un ou deux coups d\u2019\u00e9clat dans ces matchs de poule sont condamner \u00e0 la derni\u00e8re place. Si la Slov\u00e9nie reste l\u2019adversaire le plus prenable, elle n\u2019a pas d\u00e9m\u00e9rit\u00e9 lors des \u00e9liminatoires, terminant \u00e0 \u00e9galit\u00e9 de points avec le Danemark. Ce duel sera d\u00e9terminant pour une potentielle troisi\u00e8me place qualificative. Mais pour les Serbes, l\u2019Euro 2024 devraient s\u2019arr\u00eater au terme des trois premiers duels.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Serbie peut-elle \u00e9crire davantage son histoire pour sa premi\u00e8re participation \u00e0 l&rsquo;Euro en tant que nation ind\u00e9pendante ?<\/p>\n","protected":false},"author":18,"featured_media":490955,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47044],"tags":[16878],"class_list":["post-490784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euro-de-football","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition<\/title>\n<meta name=\"description\" content=\"La Serbie peut-elle \u00e9crire davantage son histoire pour sa premi\u00e8re participation \u00e0 l&#039;Euro en tant que nation ind\u00e9pendante ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition\" \/>\n<meta property=\"og:description\" content=\"La Serbie peut-elle \u00e9crire davantage son histoire pour sa premi\u00e8re participation \u00e0 l&#039;Euro en tant que nation ind\u00e9pendante ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-07T14:28:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition\",\"datePublished\":\"2024-06-07T14:28:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/\"},\"wordCount\":848,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg\",\"keywords\":[\"br\u00e8ve\"],\"articleSection\":[\"Euro de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/\",\"name\":\"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg\",\"datePublished\":\"2024-06-07T14:28:27+00:00\",\"description\":\"La Serbie peut-elle \u00e9crire davantage son histoire pour sa premi\u00e8re participation \u00e0 l'Euro en tant que nation ind\u00e9pendante ?\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg\",\"width\":1200,\"height\":674,\"caption\":\"Euro 2024 La Serbie une premi\u00e8re dans la comp\u00e9tition\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition","description":"La Serbie peut-elle \u00e9crire davantage son histoire pour sa premi\u00e8re participation \u00e0 l'Euro en tant que nation ind\u00e9pendante ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition","og_description":"La Serbie peut-elle \u00e9crire davantage son histoire pour sa premi\u00e8re participation \u00e0 l'Euro en tant que nation ind\u00e9pendante ?","og_url":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2024-06-07T14:28:27+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg","type":"image\/jpeg"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition","datePublished":"2024-06-07T14:28:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/"},"wordCount":848,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg","keywords":["br\u00e8ve"],"articleSection":["Euro de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/","url":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/","name":"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg","datePublished":"2024-06-07T14:28:27+00:00","description":"La Serbie peut-elle \u00e9crire davantage son histoire pour sa premi\u00e8re participation \u00e0 l'Euro en tant que nation ind\u00e9pendante ?","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Serbie-une-premiere-dans-la-competition.jpg","width":1200,"height":674,"caption":"Euro 2024 La Serbie une premi\u00e8re dans la comp\u00e9tition"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-serbie-une-premiere-dans-la-competition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Euro 2024 : La Serbie, une premi\u00e8re dans la comp\u00e9tition"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/490784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=490784"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/490784\/revisions"}],"predecessor-version":[{"id":490956,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/490784\/revisions\/490956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/490955"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=490784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=490784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=490784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}