{"id":493085,"date":"2024-06-17T11:51:52","date_gmt":"2024-06-17T09:51:52","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=493085&#038;preview=true&#038;preview_id=493085"},"modified":"2024-06-17T21:38:20","modified_gmt":"2024-06-17T19:38:20","slug":"timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/","title":{"rendered":"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>HANDISPORT OPEN DE PARIS 2024 \u2013 Auteurs d\u2019un chrono de 50.03 sur 400 m, Timoth\u00e9e Adolphe (T11) et son guide Jeffrey Lami ont \u00e9tabli un nouveau record d\u2019Europe au Stade Charl\u00e9ty vendredi. Le sprinteur revient sur sa performance et tire le bilan des deux jours de comp\u00e9tition.<\/em><\/strong><\/p>\n<h3 style=\"text-align: justify;\">Avez-vous senti que vous pouviez battre ce record d\u2019Europe\u00a0?<\/h3>\n<p style=\"text-align: justify;\">On savait qu&rsquo;on pouvait s&rsquo;en rapprocher. On l\u2019avait dans un coin de la t\u00eate. On a couru sans se poser de questions. On avait le plan de course en t\u00eate, on a essay\u00e9 de l\u2019appliquer comme \u00e0 l\u2019entra\u00eenement et\u00a0\u00e7a s\u2019est bien pass\u00e9.<\/p>\n<h3 style=\"text-align: justify;\">Les sensations sont-elles meilleures qu\u2019en juillet dernier lors des championnats du monde qui ont eu lieu sur cette m\u00eame piste ?<\/h3>\n<p style=\"text-align: justify;\">L&rsquo;ann\u00e9e derni\u00e8re, il nous manquait quelques courses parce que j&rsquo;avais \u00e9t\u00e9 bless\u00e9 en avril et en juin donc \u00e7a avait compliqu\u00e9 les choses. Au vu de ce qui sort, \u00e7a para\u00eet \u00e9vident aujourd&rsquo;hui. J&rsquo;assimile mieux les entra\u00eenements que j&rsquo;ai faits avec Dimitri <em>(Demoni\u00e8re)<\/em> et le chrono descend de course en course. \u00c7a va devenir compliqu\u00e9 de le faire descendre, mais il reste des perspectives d&rsquo;am\u00e9lioration et on va continuer \u00e0 travailler. On est \u00e0 2 petits dixi\u00e8mes du record du monde (49.82) donc on va pouvoir s&rsquo;attaquer s\u00e9rieusement \u00e0 cette marque. Aux Jeux, il faudra que l\u2019on soit capable de r\u00e9p\u00e9ter cette performance-l\u00e0, mais \u00e7a nous permet de les aborder un peu plus sereinement.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\uddeb\ud83c\uddf7 Nouveau record d&rsquo;Europe pour Timoth\u00e9e Adolphe \ud83e\udd29<\/p>\n<p>Notre tricolore et son guide Jeffrey Lami s&rsquo;offrent le record d\u2019Europe du 400 m en 50\u2019\u201903 \ud83e\udd47<\/p>\n<p>Deuxi\u00e8me performance de l\u2019histoire et le plein de confiance alors que les Jeux paralympiques approchent \ud83d\udc4f <a href=\"https:\/\/t.co\/s1FlQNDEGB\">pic.twitter.com\/s1FlQNDEGB<\/a><\/p>\n<p>\u2014 SPORTRICOLORE (@sportricolore) <a href=\"https:\/\/twitter.com\/sportricolore\/status\/1801896256463138939?ref_src=twsrc%5Etfw\">June 15, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\">Quels sont ses d\u00e9tails \u00e0 corriger\u00a0?<\/h3>\n<p style=\"text-align: justify;\">Il va falloir analyser \u00e7a avec le coach, mais sur la fin, il faut qu&rsquo;on se d\u00e9sunisse un petit peu moins. Il faut aussi voir comment je peux l\u2019aider et lui <em>(Jeffrey Lami)<\/em> mieux finir sur ma foul\u00e9e. Le reste de la course \u00e9tait super propre, mais il faut que l\u2019on d\u00e9briefe avec la vid\u00e9o.<\/p>\n<h3 style=\"text-align: justify;\">Jeudi, vous avez couru le 100 m en 11.17, la meilleure performance de votre saison. Vous \u00eates satisfait de votre comp\u00e9tition ?<\/h3>\n<p style=\"text-align: justify;\">Oui, les deux jours sont satisfaisants. Hier, chronom\u00e9triquement, on s&rsquo;attendait \u00e0 un petit peu mieux avec Charles <em>(Renard, son guide sur le 100m)<\/em> mais le chrono continue de descendre aussi. On bat Ghavelas <em>(Athan\u00e1sios Ghav\u00e9las, le Grec champion paralympique du monde et d\u2019Europe en titre)<\/em> donc on lui envoie un message \u00e0 deux mois et demi des Jeux. C&rsquo;est une bonne chose, mais ce qui a \u00e9t\u00e9 fait sera \u00e0 refaire et \u00e0 faire en mieux aux Jeux. Il ne faut pas se contenter de cela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auteurs d\u2019un chrono de 50.03 sur 400 m, Timoth\u00e9e Adolphe (T11) et son guide Jeffrey Lami ont \u00e9tabli un nouveau record d\u2019Europe au Stade Charl\u00e9ty vendredi.<\/p>\n","protected":false},"author":80,"featured_media":493679,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2308,5753],"tags":[16878,1265,5804],"class_list":["post-493085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-handisport","tag-breve","tag-handisport","tag-timothee-adolphe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb<\/title>\n<meta name=\"description\" content=\"Auteurs d\u2019un chrono de 50.03 sur 400 m, Timoth\u00e9e Adolphe (T11) et son guide Jeffrey Lami ont \u00e9tabli un nouveau record d\u2019Europe au Stade Charl\u00e9ty vendredi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb\" \/>\n<meta property=\"og:description\" content=\"Auteurs d\u2019un chrono de 50.03 sur 400 m, Timoth\u00e9e Adolphe (T11) et son guide Jeffrey Lami ont \u00e9tabli un nouveau record d\u2019Europe au Stade Charl\u00e9ty vendredi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T09:51:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T19:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Killian Tanguy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sport_ktanguy\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/\"},\"author\":{\"name\":\"Killian Tanguy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46\"},\"headline\":\"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb\",\"datePublished\":\"2024-06-17T09:51:52+00:00\",\"dateModified\":\"2024-06-17T19:38:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/\"},\"wordCount\":497,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png\",\"keywords\":[\"br\u00e8ve\",\"handisport\",\"Timoth\u00e9e Adolphe\"],\"articleSection\":[\"Athl\u00e9tisme\",\"Handisport\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/\",\"name\":\"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png\",\"datePublished\":\"2024-06-17T09:51:52+00:00\",\"dateModified\":\"2024-06-17T19:38:20+00:00\",\"description\":\"Auteurs d\u2019un chrono de 50.03 sur 400 m, Timoth\u00e9e Adolphe (T11) et son guide Jeffrey Lami ont \u00e9tabli un nouveau record d\u2019Europe au Stade Charl\u00e9ty vendredi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png\",\"width\":1200,\"height\":674,\"caption\":\"Timoth\u00e9e Adolphe \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46\",\"name\":\"Killian Tanguy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png\",\"caption\":\"Killian Tanguy\"},\"description\":\"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.\",\"sameAs\":[\"https:\/\/killiantanguy.wixsite.com\/monsite\",\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\",\"https:\/\/www.instagram.com\/sport.killiantanguy\/\",\"https:\/\/www.linkedin.com\/in\/killiantanguy\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy\",\"https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb","description":"Auteurs d\u2019un chrono de 50.03 sur 400 m, Timoth\u00e9e Adolphe (T11) et son guide Jeffrey Lami ont \u00e9tabli un nouveau record d\u2019Europe au Stade Charl\u00e9ty vendredi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/","og_locale":"fr_FR","og_type":"article","og_title":"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb","og_description":"Auteurs d\u2019un chrono de 50.03 sur 400 m, Timoth\u00e9e Adolphe (T11) et son guide Jeffrey Lami ont \u00e9tabli un nouveau record d\u2019Europe au Stade Charl\u00e9ty vendredi.","og_url":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/profile.php?id=100009753662352","article_published_time":"2024-06-17T09:51:52+00:00","article_modified_time":"2024-06-17T19:38:20+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png","type":"image\/png"}],"author":"Killian Tanguy","twitter_card":"summary_large_image","twitter_title":"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb","twitter_creator":"@https:\/\/twitter.com\/sport_ktanguy","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/"},"author":{"name":"Killian Tanguy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46"},"headline":"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb","datePublished":"2024-06-17T09:51:52+00:00","dateModified":"2024-06-17T19:38:20+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/"},"wordCount":497,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png","keywords":["br\u00e8ve","handisport","Timoth\u00e9e Adolphe"],"articleSection":["Athl\u00e9tisme","Handisport"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/","url":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/","name":"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png","datePublished":"2024-06-17T09:51:52+00:00","dateModified":"2024-06-17T19:38:20+00:00","description":"Auteurs d\u2019un chrono de 50.03 sur 400 m, Timoth\u00e9e Adolphe (T11) et son guide Jeffrey Lami ont \u00e9tabli un nouveau record d\u2019Europe au Stade Charl\u00e9ty vendredi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Timothee-Adolphe-Ca-nous-permet-daborder-les-Jeux-un-peu-plus-sereinement-.png","width":1200,"height":674,"caption":"Timoth\u00e9e Adolphe \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/timothee-adolphe-ca-nous-permet-daborder-les-jeux-un-peu-plus-sereinement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Timoth\u00e9e Adolphe : \u00ab \u00c7a nous permet d\u2019aborder les Jeux un peu plus sereinement \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46","name":"Killian Tanguy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","caption":"Killian Tanguy"},"description":"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.","sameAs":["https:\/\/killiantanguy.wixsite.com\/monsite","https:\/\/www.facebook.com\/profile.php?id=100009753662352","https:\/\/www.instagram.com\/sport.killiantanguy\/","https:\/\/www.linkedin.com\/in\/killiantanguy\/","https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy","https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q"],"url":"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/493085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=493085"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/493085\/revisions"}],"predecessor-version":[{"id":493814,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/493085\/revisions\/493814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/493679"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=493085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=493085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=493085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}