{"id":494733,"date":"2024-06-22T16:59:17","date_gmt":"2024-06-22T14:59:17","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=494733&#038;preview=true&#038;preview_id=494733"},"modified":"2024-06-22T17:21:12","modified_gmt":"2024-06-22T15:21:12","slug":"euro-2024-la-georgie-accroche-la-republique-tcheque","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/","title":{"rendered":"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>CHAMPIONNAT D\u2019EUROPE DE FOOTBALL 2024 \u2013 La G\u00e9orgie et la R\u00e9publique Tch\u00e8que ont fait match nul (1-1) ce samedi, au Volksparkstadion de Hambourg. Un r\u00e9sultat qui arrange les deux \u00e9quipes, derni\u00e8res du groupe F, mais qui restent encore en course pour passer le premier tour.<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-le-classement-des-groupes\/\">Le classement des groupes de l\u2019Euro 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La <strong>G\u00e9orgie<\/strong> a tenu. En souffrance face \u00e0 une \u00e9quipe de <strong>R\u00e9publique Tch\u00e8que<\/strong> qui a multipli\u00e9 les attaques (26 tirs, 11 cadr\u00e9s), elle a r\u00e9ussi \u00e0 accrocher un match nul 1-1, et marque ainsi le tout premier point de son histoire.<\/p>\n<p style=\"text-align: justify;\">C\u2019est d\u2019ailleurs la <strong>G\u00e9orgie<\/strong>, qui participe \u00e0 son premier Euro, qui a d\u00e9bloqu\u00e9 le tableau d\u2019affichage. <strong>Georges Mikautadze<\/strong> a marqu\u00e9 juste avant la mi-temps sur un p\u00e9nalty provoqu\u00e9 par une main de <strong>Robin Hran\u00e1\u010d<\/strong> dans la surface. L\u2019avant-centre du <strong>FC Metz<\/strong>, d\u00e9j\u00e0 buteur <a href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-turquie-dispose-dune-vaillante-georgie\/\">face \u00e0 la Turquie<\/a> lors du premier match (1-3), a pris <strong>Jindrich Stanek<\/strong> \u00e0 contre-pied pour donner l\u2019avantage \u00e0 son \u00e9quipe.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">2 &#8211; Georges Mikautadze est devenu le 6e joueur \u00e0 marquer les 2 premiers buts de son pays \u00e0 l&rsquo;EURO, le 1er depuis Andriy Shevchenko en 2012 pour l&rsquo;Ukraine. Leader. <a href=\"https:\/\/twitter.com\/hashtag\/GEOCZE?src=hash&amp;ref_src=twsrc%5Etfw\">#GEOCZE<\/a> <a href=\"https:\/\/t.co\/qkSRj5ocWX\">pic.twitter.com\/qkSRj5ocWX<\/a><\/p>\n<p>\u2014 OptaJean (@OptaJean) <a href=\"https:\/\/twitter.com\/OptaJean\/status\/1804518181123359220?ref_src=twsrc%5Etfw\">June 22, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-de-football-calendrier-et-resultats\/\">Calendrier et r\u00e9sultats de l\u2019Euro 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le groupe de <strong>Willy Sagnol<\/strong> peut \u00e9galement remercier son gardien <strong>Giorgi Mamardashvili<\/strong> qui a \u00e9t\u00e9 un mur face aux tirs tch\u00e8ques\u00a0: triple offenses (3\u2019), tir depuis l\u2019ext\u00e9rieur de la surface d\u2019<strong>Adam Hlo\u017eek<\/strong> (27\u2019), balle rasante (45+5\u2019)\u2026en tout, les Tch\u00e8ques ont tir\u00e9 14 fois lors de la premi\u00e8re p\u00e9riode. Ils en ont cadr\u00e9 8, mais tous ont \u00e9t\u00e9 arr\u00eat\u00e9s. \u00c0 la 24e minute, <strong>Adam Hlo\u017eek<\/strong> a m\u00eame cru ouvrir le score. Apr\u00e8s une longue touche, l\u2019ailier gauche du Bayer Leverkusen a tir\u00e9 du bout du pied. Apr\u00e8s avoir \u00e9t\u00e9 repouss\u00e9 par le visage du gardien <strong>Giorgi Mamardashvili<\/strong>, le ballon a rebondi sur le sien puis sur sa main avant de finir au fond des filets. L\u2019arbitre allemand <strong>Daniel Siebert<\/strong> a donc annul\u00e9 le but apr\u00e8s la v\u00e9rification de la VAR.<\/p>\n<h2>Patrik Schick buteur puis bless\u00e9<\/h2>\n<p style=\"text-align: justify;\">Idem en deuxi\u00e8me p\u00e9riode, o\u00f9 les Tch\u00e8ques ont eu plus de 67 % de possession de la balle. C\u2019est son gardien <strong>Giorgi Mamardashvili<\/strong> qui a maintenu son \u00e9quipe en vie. Il n\u2019a p\u00each\u00e9 qu\u2019une seule fois. Juste avant l\u2019heure de jeu (59\u2019), <strong>Patrik Schick<\/strong>, meilleur buteur du dernier Euro, a eu beaucoup de r\u00e9ussite sur un corner. Apr\u00e8s une t\u00eate d&rsquo;<strong>Ond\u0159ej Lingr<\/strong>, le ballon a rebondi sur le poteau, puis la poitrine <strong>Schick<\/strong>, qui \u00e9tait au bon endroit, au bon moment. En revanche, l\u2019avant-centre du Bayer Leverkusen est ensuite sorti sur blessure quelques minutes plus tard, en se tenant le mollet.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\uddec\ud83c\uddea\ud83c\udde8\ud83c\uddff \ud835\udc0e\ud835\udc29\ud835\udc29\ud835\udc28\ud835\udc2b\ud835\udc2d\ud835\udc2e\ud835\udc27\ud835\udc22\ud835\udc2c\ud835\udc2d\ud835\udc1e, \ud835\udc0f\ud835\udc1a\ud835\udc2d\ud835\udc2b\ud835\udc22\ud835\udc24 \ud835\udc12\ud835\udc1c\ud835\udc21\ud835\udc22\ud835\udc1c\ud835\udc24 \ud835\udc11\ud835\udc04\ud835\udc0b\ud835\udc00\ud835\udc0d\ud835\udc02\ud835\udc04 \ud835\udc25\ud835\udc1a \ud835\udc11\ud835\udc1e\u0301\ud835\udc29\ud835\udc2e\ud835\udc1b\ud835\udc25\ud835\udc22\ud835\udc2a\ud835\udc2e\ud835\udc1e \ud835\udc13\ud835\udc1c\ud835\udc21\ud835\udc1e\u0300\ud835\udc2a\ud835\udc2e\ud835\udc1e !<br \/>\n\ud83e\udd8a Un vrai but de renard des surfaces&#8230; de la poitrine !<a href=\"https:\/\/twitter.com\/hashtag\/EURO2024?src=hash&amp;ref_src=twsrc%5Etfw\">#EURO2024<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/beINEURO2024?src=hash&amp;ref_src=twsrc%5Etfw\">#beINEURO2024<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/GEORCZ?src=hash&amp;ref_src=twsrc%5Etfw\">#GEORCZ<\/a> <a href=\"https:\/\/t.co\/pAGU6JCvqi\">pic.twitter.com\/pAGU6JCvqi<\/a><\/p>\n<p>\u2014 beIN SPORTS (@beinsports_FR) <a href=\"https:\/\/twitter.com\/beinsports_FR\/status\/1804521143702790480?ref_src=twsrc%5Etfw\">June 22, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Avec ce score, les deux \u00e9quipes restent en vie dans ce groupe F. Si elles sont derni\u00e8res, avant la rencontre entre la Turquie et le Portugal (18 heures), respectivement premi\u00e8re et deuxi\u00e8me, elles peuvent encore esp\u00e9rer se qualifier. Mercredi, la R\u00e9publique Tch\u00e8que retrouvera la Turquie et le G\u00e9orgie affrontera le Portugal (21 heures).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNAT D\u2019EUROPE DE FOOTBALL 2024 \u2013 La G\u00e9orgie et la R\u00e9publique Tch\u00e8que ont fait match nul 1-1, ce samedi au Volksparkstadion de Hambourg. Un r\u00e9sultat qui arrange les deux \u00e9quipes, derni\u00e8res du groupe F, mais qui restent encore en course pour passer le premier tour.<\/p>\n","protected":false},"author":80,"featured_media":494867,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47044,2301],"tags":[16878,75,7020,360],"class_list":["post-494733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euro-de-football","category-football","tag-breve","tag-football","tag-georgie","tag-republique-tcheque"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que<\/title>\n<meta name=\"description\" content=\"CHAMPIONNAT D\u2019EUROPE DE FOOTBALL 2024 \u2013 Pas de vainqueur entre la G\u00e9orgie et la R\u00e9publique Tch\u00e8que (1-1), qui restent en vie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNAT D\u2019EUROPE DE FOOTBALL 2024 \u2013 Pas de vainqueur entre la G\u00e9orgie et la R\u00e9publique Tch\u00e8que (1-1), qui restent en vie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-22T14:59:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-22T15:21:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Killian Tanguy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sport_ktanguy\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/\"},\"author\":{\"name\":\"Killian Tanguy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46\"},\"headline\":\"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que\",\"datePublished\":\"2024-06-22T14:59:17+00:00\",\"dateModified\":\"2024-06-22T15:21:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/\"},\"wordCount\":564,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"G\u00e9orgie\",\"R\u00e9publique Tch\u00e8que\"],\"articleSection\":[\"Euro de football\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/\",\"name\":\"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png\",\"datePublished\":\"2024-06-22T14:59:17+00:00\",\"dateModified\":\"2024-06-22T15:21:12+00:00\",\"description\":\"CHAMPIONNAT D\u2019EUROPE DE FOOTBALL 2024 \u2013 Pas de vainqueur entre la G\u00e9orgie et la R\u00e9publique Tch\u00e8que (1-1), qui restent en vie.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png\",\"width\":1200,\"height\":674,\"caption\":\"Euro 2024 La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46\",\"name\":\"Killian Tanguy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png\",\"caption\":\"Killian Tanguy\"},\"description\":\"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.\",\"sameAs\":[\"https:\/\/killiantanguy.wixsite.com\/monsite\",\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\",\"https:\/\/www.instagram.com\/sport.killiantanguy\/\",\"https:\/\/www.linkedin.com\/in\/killiantanguy\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy\",\"https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que","description":"CHAMPIONNAT D\u2019EUROPE DE FOOTBALL 2024 \u2013 Pas de vainqueur entre la G\u00e9orgie et la R\u00e9publique Tch\u00e8que (1-1), qui restent en vie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que","og_description":"CHAMPIONNAT D\u2019EUROPE DE FOOTBALL 2024 \u2013 Pas de vainqueur entre la G\u00e9orgie et la R\u00e9publique Tch\u00e8que (1-1), qui restent en vie.","og_url":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/profile.php?id=100009753662352","article_published_time":"2024-06-22T14:59:17+00:00","article_modified_time":"2024-06-22T15:21:12+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png","type":"image\/png"}],"author":"Killian Tanguy","twitter_card":"summary_large_image","twitter_title":"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que","twitter_creator":"@https:\/\/twitter.com\/sport_ktanguy","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/"},"author":{"name":"Killian Tanguy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46"},"headline":"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que","datePublished":"2024-06-22T14:59:17+00:00","dateModified":"2024-06-22T15:21:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/"},"wordCount":564,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png","keywords":["br\u00e8ve","Football","G\u00e9orgie","R\u00e9publique Tch\u00e8que"],"articleSection":["Euro de football","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/","url":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/","name":"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png","datePublished":"2024-06-22T14:59:17+00:00","dateModified":"2024-06-22T15:21:12+00:00","description":"CHAMPIONNAT D\u2019EUROPE DE FOOTBALL 2024 \u2013 Pas de vainqueur entre la G\u00e9orgie et la R\u00e9publique Tch\u00e8que (1-1), qui restent en vie.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/Euro-2024-La-Georgie-accroche-la-Republique-Tcheque.png","width":1200,"height":674,"caption":"Euro 2024 La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euro-2024-la-georgie-accroche-la-republique-tcheque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Euro 2024 : La G\u00e9orgie accroche la R\u00e9publique Tch\u00e8que"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46","name":"Killian Tanguy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","caption":"Killian Tanguy"},"description":"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.","sameAs":["https:\/\/killiantanguy.wixsite.com\/monsite","https:\/\/www.facebook.com\/profile.php?id=100009753662352","https:\/\/www.instagram.com\/sport.killiantanguy\/","https:\/\/www.linkedin.com\/in\/killiantanguy\/","https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy","https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q"],"url":"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/494733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=494733"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/494733\/revisions"}],"predecessor-version":[{"id":494897,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/494733\/revisions\/494897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/494867"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=494733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=494733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=494733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}