{"id":4994,"date":"2017-09-21T12:33:50","date_gmt":"2017-09-21T11:33:50","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=4994"},"modified":"2021-04-13T23:17:01","modified_gmt":"2021-04-13T21:17:01","slug":"michael-jeremiasz-toujours-coeur-handisport","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/","title":{"rendered":"Micha\u00ebl Jeremiasz, toujours au coeur du handisport"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Nous avons rencontr\u00e9 Micha\u00ebl Jeremiasz, jeune retrait\u00e9 de sa carri\u00e8re sportive, qui d\u00e9veloppe de nombreux projets professionnels comme un tournoi de tennis fauteuil fin septembre, le French Riviera Open.<\/em><\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"color: #000000;\">Micha\u00ebl, que fais-tu depuis ta retraite sportive ?<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Je travaille beaucoup plus que quand j\u2019\u00e9tais sportif de haut niveau ! \ud83d\ude42 J\u2019ai plusieurs activit\u00e9s professionnelles. Je fais du conseil en entreprise, je travaille avec Disney Adecco, Malakoff Mederic, Lacoste et Elior. Je les accompagne sur leur politique handicap en fonction de leurs secteurs d\u2019activit\u00e9s. C\u2019est tr\u00e8s diversifi\u00e9 et tr\u00e8s passionnant ! Je travaille aussi beaucoup pour mon association, \u00ab comme les autres \u00bb. Nous accompagnons les personnes en situation d&rsquo;handicap apr\u00e8s un accident de la vie. C\u2019est vraiment important pour moi car ce sont des actions que nous faisons qui sont utiles socialement. Je d\u00e9veloppe aussi les activit\u00e9s d\u2019handiamo, soci\u00e9t\u00e9 dont je suis le g\u00e9rant. Je me suis aussi impliqu\u00e9 en tant qu\u2019ambassadeur aupr\u00e8s du comit\u00e9 de candidature pour Paris 2024. J\u2019ai de beaux projets m\u00e9dias qui vont arriver dans les semaines \u00e0 venir et enfin je suis directeur du French Riviera Open, tournoi de tennis fauteuil qui se d\u00e9roulera fin septembre \u00e0 l\u2019acad\u00e9mie Patrick Mouratoglou.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"color: #000000;\">Peux-tu nous parler du plateau de joueurs qu\u2019il y a aura sur le tournoi ?<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Je suis tr\u00e8s fier car nous avons eu la confiance de grands noms du tennis en fauteuil. Il y aura Gordon Reid, qui est champion paralympique en titre et qui \u00e9tait num\u00e9ro 1 mondial en 2016. Il y aura aussi Nicolas Pfeiffer, notre num\u00e9ro 2 fran\u00e7ais et champion paralympique en double. Chez les femmes il y aura la num\u00e9ro 2 mondiale, Diede De Groot et la num\u00e9ro 1 fran\u00e7aise, Charlotte Famin. Enfin chez les quads il y aura le num\u00e9ro 1 mondial, David Wagner. 40 joueurs et joueuses vont s\u2019affronter pendant quelques jours. Avec C\u00e9dric Mocellin, un tr\u00e8s bon ami, nous sommes vraiment fier d\u2019organiser ce beau tournoi.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"color: #000000;\">Tu as lanc\u00e9 <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.sponsorise.me\/fr\/michael-jeremiasz\" target=\"_blank\" rel=\"noopener noreferrer\">une campagne de crowdfunding<\/a><\/span> pour ce tournoi, quels sont les objectifs autres que financiers ?<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">C\u2019est de faire conna\u00eetre l\u2019\u00e9v\u00e8nement, de toucher le grand public en leur parlant de ces joueurs qui sont aussi m\u00e9ritants que ceux que l\u2019on peut voir \u00e0 la t\u00e9l\u00e9. Cette campagne est destin\u00e9e au tournoi, \u00e0 la location de la tribune pour les finales mais aussi \u00e0 sensibiliser les jeunes de la r\u00e9gion au tennis fauteuil, pour que leur regard change.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"color: #000000;\">Il y a un an tu \u00e9tais porte drapeau \u00e0 Rio, qu\u2019as-tu retenu de cette exp\u00e9rience ?<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cela a \u00e9t\u00e9 une immense fiert\u00e9 pour moi et c\u2019est une reconnaissance de mes engagements. Tous les athl\u00e8tes de la d\u00e9l\u00e9gation paralympique m\u2019ont soutenu pour ce r\u00f4le et pour moi c\u2019est la plus belle des reconnaissances. Pour ces JO j\u2019ai mis mes int\u00e9r\u00eats personnels un peu de c\u00f4t\u00e9 pour vraiment m\u2019impliquer dans ce r\u00f4le et utiliser cette tribune m\u00e9diatique que m\u2019a offert ce r\u00f4le. Je me suis rendu compte que c\u2019\u00e9tait aussi le meilleur moyen de terminer ma carri\u00e8re, que c\u2019\u00e9tait la transition parfaite vers une nouvelle vie.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"color: #000000;\">Tu \u00e9tais impliqu\u00e9 dans la campagne de Paris 2024, quel sentiment domine une semaine apr\u00e8s l\u2019annonce ?<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nous sommes tous tr\u00e8s fiers car nous avions tous beaucoup travaill\u00e9 pour ce projet. Nous avions une tr\u00e8s bonne candidature<\/span><span style=\"color: #000000;\">, avec des anciens athl\u00e8tes, d\u2019autres encore en activit\u00e9, des jeunes athl\u00e8tes et des athl\u00e8tes paralympiques. Cela a \u00e9t\u00e9 une tr\u00e8s belle aventure collective et c\u2019est une victoire m\u00e9rit\u00e9e. Apr\u00e8s le sentiment de fiert\u00e9 vient celui de la responsabilit\u00e9 car nous avons fait beaucoup de promesses et nous allons devoir travailler pour les tenir.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"color: #000000;\">Qu\u2019est-ce qu\u2019on peut te souhaiter pour la suite ?<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">De continuer \u00e0 m\u2019\u00e9clater comme je le fais actuellement ! J\u2019ai vraiment une bonne \u00e9toile en ce moment. J\u2019ai plein de projets personnels et professionnels qui se concr\u00e9tisent. Et si un petit fr\u00e8re ou une petite s\u0153ur pour mon fils en 2018 voit le jour, cela serait merveilleux.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Pour soutenir Michael dans l&rsquo;organisation du French Riviera Open, c&rsquo;est par <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.sponsorise.me\/fr\/michael-jeremiasz\" target=\"_blank\" rel=\"noopener noreferrer\">ici<\/a><\/span> !\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\"><strong>Nicolas Jacquemard<\/strong><\/span><br \/>\n<\/em><a style=\"color: #000000;\" href=\"https:\/\/twitter.com\/Nico_Jacquemard\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"color: #000000;\" href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons rencontr\u00e9 Micha\u00ebl Jeremiasz, jeune retrait\u00e9 de sa carri\u00e8re sportive, qui d\u00e9veloppe de nombreux projets professionnels comme un tournoi de tennis fauteuil fin septembre, le French Riviera Open. Micha\u00ebl, que fais-tu depuis ta retraite sportive ? Je travaille beaucoup plus que quand j\u2019\u00e9tais sportif de haut niveau ! \ud83d\ude42 J\u2019ai plusieurs activit\u00e9s professionnelles. Je [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4998,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2,2302],"tags":[1004,1600],"class_list":["post-4994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-tennis","tag-paris-2024","tag-tennis-fauteuil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Micha\u00ebl Jeremiasz, toujours au coeur du handisport<\/title>\n<meta name=\"description\" content=\"Nous avons rencontr\u00e9 Micha\u00ebl Jeremiasz, jeune retrait\u00e9 de sa carri\u00e8re sportive, qui d\u00e9veloppe de nombreux projets professionnels.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Micha\u00ebl Jeremiasz, toujours au coeur du handisport\" \/>\n<meta property=\"og:description\" content=\"Nous avons rencontr\u00e9 Micha\u00ebl Jeremiasz, jeune retrait\u00e9 de sa carri\u00e8re sportive, qui d\u00e9veloppe de nombreux projets professionnels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-21T11:33:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-13T21:17:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Micha\u00ebl Jeremiasz, toujours au coeur du handisport\",\"datePublished\":\"2017-09-21T11:33:50+00:00\",\"dateModified\":\"2021-04-13T21:17:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/\"},\"wordCount\":735,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png\",\"keywords\":[\"Paris 2024\",\"tennis fauteuil\"],\"articleSection\":[\"Actualit\u00e9s\",\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/\",\"name\":\"Micha\u00ebl Jeremiasz, toujours au coeur du handisport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png\",\"datePublished\":\"2017-09-21T11:33:50+00:00\",\"dateModified\":\"2021-04-13T21:17:01+00:00\",\"description\":\"Nous avons rencontr\u00e9 Micha\u00ebl Jeremiasz, jeune retrait\u00e9 de sa carri\u00e8re sportive, qui d\u00e9veloppe de nombreux projets professionnels.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png\",\"width\":1200,\"height\":670,\"caption\":\"Michael Jeremiasz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Micha\u00ebl Jeremiasz, toujours au coeur du handisport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Micha\u00ebl Jeremiasz, toujours au coeur du handisport","description":"Nous avons rencontr\u00e9 Micha\u00ebl Jeremiasz, jeune retrait\u00e9 de sa carri\u00e8re sportive, qui d\u00e9veloppe de nombreux projets professionnels.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/","og_locale":"fr_FR","og_type":"article","og_title":"Micha\u00ebl Jeremiasz, toujours au coeur du handisport","og_description":"Nous avons rencontr\u00e9 Micha\u00ebl Jeremiasz, jeune retrait\u00e9 de sa carri\u00e8re sportive, qui d\u00e9veloppe de nombreux projets professionnels.","og_url":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2017-09-21T11:33:50+00:00","article_modified_time":"2021-04-13T21:17:01+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Micha\u00ebl Jeremiasz, toujours au coeur du handisport","datePublished":"2017-09-21T11:33:50+00:00","dateModified":"2021-04-13T21:17:01+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/"},"wordCount":735,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png","keywords":["Paris 2024","tennis fauteuil"],"articleSection":["Actualit\u00e9s","Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/","url":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/","name":"Micha\u00ebl Jeremiasz, toujours au coeur du handisport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png","datePublished":"2017-09-21T11:33:50+00:00","dateModified":"2021-04-13T21:17:01+00:00","description":"Nous avons rencontr\u00e9 Micha\u00ebl Jeremiasz, jeune retrait\u00e9 de sa carri\u00e8re sportive, qui d\u00e9veloppe de nombreux projets professionnels.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/Michael-Jeremiasz.png","width":1200,"height":670,"caption":"Michael Jeremiasz"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/michael-jeremiasz-toujours-coeur-handisport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Micha\u00ebl Jeremiasz, toujours au coeur du handisport"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/4994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=4994"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/4994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/4998"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=4994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=4994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=4994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}