{"id":500452,"date":"2024-07-14T18:14:51","date_gmt":"2024-07-14T16:14:51","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=500452&#038;preview=true&#038;preview_id=500452"},"modified":"2024-07-14T18:14:51","modified_gmt":"2024-07-14T16:14:51","slug":"piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/","title":{"rendered":"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS D&rsquo;EUROPE JUNIORS \/ U23 DE CYCLISME SUR PISTE 2024 &#8211; Fin de comp\u00e9tition r\u00e9ussie pour les Bleuets avec deux m\u00e9dailles, dont l&rsquo;or pour Marie-Divine Kouam\u00e9.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Marie-Divine Kouam\u00e9<\/strong> \u00e9tait revenue en cat\u00e9gorie d&rsquo;\u00e2ge U23 pour engranger des titres et de la confiance avant de se projeter vers les Jeux Olympiques. Jeudi, elle raflait l&rsquo;or sur la vitesse individuelle, qu&rsquo;elle disputera \u00e0 Paris. Et aujourd&rsquo;hui, elle a r\u00e9cup\u00e9r\u00e9 <a href=\"https:\/\/dicodusport.fr\/blog\/piste-championnats-deurope-jeunes-taky-marie-divine-kouame-en-or-sur-500-metres\/\">son titre acquis en 2022<\/a> sur le 500 m\u00e8tres, soit la distance sur laquelle <a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-sur-piste-marie-divine-kouame-championne-du-monde-du-500-metres\/\">elle a \u00e9t\u00e9 championne du monde voil\u00e0 deux ans \u00e0 Saint-Quentin-en-Yvelines<\/a>. Elle a toutefois d\u00fb s&#8217;employer pour couper la ligne en <strong>34.714<\/strong> et repousser l&rsquo;Allemande <strong>Clara Schneider<\/strong>, mais avec deux m\u00e9dailles d&rsquo;or, elle est comme pr\u00e9vu l&rsquo;une des stars de ces Championnats d&rsquo;Europe.<\/p>\n<p style=\"text-align: justify;\">Tout comme <strong>\u00c9tienne Oliviero<\/strong>. Le Tricolore a r\u00e9ussi une grande comp\u00e9tition, raflant l&rsquo;or sur <a href=\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-les-bleuets-champions-deurope-juniors-de-vitesse-par-equipes\/\">la vitesse par \u00e9quipes<\/a> puis <a href=\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-etienne-oliviero-champion-deurope-juniors-du-kilometre\/\">sur le kilom\u00e8tre<\/a>. Il a conclu ce dimanche en allant chercher le bronze sur la vitesse individuelle. Sorti sans r\u00e9mission en demi-finales par le futur champion <strong>Colin Rudolph<\/strong>, il a rebondi en allant chercher le bronze \u00e0 la belle contre <strong>Fabio del Medico.<\/strong> Deux m\u00e9dailles d&rsquo;or et une de bronze, on tient l&rsquo;une des futures stars de la piste tricolore. Et une comp\u00e9tition malgr\u00e9 tout r\u00e9ussie pour les Bleuets de la piste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE JUNIORS \/ U23 DE CYCLISME SUR PISTE 2024 &#8211; Fin de comp\u00e9tition r\u00e9ussie pour les Bleuets avec deux m\u00e9dailles, dont l&rsquo;or pour Marie-Divine Kouam\u00e9.<\/p>\n","protected":false},"author":59,"featured_media":500543,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[14089],"tags":[16878],"class_list":["post-500452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-piste","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS D&#039;EUROPE JUNIORS \/ U23 DE CYCLISME SUR PISTE 2024 - Fin de comp\u00e9tition r\u00e9ussie pour les Bleuets avec deux m\u00e9dailles, dont l&#039;or pour Marie-Divine Kouam\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS D&#039;EUROPE JUNIORS \/ U23 DE CYCLISME SUR PISTE 2024 - Fin de comp\u00e9tition r\u00e9ussie pour les Bleuets avec deux m\u00e9dailles, dont l&#039;or pour Marie-Divine Kouam\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-14T16:14:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres\",\"datePublished\":\"2024-07-14T16:14:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/\"},\"wordCount\":251,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png\",\"keywords\":[\"br\u00e8ve\"],\"articleSection\":[\"Cyclisme sur piste\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/\",\"name\":\"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png\",\"datePublished\":\"2024-07-14T16:14:51+00:00\",\"description\":\"CHAMPIONNATS D'EUROPE JUNIORS \/ U23 DE CYCLISME SUR PISTE 2024 - Fin de comp\u00e9tition r\u00e9ussie pour les Bleuets avec deux m\u00e9dailles, dont l'or pour Marie-Divine Kouam\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png\",\"width\":1200,\"height\":674,\"caption\":\"Piste Euro juniors U23 Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres","description":"CHAMPIONNATS D'EUROPE JUNIORS \/ U23 DE CYCLISME SUR PISTE 2024 - Fin de comp\u00e9tition r\u00e9ussie pour les Bleuets avec deux m\u00e9dailles, dont l'or pour Marie-Divine Kouam\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/","og_locale":"fr_FR","og_type":"article","og_title":"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres","og_description":"CHAMPIONNATS D'EUROPE JUNIORS \/ U23 DE CYCLISME SUR PISTE 2024 - Fin de comp\u00e9tition r\u00e9ussie pour les Bleuets avec deux m\u00e9dailles, dont l'or pour Marie-Divine Kouam\u00e9.","og_url":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2024-07-14T16:14:51+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres","datePublished":"2024-07-14T16:14:51+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/"},"wordCount":251,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png","keywords":["br\u00e8ve"],"articleSection":["Cyclisme sur piste"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/","url":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/","name":"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png","datePublished":"2024-07-14T16:14:51+00:00","description":"CHAMPIONNATS D'EUROPE JUNIORS \/ U23 DE CYCLISME SUR PISTE 2024 - Fin de comp\u00e9tition r\u00e9ussie pour les Bleuets avec deux m\u00e9dailles, dont l'or pour Marie-Divine Kouam\u00e9.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Piste-Euro-juniors-U23-Marie-Divine-Kouame-de-nouveau-en-or-sur-le-500-metres.png","width":1200,"height":674,"caption":"Piste Euro juniors U23 Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/piste-euro-juniors-u23-marie-divine-kouame-de-nouveau-en-or-sur-le-500-metres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Piste Euro juniors \/ U23 : Marie-Divine Kouam\u00e9 de nouveau en or sur le 500 m\u00e8tres"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/500452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=500452"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/500452\/revisions"}],"predecessor-version":[{"id":500553,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/500452\/revisions\/500553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/500543"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=500452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=500452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=500452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}