{"id":505103,"date":"2024-07-29T16:18:42","date_gmt":"2024-07-29T14:18:42","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=505103&#038;preview=true&#038;preview_id=505103"},"modified":"2024-07-29T16:41:59","modified_gmt":"2024-07-29T14:41:59","slug":"__trashed-68","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/","title":{"rendered":"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><b>CANO\u00cb-KAYAK JO PARIS 2024 &#8211; Sur le <strong>stade nautique de Vaires-sur-Marne, Nicolas Gestin a une fois de plus impressionn\u00e9 <\/strong>lors de sa demi-finale. Le c\u00e9iste slalomeur fran\u00e7ais a r\u00e9alis\u00e9 largement le meilleur temps et s&rsquo;est largement assur\u00e9 sa place pour la finale.\u00a0<\/b><\/i><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/programme-dates-et-resultats-canoe-kayak-slalom-jo-2024\/\">Programme et r\u00e9sultats Cano\u00eb-Kayak Slalom JO 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le parcours de cette demi-finale a \u00e9t\u00e9 s\u00e9lectif avec beaucoup de fautes parmi les 16 concurrents en course pour la finale olympique avec notamment une grosse figure technique sur les portes 6,7 et 8 pour un total de 23 portes.<\/p>\n<p style=\"text-align: justify;\"><strong>Nicolas Gestin<\/strong> a \u00e9t\u00e9 en avance tout en long tout parcours avec d\u00e9j\u00e0 une seconde d&rsquo;avance sur son dauphin <strong>Miquel Trave<\/strong> au premier temps interm\u00e9diaire avant d&rsquo;accentuer son avance au deuxi\u00e8me temps interm\u00e9diaire avec 3:50. Le Fran\u00e7ais de 24 ans est rest\u00e9 tr\u00e8s calme et a pris un risque sur la porte 18 en passant en avant alors que tous ses adversaires ont pass\u00e9 cette porte en arri\u00e8re.<\/p>\n<p style=\"text-align: justify;\">Finalement, <strong>Nicolas Gestin<\/strong> a sign\u00e9 le meilleur temps en 93:12 avec 3:57 sur l&rsquo;Espagnol <strong>Miquel Trave<\/strong>. On retrouvera donc Gestin dans une heure pour la finale. Les quatre concurrents \u00e9limin\u00e9s ont \u00e9t\u00e9 <strong>Takuya Haneda<\/strong>,<strong> Raffaello Ivaldi<\/strong> qui a connu des p\u00e9pins physiques cette ann\u00e9e, <strong>Alex Baldoni<\/strong> et <strong>Casey Eichfeld<\/strong>.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/jo-paris-2024\/\" target=\"_blank\" rel=\"noopener\">L\u2019actualit\u00e9 des JO de Paris 2024<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nicolas Gestin domine la demi-finale en C1.<\/p>\n","protected":false},"author":48,"featured_media":505199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10458,8436],"tags":[16878,1123,12920],"class_list":["post-505103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canoe-kayak","category-jo-paris-2024","tag-breve","tag-canoe-kayak","tag-jo-paris-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1<\/title>\n<meta name=\"description\" content=\"CANO\u00cb-KAYAK JO PARIS 2024 - Sur le stade nautique de Vaires-sur-Marne, Nicolas Gestin a une fois de plus impressionn\u00e9 lors de sa demi-finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1\" \/>\n<meta property=\"og:description\" content=\"CANO\u00cb-KAYAK JO PARIS 2024 - Sur le stade nautique de Vaires-sur-Marne, Nicolas Gestin a une fois de plus impressionn\u00e9 lors de sa demi-finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-29T14:18:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T14:41:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1\",\"datePublished\":\"2024-07-29T14:18:42+00:00\",\"dateModified\":\"2024-07-29T14:41:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/\"},\"wordCount\":236,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png\",\"keywords\":[\"br\u00e8ve\",\"canoe kayak\",\"JO Paris 2024\"],\"articleSection\":[\"Cano\u00eb-Kayak\",\"JO Paris 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/\",\"name\":\"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png\",\"datePublished\":\"2024-07-29T14:18:42+00:00\",\"dateModified\":\"2024-07-29T14:41:59+00:00\",\"description\":\"CANO\u00cb-KAYAK JO PARIS 2024 - Sur le stade nautique de Vaires-sur-Marne, Nicolas Gestin a une fois de plus impressionn\u00e9 lors de sa demi-finale.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png\",\"width\":1200,\"height\":674,\"caption\":\"Cano\u00eb-Kayak JO 2024 Nicolas Gestin domine la demi-finale en C1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1","description":"CANO\u00cb-KAYAK JO PARIS 2024 - Sur le stade nautique de Vaires-sur-Marne, Nicolas Gestin a une fois de plus impressionn\u00e9 lors de sa demi-finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/","og_locale":"fr_FR","og_type":"article","og_title":"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1","og_description":"CANO\u00cb-KAYAK JO PARIS 2024 - Sur le stade nautique de Vaires-sur-Marne, Nicolas Gestin a une fois de plus impressionn\u00e9 lors de sa demi-finale.","og_url":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2024-07-29T14:18:42+00:00","article_modified_time":"2024-07-29T14:41:59+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1","datePublished":"2024-07-29T14:18:42+00:00","dateModified":"2024-07-29T14:41:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/"},"wordCount":236,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png","keywords":["br\u00e8ve","canoe kayak","JO Paris 2024"],"articleSection":["Cano\u00eb-Kayak","JO Paris 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/__trashed-68\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/","url":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/","name":"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png","datePublished":"2024-07-29T14:18:42+00:00","dateModified":"2024-07-29T14:41:59+00:00","description":"CANO\u00cb-KAYAK JO PARIS 2024 - Sur le stade nautique de Vaires-sur-Marne, Nicolas Gestin a une fois de plus impressionn\u00e9 lors de sa demi-finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/__trashed-68\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/07\/Canoe-Kayak-JO-2024-Nicolas-Gestin-domine-la-demi-finale-en-C1.png","width":1200,"height":674,"caption":"Cano\u00eb-Kayak JO 2024 Nicolas Gestin domine la demi-finale en C1"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/__trashed-68\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Cano\u00eb-Kayak JO 2024 : Nicolas Gestin domine la demi-finale en C1"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/505103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=505103"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/505103\/revisions"}],"predecessor-version":[{"id":505202,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/505103\/revisions\/505202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/505199"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=505103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=505103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=505103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}