{"id":506784,"date":"2024-08-01T14:47:37","date_gmt":"2024-08-01T12:47:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=506784&#038;preview=true&#038;preview_id=506784"},"modified":"2024-08-01T14:47:37","modified_gmt":"2024-08-01T12:47:37","slug":"basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/","title":{"rendered":"Basket 3&#215;3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>BASKET 3X3 (H) JO 2024 &#8211; Apr\u00e8s deux succ\u00e8s \u00e9triqu\u00e9s face \u00e0 la Lituanie et la Pologne, les Bleus ont perdu leur premier match face aux Pays-Bas, 20-13.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/jo-paris-2024\/\" target=\"_blank\" rel=\"noopener\">L\u2019actualit\u00e9 des JO de Paris 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Avec une adresse \u00e0 distance catastrophique (2\/17 sur les tirs \u00e0 2 points), L&rsquo;\u00e9quipe de France de Basket 3&#215;3 hommes a perdu sa 3<sup>\u00e8me<\/sup> victoire en autant de matchs dans ce tournoi olympique. <strong>Lucas Dussoulier<\/strong> a \u00e9t\u00e9 l&rsquo;homme fort des Tricolores avec 6 points et une belle efficacit\u00e9, contrairement \u00e0 ses partenaires <strong>Jules Rambaut<\/strong>\u00a0et <strong>Timoth\u00e9 Vergiat<\/strong>, qui comptent tout de m\u00eame 3 points chacun. <strong>Franck Seguela <\/strong>a \u00e9t\u00e9 en d\u00e9licatesse avec son tir, 0\/6 de loin sur ce match pour lui. Il faudra se rattraper ce soir face \u00e0 la Serbie \u00e0 22h35, gros match en perspective !<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/Paris2024?src=hash&amp;ref_src=twsrc%5Etfw\">#Paris2024<\/a> | \ud83c\udfc0 La premi\u00e8re d\u00e9faite des Bleus en basket 3&#215;3 ! Domin\u00e9e et men\u00e9e tout le match, l&rsquo;\u00e9quipe de France s&rsquo;est inclin\u00e9e 20-13 face aux Pays-Bas \ud83c\uddf3\ud83c\uddf1<\/p>\n<p>\ud83d\udcfa \u00c0 suivre en direct : <a href=\"https:\/\/t.co\/OK0hkyRtsF\">https:\/\/t.co\/OK0hkyRtsF<\/a> <a href=\"https:\/\/t.co\/mgikkVJvt0\">pic.twitter.com\/mgikkVJvt0<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1818989051405353029?ref_src=twsrc%5Etfw\">August 1, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0 <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-basket-3x3-hommes-jo-2024\/\" target=\"_blank\" rel=\"noopener\">Calendrier et r\u00e9sultats du tournoi masculin de basket 3&#215;3<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>BASKET 3X3 (H) JO 2024 &#8211; Apr\u00e8s deux succ\u00e8s \u00e9triqu\u00e9s face \u00e0 la Lituanie et la Pologne, les Bleus ont perdu leur premier match face aux Pays-Bas, 20-13.<\/p>\n","protected":false},"author":21,"featured_media":506794,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[27116,8436],"tags":[16878,1506,19184,1504,12920,1004],"class_list":["post-506784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","category-jo-paris-2024","tag-breve","tag-jeux-olympiques-2024","tag-jeux-olympiques-de-paris","tag-jo-2024","tag-jo-paris-2024","tag-paris-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basket 3x3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas<\/title>\n<meta name=\"description\" content=\"BASKET 3X3 (H) JO 2024 - Apr\u00e8s deux succ\u00e8s \u00e9triqu\u00e9s face \u00e0 la Lituanie et la Pologne, les Bleus ont perdu leur premier match face aux Pays-Bas, 20-13.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basket 3x3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas\" \/>\n<meta property=\"og:description\" content=\"BASKET 3X3 (H) JO 2024 - Apr\u00e8s deux succ\u00e8s \u00e9triqu\u00e9s face \u00e0 la Lituanie et la Pologne, les Bleus ont perdu leur premier match face aux Pays-Bas, 20-13.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-01T12:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mathieu Veillon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Basket 3x3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/MathieuVeillon\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/\"},\"author\":{\"name\":\"Mathieu Veillon\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806\"},\"headline\":\"Basket 3&#215;3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas\",\"datePublished\":\"2024-08-01T12:47:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/\"},\"wordCount\":202,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png\",\"keywords\":[\"br\u00e8ve\",\"Jeux olympiques 2024\",\"Jeux Olympiques de Paris\",\"JO 2024\",\"JO Paris 2024\",\"Paris 2024\"],\"articleSection\":[\"Basket-ball 3x3\",\"JO Paris 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/\",\"name\":\"Basket 3x3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png\",\"datePublished\":\"2024-08-01T12:47:37+00:00\",\"description\":\"BASKET 3X3 (H) JO 2024 - Apr\u00e8s deux succ\u00e8s \u00e9triqu\u00e9s face \u00e0 la Lituanie et la Pologne, les Bleus ont perdu leur premier match face aux Pays-Bas, 20-13.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png\",\"width\":1200,\"height\":674,\"caption\":\"Basket 3x3 hommes JO 2024 Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Basket 3&#215;3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806\",\"name\":\"Mathieu Veillon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg\",\"caption\":\"Mathieu Veillon\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis septembre 2015 - Ma d\u00e9finition du bonheur ? Une galette-saucisse au Roazhon Park ou un caf\u00e9 devant un Lakers\/Celtics au petit matin. Fid\u00e8le membre de la team insomniaque de la r\u00e9dac, j\u2019ai le pouvoir de rester \u00e9veill\u00e9 jusqu\u2019\u00e0 l\u2019aube pour faire vivre aux lecteurs ma passion du sport. Ainsi, j\u2019\u00e9cris principalement sur la NBA, le biathlon, le cyclisme ou encore la F1. Comptez dans mes exploits sportifs le fait d\u2019avoir fait gagner le Tour de France 2018 \u00e0 Tony Gallopin sur Pro Cycling Manager, ou encore d\u2019avoir men\u00e9 l\u2019\u00e9quipe nationale de Bretagne en finale de Coupe du monde sur Football Manager.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/MathieuVeillon\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/mathieu\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Basket 3x3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas","description":"BASKET 3X3 (H) JO 2024 - Apr\u00e8s deux succ\u00e8s \u00e9triqu\u00e9s face \u00e0 la Lituanie et la Pologne, les Bleus ont perdu leur premier match face aux Pays-Bas, 20-13.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/","og_locale":"fr_FR","og_type":"article","og_title":"Basket 3x3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas","og_description":"BASKET 3X3 (H) JO 2024 - Apr\u00e8s deux succ\u00e8s \u00e9triqu\u00e9s face \u00e0 la Lituanie et la Pologne, les Bleus ont perdu leur premier match face aux Pays-Bas, 20-13.","og_url":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-08-01T12:47:37+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png","type":"image\/png"}],"author":"Mathieu Veillon","twitter_card":"summary_large_image","twitter_title":"Basket 3x3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas","twitter_creator":"@https:\/\/twitter.com\/MathieuVeillon","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/"},"author":{"name":"Mathieu Veillon","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806"},"headline":"Basket 3&#215;3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas","datePublished":"2024-08-01T12:47:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/"},"wordCount":202,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png","keywords":["br\u00e8ve","Jeux olympiques 2024","Jeux Olympiques de Paris","JO 2024","JO Paris 2024","Paris 2024"],"articleSection":["Basket-ball 3x3","JO Paris 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/","url":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/","name":"Basket 3x3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png","datePublished":"2024-08-01T12:47:37+00:00","description":"BASKET 3X3 (H) JO 2024 - Apr\u00e8s deux succ\u00e8s \u00e9triqu\u00e9s face \u00e0 la Lituanie et la Pologne, les Bleus ont perdu leur premier match face aux Pays-Bas, 20-13.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Basket-3x3-hommes-JO-2024-Premiere-defaite-pour-la-France-face-aux-Pays-Bas.png","width":1200,"height":674,"caption":"Basket 3x3 hommes JO 2024 Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-hommes-jo-2024-premiere-defaite-pour-la-france-face-aux-pays-bas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Basket 3&#215;3 hommes JO 2024 : Premi\u00e8re d\u00e9faite pour la France face aux Pays-Bas"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806","name":"Mathieu Veillon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","caption":"Mathieu Veillon"},"description":"Journaliste\/r\u00e9dacteur depuis septembre 2015 - Ma d\u00e9finition du bonheur ? Une galette-saucisse au Roazhon Park ou un caf\u00e9 devant un Lakers\/Celtics au petit matin. Fid\u00e8le membre de la team insomniaque de la r\u00e9dac, j\u2019ai le pouvoir de rester \u00e9veill\u00e9 jusqu\u2019\u00e0 l\u2019aube pour faire vivre aux lecteurs ma passion du sport. Ainsi, j\u2019\u00e9cris principalement sur la NBA, le biathlon, le cyclisme ou encore la F1. Comptez dans mes exploits sportifs le fait d\u2019avoir fait gagner le Tour de France 2018 \u00e0 Tony Gallopin sur Pro Cycling Manager, ou encore d\u2019avoir men\u00e9 l\u2019\u00e9quipe nationale de Bretagne en finale de Coupe du monde sur Football Manager.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/MathieuVeillon"],"url":"https:\/\/dicodusport.fr\/blog\/author\/mathieu\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/506784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=506784"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/506784\/revisions"}],"predecessor-version":[{"id":506795,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/506784\/revisions\/506795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/506794"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=506784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=506784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=506784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}