{"id":507334,"date":"2024-08-02T19:56:39","date_gmt":"2024-08-02T17:56:39","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=507334&#038;preview=true&#038;preview_id=507334"},"modified":"2024-08-02T19:59:33","modified_gmt":"2024-08-02T17:59:33","slug":"water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/","title":{"rendered":"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><b>WATER-POLO JO PARIS 2024 &#8211; Apr\u00e8s leur d\u00e9faite inaugurale face \u00e0 l\u2019Espagne (5-16) et leur exploit contre l\u2019Italie (9-8), l\u2019\u00e9quipe de France f\u00e9minine a \u00e9t\u00e9 domin\u00e9e par les \u00c9tats-Unis (5-17), champions du monde et triples champions olympiques en titre, pour le compte de la 3e journ\u00e9e de la phase de poules, au Centre Aquatique de Saint-Denis, vendredi. D\u00e8s le troisi\u00e8me quart-temps, l&rsquo;agressivit\u00e9 am\u00e9ricaine a eu raison des Fran\u00e7aises.\u00a0<\/b><\/i><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/water-polo-femmes-jo-2024-calendrier-horaires-et-resultats\/\">Calendrier et r\u00e9sultats Water-polo f\u00e9minin JO 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Apr\u00e8s que <strong>Camelia Bouloukbachi<\/strong> ait touch\u00e9 le poteau, <strong>Maddie Musselman<\/strong> a ouvert le score sur une attaque rapide (1-0). <strong>Kenna Flynn<\/strong> a doubl\u00e9 la marque sur un p\u00e9nalty plac\u00e9 au-dessus de la t\u00eate de la gardienne fran\u00e7aise (2-0). Mais, <strong>Audrey Daule<\/strong> a r\u00e9duit l&rsquo;\u00e9cart sur un lob parfaitement dos\u00e9. <strong>Jovana Sekulic<\/strong> a profit\u00e9 d&rsquo;une action rapide sur une sup\u00e9riorit\u00e9 num\u00e9rique pour redonner deux buts d&rsquo;avance aux Am\u00e9ricaines (3-1). La porti\u00e8re fran\u00e7aise <strong>Mia Rycraw<\/strong> a r\u00e9ussi de belles parades pour \u00e9viter un score plus lourd.<\/p>\n<p style=\"text-align: justify;\">Puis, apr\u00e8s un changement d&rsquo;aile rapide, la jeune <strong>Jewel Roemer<\/strong> a marqu\u00e9 le quatri\u00e8me but pour les \u00c9tats-Unis. N\u00e9anmoins, rapidement derri\u00e8re, <strong>Orsolya Hertzka<\/strong> a r\u00e9duit la marque pour les Fran\u00e7aises (2-4). <strong>Maddie Musselman<\/strong> a r\u00e9ussi \u00e0 s&rsquo;imposer au c\u0153ur de la d\u00e9fense tricolore pour le but du 5-2. Tara Pratice a accentu\u00e9 l&rsquo;avance des Am\u00e9ricaines sur une sup\u00e9riorit\u00e9 num\u00e9rique au milieu du deuxi\u00e8me quart-temps, tandis que <strong>Rachel Fattal<\/strong> a marqu\u00e9 le but du 2-7 \u00e0 moins de deux minutes de la fin du deuxi\u00e8me quart-temps d&rsquo;un tir puissant. La gauch\u00e8re <strong>Juliette Dhalluin<\/strong> a marqu\u00e9 son septi\u00e8me but du tournoi (3-8).<\/p>\n<h2 style=\"text-align: justify;\">Les Bleues coulent<\/h2>\n<p style=\"text-align: justify;\">En difficult\u00e9 en attaque en ne pouvant pas servir les pointes basses, <strong>Orsolya Hertzka<\/strong> a r\u00e9ussi \u00e0 trouver l&rsquo;ouverture sur un tir lointain (4-7). <strong>Maddie Musselman<\/strong> a redonn\u00e9 de l&rsquo;air aux \u00c9tats-Unis sur un tir d\u00e9vi\u00e9 avant que <strong>Rachel Fattal<\/strong> ne marque \u00e0 bout portant (9-4). Par la suite, les Am\u00e9ricaines ont d\u00e9roul\u00e9 avec des r\u00e9alisations de<strong> Kenna Flynn<\/strong>, de<strong> Jordan Raney<\/strong> sur sup\u00e9riorit\u00e9 num\u00e9rique et de <strong>Ryann Neushul<\/strong> sur p\u00e9nalty (4-12). <strong>Tiziana Raspo<\/strong>, 18 ans, a marqu\u00e9 le cinqui\u00e8me but avec l&rsquo;aide du poteau (5-12). Mais, <strong>Ryann Neushul<\/strong> a parfaitement conclu une action collective \u00e0 25 secondes de la fin du troisi\u00e8me quart-temps (5-13).<\/p>\n<p style=\"text-align: justify;\">Puis, apr\u00e8s un but de la pointe basse <strong>Maggie Steffens,<\/strong> <strong>Maddie Musselman<\/strong> a marqu\u00e9 son quatri\u00e8me but du match en 5 tirs tent\u00e9s au d\u00e9but du quatri\u00e8me quart-temps (15-5). L&rsquo;\u00e9quipe de France a alors d\u00e9cid\u00e9 de changer de gardienne avec l&rsquo;entr\u00e9e de la jeune <strong>Pasipha\u00e9 Martineaud-Peret<\/strong>. Cependant, cela n&rsquo;a rien chang\u00e9 \u00e0 la situation puisque <strong>Kaleigh Gilchrist<\/strong> et<strong> Jenna Flynn<\/strong> ont encore plus aggrav\u00e9 le score (17-5). Apr\u00e8s un dernier temps-mort de la France,<\/p>\n<p style=\"text-align: justify;\">Enfin, la qualification pour les quarts se jouera face \u00e0 la Gr\u00e8ce, dimanche, \u00e0 20h.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/jo-paris-2024\/\" target=\"_blank\" rel=\"noopener\">L\u2019actualit\u00e9 des JO de Paris 2024<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis<\/p>\n","protected":false},"author":48,"featured_media":507449,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[8436,9558],"tags":[32415,16878,1504,20773,12920,883],"class_list":["post-507334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-paris-2024","category-water-polo","tag-actu","tag-breve","tag-jo-2024","tag-jo-de-paris","tag-jo-paris-2024","tag-water-polo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis<\/title>\n<meta name=\"description\" content=\"Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\" \/>\n<meta property=\"og:description\" content=\"Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T17:56:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T17:59:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\",\"datePublished\":\"2024-08-02T17:56:39+00:00\",\"dateModified\":\"2024-08-02T17:59:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/\"},\"wordCount\":536,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"JO 2024\",\"JO de Paris\",\"JO Paris 2024\",\"water polo\"],\"articleSection\":[\"JO Paris 2024\",\"Water-polo\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/\",\"name\":\"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png\",\"datePublished\":\"2024-08-02T17:56:39+00:00\",\"dateModified\":\"2024-08-02T17:59:33+00:00\",\"description\":\"Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png\",\"width\":1200,\"height\":674,\"caption\":\"Water-polo JO 2024 Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis","description":"Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/","og_locale":"fr_FR","og_type":"article","og_title":"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis","og_description":"Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis","og_url":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2024-08-02T17:56:39+00:00","article_modified_time":"2024-08-02T17:59:33+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis","datePublished":"2024-08-02T17:56:39+00:00","dateModified":"2024-08-02T17:59:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/"},"wordCount":536,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png","keywords":["actu","br\u00e8ve","JO 2024","JO de Paris","JO Paris 2024","water polo"],"articleSection":["JO Paris 2024","Water-polo"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/","url":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/","name":"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png","datePublished":"2024-08-02T17:56:39+00:00","dateModified":"2024-08-02T17:59:33+00:00","description":"Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Water-polo-JO-2024-Lourde-defaite-des-Bleues-contre-les-Etats-Unis.png","width":1200,"height":674,"caption":"Water-polo JO 2024 Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/water-polo-jo-2024-lourde-defaite-des-bleues-contre-les-etats-unis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Water-polo JO 2024 : Lourde d\u00e9faite des Bleues contre les \u00c9tats-Unis"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/507334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=507334"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/507334\/revisions"}],"predecessor-version":[{"id":507456,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/507334\/revisions\/507456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/507449"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=507334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=507334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=507334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}