{"id":511198,"date":"2024-08-10T13:40:33","date_gmt":"2024-08-10T11:40:33","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=511198&#038;preview=true&#038;preview_id=511198"},"modified":"2024-08-10T14:22:16","modified_gmt":"2024-08-10T12:22:16","slug":"transferts-om-marseille-signe-gero-rulli","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/","title":{"rendered":"Transferts OM : Marseille signe Geronimo Rulli"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE 1 2024-2025 &#8211; Selon Fabrizio Romano, l&rsquo;Olympique de Marseille va signer le gardien argentin Geronimo Rulli.\u00a0<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/mercato-om-tableau-des-transferts-2024-2025\/\">Mercato OM : Tableau des transferts 2024-2025<\/a>\u00a0<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Comme attendu apr\u00e8s une saison rat\u00e9e, l&rsquo;<strong>Olympique de Marseille<\/strong> va modifier son effectif en profondeur pour tenter d&rsquo;inverser la tendance. <strong>Roberto De Zerbi<\/strong> travaille depuis plusieurs semaines avec <strong>Pablo<\/strong> <strong>Longoria<\/strong> et <strong>Mehdi Benatia<\/strong> pour construire un groupe capable de se qualifier en Ligue des Champions la saison prochaine.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-veut-signer-jonathan-rowe\/\" target=\"_blank\" rel=\"noopener\">Transferts OM : Marseille veut signer Jonathan Rowe<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Marseille signe Geronimo Rulli<\/h2>\n<p style=\"text-align: justify;\">Si le secteur offensif est un des chantiers majeurs, l&rsquo;<strong>OM<\/strong> est aussi en qu\u00eate d&rsquo;un nouveau gardien de but, puisque <strong>Pau Lopez<\/strong> n&rsquo;est plus dans les plans du nouveau coach olympien. De nombreuses pistes ont \u00e9t\u00e9 \u00e9tudi\u00e9es par les dirigeants marseillais et c&rsquo;est finalement <strong>Geronimo Rulli<\/strong> qui aura la lourde t\u00e2che de garder les buts phoc\u00e9ens cette saison.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;Argentin de 32 ans a beaucoup voyag\u00e9 pendant sa carri\u00e8re avant d&rsquo;atterrir \u00e0 l&rsquo;<strong>Ajax<\/strong> en 2023. International argentin \u00e0 quatre reprises, il a aussi fait le bonheur de la Real Sociedad et de <strong>Villarreal<\/strong> en Espagne. <strong>Geronimo<\/strong> <strong>Rulli<\/strong> conna\u00eet bien le championnat de France puisqu&rsquo;il avait \u00e9t\u00e9 pr\u00eat\u00e9 \u00e0 <strong>Montpellier<\/strong> lors de la saison 2019-2020. L&rsquo;<strong>Olympique de Marseille<\/strong> a trouv\u00e9 un accord avec le club n\u00e9erlandais et son officialisation est imminente.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83d\udd35\u26aa\ufe0f\u270d\ud83c\udffb All signed and sealed for Geronimo Rulli to become new Olympique Marseille player.<\/p>\n<p>OM just waiting for documents to be sent back from Ajax and then deal will be officially confirmed. <a href=\"https:\/\/t.co\/U93HvtP9fa\">pic.twitter.com\/U93HvtP9fa<\/a><\/p>\n<p>\u2014 Fabrizio Romano (@FabrizioRomano) <a href=\"https:\/\/twitter.com\/FabrizioRomano\/status\/1822194444457623601?ref_src=twsrc%5Etfw\">August 10, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2024-2025 &#8211; Selon Fabrizio Romano, l&rsquo;Olympique de Marseille va signer le gardien argentin Gero Rulli.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":511207,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301,47045],"tags":[16878,75,446,17054,1889],"class_list":["post-511198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-breve","tag-football","tag-marseille","tag-mercato-om","tag-om"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts OM : Marseille signe Geronimo Rulli<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2024-2025 - Selon Fabrizio Romano, l&#039;Olympique de Marseille va signer le gardien argentin Gero Rulli.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts OM : Marseille signe Geronimo Rulli\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2024-2025 - Selon Fabrizio Romano, l&#039;Olympique de Marseille va signer le gardien argentin Gero Rulli.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-10T11:40:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-10T12:22:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts OM : Marseille signe Geronimo Rulli\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts OM : Marseille signe Geronimo Rulli\",\"datePublished\":\"2024-08-10T11:40:33+00:00\",\"dateModified\":\"2024-08-10T12:22:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/\"},\"wordCount\":280,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Marseille\",\"Mercato OM\",\"OM\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/\",\"name\":\"Transferts OM : Marseille signe Geronimo Rulli\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png\",\"datePublished\":\"2024-08-10T11:40:33+00:00\",\"dateModified\":\"2024-08-10T12:22:16+00:00\",\"description\":\"LIGUE 1 2024-2025 - Selon Fabrizio Romano, l'Olympique de Marseille va signer le gardien argentin Gero Rulli.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts OM : Marseille signe Geronimo Rulli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts OM : Marseille signe Geronimo Rulli","description":"LIGUE 1 2024-2025 - Selon Fabrizio Romano, l'Olympique de Marseille va signer le gardien argentin Gero Rulli.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts OM : Marseille signe Geronimo Rulli","og_description":"LIGUE 1 2024-2025 - Selon Fabrizio Romano, l'Olympique de Marseille va signer le gardien argentin Gero Rulli.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-08-10T11:40:33+00:00","article_modified_time":"2024-08-10T12:22:16+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts OM : Marseille signe Geronimo Rulli","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts OM : Marseille signe Geronimo Rulli","datePublished":"2024-08-10T11:40:33+00:00","dateModified":"2024-08-10T12:22:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/"},"wordCount":280,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png","keywords":["br\u00e8ve","Football","Marseille","Mercato OM","OM"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/","name":"Transferts OM : Marseille signe Geronimo Rulli","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png","datePublished":"2024-08-10T11:40:33+00:00","dateModified":"2024-08-10T12:22:16+00:00","description":"LIGUE 1 2024-2025 - Selon Fabrizio Romano, l'Olympique de Marseille va signer le gardien argentin Gero Rulli.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Transferts-OM-Marseille-signe-Gero-Rulli.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-signe-gero-rulli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts OM : Marseille signe Geronimo Rulli"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/511198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=511198"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/511198\/revisions"}],"predecessor-version":[{"id":511235,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/511198\/revisions\/511235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/511207"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=511198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=511198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=511198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}