{"id":511248,"date":"2024-08-10T16:39:08","date_gmt":"2024-08-10T14:39:08","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=511248&#038;preview=true&#038;preview_id=511248"},"modified":"2024-08-11T20:34:02","modified_gmt":"2024-08-11T18:34:02","slug":"handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/","title":{"rendered":"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>HANDBALL JO 2024 &#8211; La France n&rsquo;a pas fait le poids. La Norv\u00e8ge a survol\u00e9 cette finale olympique de handball du d\u00e9but \u00e0 la fin. Une prestation parfaite des Scandinaves, les Bleues doivent se contenter de la m\u00e9daille d&rsquo;argent, comme \u00e0 Rio.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/jo-paris-2024\/\" target=\"_blank\" rel=\"noopener\">L\u2019actualit\u00e9 des JO de Paris 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">France &#8211; Norv\u00e8ge. Un classique ind\u00e9modable du handball mondial depuis maintenant 15 ans. Pour la premi\u00e8re fois, ces deux nations s&rsquo;affrontent en finale des Jeux Olympiques. 9 mois apr\u00e8s le sacre mondial des Bleues face \u00e0 cette m\u00eame \u00e9quipe (31-28), les retrouvailles s&rsquo;annoncent grandioses. <\/span><b>Nora Mork<\/b><span style=\"font-weight: 400;\">, <\/span><b>Stine<\/b> <b>Oftedal <\/b><span style=\"font-weight: 400;\">et compagnie sont plong\u00e9es dans l&rsquo;enfer de Pierre-Mauroy et ses 27 000 fans chauff\u00e9s \u00e0 blanc. Mais la pression populaire n&rsquo;a pas pes\u00e9 un instant sur les \u00e9paules des joueuses v\u00eatues de noir. Un r\u00e9cital de bout en bout. <\/span><b>Oftedal<\/b><span style=\"font-weight: 400;\"> conclut sa carri\u00e8re en grande reine, remportant le dernier titre qui lui manquait lors de son dernier match (29-21).<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">M\u00c9DAILL\u00c9ES D&rsquo;ARGENT ! \ud83e\udd48<br \/>\nNos BLEUES s&rsquo;inclinent en finale face aux Norv\u00e9giennes \ud83c\uddf3\ud83c\uddf429-21\ud83c\uddeb\ud83c\uddf7<br \/>\nC&rsquo;est la fin d&rsquo;une magnifique aventure entre Paris et Lille qui se termine avec une belle m\u00e9daille d&rsquo;argent, la troisi\u00e8me m\u00e9daille olympique de suite pour l&rsquo;\u00e9quipe de France f\u00e9minine ! \ud83e\udd48\ud83d\udc4f\u2026 <a href=\"https:\/\/t.co\/Wv8BuzknLj\">pic.twitter.com\/Wv8BuzknLj<\/a><\/p>\n<p>\u2014 Equipes de France de Handball (@FRAHandball) <a href=\"https:\/\/twitter.com\/FRAHandball\/status\/1822279083348140376?ref_src=twsrc%5Etfw\">August 10, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Reistad et Oftedal portent leur pays<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Comme attendu, le rythme est soutenu sur ce d\u00e9but de finale. La d\u00e9fense fran\u00e7aise est bien en place et les Norv\u00e9giennes doivent travailler pour trouver les br\u00e8ches. Elles y arrivent par moments, apr\u00e8s de longues s\u00e9quences. Le score \u00e0 la fin du premier quart d&rsquo;heure est de 6-5 pour l&rsquo;\u00e9quipe de France. <\/span><b>Pauletta Foppa <\/b><span style=\"font-weight: 400;\">\u00e9tait moins \u00e0 son avantage en demi-finale mais c&rsquo;est l&rsquo;exact oppos\u00e9 ce samedi. Ses co\u00e9quipi\u00e8res ne se g\u00eanent pas pour la servir \u00e0 outrance. Les bonnes prises de position de la Brestoise permettent des buts presque gratuits.<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Olivier Krumbholz<\/b><span style=\"font-weight: 400;\">, m\u00eame pour son dernier match en tant que s\u00e9lectionneur, continue ses rotations. <\/span><b>M\u00e9line Nocandy, Lena Grandveau <\/b><span style=\"font-weight: 400;\">et <\/span><b>Orlane Kanor<\/b><span style=\"font-weight: 400;\"> apportent leur punch et la France trouve un nouveau souffle. Les aili\u00e8res sont aussi pr\u00e9sentes \u00e0 la finition. Mais les Scandinaves r\u00e9sistent. <\/span><b>Henny Reistad <\/b><span style=\"font-weight: 400;\">et <\/span><b>Stine Oftedal<\/b><span style=\"font-weight: 400;\">, qui dispute la derni\u00e8re rencontre d&rsquo;une carri\u00e8re immens\u00e9ment riche, tiennent la barre du bateau Norv\u00e8ge. Gr\u00e2ce \u00e0 ses deux stars, le tableau d&rsquo;affichage montre 15-13 en faveur des championnes d&rsquo;Europe en titre. Un meilleur finish les font passer devant.<\/span><\/p>\n<h2 style=\"text-align: justify;\">La Norv\u00e8ge s&rsquo;offre un r\u00e9cital<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La reprise du match se fait dans la difficult\u00e9 pour les Bleues. Pas de but dans les 10 premi\u00e8res minutes, pendant que la Norv\u00e8ge en ajoute deux pour obtenir le plus grand \u00e9cart de la partie. Celui-ci va m\u00eame monter jusqu&rsquo;\u00e0 6. Les Fran\u00e7aises se retrouvent dans les m\u00eames difficult\u00e9s que face \u00e0 la Su\u00e8de. Peu d&rsquo;efficacit\u00e9 au tir, plus de mal \u00e0 bloquer les tireuses adverses, le score s&rsquo;\u00e9largit. <\/span><b>Krumbholz <\/b><span style=\"font-weight: 400;\">veut mettre en place de la nouveaut\u00e9 avec une d\u00e9fense \u00e9tag\u00e9e en 2-4 et plus de dynamisme. La base arri\u00e8re norv\u00e9gienne continue pourtant son travail de sape en \u00e9claboussant de son talent le match.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La Norv\u00e8ge \u00e9tait simplement trop forte. \u00c0 44 ans, <\/span><b>Katrine Lunde <\/b><span style=\"font-weight: 400;\">a r\u00e9ussi une immense rencontre dans la cage et empoche un 3e titre olympique. Leur r\u00e9ussite est totale, quand les championnes olympiques de Tokyo ont manqu\u00e9 de jus lors de cette finale. Apr\u00e8s un tournoi parfait avec 7 victoires sur 7 possibles, l&rsquo;\u00e9quipe de France tombe en finale, avec les honneurs. La fin d&rsquo;une \u00e8re, le d\u00e9but d&rsquo;une nouvelle, avec le retrait d<\/span><b>&lsquo;Olivier Krumbholz<\/b><span style=\"font-weight: 400;\">, l&rsquo;homme qui a plac\u00e9 le handball f\u00e9minin tricolore sur le toit du monde. Cette m\u00e9daille d&rsquo;argent sera sa 15e \u00e0 la t\u00eate du groupe France. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge<\/p>\n","protected":false},"author":61,"featured_media":511371,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2304,8436],"tags":[16878,30,405,1506,19184,1504,12920,1345,1004,24],"class_list":["post-511248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handball","category-jo-paris-2024","tag-breve","tag-france","tag-handball","tag-jeux-olympiques-2024","tag-jeux-olympiques-de-paris","tag-jo-2024","tag-jo-paris-2024","tag-norvege","tag-paris-2024","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge<\/title>\n<meta name=\"description\" content=\"La France n&#039;a pas fait le poids. La Norv\u00e8ge a survol\u00e9 cette finale olympique de handball du d\u00e9but \u00e0 la fin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge\" \/>\n<meta property=\"og:description\" content=\"La France n&#039;a pas fait le poids. La Norv\u00e8ge a survol\u00e9 cette finale olympique de handball du d\u00e9but \u00e0 la fin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-10T14:39:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-11T18:34:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Gorce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/pierregorce12\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/\"},\"author\":{\"name\":\"Pierre Gorce\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\"},\"headline\":\"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge\",\"datePublished\":\"2024-08-10T14:39:08+00:00\",\"dateModified\":\"2024-08-11T18:34:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/\"},\"wordCount\":685,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png\",\"keywords\":[\"br\u00e8ve\",\"France\",\"Handball\",\"Jeux olympiques 2024\",\"Jeux Olympiques de Paris\",\"JO 2024\",\"JO Paris 2024\",\"Norv\u00e8ge\",\"Paris 2024\",\"sport\"],\"articleSection\":[\"Handball\",\"JO Paris 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/\",\"name\":\"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png\",\"datePublished\":\"2024-08-10T14:39:08+00:00\",\"dateModified\":\"2024-08-11T18:34:02+00:00\",\"description\":\"La France n'a pas fait le poids. La Norv\u00e8ge a survol\u00e9 cette finale olympique de handball du d\u00e9but \u00e0 la fin.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Handball JO 2024 Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge (1)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\",\"name\":\"Pierre Gorce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"caption\":\"Pierre Gorce\"},\"description\":\"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12\"],\"birthDate\":\"1999-08-29\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge","description":"La France n'a pas fait le poids. La Norv\u00e8ge a survol\u00e9 cette finale olympique de handball du d\u00e9but \u00e0 la fin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/","og_locale":"fr_FR","og_type":"article","og_title":"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge","og_description":"La France n'a pas fait le poids. La Norv\u00e8ge a survol\u00e9 cette finale olympique de handball du d\u00e9but \u00e0 la fin.","og_url":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-08-10T14:39:08+00:00","article_modified_time":"2024-08-11T18:34:02+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png","type":"image\/png"}],"author":"Pierre Gorce","twitter_card":"summary_large_image","twitter_title":"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge","twitter_creator":"@https:\/\/twitter.com\/pierregorce12","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/"},"author":{"name":"Pierre Gorce","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018"},"headline":"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge","datePublished":"2024-08-10T14:39:08+00:00","dateModified":"2024-08-11T18:34:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/"},"wordCount":685,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png","keywords":["br\u00e8ve","France","Handball","Jeux olympiques 2024","Jeux Olympiques de Paris","JO 2024","JO Paris 2024","Norv\u00e8ge","Paris 2024","sport"],"articleSection":["Handball","JO Paris 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/","url":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/","name":"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png","datePublished":"2024-08-10T14:39:08+00:00","dateModified":"2024-08-11T18:34:02+00:00","description":"La France n'a pas fait le poids. La Norv\u00e8ge a survol\u00e9 cette finale olympique de handball du d\u00e9but \u00e0 la fin.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Handball-JO-2024-Les-Bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-Norvege-1.png","width":1200,"height":674,"caption":"Handball JO 2024 Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge (1)"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/handball-jo-2024-les-bleues-vice-championnes-olympiques-apres-leur-defaite-face-a-la-norvege\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Handball JO 2024 : Les Bleues vice-championnes olympiques apr\u00e8s leur d\u00e9faite face \u00e0 la Norv\u00e8ge"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018","name":"Pierre Gorce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","caption":"Pierre Gorce"},"description":"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12"],"birthDate":"1999-08-29","url":"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/511248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=511248"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/511248\/revisions"}],"predecessor-version":[{"id":511952,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/511248\/revisions\/511952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/511371"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=511248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=511248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=511248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}