{"id":512027,"date":"2024-08-17T07:01:03","date_gmt":"2024-08-17T05:01:03","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=512027&#038;preview=true&#038;preview_id=512027"},"modified":"2024-08-17T07:01:22","modified_gmt":"2024-08-17T05:01:22","slug":"tour-despagne-2024-parcours-et-profil-de-la-1ere-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/","title":{"rendered":"Tour d&rsquo;Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2024\/tour-espagne-2024\/\">TOUR D&rsquo;ESPAGNE 2024<\/a> &#8211; La 79e \u00e9dition de la Vuelta a Espa\u00f1a d\u00e9butera le samedi 17 ao\u00fbt dans la capitale portugaise, Lisbonne. Ce n&rsquo;est que la cinqui\u00e8me fois que la Vuelta s&rsquo;\u00e9lancera hors d&rsquo;Espagne, apr\u00e8s d\u00e9\u00e0 Lisbonne (1997), Assen (2009), N\u00eemes (2017) et Utrecht (2022). La premi\u00e8re \u00e9tape sera un contre-la-montre de 12 kilom\u00e8tres tout plat et peu technique.\u00a0<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-engages-et-favoris-de-la-vuelta\/\">Tour d&rsquo;Espagne 2024 : Engag\u00e9s et Favoris de la Vuelta<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Parcours et profil de la 1\u00e8re \u00e9tape Tour d&rsquo;Espagne 2024<\/h2>\n<p style=\"text-align: justify;\">Pas de balade dans le centre historique de la Capitale portugaise, les coureurs longeront la rive nord du Tage, le plus long fleuve de la p\u00e9ninsule Ib\u00e9rique en passant devant des Monuments historiques. Le d\u00e9part sera donn\u00e9 \u00e0 <strong>Lisbonne<\/strong> pour prendre la direction de l&rsquo;est jusqu&rsquo;\u00e0 <strong>Oeiras<\/strong>, \u00e0 l&#8217;embouchure du fleuve. La rampe de d\u00e9part se situera sur la <em>Pra\u00e7a<\/em>\u00a0<em>do<\/em>\u00a0<em>Imp\u00e9rio,\u00a0<\/em>une grande place avec un espace vert monumental \u00e0 la forme carr\u00e9e classique avec des fontaines circulaires ainsi que des statues. Le premier coureur partira \u00e0 16h23 tandis que le dernier s&rsquo;\u00e9lancera \u00e0 19h18.<\/p>\n<p style=\"text-align: justify;\">Quelques m\u00e8tres apr\u00e8s, les coureurs vireront \u00e0 droite pour une longue portion rectiligne sur la N6, le long du Tage. Dans un premier temps, ils passeront devant des Monuments dans la premi\u00e8re moiti\u00e9 du chrono, \u00e0 c\u00f4t\u00e9 de la Tour de Belem, de l&rsquo;Aquarium Vasco de Gama (aquarium et mus\u00e9e oc\u00e9anographique de la fin du XIXe si\u00e8cle, consacr\u00e9s \u00e0 la vie marine des eaux portugaises) et le Palais de Caxias (ancien lieu de r\u00e9sidence d\u2019\u00e9t\u00e9 des souverains lusitaniens). Puis, dans la seconde moiti\u00e9, les coureurs passeront pr\u00e8s de plages comme la Praia Velha, de Pa\u00e7o de Arcos et de Santo Amaro.<\/p>\n<p style=\"text-align: justify;\">Enfin, apr\u00e8s \u00eatre pass\u00e9 \u00e0 proximit\u00e9 de la Piscina Oce\u00e2nica de Oeiras, l&rsquo;arriv\u00e9e sera jug\u00e9e pr\u00e8s de la Praia da Torre avec une belle vue sur le Fort de S\u00e3o Juli\u00e3o da Barra, une des plus grandes fortifications maritimes du Portugal.<\/p>\n<div id=\"attachment_512832\" style=\"width: 970px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-1ere-etape-Tour-dEspagne-2024.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-512832\" class=\"size-full wp-image-512832\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-1ere-etape-Tour-dEspagne-2024.jpg\" alt=\"Profil 1\u00e8re \u00e9tape Tour d'Espagne 2024\" width=\"960\" height=\"338\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-1ere-etape-Tour-dEspagne-2024.jpg 960w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-1ere-etape-Tour-dEspagne-2024-300x106.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-1ere-etape-Tour-dEspagne-2024-768x270.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><p id=\"caption-attachment-512832\" class=\"wp-caption-text\">Profil 1\u00e8re \u00e9tape Tour d&rsquo;Espagne 2024<\/p><\/div>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2024\/\">L\u2019actualit\u00e9 du cyclisme sur route<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Parcours et profil de la 1\u00e8re \u00e9tape du Tour d&rsquo;Espagne 2024<\/p>\n","protected":false},"author":48,"featured_media":512831,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47042],"tags":[16878,2875],"class_list":["post-512027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-espagne","tag-breve","tag-cyclisme-feminin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour d&#039;Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape<\/title>\n<meta name=\"description\" content=\"TOUR D&#039;ESPAGNE 2024 - Parcours et profil de la 1\u00e8re \u00e9tape du Tour d&#039;Espagne 2024, qui se d\u00e9roule ce samedi 17 ao\u00fbt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour d&#039;Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"TOUR D&#039;ESPAGNE 2024 - Parcours et profil de la 1\u00e8re \u00e9tape du Tour d&#039;Espagne 2024, qui se d\u00e9roule ce samedi 17 ao\u00fbt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-17T05:01:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-17T05:01:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour d&#039;Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Tour d&rsquo;Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\",\"datePublished\":\"2024-08-17T05:01:03+00:00\",\"dateModified\":\"2024-08-17T05:01:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png\",\"keywords\":[\"br\u00e8ve\",\"cyclisme f\u00e9minin\"],\"articleSection\":[\"Tour d'Espagne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/\",\"name\":\"Tour d'Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png\",\"datePublished\":\"2024-08-17T05:01:03+00:00\",\"dateModified\":\"2024-08-17T05:01:22+00:00\",\"description\":\"TOUR D'ESPAGNE 2024 - Parcours et profil de la 1\u00e8re \u00e9tape du Tour d'Espagne 2024, qui se d\u00e9roule ce samedi 17 ao\u00fbt.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png\",\"width\":1200,\"height\":674,\"caption\":\"Tour d'Espagne 2024 Parcours et profil de la 1\u00e8re \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour d&#8217;Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour d'Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","description":"TOUR D'ESPAGNE 2024 - Parcours et profil de la 1\u00e8re \u00e9tape du Tour d'Espagne 2024, qui se d\u00e9roule ce samedi 17 ao\u00fbt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour d'Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","og_description":"TOUR D'ESPAGNE 2024 - Parcours et profil de la 1\u00e8re \u00e9tape du Tour d'Espagne 2024, qui se d\u00e9roule ce samedi 17 ao\u00fbt.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2024-08-17T05:01:03+00:00","article_modified_time":"2024-08-17T05:01:22+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"Tour d'Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Tour d&rsquo;Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","datePublished":"2024-08-17T05:01:03+00:00","dateModified":"2024-08-17T05:01:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png","keywords":["br\u00e8ve","cyclisme f\u00e9minin"],"articleSection":["Tour d'Espagne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/","name":"Tour d'Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png","datePublished":"2024-08-17T05:01:03+00:00","dateModified":"2024-08-17T05:01:22+00:00","description":"TOUR D'ESPAGNE 2024 - Parcours et profil de la 1\u00e8re \u00e9tape du Tour d'Espagne 2024, qui se d\u00e9roule ce samedi 17 ao\u00fbt.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-1ere-etape.png","width":1200,"height":674,"caption":"Tour d'Espagne 2024 Parcours et profil de la 1\u00e8re \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-1ere-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour d&#8217;Espagne 2024 : Parcours et profil de la 1\u00e8re \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/512027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=512027"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/512027\/revisions"}],"predecessor-version":[{"id":512833,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/512027\/revisions\/512833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/512831"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=512027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=512027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=512027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}