{"id":512032,"date":"2024-08-18T12:10:15","date_gmt":"2024-08-18T10:10:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=512032&#038;preview=true&#038;preview_id=512032"},"modified":"2024-08-18T12:10:47","modified_gmt":"2024-08-18T10:10:47","slug":"tour-despagne-2024-parcours-et-profil-de-la-2eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/","title":{"rendered":"Tour d&rsquo;Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOUR D&rsquo;ESPAGNE 2024 &#8211; La deuxi\u00e8me \u00e9tape de la Vuelta reliera<\/em><\/strong><em>\u00a0<strong>Cascais \u00e0 Ourem pour 191 km et une arriv\u00e9e pour les sprinteurs malgr\u00e9 plus de 2500 m\u00e8tres de d\u00e9nivel\u00e9. Parcours et profil.<\/strong><\/em><\/p>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-classement-general-de-la-vuelta\/\">Tour d\u2019Espagne 2024 : Classement g\u00e9n\u00e9ral de la Vuelta<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Parcours et profil de la 2\u00e8me \u00e9tape Tour d\u2019Espagne 2024<\/h2>\n<p style=\"text-align: justify;\">D&rsquo;abord, les coureurs partiront de <strong>Cascais<\/strong> \u00e0 11h50, une ville et station baln\u00e9aire du Portugal, situ\u00e9e sur le front de l\u2019Oc\u00e9an Atlantique, \u00e0 30 kilom\u00e8tres \u00e0 l\u2019ouest de la capitale Lisbonne, \u00e0 c\u00f4t\u00e9 de la ville d&rsquo;Estoril. Ils iront ensuite vers le nord avec quelques reliefs tout au long de la journ\u00e9e, mais rien d&rsquo;insurmontable pour les sprinteurs.<\/p>\n<p style=\"text-align: justify;\">D\u00e8s les premiers kilom\u00e8tres, ils p\u00e9n\u00e9treront dans le massif de Sintra pour gravir l&rsquo;<strong>Alto do Lagoa Azul <\/strong>(5,3 km \u00e0 4,8 %, avec des rampes \u00e0 plus de 7 % dans sa seconde moiti\u00e9), apr\u00e8s 9 kilom\u00e8tres de course. Puis, la route deviendra de plus en plus plate pendant 110 kilom\u00e8tres, sur des routes rectilignes, en passant par les localit\u00e9s de <strong>Sintra<\/strong>, de <strong>Mafra<\/strong>, de <strong>Gadril<\/strong>, de\u00a0<strong>Torres Vedras,<\/strong> de <strong>Bombarra<\/strong> et de <strong>Obidos<\/strong>.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-ce-quil-faut-retenir-du-parcours\/\" class=\"vlp-link\" title=\"Tour d&#039;Espagne 2024 : Ce qu&#039;il faut retenir du parcours\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Tour-dEspagne-2024-Ce-quil-faut-retenir-du-parcours.png\" class=\"attachment-800x445 size-800x445\" alt=\"Tour d&#039;Espagne 2024 Ce qu&#039;il faut retenir du parcours\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Tour-dEspagne-2024-Ce-quil-faut-retenir-du-parcours.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Tour-dEspagne-2024-Ce-quil-faut-retenir-du-parcours-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Tour-dEspagne-2024-Ce-quil-faut-retenir-du-parcours-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Tour-dEspagne-2024-Ce-quil-faut-retenir-du-parcours-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Tour d'Espagne 2024 : Ce qu'il faut retenir du parcours<\/div><div class=\"vlp-block-1 vlp-link-summary\">TOUR D'ESPAGNE 2024 - Le parcours de l'\u00e9dition 2024 a \u00e9t\u00e9 d\u00e9voil\u00e9. Avec une seconde partie d'\u00e9preuve tr\u00e8s \u00e9prouvante.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h3 style=\"text-align: justify;\">Final accident\u00e9, les sprinteurs dans le coup ?<\/h3>\n<p style=\"text-align: justify;\">Ensuite, la route redeviendra plus accident\u00e9e pendant une cinquantaine de kilom\u00e8tres. Apr\u00e8s avoir franchi la ville d&rsquo;<strong>Alcoba\u00e7a<\/strong> pour le sprint interm\u00e9diaire, les concurrents graviront l&rsquo;<strong>Alto da Batalha<\/strong> (6,9 km \u00e0 3,3 % avec un pied difficile avec 2 premiers kilom\u00e8tres autour de 7 %), qui se trouvera \u00e0 dix-neuf kilom\u00e8tres de l&rsquo;arriv\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Enfin, les derniers kilom\u00e8tres seront descendants et plats sur des routes avec peu de virages jusqu&rsquo;\u00e0 la ville d&rsquo;arriv\u00e9e d&rsquo;<b>Our\u00e9m, <\/b>une ville connue pour son ch\u00e2teau. Le dernier kilom\u00e8tre sera en l\u00e9ger faux plat montant sur la <em>Rua Doutor Armando<\/em>\u00a0Henriques\u00a0<em>Reis Vieira<\/em> pour une arriv\u00e9e vers 16h15.<\/p>\n<div id=\"attachment_513016\" style=\"width: 970px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-2eme-etape-Tour-dEspagne-2024.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-513016\" class=\"size-full wp-image-513016\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-2eme-etape-Tour-dEspagne-2024.jpg\" alt=\"Profil 2\u00e8me \u00e9tape Tour d'Espagne 2024\" width=\"960\" height=\"323\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-2eme-etape-Tour-dEspagne-2024.jpg 960w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-2eme-etape-Tour-dEspagne-2024-300x101.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-2eme-etape-Tour-dEspagne-2024-768x258.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><p id=\"caption-attachment-513016\" class=\"wp-caption-text\">Profil 2\u00e8me \u00e9tape Tour d&rsquo;Espagne 2024<\/p><\/div>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2024\/\">L\u2019actualit\u00e9 du cyclisme sur route<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Parcours et profil de la 2\u00e8me \u00e9tape Tour d\u2019Espagne 2024<\/p>\n","protected":false},"author":48,"featured_media":513018,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47042],"tags":[16878,2875],"class_list":["post-512032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-espagne","tag-breve","tag-cyclisme-feminin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour d&#039;Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"Parcours et profil de la 2\u00e8me \u00e9tape Tour d\u2019Espagne 2024, qui se d\u00e9roule ce dimanche 18 ao\u00fbt 2024 entre Cascais et Ourem.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour d&#039;Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"Parcours et profil de la 2\u00e8me \u00e9tape Tour d\u2019Espagne 2024, qui se d\u00e9roule ce dimanche 18 ao\u00fbt 2024 entre Cascais et Ourem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-18T10:10:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-18T10:10:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape-1024x575.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour d&#039;Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Tour d&rsquo;Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape\",\"datePublished\":\"2024-08-18T10:10:15+00:00\",\"dateModified\":\"2024-08-18T10:10:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/\"},\"wordCount\":411,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape.png\",\"keywords\":[\"br\u00e8ve\",\"cyclisme f\u00e9minin\"],\"articleSection\":[\"Tour d'Espagne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/\",\"name\":\"Tour d'Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape.png\",\"datePublished\":\"2024-08-18T10:10:15+00:00\",\"dateModified\":\"2024-08-18T10:10:47+00:00\",\"description\":\"Parcours et profil de la 2\u00e8me \u00e9tape Tour d\u2019Espagne 2024, qui se d\u00e9roule ce dimanche 18 ao\u00fbt 2024 entre Cascais et Ourem.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape.png\",\"width\":1200,\"height\":674,\"caption\":\"Tour d'Espagne 2024 Parcours et profil de la 2\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour d&#8217;Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour d'Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape","description":"Parcours et profil de la 2\u00e8me \u00e9tape Tour d\u2019Espagne 2024, qui se d\u00e9roule ce dimanche 18 ao\u00fbt 2024 entre Cascais et Ourem.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour d'Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape","og_description":"Parcours et profil de la 2\u00e8me \u00e9tape Tour d\u2019Espagne 2024, qui se d\u00e9roule ce dimanche 18 ao\u00fbt 2024 entre Cascais et Ourem.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2024-08-18T10:10:15+00:00","article_modified_time":"2024-08-18T10:10:47+00:00","og_image":[{"width":1024,"height":575,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape-1024x575.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"Tour d'Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Tour d&rsquo;Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape","datePublished":"2024-08-18T10:10:15+00:00","dateModified":"2024-08-18T10:10:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/"},"wordCount":411,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape.png","keywords":["br\u00e8ve","cyclisme f\u00e9minin"],"articleSection":["Tour d'Espagne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/","name":"Tour d'Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape.png","datePublished":"2024-08-18T10:10:15+00:00","dateModified":"2024-08-18T10:10:47+00:00","description":"Parcours et profil de la 2\u00e8me \u00e9tape Tour d\u2019Espagne 2024, qui se d\u00e9roule ce dimanche 18 ao\u00fbt 2024 entre Cascais et Ourem.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Parcours-et-profil-de-la-2eme-etape.png","width":1200,"height":674,"caption":"Tour d'Espagne 2024 Parcours et profil de la 2\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-parcours-et-profil-de-la-2eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour d&#8217;Espagne 2024 : Parcours et profil de la 2\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/512032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=512032"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/512032\/revisions"}],"predecessor-version":[{"id":513295,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/512032\/revisions\/513295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/513018"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=512032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=512032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=512032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}