{"id":515222,"date":"2024-08-27T17:34:25","date_gmt":"2024-08-27T15:34:25","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=515222&#038;preview=true&#038;preview_id=515222"},"modified":"2024-08-27T18:08:10","modified_gmt":"2024-08-27T16:08:10","slug":"tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/","title":{"rendered":"Tour d&rsquo;Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOUR D&rsquo;ESPAGNE 2024 &#8211; Wout Van Aert (Visma Lease a bike) s&rsquo;est impos\u00e9 sur la 10e \u00e9tape au terme d&rsquo;une \u00e9chapp\u00e9e. Imperturbable tout au long de la journ\u00e9e, le Belge a fait exploser le groupe de t\u00eate pour rallier la ligne accompagn\u00e9 du Fran\u00e7ais Quentin Pacher, qui doit se contenter de la 2e place. Dans le peloton, les favoris n&rsquo;ont pas boug\u00e9.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-classement-general-de-la-vuelta\/\">Tour d&rsquo;Espagne 2024 &#8211; Classement g\u00e9n\u00e9ral de la Vuelta<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-classement-10eme-etape-de-la-vuelta\/\">Tour d&rsquo;Espagne 2024 &#8211; Le classement de la 10\u00e8me \u00e9tape<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Suite \u00e0 une 9e \u00e9tape absolument folle dimanche, le peloton de <strong>Vuelta<\/strong> a pris un repos bien m\u00e9rit\u00e9 dimanche avant de partir \u00e0 l&rsquo;assaut de la deuxi\u00e8me semaine ce lundi. La <strong>10e \u00e9tape<\/strong> s&rsquo;annon\u00e7ait une nouvelle fois spectaculaire avec 160km entre <strong>Ponteareas<\/strong> et <strong>Baiona<\/strong>. L&rsquo;Alto de Fonfria d\u00e8s les premiers devait permettre de voir une \u00e9chapp\u00e9e de costauds se former, avant d&rsquo;aborder 60 derni\u00e8res bornes casse-pattes avec trois difficult\u00e9s pour 22 km d&rsquo;ascension en cumul\u00e9 \u00e0 pr\u00e8s de 6% de moyenne. De quoi promettre un beau spectacle.<\/p>\n<h2 style=\"text-align: justify;\">Cinq costauds se d\u00e9gagent au terme d&rsquo;une guerre sans merci<\/h2>\n<p style=\"text-align: justify;\">Et comme pr\u00e9vu, la guerre va \u00eatre terrible dans la premi\u00e8re ascension. Le peloton est mis en pi\u00e8ces par des multiples attaques. Malgr\u00e9 les tentatives franches de <strong>Wout Van Aert<\/strong> (Visma Lease a Bike) ou <strong>Marc Soler<\/strong> (UAE Team Emirates), le peloton ne laisse pas filer, et la bataille se prolonge bien au-del\u00e0 de la premi\u00e8re difficult\u00e9 du jour. \u00c0 force d&rsquo;insister, les deux hommes filent avec le jeune belge<strong> William Lecerf<\/strong> (Soudal-Quick Step), avant d&rsquo;\u00eatre rattrap\u00e9s par <strong>Quentin Pacher<\/strong> (Groupama-FDJ) et <strong>Juri Hollmann<\/strong> (Alpecin-Deceuninck).<\/p>\n<p style=\"text-align: justify;\">Il aura fallu pr\u00e8s d&rsquo;une heure et demie de course et soixante kilom\u00e8tres pour que ce coup ne se d\u00e9tache enfin. Ce quintet va alors essayer de prendre le maximum d&rsquo;avance dans la partie de plaine avant d&rsquo;aborder soixante derni\u00e8res bornes aux allures de toboggan. Cela va se faire ais\u00e9ment puisque le peloton l\u00e8ve le pied, et les premi\u00e8res pentes sont abord\u00e9es avec plus de six minutes d&rsquo;avance.<\/p>\n<p style=\"text-align: justify;\">La situation va se stabiliser dans cette ascension, les deux groupes \u00e9voluant \u00e0 une cadence similaire. Mais ce temps de r\u00e9pit va rapidement \u00eatre mis \u00e0 mal par une grosse acc\u00e9l\u00e9ration du peloton dans la deuxi\u00e8me difficult\u00e9. L&rsquo;\u00e9cart diminue, mais la temp\u00eate est rapidement calm\u00e9e. Au sommet, les cinq hommes de t\u00eate ont encore pr\u00e8s de six minutes d&rsquo;avance. La victoire va donc se jouer \u00e0 l&rsquo;avant. Avant d&rsquo;entamer les premi\u00e8res pentes, Van Aert place une acc\u00e9l\u00e9ration pour le sprint interm\u00e9diaire, et seul Pacher parvient \u00e0 accrocher sa roue.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"nl\">\ud83d\udeb4\ud83c\uddea\ud83c\uddf8 | Een sprint voor de punten, Soler bij de auto. Van Aert ziet het als een ideaal moment om de kopgroep van vijf terug te brengen tot een vlucht van twee. Alleen Pacher kan hem &#8211; met moeite &#8211; volgen. <a href=\"https:\/\/twitter.com\/hashtag\/LaVuelta24?src=hash&amp;ref_src=twsrc%5Etfw\">#LaVuelta24<\/a><\/p>\n<p>\ud83d\udcfa Stream koers op HBO Max <a href=\"https:\/\/t.co\/q5PAnvJvgn\">pic.twitter.com\/q5PAnvJvgn<\/a><\/p>\n<p>\u2014 Eurosport Nederland (@Eurosport_NL) <a href=\"https:\/\/twitter.com\/Eurosport_NL\/status\/1828443942733447473?ref_src=twsrc%5Etfw\">August 27, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Intouchable, Wout Van Aert crucifie Quentin Pacher<\/h2>\n<p style=\"text-align: justify;\">Le duo franco-belge collabore, et prend rapidement de l&rsquo;avance, profitant du manque d&rsquo;entente entre les trois membres l\u00e2ch\u00e9s de l&rsquo;\u00e9chapp\u00e9e initiale. Progressivement, Hollmann l\u00e2che prise, puis Soler se fait larguer par Lecerf avant de le rattraper. Mais ces mouvements sont insuffisants pour recoller sur les deux hommes de t\u00eate, qui conservent une trentaine de secondes d&rsquo;avance au moment de plonger dans la descente. Un dernier talus se pr\u00e9sente alors devant les deux hommes. <strong>Quentin Pacher<\/strong> va tenter d&rsquo;acc\u00e9l\u00e9rer, mais <strong>Wout Van Aert<\/strong> reste impassible, et semble intouchable.<\/p>\n<p style=\"text-align: justify;\">Dans un fauteuil, il va alors rallier la ligne sereinement avant de crucifier le Fran\u00e7ais au sprint avec une facilit\u00e9 impressionnante. Pour la troisi\u00e8me fois depuis le weekend dernier, le Belge d\u00e9ploie ses ailes sur cette Vuelta au terme d&rsquo;une journ\u00e9e ma\u00eetris\u00e9e d&rsquo;une main de ma\u00eetre. Pacher est lui tomb\u00e9 sur plus fort, et se satisfait d&rsquo;une belle 2e place, alors que <strong>Marc Soler<\/strong> compl\u00e8te le podium du jour.<\/p>\n<p style=\"text-align: justify;\">Dans le peloton, les leaders vont se neutraliser dans l&rsquo;ascension avant que la <strong>EF-Education EasyPost<\/strong> ne mette le feu aux poudres suite \u00e0 une \u00e9norme acc\u00e9l\u00e9ration de <strong>Jefferson Cepeda<\/strong>, avec <strong>Richard Carapaz<\/strong> dans la roue. Cela r\u00e9duit le groupe \u00e0 une vingtaine d&rsquo;unit\u00e9s, mais aucune attaque ne sera d\u00e9clench\u00e9e, et la D\u00e9cathlon-AG2R va alors assurer le tempo jusqu&rsquo;au sommet pour prot\u00e9ger le maillot rouge, <strong>Ben O&rsquo;Connor<\/strong>. Tout le monde va ainsi rallier l&rsquo;arriv\u00e9e ensemble, sereinement, alors que les bonifications ont \u00e9t\u00e9 d\u00e9j\u00e0 r\u00e9cup\u00e9r\u00e9es par les \u00e9chapp\u00e9s. Mardi, la 11e \u00e9tape devrait une nouvelle fois faire la part belle \u00e0 une \u00e9chapp\u00e9e.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Wout van Aert trop fort pour Quentin Pacher ! Le maillot vert s&rsquo;impose sans forcer sur la 10e \u00e9tape et remporte une troisi\u00e8me victoire dans cette <a href=\"https:\/\/twitter.com\/hashtag\/Vuelta?src=hash&amp;ref_src=twsrc%5Etfw\">#Vuelta<\/a> ! <a href=\"https:\/\/twitter.com\/hashtag\/LesRP?src=hash&amp;ref_src=twsrc%5Etfw\">#LesRP<\/a> <a href=\"https:\/\/t.co\/jj1bKsORNp\">pic.twitter.com\/jj1bKsORNp<\/a><\/p>\n<p>\u2014 Eurosport France (@Eurosport_FR) <a href=\"https:\/\/twitter.com\/Eurosport_FR\/status\/1828456152301998535?ref_src=twsrc%5Etfw\">August 27, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOUR D&rsquo;ESPAGNE 2024 &#8211; Wout Van Aert (Visma Lease a bike) s&rsquo;est impos\u00e9 sur la 10e \u00e9tape au terme d&rsquo;une \u00e9chapp\u00e9e gagnante. Imperturbable tout au long de la journ\u00e9e, le Belge a fait exploser le groupe de t\u00eate pour rallier la ligne accompagn\u00e9 du Fran\u00e7ais Quentin Pacher, qui doit se contenter de la 2e place. Dans le peloton, les favoris n&rsquo;ont pas boug\u00e9.<\/p>\n","protected":false},"author":55,"featured_media":515290,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47042],"tags":[16878,24],"class_list":["post-515222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-espagne","tag-breve","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour d&#039;Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e<\/title>\n<meta name=\"description\" content=\"TOUR D&#039;ESPAGNE 2024 - Ce lundi, Wout Van Aert a remport\u00e9 la 10e \u00e9tape \u00e0 Baiona en r\u00e9glant Quentin Pacher au sprint.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour d&#039;Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e\" \/>\n<meta property=\"og:description\" content=\"TOUR D&#039;ESPAGNE 2024 - Ce lundi, Wout Van Aert a remport\u00e9 la 10e \u00e9tape \u00e0 Baiona en r\u00e9glant Quentin Pacher au sprint.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-27T15:34:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-27T16:08:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour d&#039;Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Tour d&rsquo;Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e\",\"datePublished\":\"2024-08-27T15:34:25+00:00\",\"dateModified\":\"2024-08-27T16:08:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/\"},\"wordCount\":891,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png\",\"keywords\":[\"br\u00e8ve\",\"sport\"],\"articleSection\":[\"Tour d'Espagne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/\",\"name\":\"Tour d'Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png\",\"datePublished\":\"2024-08-27T15:34:25+00:00\",\"dateModified\":\"2024-08-27T16:08:10+00:00\",\"description\":\"TOUR D'ESPAGNE 2024 - Ce lundi, Wout Van Aert a remport\u00e9 la 10e \u00e9tape \u00e0 Baiona en r\u00e9glant Quentin Pacher au sprint.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Tour d'Espagne 2024 Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour d&#8217;Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour d'Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e","description":"TOUR D'ESPAGNE 2024 - Ce lundi, Wout Van Aert a remport\u00e9 la 10e \u00e9tape \u00e0 Baiona en r\u00e9glant Quentin Pacher au sprint.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour d'Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e","og_description":"TOUR D'ESPAGNE 2024 - Ce lundi, Wout Van Aert a remport\u00e9 la 10e \u00e9tape \u00e0 Baiona en r\u00e9glant Quentin Pacher au sprint.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-08-27T15:34:25+00:00","article_modified_time":"2024-08-27T16:08:10+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Tour d'Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Tour d&rsquo;Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e","datePublished":"2024-08-27T15:34:25+00:00","dateModified":"2024-08-27T16:08:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/"},"wordCount":891,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png","keywords":["br\u00e8ve","sport"],"articleSection":["Tour d'Espagne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/","url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/","name":"Tour d'Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png","datePublished":"2024-08-27T15:34:25+00:00","dateModified":"2024-08-27T16:08:10+00:00","description":"TOUR D'ESPAGNE 2024 - Ce lundi, Wout Van Aert a remport\u00e9 la 10e \u00e9tape \u00e0 Baiona en r\u00e9glant Quentin Pacher au sprint.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-dEspagne-2024-Wout-Van-Aert-fait-la-passe-de-trois-en-echappee-Quentin-Pacher-2e-1.png","width":1200,"height":674,"caption":"Tour d'Espagne 2024 Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2024-wout-van-aert-fait-la-passe-de-trois-en-echappee-quentin-pacher-2e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour d&#8217;Espagne 2024 : Wout Van Aert fait la passe de trois en \u00e9chapp\u00e9e, Quentin Pacher 2e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/515222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=515222"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/515222\/revisions"}],"predecessor-version":[{"id":515293,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/515222\/revisions\/515293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/515290"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=515222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=515222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=515222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}