{"id":515862,"date":"2025-05-16T23:17:10","date_gmt":"2025-05-16T21:17:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=515862&#038;preview=true&#038;preview_id=515862"},"modified":"2025-08-29T12:57:09","modified_gmt":"2025-08-29T10:57:09","slug":"classement-pro-d2-2024-2025","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/","title":{"rendered":"Pro D2 2024-2025 &#8211; Classement final"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>PRO D2 2024-2025 &#8211; D\u00e9couvrez le classement de la saison r\u00e9guli\u00e8re de Pro D2 2024-2025, qui se d\u00e9roule du jeudi 29 ao\u00fbt 2024 au vendredi 16 mai 2025.\u00a0<\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/\">L&rsquo;actualit\u00e9 du rugby \u00e0 XV<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Pro D2 &#8211; Classement de la saison 2024-2025<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Classement de la Pro D2 mis \u00e0 jour ce vendredi 16 mai \u00e0 23h15.<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table class=\"table-style-2\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><strong>#<\/strong><\/td>\n<td style=\"width: 50.0606%;vertical-align: middle;text-align: center\"><strong>Clubs<\/strong><\/td>\n<td style=\"text-align: center;width: 6.5%;vertical-align: middle\"><strong><abbr title=\"Points\">Pts<\/abbr><\/strong><\/td>\n<td style=\"text-align: center;width: 6.5%;vertical-align: middle\"><strong><abbr title=\"Jou\u00e9s\">J<\/abbr><\/strong><\/td>\n<td style=\"text-align: center;width: 6.5%;vertical-align: middle\"><strong><abbr title=\"Gagn\u00e9s\">G<\/abbr><\/strong><\/td>\n<td style=\"text-align: center;width: 6.5%;vertical-align: middle\"><strong><abbr title=\"Nuls\">N<\/abbr><\/strong><\/td>\n<td style=\"text-align: center;width: 6.5%;vertical-align: middle\"><strong><abbr title=\"Perdus\">P<\/abbr><\/strong><\/td>\n<td style=\"text-align: center;width: 6.5%;vertical-align: middle\"><strong><abbr title=\"Bonus\">B<\/abbr><\/strong><\/td>\n<td style=\"text-align: center;width: 6.5%;vertical-align: middle\"><strong><abbr title=\"Diff\u00e9rence\">diff<\/abbr><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">1.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #05519d;font-size: 1.3em\">\u25cf<\/span> GRENOBLE<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>98<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">21<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">9<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">14<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+310<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">2.<\/span><\/td>\n<td class=\"tdcol-30\" style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #000000;font-size: 1.3em\">\u25cf<\/span> BRIVE<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>94<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">20<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">10<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">14<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+149<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">3.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #012255;font-size: 1.3em\">\u25cf<\/span> COLOMIERS<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>87<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">18<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">1<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">11<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">13<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+151<\/td>\n<\/tr>\n<tr>\n<td class=\"tdcol-5\" style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">4.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #000000;font-size: 1.3em\">\u25cf<\/span> PROVENCE RUGBY<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>82<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">17<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">1<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">12<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">12<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+96<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">5.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #371a4f;font-size: 1.3em\">\u25cf<\/span>\u00a0SOYAUX-ANGOUL\u00caME<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>80<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">17<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">2<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">11<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">8<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+34<\/td>\n<\/tr>\n<tr class=\"promu2\">\n<td class=\"tdcol-5\" style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">6.<\/span><\/td>\n<td class=\"tdcol-30\" style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #00955c;font-size: 1.3em\">\u25cf<\/span> MONTAUBAN<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>77<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">17<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">13<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">9<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+19<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">7.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #fe0002;font-size: 1.3em\">\u25cf<\/span> B\u00c9ZIERS<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>77<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">16<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">14<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">13<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+74<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">8.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #f6df12;font-size: 1.3em\">\u25cf<\/span> NEVERS<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>64<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">13<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">17<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">12<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+58<\/td>\n<\/tr>\n<tr class=\"promu2\">\n<td class=\"tdcol-5\" style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">9.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #e30013;font-size: 1.3em\">\u25cf<\/span> DAX<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>64<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">14<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">16<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">9<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">-42<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">10.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #fff118;font-size: 1.3em\">\u25cf<\/span> STADE MONTOIS<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>62<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">14<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">16<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">6<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">-151<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">11.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #e30013;font-size: 1.3em\">\u25cf<\/span> DAX<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>61<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">13<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">1<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">16<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">7<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">-113<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">12.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #ee2c2c;font-size: 1.3em\">\u25cf<\/span> OYONNAX<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>61<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">12<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">1<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">17<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">11<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">+33<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">13.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #fff118;font-size: 1.3em\">\u25cf<\/span>\u00a0STADE MONTOIS<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>60<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">13<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">17<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">8<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">-63<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">14.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #1e3663;font-size: 1.3em\">\u25cf<\/span> AGEN<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>59<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">12<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">18<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">11<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">-35<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">15.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #f31a25;font-size: 1.3em\">\u25cf<\/span> AURILLAC<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>57<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">13<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">17<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">5<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">-173<\/td>\n<\/tr>\n<tr>\n<td class=\"tdcol-5\" style=\"width: 3.39394%;text-align: center;vertical-align: middle\"><span style=\"font-size: 14px\">16.<\/span><\/td>\n<td style=\"width: 50.0606%;text-align: left;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><span style=\"color: #000000;font-size: 1.3em\">\u25cf<\/span> NICE<\/span><\/strong><\/td>\n<td class=\"table__col table__col--points\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\"><strong>35<\/strong><\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">30<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">7<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">0<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">23<\/td>\n<td class=\"table__col\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">7<\/td>\n<td class=\"table__col table__col--lastItemMobile\" style=\"width: 6.5%;text-align: center\" data-v-60fe7fea=\"\">-347<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em>*Mi-d\u00e9cembre, le <b>Biarritz<\/b>\u00a0<strong>Olympique<\/strong> a \u00e9t\u00e9 sanctionn\u00e9 d&rsquo;un retrait de cinq points au classement de Pro D2 par le Conseil de Discipline du Rugby Fran\u00e7ais, et ce, en raison de la \u00ab non-communication aux commissions de contr\u00f4le \u00bb de documents demand\u00e9s. Finalement, <strong>fin janvier<\/strong>, le recours du BO a \u00e9t\u00e9 re\u00e7u favorablement par la Commission d&rsquo;appel. Le club basque a r\u00e9cup\u00e9r\u00e9 quatre points.<\/em><\/span><\/p>\n<h3 style=\"text-align: justify;\">Bar\u00e8me des points pour le classement de Pro D2<\/h3>\n<p style=\"text-align: justify;\"><strong>Victoire :<\/strong> 4 points<br \/>\n<strong>Victoire avec bonus offensif :<\/strong> 5 points<br \/>\n<strong>D\u00e9faite :<\/strong> 0 point<br \/>\n<strong>D\u00e9faite avec bonus d\u00e9fensif :<\/strong> 1 point<br \/>\n<strong>Match nul :<\/strong> 2 points<\/p>\n<p><strong>Attribution du bonus offensif\u00a0 :<\/strong> 3 essais inscrits de plus que l&rsquo;adversaire<br \/>\n<strong>Attribution du bonus d\u00e9fensif :<\/strong> D\u00e9faite par 5 points d&rsquo;\u00e9cart ou moins<\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/dupont-russell-biggar-les-salaires-des-6-joueurs-de-rugby-les-mieux-payes\/\" class=\"vlp-link\" title=\"Dupont, Russell, Biggar : Les salaires des 6 joueurs de rugby les mieux pay\u00e9s\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 800px;\" width=\"800\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Dupont-Russell-Biggar-Les-salaires-des-6-joueurs-de-rugby-les-mieux-payes.png\" class=\"attachment-800x445 size-800x445\" alt=\"Dupont, Russell, Biggar Les salaires des 6 joueurs de rugby les mieux pay\u00e9s\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Dupont-Russell-Biggar-Les-salaires-des-6-joueurs-de-rugby-les-mieux-payes.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Dupont-Russell-Biggar-Les-salaires-des-6-joueurs-de-rugby-les-mieux-payes-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Dupont-Russell-Biggar-Les-salaires-des-6-joueurs-de-rugby-les-mieux-payes-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Dupont, Russell, Biggar : Les salaires des 6 joueurs de rugby les mieux pay\u00e9s<\/div><div class=\"vlp-block-1 vlp-link-summary\">RUGBY \u00c0 XV - R\u00e9cemment, le m\u00e9dia britannique Ruck a d\u00e9voil\u00e9 les salaires des 6 joueurs les mieux pay\u00e9s au monde. Parmi eux, on retrouve le capitaine du XV de France, Antoine Dupont.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>PRO D2 2024-2025 &#8211; D\u00e9couvrez le classement de la saison r\u00e9guli\u00e8re de Pro D2 2024-2025, qui se d\u00e9roule du jeudi 29 ao\u00fbt 2024 au vendredi 16 mai 2025.\u00a0<\/p>\n","protected":false},"author":4,"featured_media":515872,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129],"tags":[16878,1839],"class_list":["post-515862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-breve","tag-pro-d2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pro D2 2024-2025 - Classement final - Rugby \u00e0 XV<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le classement de la saison r\u00e9guli\u00e8re de Pro D2 2024-2025, qui se d\u00e9roule du jeudi 29 ao\u00fbt 2024 au vendredi 16 mai 2025.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pro D2 2024-2025 - Classement final\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le classement de la saison r\u00e9guli\u00e8re de Pro D2 2024-2025, qui se d\u00e9roule du jeudi 29 ao\u00fbt 2024 au vendredi 16 mai 2025.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-16T21:17:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T10:57:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pro D2 2024-2025 - Classement final\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Pro D2 2024-2025 &#8211; Classement final\",\"datePublished\":\"2025-05-16T21:17:10+00:00\",\"dateModified\":\"2025-08-29T10:57:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\"},\"wordCount\":313,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png\",\"keywords\":[\"br\u00e8ve\",\"Pro D2\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\",\"name\":\"Pro D2 2024-2025 - Classement final - Rugby \u00e0 XV\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png\",\"datePublished\":\"2025-05-16T21:17:10+00:00\",\"dateModified\":\"2025-08-29T10:57:09+00:00\",\"description\":\"D\u00e9couvrez le classement de la saison r\u00e9guli\u00e8re de Pro D2 2024-2025, qui se d\u00e9roule du jeudi 29 ao\u00fbt 2024 au vendredi 16 mai 2025.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png\",\"width\":1200,\"height\":674,\"caption\":\"Classement Pro D2 2024-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro D2 2024-2025 &#8211; Classement final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pro D2 2024-2025 - Classement final - Rugby \u00e0 XV","description":"D\u00e9couvrez le classement de la saison r\u00e9guli\u00e8re de Pro D2 2024-2025, qui se d\u00e9roule du jeudi 29 ao\u00fbt 2024 au vendredi 16 mai 2025.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Pro D2 2024-2025 - Classement final","og_description":"D\u00e9couvrez le classement de la saison r\u00e9guli\u00e8re de Pro D2 2024-2025, qui se d\u00e9roule du jeudi 29 ao\u00fbt 2024 au vendredi 16 mai 2025.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-05-16T21:17:10+00:00","article_modified_time":"2025-08-29T10:57:09+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Pro D2 2024-2025 - Classement final","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Pro D2 2024-2025 &#8211; Classement final","datePublished":"2025-05-16T21:17:10+00:00","dateModified":"2025-08-29T10:57:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/"},"wordCount":313,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png","keywords":["br\u00e8ve","Pro D2"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/","url":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/","name":"Pro D2 2024-2025 - Classement final - Rugby \u00e0 XV","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png","datePublished":"2025-05-16T21:17:10+00:00","dateModified":"2025-08-29T10:57:09+00:00","description":"D\u00e9couvrez le classement de la saison r\u00e9guli\u00e8re de Pro D2 2024-2025, qui se d\u00e9roule du jeudi 29 ao\u00fbt 2024 au vendredi 16 mai 2025.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Classement-Pro-D2-2024-2025.png","width":1200,"height":674,"caption":"Classement Pro D2 2024-2025"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pro D2 2024-2025 &#8211; Classement final"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/515862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=515862"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/515862\/revisions"}],"predecessor-version":[{"id":553329,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/515862\/revisions\/553329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/515872"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=515862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=515862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=515862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}