{"id":516623,"date":"2024-09-01T08:26:10","date_gmt":"2024-09-01T06:26:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=516623&#038;preview=true&#038;preview_id=516623"},"modified":"2024-09-01T16:50:31","modified_gmt":"2024-09-01T14:50:31","slug":"jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/","title":{"rendered":"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/jeux-paralympiques-paris-2024\/\">JEUX PARALYMPIQUES PARIS 2024<\/a> &#8211; Du 28 ao\u00fbt au 8 septembre, pr\u00e8s de 240 athl\u00e8tes tricolores se succ\u00e8dent afin de valider un long projet, une m\u00e9daille paralympique. Et pourquoi pas le plus beau des m\u00e9taux ? Voici le programme des Fran\u00e7ais pour le dimanche 1er septembre.<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-les-chances-de-medailles-francaises-du-1er-septembre\/\">Jeux Paralympiques 2024 : Les chances de m\u00e9dailles fran\u00e7aises du 1er septembre<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Toutes les \u00e9preuves de triathlon, qui devaient se d\u00e9rouler ce dimanche 1er septembre sont report\u00e9es au lendemain, par mesure de pr\u00e9caution concernant la baignabilit\u00e9 de la Seine.<\/strong> Mais l&rsquo;\u00e9quipe de France poss\u00e8de encore de grandes chances de glaner quelques r\u00e9compenses suppl\u00e9mentaires. Car les Bleu(e)s du cyclisme sur piste sont encore pr\u00e9sents pour garnir un peu plus le panier tricolore. L&rsquo;aviron et le tir peuvent \u00e9galement augmenter le compteur et quatre finales en athl\u00e9tisme vous attendent ce soir, a minima. Parmi celles-ci, le 100 m de <strong>F\u00e9licien Siapo<\/strong> ou encore le saut en longueur avec <strong>Mandy-Fran\u00e7ois \u00c9lie<\/strong> et <strong>Manon Genest<\/strong>. <strong>Lucas Mazur<\/strong> vise quant \u00e0 lui une place pour l&rsquo;ultime \u00e9tape SL4 de badminton.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-de-paris-2024-tableau-des-medailles\/\">Jeux Paralympiques de Paris 2024 \u2013 Tableau des m\u00e9dailles<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Les Fran\u00e7ais en lice le 1er septembre<\/h2>\n<p style=\"text-align: justify;\">Horaires avec *\u00a0: si qualification<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Horaires en rouge\u00a0: finale<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>9h30<\/strong>\u00a0: <u>Para tir sportif<\/u> \u2013 R3 carabine 10 m couch\u00e9 mixte SH1 (qualifications, <em>Centre National de Tir<\/em>) avec <strong>C\u00e9dric F\u00e8vre<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>9h34\u00a0<\/strong>: <u>Para tir \u00e0 l\u2019arc<\/u> \u2013 \u00c9preuve individuelle hommes W1 (8<sup>\u00e8mes<\/sup>, <em>Invalides<\/em>) avec <strong>Damien Letulle<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>9h45\u00a0<\/strong>:\u00a0<u>Para natation<\/u>\u00a0\u2013 100 m nage libre F S10 (s\u00e9ries,\u00a0<em>Paris La D\u00e9fense Arena<\/em>) avec <strong>\u00c9lodie Lorandi<\/strong>\u00a0et <strong>\u00c9meline Pierre<\/strong><\/p>\n<p><b>10h30 <\/b>:\u00a0<u>Boccia<\/u> \u2013 Individuel H BC3 (quarts, <em>Arena Paris Sud<\/em>) avec\u00a0<strong>Jules M\u00e9nard<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>10h35<\/strong>\u00a0: <u>Para natation<\/u> \u2013 150 m 3 nages H SM4 (s\u00e9ries, <em>Paris La D\u00e9fense Arena<\/em>) avec <strong>Dimitri Granjux<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>11h10\u00a0<\/strong>:\u00a0<u>Para aviron<\/u>\u00a0\u2013 PR1 Skiff F (finale,\u00a0<em>Stade Nautique de Vaires-sur-Marne<\/em>) avec<strong>\u00a0Nathalie Benoit<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>11h26<\/strong>\u00a0: <u>Para cyclisme sur piste<\/u> \u2013 Poursuite individuelle F 3 000 m B (qualifications, <em>V\u00e9lodrome National<\/em>) avec <strong>Anne-Sophie Centis<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>11h30<\/strong>\u00a0: <u>Para tir sportif<\/u> \u2013 R5 carabine 10 m couch\u00e9 mixte SH2 (qualifications, <em>Centre National de Tir<\/em>) avec <strong>Tanguy de La Forest<\/strong> et <strong>Pierre Guillaume-Sage<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>11h30\u00a0<\/strong>:\u00a0<u>Para aviron<\/u>\u00a0\u2013 PR1 Skiff H (finale,\u00a0<em>Stade Nautique de Vaires-sur-Marne<\/em>) avec<strong>\u00a0Alexis Sanchez<\/strong><\/span><\/p>\n<p><span style=\"color: #ff0000;\"><strong>11h50 <\/strong>:\u00a0<u>Para aviron<\/u> \u2013 PR2 Deux de couple mixte (finale, <em>Stade Nautique de Vaires-sur-Marne<\/em>) avec<strong> Perle Bouge<\/strong>\/<strong>Benjamin Daviet<\/strong><\/span><\/p>\n<p><b>11h55 <\/b>:\u00a0<u>Boccia<\/u> \u2013 Individuel F BC1 (demies, <em>Arena Paris Sud<\/em>) avec\u00a0<strong>Aur\u00e9lie Aubert<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 12h\u00a0<\/strong>:\u00a0<u>Tennis fauteuil<\/u>\u00a0\u2013 En 1<sup>er<\/sup>\u00a0sur le Suzanne Lenglen, Simple H (2<sup>\u00e8me<\/sup>\u00a0tour,\u00a0<em>Roland-Garros<\/em>) avec <strong>Fr\u00e9d\u00e9ric Cattan\u00e9o<\/strong><\/p>\n<p style=\"text-align: justify;\">\u2013 En 4<sup>\u00e8me<\/sup>\u00a0sur le Suzanne Lenglen, Double H (2<sup>\u00e8me<\/sup>\u00a0tour,\u00a0<em>Roland-Garros<\/em>) avec <strong>Fr\u00e9d\u00e9ric Cattan\u00e9o<\/strong>\/<strong>St\u00e9phane Houdet<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 12h<\/strong>\u00a0:\u00a0<u>Tennis fauteuil<\/u>\u00a0\u2013 En 2<sup>\u00e8me<\/sup>\u00a0sur le Philippe Chatrier, Simple H (2<sup>\u00e8me<\/sup>\u00a0tour,\u00a0<em>Roland-Garros<\/em>) avec <strong>St\u00e9phane Houdet<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 12h<\/strong>\u00a0:\u00a0<u>Tennis fauteuil<\/u>\u00a0\u2013 En 2<sup>nd<\/sup>\u00a0sur court 14, Double H (2<sup>\u00e8me<\/sup> tour,\u00a0<em>Roland-Garros<\/em>) avec<strong> Ga\u00ebtan Menguy<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>12h10\u00a0<\/strong>:\u00a0<u>Para aviron<\/u>\u00a0\u2013 PR3 Deux de couple mixte (finale,\u00a0<em>Stade Nautique de Vaires-sur-Marne<\/em>) avec<strong>\u00a0Laurent Cadot\/Guylaine Marchand<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>12h24<\/strong>\u00a0: <u>Para cyclisme sur piste<\/u> \u2013 Poursuite individuelle F 3 000 m C5 (qualifications, <em>V\u00e9lodrome National<\/em>) avec <strong>Marie Patouillet <\/strong>et <strong>He\u00efdi Gaugain<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udd25 La vasque rena\u00eet dans le ciel de Paris.<\/p>\n<p>Elle est allum\u00e9e par \u00c9lodie Lorandi, Charles Antoine Kouakou, Fabien Lamirault, Alexis Hanquinquant et Nantenin Ke\u00efta. <a href=\"https:\/\/t.co\/vcAPnzgXMT\">pic.twitter.com\/vcAPnzgXMT<\/a><\/p>\n<p>\u2014 franceinfo (@franceinfo) <a href=\"https:\/\/twitter.com\/franceinfo\/status\/1828909991056519480?ref_src=twsrc%5Etfw\">August 28, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"color: #ff0000;\"><strong>12h36 <\/strong>:\u00a0<u>Para aviron<\/u> \u2013 PR3 Quatre de pointe avec barreur mixte (finale, <em>Stade Nautique de Vaires-sur-Marne<\/em>)\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>12h50\u00a0<\/strong>:\u00a0<u>Para athl\u00e9tisme<\/u>\u00a0\u2013 400 m H T53 (s\u00e9ries,\u00a0<em>Stade de France<\/em>) avec<strong>\u00a0Pierre Fairbank<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>12h55<\/strong>\u00a0: <u>Para cyclisme sur piste<\/u> \u2013 Vitesse par \u00e9quipes Open 750 m C1-5 (qualifications, <em>V\u00e9lodrome National<\/em>)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>15h<\/strong>\u00a0: <u>Para tir sportif<\/u> \u2013 R5 carabine 10 m couch\u00e9 mixte SH2 (finale, <em>Centre National de Tir<\/em>) avec <strong>Tanguy de La Forest<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>15h22<\/strong>\u00a0: <u>Para cyclisme sur piste<\/u> \u2013 Poursuite individuelle F 3 000 m C5 (finale, <em>V\u00e9lodrome National<\/em>) avec <strong>Marie Patouillet <\/strong>et <strong>He\u00efdi Gaugain<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>15h30<\/strong>\u00a0: <u>Para cyclisme sur piste<\/u> \u2013 Vitesse par \u00e9quipes Open 750 m C1-5 (course pour le bronze, <em>V\u00e9lodrome National<\/em>)<\/p>\n<p style=\"text-align: justify;\"><strong>16h21\u00a0<\/strong>: <u>Para tir \u00e0 l\u2019arc<\/u> \u2013 Individuelle open arc \u00e0 poulies hommes (8<sup>\u00e8mes<\/sup>, <em>Invalides<\/em>) avec <strong>Maxime Gu\u00e9rin<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>17h<\/strong>\u00a0: <u>Para tennis de table<\/u> \u2013 Simple femmes WS4 (8<sup>\u00e8mes<\/sup>, <em>Arena Paris Sud<\/em>) avec <strong>Flora Vautier<\/strong><\/p>\n<p><strong>17h30<\/strong>\u00a0: <u>Rugby fauteuil<\/u> \u2013 France\u00a0\ud83c\uddeb\ud83c\uddf7 \u2013 \ud83c\udde9\ud83c\uddea Allemagne (match de classement, <em>Arena Champ-de-Mars<\/em>)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>17h51 <\/strong>:\u00a0<u>Para natation<\/u>\u00a0\u2013 100 m nage libre F S10 (finale,\u00a0<em>Paris La D\u00e9fense Arena<\/em>) avec <strong>\u00c9meline Pierre<\/strong><\/span><\/p>\n<p><b>\u00c0 partir de 18h20 <\/b>: <u>Para badminton<\/u> \u2013 Simple H SL4 (demies, <em>Arena La Chapelle<\/em>) avec <strong>Lucas Mazur<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>18h30<\/strong>\u00a0: <u>Para tennis de table<\/u> \u2013 Simple hommes MS10 (8<sup>\u00e8mes<\/sup>, <em>Arena Paris Sud<\/em>) avec <strong>Mat\u00e9o Boh\u00e9as<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>19h\u00a0<\/strong>:\u00a0<u>Para athl\u00e9tisme<\/u>\u00a0\u2013 Lancer de poids F F20 (finale,\u00a0<em>Stade de France<\/em>) avec<strong>\u00a0Gloria Agblemagnon<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>19h<\/strong>\u00a0: <u>Goalball (F)<\/u> \u2013 France\u00a0\ud83c\uddeb\ud83c\uddf7 &#8211; \ud83c\uddef\ud83c\uddf5 Japon (Phase de poule D, <em>Arena Paris Sud<\/em>)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>19h02<\/strong>\u00a0: <u>Para natation<\/u> \u2013 150 m 3 nages H SM4 (finale, <em>Paris La D\u00e9fense Arena<\/em>) avec <strong>Dimitri Granjux<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>19h10\u00a0<\/strong>:\u00a0<u>Para athl\u00e9tisme<\/u>\u00a0\u2013 Saut en hauteur H T47 (finale,\u00a0<em>Stade de France<\/em>) avec<strong>\u00a0Alexandre Dipoko-Ewane<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>19h15<\/strong>\u00a0: <u>Para tennis de table<\/u> \u2013 Simple femmes WS8 (8<sup>\u00e8mes<\/sup>, <em>Arena Paris Sud<\/em>) avec <strong>Lucie Hauti\u00e8re<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>19h37\u00a0<\/strong>:\u00a0<u>Para athl\u00e9tisme<\/u>\u00a0\u2013 100 m H T44 (finale,\u00a0<em>Stade de France<\/em>) avec<strong>\u00a0F\u00e9licien Siapo<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>20h<\/strong>\u00a0: <u>Volleyball assis (F)<\/u> \u2013 France \ud83c\uddeb\ud83c\uddf7 \u2013\u00a0\ud83c\uddfa\ud83c\uddf8 \u00c9tats-Unis (tour pr\u00e9liminaire poule A, <em>Arena Paris Nord<\/em>)<\/p>\n<p><b>\u00c0 partir de 20h <\/b>: <u>Para badminton<\/u> \u2013 Simple H SH6 (demies, <em>Arena La Chapelle<\/em>) avec <strong>Charles Noakes<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>20h07 <\/strong>:\u00a0<u>Para athl\u00e9tisme<\/u>\u00a0\u2013 400 m H T53 (finale,\u00a0<em>Stade de France<\/em>) avec<strong>\u00a0Pierre Fairbank<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>20h30<\/strong>\u00a0: <u>C\u00e9cifoot (H)<\/u> \u2013 France\u00a0\ud83c\uddeb\ud83c\uddf7 \u2013 \ud83c\udde8\ud83c\uddf3 Chine (tour pr\u00e9liminaire groupe A, <em>Stade Tour Eiffel<\/em>)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>20h41\u00a0<\/strong>:\u00a0<u>Para athl\u00e9tisme<\/u>\u00a0\u2013 Saut en longueur F T37 (finale,\u00a0<em>Stade de France<\/em>) avec<strong>\u00a0Mandy Fran\u00e7ois-\u00c9lie<\/strong> et <strong>Manon Genest<\/strong><\/span><\/p>\n<p><span style=\"color: #ff0000;\"><strong>21h05<\/strong>\u00a0: <u>Para athl\u00e9tisme<\/u> \u2013 400 m H T11 (finale, <em>Stade de France<\/em>) avec <strong>Timoth\u00e9e Adolphe<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>21h30<\/strong>\u00a0: <u>Para tennis de table<\/u> \u2013 Simple femmes WS6 (8<sup>\u00e8mes<\/sup>, <em>Arena Paris Sud<\/em>) avec <strong>Morgen Caillaud<\/strong><\/p>\n<p style=\"text-align: justify;\">Ce programme est susceptible d\u2019\u00eatre modifi\u00e9 selon les r\u00e9sultats<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programme des Fran\u00e7ais du dimanche 1er septembre<\/p>\n","protected":false},"author":18,"featured_media":516664,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[21286],"tags":[32415,16878,30151],"class_list":["post-516623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeux-paralympiques-paris-2024","tag-actu","tag-breve","tag-jeux-paralympiques-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre<\/title>\n<meta name=\"description\" content=\"JEUX PARALYMPIQUES PARIS 2024 - D\u00e9couvrez le programme complet des Fran\u00e7ais pour le dimanche 1er septembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre\" \/>\n<meta property=\"og:description\" content=\"JEUX PARALYMPIQUES PARIS 2024 - D\u00e9couvrez le programme complet des Fran\u00e7ais pour le dimanche 1er septembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-01T06:26:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-01T14:50:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre\",\"datePublished\":\"2024-09-01T06:26:10+00:00\",\"dateModified\":\"2024-09-01T14:50:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/\"},\"wordCount\":969,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Jeux Paralympiques 2024\"],\"articleSection\":[\"Jeux Paralympiques de Paris 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/\",\"name\":\"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png\",\"datePublished\":\"2024-09-01T06:26:10+00:00\",\"dateModified\":\"2024-09-01T14:50:31+00:00\",\"description\":\"JEUX PARALYMPIQUES PARIS 2024 - D\u00e9couvrez le programme complet des Fran\u00e7ais pour le dimanche 1er septembre.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png\",\"width\":1200,\"height\":674,\"caption\":\"Jeux Paralympiques 2024 Programme des Fran\u00e7ais du dimanche 1er septembre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre","description":"JEUX PARALYMPIQUES PARIS 2024 - D\u00e9couvrez le programme complet des Fran\u00e7ais pour le dimanche 1er septembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/","og_locale":"fr_FR","og_type":"article","og_title":"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre","og_description":"JEUX PARALYMPIQUES PARIS 2024 - D\u00e9couvrez le programme complet des Fran\u00e7ais pour le dimanche 1er septembre.","og_url":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2024-09-01T06:26:10+00:00","article_modified_time":"2024-09-01T14:50:31+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre","datePublished":"2024-09-01T06:26:10+00:00","dateModified":"2024-09-01T14:50:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/"},"wordCount":969,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png","keywords":["actu","br\u00e8ve","Jeux Paralympiques 2024"],"articleSection":["Jeux Paralympiques de Paris 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/","url":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/","name":"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png","datePublished":"2024-09-01T06:26:10+00:00","dateModified":"2024-09-01T14:50:31+00:00","description":"JEUX PARALYMPIQUES PARIS 2024 - D\u00e9couvrez le programme complet des Fran\u00e7ais pour le dimanche 1er septembre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Jeux-Paralympiques-2024-Programme-des-Francais-du-dimanche-1er-septembre.png","width":1200,"height":674,"caption":"Jeux Paralympiques 2024 Programme des Fran\u00e7ais du dimanche 1er septembre"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-2024-programme-des-francais-du-dimanche-1er-septembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Jeux Paralympiques 2024 : Programme des Fran\u00e7ais du dimanche 1er septembre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/516623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=516623"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/516623\/revisions"}],"predecessor-version":[{"id":516903,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/516623\/revisions\/516903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/516664"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=516623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=516623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=516623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}