{"id":517620,"date":"2024-09-04T14:45:15","date_gmt":"2024-09-04T12:45:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=517620&#038;preview=true&#038;preview_id=517620"},"modified":"2024-09-04T20:29:16","modified_gmt":"2024-09-04T18:29:16","slug":"cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/","title":{"rendered":"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 &#8211; Dorian Foulon poursuit la moisson tricolore en cyclisme, avec le bronze sur le contre-la-montre C5. Le Fran\u00e7ais empoche une nouvelle m\u00e9daille, apr\u00e8s l&rsquo;or sur la poursuite sur piste. Mais est tomb\u00e9 sur plus fort que lui, en terminant \u00e0 58 secondes de Daniel Abraham Gebru et 32 d&rsquo;Alistair Donohoe.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/jeux-paralympiques-paris-2024\/\">L\u2019actualit\u00e9 des Jeux Paralympiques de Paris 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Tout vient \u00e0 point \u00e0 qui sait attendre. Et <strong>Dorian Foulon<\/strong> a su attendre dans son contre-la-montre. Certes, par d&rsquo;or pour le Fran\u00e7ais, comme sur la poursuite sur piste, mais une nouvelle m\u00e9daille pour lui aussi. Le bronze sur le contre-la-montre cat\u00e9gorie C5. Le cyclisme, d\u00e9cid\u00e9ment pourvoyeur de m\u00e9dailles, dans ces Jeux Paralympiques et une \u00e9dition r\u00e9ussie pour le Fran\u00e7ais, avec deux m\u00e9dailles, contre une il y a trois ans \u00e0 Tokyo : \u00ab\u00a0<em>C&rsquo;est une satisfaction, m\u00eame si j&rsquo;aurais aim\u00e9 une autre couleur<\/em>\u00ab\u00a0, confie le coureur, au micro de France T\u00e9l\u00e9visions, une fois la ligne d&rsquo;arriv\u00e9e franchie. Laissant parler sa satisfaction, alors qu&rsquo;il restera la course en ligne.<\/p>\n<h2>Dorian Foulon est mont\u00e9 en puissance sur ce chrono<\/h2>\n<p style=\"text-align: justify;\">La m\u00e9daille de bronze de la patience pour le Fran\u00e7ais, qui est parti prudemment. Sixi\u00e8me au premier interm\u00e9diaire puis quatri\u00e8me sur le second, il a fallu attendre le dernier inter, celui du 19.9 km, pour le voir monter pour la premi\u00e8re fois virtuellement sur le podium, en troisi\u00e8me position. Qu&rsquo;il ne quittera plus. Car il a su repousser <strong>Lauro Cesar Mouro Chaman<\/strong> \u00e0 neuf secondes. Le Br\u00e9silien, longtemps devant le Fran\u00e7ais, \u00e9tait la principale menace. Mais qui aura moins su lisser son effort, par rapport au Tricolore.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-de-paris-2024-tableau-des-medailles\/\">Jeux Paralympiques de Paris 2024 \u2013 Tableau des m\u00e9dailles<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">En revanche, l&rsquo;or et m\u00eame l&rsquo;argent \u00e9taient totalement inatteignables. Le N\u00e9erlandais (encore un)<strong> Daniel Abraham<\/strong> explosant les compteurs. Pour s&rsquo;imposer avec 27 secondes d&rsquo;avance sur l&rsquo;Australien <strong>Alistair Donoho\u00e9.<\/strong> Le premier cit\u00e9, d\u00e9j\u00e0 en t\u00eate \u00e0 l&rsquo;avant-dernier interm\u00e9diaire, a encore plus creus\u00e9 les \u00e9carts sur tout le monde. Repoussant <strong>Dorian Foulon<\/strong> \u00e0 quasiment une minute (58 secondes).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">M\u00c9DAILLE DE BRONZE \ud83e\udd49<\/p>\n<p>Apr\u00e8s le titre paralympique en cyclisme sur piste, Dorian Foulon monte de nouveau sur le podium mais cette fois-ci, en para cyclisme sur route ! \ud83d\ude4c<a href=\"https:\/\/twitter.com\/hashtag\/AllezLesBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#AllezLesBleus<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Paris2024?src=hash&amp;ref_src=twsrc%5Etfw\">#Paris2024<\/a> <a href=\"https:\/\/t.co\/eg0eSD6elL\">pic.twitter.com\/eg0eSD6elL<\/a><\/p>\n<p>\u2014 Equipe France (@EquipeFRA) <a href=\"https:\/\/twitter.com\/EquipeFRA\/status\/1831311088274604328?ref_src=twsrc%5Etfw\">September 4, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 &#8211; Dorian Foulon poursuit la moisson tricolore en cyclisme, avec le bronze sur le contre-la-montre C5. Le Fran\u00e7ais empoche une nouvelle m\u00e9daille, apr\u00e8s l&rsquo;or sur la poursuite sur piste. Mais est tomb\u00e9 sur plus fort que lui, en terminant \u00e0 58 secondes de Daniel Abraham Gebru et 32 d&rsquo;Alistair Donohoe.<\/p>\n","protected":false},"author":83,"featured_media":517809,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2307,21286],"tags":[32415,16878,11197,18878,30151,34960,1004],"class_list":["post-517620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme","category-jeux-paralympiques-paris-2024","tag-actu","tag-breve","tag-cyclisme-sur-route","tag-dorian-foulon","tag-jeux-paralympiques-2024","tag-jeux-paralympiques-de-paris","tag-paris-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5<\/title>\n<meta name=\"description\" content=\"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Dorian Foulon poursuit la moisson tricolore en cyclisme, avec le bronze sur le contre-la-montre C5.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5\" \/>\n<meta property=\"og:description\" content=\"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Dorian Foulon poursuit la moisson tricolore en cyclisme, avec le bronze sur le contre-la-montre C5.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-04T12:45:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-04T18:29:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5\",\"datePublished\":\"2024-09-04T12:45:15+00:00\",\"dateModified\":\"2024-09-04T18:29:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/\"},\"wordCount\":421,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Cyclisme sur route\",\"Dorian Foulon\",\"Jeux Paralympiques 2024\",\"Jeux Paralympiques de Paris\",\"Paris 2024\"],\"articleSection\":[\"Cyclisme\",\"Jeux Paralympiques de Paris 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/\",\"name\":\"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png\",\"datePublished\":\"2024-09-04T12:45:15+00:00\",\"dateModified\":\"2024-09-04T18:29:16+00:00\",\"description\":\"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Dorian Foulon poursuit la moisson tricolore en cyclisme, avec le bronze sur le contre-la-montre C5.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Cyclisme sur route Jeux Paralympiques 2024 Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5","description":"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Dorian Foulon poursuit la moisson tricolore en cyclisme, avec le bronze sur le contre-la-montre C5.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/","og_locale":"fr_FR","og_type":"article","og_title":"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5","og_description":"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Dorian Foulon poursuit la moisson tricolore en cyclisme, avec le bronze sur le contre-la-montre C5.","og_url":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-09-04T12:45:15+00:00","article_modified_time":"2024-09-04T18:29:16+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5","datePublished":"2024-09-04T12:45:15+00:00","dateModified":"2024-09-04T18:29:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/"},"wordCount":421,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png","keywords":["actu","br\u00e8ve","Cyclisme sur route","Dorian Foulon","Jeux Paralympiques 2024","Jeux Paralympiques de Paris","Paris 2024"],"articleSection":["Cyclisme","Jeux Paralympiques de Paris 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/","url":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/","name":"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png","datePublished":"2024-09-04T12:45:15+00:00","dateModified":"2024-09-04T18:29:16+00:00","description":"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Dorian Foulon poursuit la moisson tricolore en cyclisme, avec le bronze sur le contre-la-montre C5.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Dorian-Foulon-en-bronze-sur-le-contre-la-montre-categorie-C5-1.png","width":1200,"height":674,"caption":"Cyclisme sur route Jeux Paralympiques 2024 Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-dorian-foulon-en-bronze-sur-le-contre-la-montre-categorie-c5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Cyclisme sur route Jeux Paralympiques 2024 : Dorian Foulon en bronze sur le contre-la-montre cat\u00e9gorie C5"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/517620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=517620"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/517620\/revisions"}],"predecessor-version":[{"id":517658,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/517620\/revisions\/517658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/517809"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=517620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=517620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=517620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}