{"id":517940,"date":"2024-09-05T15:11:42","date_gmt":"2024-09-05T13:11:42","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=517940&#038;preview=true&#038;preview_id=517940"},"modified":"2024-09-05T19:43:44","modified_gmt":"2024-09-05T17:43:44","slug":"cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/","title":{"rendered":"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 &#8211; Lo\u00efc Vergnaud n&rsquo;a rien pu faire face \u00e0 Mitch Valize. D\u00e9j\u00e0 deuxi\u00e8me sur le contre-la-montre hier, le coureur fran\u00e7ais remporte la m\u00e9daille d&rsquo;argent sur la course en ligne.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/jeux-paralympiques-paris-2024\/\">L\u2019actualit\u00e9 des Jeux Paralympiques de Paris 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Quatre fois <a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-le-contre-la-montre-categorie-h5\/\">m\u00e9daill\u00e9 d\u2019argent<\/a> sur les Jeux paralympiques, et maintenant une 5e. <b>Lo\u00efc Vergnaud<\/b> poursuit la moisson fran\u00e7aise sur le para cyclisme. Apr\u00e8s les 11 m\u00e9dailles d\u2019hier (dont 4 en or), et celle <a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-le-double-dore-de-florian-jouanny-sur-la-course-en-ligne-h1-2\/\">en or de <b>Florian Jouanny<\/b><\/a> ce matin, c\u2019est au tour de Lo\u00efc Vergnaud de s\u2019illustrer sur les routes de <b>Clichy-sous-Bois.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p style=\"text-align: justify;\">En d\u00e9but de course, une chute chamboule le sc\u00e9nario. <b>Tim de Vries<\/b>, \u00e9quipier du grand favori <b>Mitch Valize<\/b>, n\u2019a jamais r\u00e9ussi \u00e0 revenir sur le groupe de t\u00eate. \u00c0 la fin du 1er tour, de Vries compte plus de 40 secondes de retard sur les cinq hommes de t\u00eate. Au sein de ce groupe, Vergnaud tente plusieurs attaques. Derri\u00e8re, Valize a \u00e9t\u00e9 oblig\u00e9 de r\u00e9agir. Le N\u00e9erlandais a fait exploser tout le monde dans la c\u00f4te de <strong>Courtry<\/strong>, sauf le Fran\u00e7ais.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\">Une gestion parfaite de Lo\u00efc Vergnaud<\/h2>\n<p style=\"text-align: justify;\">D\u00e8s lors, les deux premi\u00e8res places du podium sont d\u00e9finies, avec 20 secondes d\u2019avance \u00e0 la mi-course. Reste \u00e0 conna\u00eetre l\u2019ordre. Dans le 3e passage de la c\u00f4te de Courtry, <strong>Mitch Valize<\/strong> fait la d\u00e9cision, distan\u00e7ant son concurrent. Au passage sur la ligne, \u00e0 l\u2019entame du dernier tour, Vergnaud compte 43 secondes de retard sur son adversaire n\u00e9erlandais. Derri\u00e8re, <strong>Luis Costa<\/strong> et <strong>Pavlo Bal<\/strong> sont \u00e0 1.50 minute de la 2e place.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/Paris2024?src=hash&amp;ref_src=twsrc%5Etfw\">#Paris2024<\/a> | \ud83c\uddeb\ud83c\uddf7 Lo\u00efc Vergnaud accuse le coup, il se fait distancer par Mitch Valize. \ud83c\uddf3\ud83c\uddf1<\/p>\n<p>Il va d\u00e9sormais tenter de s\u00e9curiser la 2e place synonyme de m\u00e9daille d&rsquo;argent.<\/p>\n<p>\ud83d\udcfa Suivez les <a href=\"https:\/\/twitter.com\/hashtag\/JeuxParalympiques?src=hash&amp;ref_src=twsrc%5Etfw\">#JeuxParalympiques<\/a> en direct : <a href=\"https:\/\/t.co\/hHHwOiAOqk\">https:\/\/t.co\/hHHwOiAOqk<\/a> <a href=\"https:\/\/t.co\/qv4gsmgwKv\">pic.twitter.com\/qv4gsmgwKv<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1831672262514159728?ref_src=twsrc%5Etfw\">September 5, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">La gestion est parfaite du c\u00f4t\u00e9 fran\u00e7ais, qui ne s\u2019est pas mis dans le rouge pour suivre Valize, bien trop fort sur cette olympiade. <strong>Mitch Valize<\/strong> remporte la m\u00e9daille d\u2019or, avec 1.15 minute d\u2019avance sur la 2e place. \u00c0 45 ans, <strong>Lo\u00efc Vergnaud<\/strong> remporte la m\u00e9daille d\u2019argent des Jeux paralympiques de Paris 2024 dans la cat\u00e9gorie H5, la 13e pour le para-cyclisme sur route en deux jours.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">VICE-CHAMPION PARALYMPIQUE \ud83e\udd48<\/p>\n<p>Notre cycliste remporte deux belles m\u00e9dailles d&rsquo;argent, sur le contre-la-montre et la course en ligne.<a href=\"https:\/\/twitter.com\/hashtag\/AllezLesBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#AllezLesBleus<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Paris2024?src=hash&amp;ref_src=twsrc%5Etfw\">#Paris2024<\/a> <a href=\"https:\/\/t.co\/4ycF9zWLkK\">pic.twitter.com\/4ycF9zWLkK<\/a><\/p>\n<p>\u2014 Equipe France (@EquipeFRA) <a href=\"https:\/\/twitter.com\/EquipeFRA\/status\/1831680406568972313?ref_src=twsrc%5Etfw\">September 5, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo\u00efc Vergnaud en argent sur la course en ligne (H5)<\/p>\n","protected":false},"author":88,"featured_media":518141,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2307,21286],"tags":[16878,30151,34960,1004,24],"class_list":["post-517940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme","category-jeux-paralympiques-paris-2024","tag-breve","tag-jeux-paralympiques-2024","tag-jeux-paralympiques-de-paris","tag-paris-2024","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)<\/title>\n<meta name=\"description\" content=\"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Lo\u00efc Vergnaud n&#039;a rien pu faire face \u00e0 Mitch Valize. D\u00e9j\u00e0 deuxi\u00e8me sur le contre-la-montre hier, le coureur fran\u00e7ais remporte la m\u00e9daille d&#039;argent sur la course en ligne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)\" \/>\n<meta property=\"og:description\" content=\"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Lo\u00efc Vergnaud n&#039;a rien pu faire face \u00e0 Mitch Valize. D\u00e9j\u00e0 deuxi\u00e8me sur le contre-la-montre hier, le coureur fran\u00e7ais remporte la m\u00e9daille d&#039;argent sur la course en ligne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-05T13:11:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-05T17:43:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Paul Lalevee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/\"},\"author\":{\"name\":\"Paul Lalevee\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd\"},\"headline\":\"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)\",\"datePublished\":\"2024-09-05T13:11:42+00:00\",\"dateModified\":\"2024-09-05T17:43:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/\"},\"wordCount\":450,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png\",\"keywords\":[\"br\u00e8ve\",\"Jeux Paralympiques 2024\",\"Jeux Paralympiques de Paris\",\"Paris 2024\",\"sport\"],\"articleSection\":[\"Cyclisme\",\"Jeux Paralympiques de Paris 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/\",\"name\":\"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png\",\"datePublished\":\"2024-09-05T13:11:42+00:00\",\"dateModified\":\"2024-09-05T17:43:44+00:00\",\"description\":\"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Lo\u00efc Vergnaud n'a rien pu faire face \u00e0 Mitch Valize. D\u00e9j\u00e0 deuxi\u00e8me sur le contre-la-montre hier, le coureur fran\u00e7ais remporte la m\u00e9daille d'argent sur la course en ligne.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Cyclisme sur route Jeux Paralympiques 2024 Lo\u00efc Vergnaud en argent sur la course en ligne (H5) (1)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd\",\"name\":\"Paul Lalevee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"caption\":\"Paul Lalevee\"},\"description\":\"La bulle Disney pendant le Covid, le Tour 2019, la Coupe du monde 2018. Ces trois \u00e9v\u00e9nements majeurs sont ancr\u00e9s dans ma t\u00eate de fan de sport, n\u00e9gativement ou positivement. Passionn\u00e9 de sport depuis l'enfance, j'ai d\u00e9cid\u00e9 de mettre ma passion de l'\u00e9criture au service de cette premi\u00e8re passion.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/paul-lalevee\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)","description":"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Lo\u00efc Vergnaud n'a rien pu faire face \u00e0 Mitch Valize. D\u00e9j\u00e0 deuxi\u00e8me sur le contre-la-montre hier, le coureur fran\u00e7ais remporte la m\u00e9daille d'argent sur la course en ligne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/","og_locale":"fr_FR","og_type":"article","og_title":"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)","og_description":"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Lo\u00efc Vergnaud n'a rien pu faire face \u00e0 Mitch Valize. D\u00e9j\u00e0 deuxi\u00e8me sur le contre-la-montre hier, le coureur fran\u00e7ais remporte la m\u00e9daille d'argent sur la course en ligne.","og_url":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-09-05T13:11:42+00:00","article_modified_time":"2024-09-05T17:43:44+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png","type":"image\/png"}],"author":"Paul Lalevee","twitter_card":"summary_large_image","twitter_title":"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/"},"author":{"name":"Paul Lalevee","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd"},"headline":"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)","datePublished":"2024-09-05T13:11:42+00:00","dateModified":"2024-09-05T17:43:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/"},"wordCount":450,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png","keywords":["br\u00e8ve","Jeux Paralympiques 2024","Jeux Paralympiques de Paris","Paris 2024","sport"],"articleSection":["Cyclisme","Jeux Paralympiques de Paris 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/","url":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/","name":"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png","datePublished":"2024-09-05T13:11:42+00:00","dateModified":"2024-09-05T17:43:44+00:00","description":"CYCLISME SUR ROUTE JEUX PARALYMPIQUES 2024 - Lo\u00efc Vergnaud n'a rien pu faire face \u00e0 Mitch Valize. D\u00e9j\u00e0 deuxi\u00e8me sur le contre-la-montre hier, le coureur fran\u00e7ais remporte la m\u00e9daille d'argent sur la course en ligne.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Cyclisme-sur-route-Jeux-Paralympiques-2024-Loic-Vergnaud-en-argent-sur-la-course-en-ligne-H5-1.png","width":1200,"height":674,"caption":"Cyclisme sur route Jeux Paralympiques 2024 Lo\u00efc Vergnaud en argent sur la course en ligne (H5) (1)"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/cyclisme-sur-route-jeux-paralympiques-2024-loic-vergnaud-en-argent-sur-la-course-en-ligne-h5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Cyclisme sur route Jeux Paralympiques 2024 : Lo\u00efc Vergnaud en argent sur la course en ligne (H5)"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd","name":"Paul Lalevee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","caption":"Paul Lalevee"},"description":"La bulle Disney pendant le Covid, le Tour 2019, la Coupe du monde 2018. Ces trois \u00e9v\u00e9nements majeurs sont ancr\u00e9s dans ma t\u00eate de fan de sport, n\u00e9gativement ou positivement. Passionn\u00e9 de sport depuis l'enfance, j'ai d\u00e9cid\u00e9 de mettre ma passion de l'\u00e9criture au service de cette premi\u00e8re passion.","url":"https:\/\/dicodusport.fr\/blog\/author\/paul-lalevee\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/517940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=517940"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/517940\/revisions"}],"predecessor-version":[{"id":518142,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/517940\/revisions\/518142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/518141"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=517940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=517940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=517940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}