{"id":518264,"date":"2024-09-06T07:45:03","date_gmt":"2024-09-06T05:45:03","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=518264&#038;preview=true&#038;preview_id=518264"},"modified":"2024-09-06T07:45:03","modified_gmt":"2024-09-06T05:45:03","slug":"us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/","title":{"rendered":"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l&rsquo;affiche de la finale"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>US OPEN 2024 &#8211; Pour la seconde ann\u00e9e cons\u00e9cutive, il y aura une Am\u00e9ricaine en finale de l&rsquo;US Open. Si Emma Navarro n&rsquo;a pas r\u00e9sist\u00e9 aux coups d&rsquo;Aryna Sabalenka, Jessica Pegula est, elle, parvenue \u00e0 renverser le match face \u00e0 la Tch\u00e8que Karolina Muchova.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/tennis\/us-open-2024\/\">Toute l&rsquo;actualit\u00e9 de l&rsquo;US Open 2024<\/a><\/strong><\/li>\n<\/ul>\n<h2>Sabalenka, premi\u00e8re finaliste de l&rsquo;US Open<\/h2>\n<p style=\"text-align: justify;\">Premi\u00e8res \u00e0 ouvrir le bal sur le <em>Arthur Ashe Stadium<\/em>, <strong>Emma Navarro<\/strong> et <strong>Aryna Sabalenka<\/strong> avaient toutes deux le m\u00eame objectif, atteindre la finale. Une premi\u00e8re en Grand Chelem pour l\u2019Am\u00e9ricaine qui pouvait compter sur le soutien du public, une seconde cons\u00e9cutive \u00e0 l\u2019US Open pour la B\u00e9larusse. Et malheureusement pour la locale, la hi\u00e9rarchie a \u00e9t\u00e9 respect\u00e9e, m\u00eame si le bras de la finaliste de l\u2019ann\u00e9e pass\u00e9e s\u2019est quelque peu tendu pour conclure.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 voir \u00e9galement &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/us-open-2024-le-tableau-de-simple-dames\/\">Le tableau de simple dames<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Forte de 16 coups gagnants, <strong>Sabalenka<\/strong> prenait ais\u00e9ment la premi\u00e8re manche. Mais \u00e7a se compliquait pour la n\u00b02 mondiale dans le second acte malgr\u00e9 un avantage cons\u00e9quent. Car <strong>Emma Navarro<\/strong> n\u2019a rien l\u00e2ch\u00e9. Men\u00e9e 5-2, cette derni\u00e8re revenait \u00e0 5-5 alors que la B\u00e9larusse servait pour le match. Puis c\u2019est elle qui se d\u00e9tachait 2-0 dans le tie-break. Ce qui a vite fait r\u00e9agir <strong>Aryna Sabalenka<\/strong> qui alignait les sept derniers points pour s\u2019offrir une 11<sup>\u00e8me<\/sup> victoire cons\u00e9cutive.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">ARYNA SABALENKA RETURNS TO THE FINAL! <a href=\"https:\/\/t.co\/VO26TIDNhu\">pic.twitter.com\/VO26TIDNhu<\/a><\/p>\n<p>\u2014 US Open Tennis (@usopen) <a href=\"https:\/\/twitter.com\/usopen\/status\/1831856524865790150?ref_src=twsrc%5Etfw\">September 6, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Malgr\u00e9 cette d\u00e9faite, <strong>Emma Navarro<\/strong> int\u00e8gre le top 10 gr\u00e2ce \u00e0 cette magnifique quinzaine et pointe \u00e0 la 8<sup>\u00e8me<\/sup> place WTA. En cas d\u2019ultime succ\u00e8s samedi, la double vainqueure de l\u2019Open d\u2019Australie (2023-2024) pourrait quant \u00e0 elle devenir la premi\u00e8re joueuse \u00e0 s\u2019imposer sur les deux Grands Chelem de dur la m\u00eame ann\u00e9e depuis <b>Angelique Kerber<\/b>\u00a0en 2016. L\u2019an dernier, <strong>Sabalenka<\/strong> s\u2019\u00e9tait inclin\u00e9e en finale contre <strong>Coco Gauff<\/strong>. Elle sera une nouvelle fois oppos\u00e9e \u00e0 une Am\u00e9ricaine, <strong>Jessica Pegula<\/strong>, tombeuse de <strong>Karolina Muchova<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Jessica Pegula, retour au troisi\u00e8me rang mondial<\/strong><\/h2>\n<p style=\"text-align: justify;\">Sur deux Am\u00e9ricaines, il y en aura bien une en demi-finales de l&rsquo;US Open. Entre <strong>Jessica Pegula<\/strong> et <strong>Karolina Muchova<\/strong>, qui n\u2019avaient pas conc\u00e9d\u00e9 le moindre set dans cette \u00e9dition, le classement a l\u00e0 aussi \u00e9t\u00e9 suivi \u00e0 la lettre. Pourtant, c\u2019est la Tch\u00e8que qui entrait le mieux dans le duel. Plus exp\u00e9riment\u00e9 \u00e0 ce stade d\u2019un Majeur, <strong>Muchova<\/strong> pliait en moins de 30 minutes la premi\u00e8re manche 6-1 face \u00e0 une <strong>Pegula<\/strong> prise par l\u2019enjeu. La locale avait du mal \u00e0 trouver les r\u00e9ponses, break\u00e9e imm\u00e9diatement dans le deuxi\u00e8me set. Mais de plus en plus agressive, elle refaisait d\u2019abord son retard puis revenait \u00e0 hauteur dans le match. La finaliste de Roland-Garros 2023 avait beau s\u2019\u00e9chapper un instant de la ferveur populaire, son retour sur le court ne changeait rien.<\/p>\n<p style=\"text-align: justify;\"><strong>Jessica Pegula<\/strong> avait repris l\u2019ascendant psychologique et capitalisait en prenant le service de <strong>Muchova<\/strong> \u00e0 l\u2019entame du troisi\u00e8me set, 2-0. La Tch\u00e8que avait une petite occasion de d\u00e9breaker mais celle-ci terminait dans le filet. Pire encore, c\u2019est sur sa mise en jeu qu\u2019elle laissait filer la rencontre. Emport\u00e9e par la foule, l\u2019Am\u00e9ricaine s&rsquo;en sort 1-6, 6-4, 6-2 et vivra une premi\u00e8re finale en Grand Chelem, en plus de reprendre (apr\u00e8s 2022) la place de n\u00b03 mondiale au d\u00e9triment d\u2019<strong>Elena Rybakina<\/strong>. En point de mire dor\u00e9navant, <strong>Aryna Sabalenka<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Believe it, Jessica Pegula!<\/p>\n<p>You&rsquo;re in a Grand Slam final! <a href=\"https:\/\/t.co\/4VYlp8GtPq\">pic.twitter.com\/4VYlp8GtPq<\/a><\/p>\n<p>\u2014 US Open Tennis (@usopen) <a href=\"https:\/\/twitter.com\/usopen\/status\/1831898225709634007?ref_src=twsrc%5Etfw\">September 6, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Aryna Sabalenka vs Jessica Pegula, l&rsquo;affiche de la finale<\/p>\n","protected":false},"author":18,"featured_media":518268,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47091],"tags":[32415,7634,16878,17085],"class_list":["post-518264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-us-open","tag-actu","tag-aryna-sabalenka","tag-breve","tag-jessica-pegula"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l&#039;affiche de la finale<\/title>\n<meta name=\"description\" content=\"US OPEN 2024 - Jessica Pegula et Aryna Sabalenka, respectivement tombeuses de Navarro et Muchova, s&#039;affronteront en finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l&#039;affiche de la finale\" \/>\n<meta property=\"og:description\" content=\"US OPEN 2024 - Jessica Pegula et Aryna Sabalenka, respectivement tombeuses de Navarro et Muchova, s&#039;affronteront en finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-06T05:45:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l&#039;affiche de la finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l&rsquo;affiche de la finale\",\"datePublished\":\"2024-09-06T05:45:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/\"},\"wordCount\":641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png\",\"keywords\":[\"actu\",\"Aryna Sabalenka\",\"br\u00e8ve\",\"Jessica Pegula\"],\"articleSection\":[\"US Open\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/\",\"name\":\"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l'affiche de la finale\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png\",\"datePublished\":\"2024-09-06T05:45:03+00:00\",\"description\":\"US OPEN 2024 - Jessica Pegula et Aryna Sabalenka, respectivement tombeuses de Navarro et Muchova, s'affronteront en finale.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png\",\"width\":1200,\"height\":674,\"caption\":\"US Open 2024 Aryna Sabalenka vs Jessica Pegula, l'affiche de la finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l&#8217;affiche de la finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l'affiche de la finale","description":"US OPEN 2024 - Jessica Pegula et Aryna Sabalenka, respectivement tombeuses de Navarro et Muchova, s'affronteront en finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l'affiche de la finale","og_description":"US OPEN 2024 - Jessica Pegula et Aryna Sabalenka, respectivement tombeuses de Navarro et Muchova, s'affronteront en finale.","og_url":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2024-09-06T05:45:03+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l'affiche de la finale","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l&rsquo;affiche de la finale","datePublished":"2024-09-06T05:45:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/"},"wordCount":641,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png","keywords":["actu","Aryna Sabalenka","br\u00e8ve","Jessica Pegula"],"articleSection":["US Open"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/","url":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/","name":"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l'affiche de la finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png","datePublished":"2024-09-06T05:45:03+00:00","description":"US OPEN 2024 - Jessica Pegula et Aryna Sabalenka, respectivement tombeuses de Navarro et Muchova, s'affronteront en finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/US-Open-2024-Aryna-Sabalenka-vs-Jessica-Pegula-laffiche-de-la-finale.png","width":1200,"height":674,"caption":"US Open 2024 Aryna Sabalenka vs Jessica Pegula, l'affiche de la finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/us-open-2024-aryna-sabalenka-vs-jessica-pegula-l-affiche-de-la-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"US Open 2024 : Aryna Sabalenka vs Jessica Pegula, l&#8217;affiche de la finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=518264"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518264\/revisions"}],"predecessor-version":[{"id":518269,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518264\/revisions\/518269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/518268"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=518264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=518264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=518264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}