{"id":518634,"date":"2024-09-07T14:19:53","date_gmt":"2024-09-07T12:19:53","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=518634&#038;preview=true&#038;preview_id=518634"},"modified":"2024-09-07T14:35:03","modified_gmt":"2024-09-07T12:35:03","slug":"finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/","title":{"rendered":"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : La France s&rsquo;incline face aux Pays-Bas"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FINALE WOMEN&rsquo;S SERIES 3\u00d73 2024 HANGZHOU &#8211; Pour son deuxi\u00e8me match, l&rsquo;\u00e9quipe de France s&rsquo;est inclin\u00e9e face aux Pays-Bas.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/programme-et-resultats-finale-womens-series-3x3-2024-hangzhou\/\"><strong>Programme et r\u00e9sultats Finale Women&rsquo;s Series 3X3 2024 Hangzhou<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Apr\u00e8s leur <a title=\"Finale Women\u2019s Series 3\u00d73 2024 Hangzhou : Les Bleues d\u00e9butent par une victoire face \u00e0 la R\u00e9publique Tch\u00e8que\" href=\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-debutent-par-une-victoire-face-a-la-republique-tcheque\/\" target=\"_blank\" rel=\"noopener\">victoire inaugurale face \u00e0 la R\u00e9publique tch\u00e8que<\/a>, les Bleues encha\u00eenaient face aux Pays-Bas.<\/p>\n<h2>Les Bleus en \u00e9chec au tir<\/h2>\n<p style=\"text-align: justify;\">Les Fran\u00e7aises prennent les commandes du match, mais les Pays-Bas restent au contact (3-3). 4 fautes de part et d&rsquo;autre, aucune \u00e9quipe ne parvient \u00e0 se d\u00e9tacher \u00e0 la mi-match (8-8). Mais les Fran\u00e7aises sont les premi\u00e8res \u00e0 tomber dans la p\u00e9nalit\u00e9 (6 fautes), et ne sont pas en r\u00e9ussite \u00e0 2 points. Au contraire de <strong>Noortje Driessen <\/strong>(11-8). S&rsquo;en suivent 3 \u00e9checs \u00e0 2 points pour les Bleues et autant de rebonds. Mais sans marquer. La d\u00e9fense agressive d&rsquo;<strong>Anna Ngo Ndjock <\/strong>permet aux Fran\u00e7aises de r\u00e9cup\u00e9rer des ballons.<strong><br \/>\n<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"ht\">\ud83d\udca8 Limouzin. is. FAST! \u26a1\ufe0f\ud83c\uddeb\ud83c\uddf7<a href=\"https:\/\/twitter.com\/hashtag\/3x3WSHangzhou?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3WSHangzhou<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/3x3WS?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3WS<\/a> <a href=\"https:\/\/t.co\/GxBtssy3Kp\">pic.twitter.com\/GxBtssy3Kp<\/a><\/p>\n<p>\u2014 3&#215;3 Basketball |FIBA3x3 (@FIBA3x3) <a href=\"https:\/\/twitter.com\/FIBA3x3\/status\/1832389529115795886?ref_src=twsrc%5Etfw\">September 7, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Dans les 2 derni\u00e8res minutes, les N\u00e9erlandaises sont envoy\u00e9es sur la ligne des lancers francs. Heureusement pour les Bleues, <strong>Zo\u00eb Slagter <\/strong>n&rsquo;en marque qu&rsquo;un sur les trois. Mais les Pays-Bas gardent leur avance (13-11). Si les Fran\u00e7aises sont furtivement revenues \u00e0 -1 dans la derni\u00e8res minute (13-12), un panier rapide des N\u00e9erlandaises leur a permis de ne pas trop douter. La derni\u00e8res chance est \u00e9videmment pour <strong>Marie-\u00c8ve Paget<\/strong> \u00e0 2 points mais quand \u00e7a ne veut pas&#8230; Avec 3 secondes \u00e0 jouer, <strong>Hortense Limouzin\u00a0<\/strong>fait faute. Driessen rate ses deux lancers mais les Pays-Bas sont au rebond. Les Fran\u00e7aises s&rsquo;inclinent 12-14 avec un cinglant 0\/12 \u00e0 2 points qui les ont plomb\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FINALE WOMEN&rsquo;S SERIES 3\u00d73 2024 HANGZHOU &#8211; Pour son deuxi\u00e8me match, l&rsquo;\u00e9quipe de France s&rsquo;est inclin\u00e9e face aux Pays-Bas.<\/p>\n","protected":false},"author":12,"featured_media":518653,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[27116],"tags":[18233,9140,16878],"class_list":["post-518634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","tag-3x3","tag-basket-3x3","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finale Women\u2019s Series 3x3 2024 Hangzhou : La France s&#039;incline face aux Pays-Bas<\/title>\n<meta name=\"description\" content=\"FINALE WOMEN&#039;S SERIES 3\u00d73 2024 HANGZHOU - Pour son deuxi\u00e8me match, l&#039;\u00e9quipe de France s&#039;est inclin\u00e9e face aux Pays-Bas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finale Women\u2019s Series 3x3 2024 Hangzhou : La France s&#039;incline face aux Pays-Bas\" \/>\n<meta property=\"og:description\" content=\"FINALE WOMEN&#039;S SERIES 3\u00d73 2024 HANGZHOU - Pour son deuxi\u00e8me match, l&#039;\u00e9quipe de France s&#039;est inclin\u00e9e face aux Pays-Bas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-07T12:19:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-07T12:35:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Finale Women\u2019s Series 3x3 2024 Hangzhou : La France s&#039;incline face aux Pays-Bas\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : La France s&rsquo;incline face aux Pays-Bas\",\"datePublished\":\"2024-09-07T12:19:53+00:00\",\"dateModified\":\"2024-09-07T12:35:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png\",\"keywords\":[\"3X3\",\"Basket 3x3\",\"br\u00e8ve\"],\"articleSection\":[\"Basket-ball 3x3\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/\",\"name\":\"Finale Women\u2019s Series 3x3 2024 Hangzhou : La France s'incline face aux Pays-Bas\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png\",\"datePublished\":\"2024-09-07T12:19:53+00:00\",\"dateModified\":\"2024-09-07T12:35:03+00:00\",\"description\":\"FINALE WOMEN'S SERIES 3\u00d73 2024 HANGZHOU - Pour son deuxi\u00e8me match, l'\u00e9quipe de France s'est inclin\u00e9e face aux Pays-Bas.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png\",\"width\":1200,\"height\":674,\"caption\":\"Finale Women\u2019s Series 3x3 2024 Hangzhou La France s'incline face aux Pays-Bas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : La France s&#8217;incline face aux Pays-Bas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finale Women\u2019s Series 3x3 2024 Hangzhou : La France s'incline face aux Pays-Bas","description":"FINALE WOMEN'S SERIES 3\u00d73 2024 HANGZHOU - Pour son deuxi\u00e8me match, l'\u00e9quipe de France s'est inclin\u00e9e face aux Pays-Bas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/","og_locale":"fr_FR","og_type":"article","og_title":"Finale Women\u2019s Series 3x3 2024 Hangzhou : La France s'incline face aux Pays-Bas","og_description":"FINALE WOMEN'S SERIES 3\u00d73 2024 HANGZHOU - Pour son deuxi\u00e8me match, l'\u00e9quipe de France s'est inclin\u00e9e face aux Pays-Bas.","og_url":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-09-07T12:19:53+00:00","article_modified_time":"2024-09-07T12:35:03+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Finale Women\u2019s Series 3x3 2024 Hangzhou : La France s'incline face aux Pays-Bas","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : La France s&rsquo;incline face aux Pays-Bas","datePublished":"2024-09-07T12:19:53+00:00","dateModified":"2024-09-07T12:35:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png","keywords":["3X3","Basket 3x3","br\u00e8ve"],"articleSection":["Basket-ball 3x3"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/","url":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/","name":"Finale Women\u2019s Series 3x3 2024 Hangzhou : La France s'incline face aux Pays-Bas","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png","datePublished":"2024-09-07T12:19:53+00:00","dateModified":"2024-09-07T12:35:03+00:00","description":"FINALE WOMEN'S SERIES 3\u00d73 2024 HANGZHOU - Pour son deuxi\u00e8me match, l'\u00e9quipe de France s'est inclin\u00e9e face aux Pays-Bas.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-Series-3x3-2024-Hangzhou-La-France-sincline-face-aux-Pays-Bas.png","width":1200,"height":674,"caption":"Finale Women\u2019s Series 3x3 2024 Hangzhou La France s'incline face aux Pays-Bas"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-la-france-sincline-face-aux-pays-bas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : La France s&#8217;incline face aux Pays-Bas"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=518634"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518634\/revisions"}],"predecessor-version":[{"id":518652,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518634\/revisions\/518652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/518653"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=518634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=518634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=518634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}