{"id":518985,"date":"2024-09-08T14:01:54","date_gmt":"2024-09-08T12:01:54","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=518985&#038;preview=true&#038;preview_id=518985"},"modified":"2024-09-08T14:07:56","modified_gmt":"2024-09-08T12:07:56","slug":"finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/","title":{"rendered":"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FINALE WOMEN&rsquo;S SERIES 3\u00d73 2024 HANGZHOU &#8211; Vainqueurs de leur demi-finale face \u00e0 l&rsquo;Italie, les Bleues sont en finale.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir domin\u00e9 la Chine U24, la France a \u00e9cart\u00e9 l&rsquo;Italie.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/programme-et-resultats-finale-womens-series-3x3-2024-hangzhou\/\"><strong>Programme et r\u00e9sultats Finale Women&rsquo;s Series 3X3 2024 Hangzhou<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les Bleues d\u00e9marrent en trombe par un 3-0. Les deux \u00e9quipes sont peu en r\u00e9ussite \u00e0 2 points, les Fran\u00e7aises appuient alors \u00e0 l&rsquo;int\u00e9rieur. Jusqu&rsquo;au panier \u00e0 2 points de <strong>Marie Man\u00e9<\/strong> qui a la main chaude aujourd&rsquo;hui, pour cr\u00e9er un premier \u00e9cart (4-9). Les Italiennes ont trop peu utilis\u00e9 leur diff\u00e9rence de taille sous le panier mais ont fini par en jouer en fin de match (8-11).<\/p>\n<p style=\"text-align: justify;\">Et suite aux \u00e9checs fran\u00e7ais, elles se sont rapproch\u00e9es \u00e0 11-12 dans la derni\u00e8re minute. Mais <strong>Hortense Limouzin<\/strong> s&rsquo;est montr\u00e9e intraitable en d\u00e9fense. Et <strong>Anna Ngo Ndjock<\/strong> va marquer un 2-points crucial, comme en d\u00e9but de rencontre. Les Bleues s&rsquo;imposent finalement 15-11 et se qualifient pour la finale ! Rendez-vous \u00e0 14h50.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83e\ude99 DIMING AND DISHING! \ud83d\udd25\ud83c\uddeb\ud83c\uddf7<\/p>\n<p>\ud83e\udd29 France are FINAL-BOUND! \ud83c\udfc6<a href=\"https:\/\/twitter.com\/hashtag\/3x3WSHangzhou?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3WSHangzhou<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/3x3WS?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3WS<\/a> <a href=\"https:\/\/t.co\/UwBPwifwcM\">pic.twitter.com\/UwBPwifwcM<\/a><\/p>\n<p>\u2014 3&#215;3 Basketball |FIBA3x3 (@FIBA3x3) <a href=\"https:\/\/twitter.com\/FIBA3x3\/status\/1832749762409349204?ref_src=twsrc%5Etfw\">September 8, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direction la finale pour la France.<\/p>\n","protected":false},"author":12,"featured_media":518976,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[27116],"tags":[18233,32415,9140,16878],"class_list":["post-518985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","tag-3x3","tag-actu","tag-basket-3x3","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finale Women\u2019s Series 3x3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale<\/title>\n<meta name=\"description\" content=\"FINALE WOMEN&#039;S SERIES 3\u00d73 2024 Hangzhou - La France s&#039;est impos\u00e9e face \u00e0 l&#039;Italie et jouera la grande finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finale Women\u2019s Series 3x3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale\" \/>\n<meta property=\"og:description\" content=\"FINALE WOMEN&#039;S SERIES 3\u00d73 2024 Hangzhou - La France s&#039;est impos\u00e9e face \u00e0 l&#039;Italie et jouera la grande finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-08T12:01:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-08T12:07:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Finale Women\u2019s Series 3x3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale\",\"datePublished\":\"2024-09-08T12:01:54+00:00\",\"dateModified\":\"2024-09-08T12:07:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/\"},\"wordCount\":209,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png\",\"keywords\":[\"3X3\",\"actu\",\"Basket 3x3\",\"br\u00e8ve\"],\"articleSection\":[\"Basket-ball 3x3\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/\",\"name\":\"Finale Women\u2019s Series 3x3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png\",\"datePublished\":\"2024-09-08T12:01:54+00:00\",\"dateModified\":\"2024-09-08T12:07:56+00:00\",\"description\":\"FINALE WOMEN'S SERIES 3\u00d73 2024 Hangzhou - La France s'est impos\u00e9e face \u00e0 l'Italie et jouera la grande finale.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finale Women\u2019s Series 3x3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale","description":"FINALE WOMEN'S SERIES 3\u00d73 2024 Hangzhou - La France s'est impos\u00e9e face \u00e0 l'Italie et jouera la grande finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"Finale Women\u2019s Series 3x3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale","og_description":"FINALE WOMEN'S SERIES 3\u00d73 2024 Hangzhou - La France s'est impos\u00e9e face \u00e0 l'Italie et jouera la grande finale.","og_url":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-09-08T12:01:54+00:00","article_modified_time":"2024-09-08T12:07:56+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Finale Women\u2019s Series 3x3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale","datePublished":"2024-09-08T12:01:54+00:00","dateModified":"2024-09-08T12:07:56+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/"},"wordCount":209,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png","keywords":["3X3","actu","Basket 3x3","br\u00e8ve"],"articleSection":["Basket-ball 3x3"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/","url":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/","name":"Finale Women\u2019s Series 3x3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png","datePublished":"2024-09-08T12:01:54+00:00","dateModified":"2024-09-08T12:07:56+00:00","description":"FINALE WOMEN'S SERIES 3\u00d73 2024 Hangzhou - La France s'est impos\u00e9e face \u00e0 l'Italie et jouera la grande finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Finale-Womens-series-demi-finale.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/finale-womens-series-3x3-2024-hangzhou-les-bleues-qualifiees-pour-la-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Finale Women\u2019s Series 3&#215;3 2024 Hangzhou : Les Bleues qualifi\u00e9es pour la finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=518985"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518985\/revisions"}],"predecessor-version":[{"id":519091,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/518985\/revisions\/519091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/518976"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=518985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=518985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=518985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}