{"id":51907,"date":"2019-10-20T18:31:10","date_gmt":"2019-10-20T16:31:10","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=51907&#038;preview=true&#038;preview_id=51907"},"modified":"2019-10-20T18:38:53","modified_gmt":"2019-10-20T16:38:53","slug":"super-league-vincent-luis-s-impose-en-patron-malte","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/","title":{"rendered":"Super League : Vincent Luis s&rsquo;impose en patron \u00e0 Malte"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Au terme d&rsquo;un week-end rondement men\u00e9, Vincent Luis a remport\u00e9 la manche de <a href=\"https:\/\/superleaguetriathlon.com\/\" target=\"_blank\" rel=\"noopener\">Super League<\/a> \u00e0 Malte. Le champion du monde en titre continue de surfer sur l&rsquo;ann\u00e9e 2019.<br \/>\n<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Sans rival en demi-finale ce samedi, le Fran\u00e7ais <strong>Vincent Luis<\/strong> a de nouveau \u00e9t\u00e9 imp\u00e9rial en finale ce dimanche apr\u00e8s-midi, \u00e0 Malte. Apr\u00e8s un contre-la-montre en cyclisme pour d\u00e9terminer l&rsquo;ordre de d\u00e9part, les triathl\u00e8tes qualifi\u00e9s ont d\u00fb r\u00e9aliser un double triathlon en finale (300 m de natation, 4 kilom\u00e8tres sur le v\u00e9lo et 1,6 km de course \u00e0 chaque fois).<\/p>\n<p style=\"text-align: justify;\">Le natif de Vesoul, num\u00e9ro un mondial et champion du monde fin ao\u00fbt, a r\u00e9gl\u00e9 dans la bosse finale le Norv\u00e9gien <strong>Kristian Blummenfelt<\/strong>. Le N\u00e9o-Z\u00e9landais <strong>Hayden Wilde<\/strong> compl\u00e8te le podium. <strong>Pierre Le Corre<\/strong> prend quant \u00e0 lui la 6\u00e8me place, devant un autre Fran\u00e7ais, le Manosquin <strong>Anthony Pujades<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Vincent Luis<\/strong>, 30 ans et vainqueur de l&rsquo;\u00e9dition de 2018\/2019 de la <strong>Super League<\/strong>, est bien parti pour r\u00e9cidiv\u00e9 lors de l&rsquo;exercice 2019\/2020, puisque <a href=\"https:\/\/dicodusport.fr\/blog\/cassandre-beaugrand-et-vincent-luis-s-imposent-sur-la-super-league-de-jersey\/\" target=\"_blank\" rel=\"noopener\">le Tricolore avait d\u00e9j\u00e0 remport\u00e9 la premi\u00e8re manche \u00e0 <strong>Jersey<\/strong><\/a>, fin septembre.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f44f;&#x1f1eb;&#x1f1f7; Vincent Luis s&rsquo;impose sur le triathlon de Malte !<a href=\"https:\/\/twitter.com\/hashtag\/lequipeTRIATHLON?src=hash&amp;ref_src=twsrc%5Etfw\">#lequipeTRIATHLON<\/a> <a href=\"https:\/\/t.co\/6OXtNl3LIF\">pic.twitter.com\/6OXtNl3LIF<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/1185934502532698112?ref_src=twsrc%5Etfw\">October 20, 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Cassandre Beaugrand frustr\u00e9e<\/h2>\n<p style=\"text-align: justify;\">Chez les dames, la victoire est revenue \u00e0 la championne du monde en titre, l&rsquo;Am\u00e9ricaine <strong>Katie Zaferes<\/strong>. C\u00f4t\u00e9 Bleues, grosse d\u00e9ception pour <strong>Cassandre Beaugrand<\/strong> : la native de Livry-Gargan, laur\u00e9ate de l&rsquo;\u00e9tape de <strong>Jersey<\/strong>, a \u00e9t\u00e9 victime d&rsquo;un incident m\u00e9canique en finale, lors de la derni\u00e8re portion en v\u00e9lo, alors m\u00eame qu&rsquo;elle \u00e9tait en t\u00eate de course. <strong>L\u00e9onie P\u00e9riault<\/strong> a pris la sixi\u00e8me place.<\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au terme d&rsquo;un week-end rondement men\u00e9, Vincent Luis a remport\u00e9 la manche de Super League \u00e0 Malte. Le champion du monde en titre continue de surfer sur l&rsquo;ann\u00e9e 2019.<\/p>\n","protected":false},"author":4,"featured_media":51908,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8303],"tags":[3795,589,1874],"class_list":["post-51907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-triathlon","tag-super-league","tag-triathlon","tag-vincent-luis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Super League : Vincent Luis s&#039;impose en patron \u00e0 Malte<\/title>\n<meta name=\"description\" content=\"Triathlon - Au terme d&#039;un week-end rondement men\u00e9, Vincent Luis a remport\u00e9, en costaud, la manche de Super League \u00e0 Malte\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Super League : Vincent Luis s&#039;impose en patron \u00e0 Malte\" \/>\n<meta property=\"og:description\" content=\"Triathlon - Au terme d&#039;un week-end rondement men\u00e9, Vincent Luis a remport\u00e9, en costaud, la manche de Super League \u00e0 Malte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-20T16:31:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-20T16:38:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Super League : Vincent Luis s&#039;impose en patron \u00e0 Malte\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Super League : Vincent Luis s&rsquo;impose en patron \u00e0 Malte\",\"datePublished\":\"2019-10-20T16:31:10+00:00\",\"dateModified\":\"2019-10-20T16:38:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png\",\"keywords\":[\"Super League\",\"triathlon\",\"Vincent Luis\"],\"articleSection\":[\"Triathlon\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/\",\"name\":\"Super League : Vincent Luis s'impose en patron \u00e0 Malte\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png\",\"datePublished\":\"2019-10-20T16:31:10+00:00\",\"dateModified\":\"2019-10-20T16:38:53+00:00\",\"description\":\"Triathlon - Au terme d'un week-end rondement men\u00e9, Vincent Luis a remport\u00e9, en costaud, la manche de Super League \u00e0 Malte\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png\",\"width\":800,\"height\":445,\"caption\":\"Super League Vincent Luis s'impose en patron \u00e0 Malte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Super League : Vincent Luis s&rsquo;impose en patron \u00e0 Malte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Super League : Vincent Luis s'impose en patron \u00e0 Malte","description":"Triathlon - Au terme d'un week-end rondement men\u00e9, Vincent Luis a remport\u00e9, en costaud, la manche de Super League \u00e0 Malte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/","og_locale":"fr_FR","og_type":"article","og_title":"Super League : Vincent Luis s'impose en patron \u00e0 Malte","og_description":"Triathlon - Au terme d'un week-end rondement men\u00e9, Vincent Luis a remport\u00e9, en costaud, la manche de Super League \u00e0 Malte","og_url":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2019-10-20T16:31:10+00:00","article_modified_time":"2019-10-20T16:38:53+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Super League : Vincent Luis s'impose en patron \u00e0 Malte","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Super League : Vincent Luis s&rsquo;impose en patron \u00e0 Malte","datePublished":"2019-10-20T16:31:10+00:00","dateModified":"2019-10-20T16:38:53+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png","keywords":["Super League","triathlon","Vincent Luis"],"articleSection":["Triathlon"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/","url":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/","name":"Super League : Vincent Luis s'impose en patron \u00e0 Malte","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png","datePublished":"2019-10-20T16:31:10+00:00","dateModified":"2019-10-20T16:38:53+00:00","description":"Triathlon - Au terme d'un week-end rondement men\u00e9, Vincent Luis a remport\u00e9, en costaud, la manche de Super League \u00e0 Malte","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/10\/Super-League-Vincent-Luis-simpose-en-patron-\u00e0-Malte.png","width":800,"height":445,"caption":"Super League Vincent Luis s'impose en patron \u00e0 Malte"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/super-league-vincent-luis-s-impose-en-patron-malte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Super League : Vincent Luis s&rsquo;impose en patron \u00e0 Malte"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/51907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=51907"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/51907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/51908"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=51907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=51907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=51907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}