{"id":519911,"date":"2024-09-12T18:45:12","date_gmt":"2024-09-12T16:45:12","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=519911&#038;preview=true&#038;preview_id=519911"},"modified":"2024-09-12T18:51:46","modified_gmt":"2024-09-12T16:51:46","slug":"marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/","title":{"rendered":"Marseille &#8211; Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2024-2025\/\" target=\"_blank\" rel=\"noopener\">LIGUE 1 2024-2025<\/a><b> &#8211; Ce samedi, Marseille re\u00e7oit Nice dans le cadre de la 4\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.<\/b><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<\/strong><a title=\"Classement Ligue 1 2024-2025\" href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2024-2025\/\" rel=\"\"><strong>Le classement de la Ligue 1<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Olympique de Marseille<\/strong> veut confirmer son bon d\u00e9but de saison face \u00e0 <strong>Nice<\/strong> ce samedi. Les <strong>Marseillais<\/strong> ont commenc\u00e9 la saison par une victoire sur la pelouse du <strong>Stade Brestois<\/strong> avant de conc\u00e9der le nul \u00e0 la maison face \u00e0 <strong>Reims<\/strong>. Les <strong>Marseillais<\/strong> ont ensuite battu <strong>Toulouse<\/strong> avant la tr\u00eave hivernale avec un doubl\u00e9 de leur recrue, <strong>Mason<\/strong> <strong>Greenwood<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Nice<\/strong> a fait de son c\u00f4t\u00e9 un faux d\u00e9part avec une d\u00e9faite 2-1 face \u00e0 <strong>Auxerre<\/strong> lors de la premi\u00e8re journ\u00e9e. Les <strong>Ni\u00e7ois<\/strong> ont ensuite conc\u00e9d\u00e9 le nul \u00e0 la maison face \u00e0 <strong>Toulouse<\/strong> avant de gagner leur premier match face \u00e0 Angers sur le score de 4-1. Une belle victoire des Aiglons malgr\u00e9 une rencontre termin\u00e9e \u00e0 10 apr\u00e8s le carton rouge de <strong>Mo\u00efse<\/strong> <strong>Bombito<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La saison pass\u00e9e, <strong>Nice<\/strong> s&rsquo;est impos\u00e9 \u00e0 l&rsquo;aller et les deux \u00e9quipes se sont s\u00e9par\u00e9es sur un match nul au retour. Chez les bookmakers, <strong>Marseille<\/strong> est favori pour cette rencontre face \u00e0 <strong>Nice<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Ligue 1 : Le Programme TV du match Marseille &#8211; Nice<\/h2>\n<h3 style=\"text-align: justify;\">Samedi 14 septembre 2024<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur beIN SPORTS 1<\/b><b>\u00a0: <\/b>D\u00e9but du match \u00e0<strong> 17h00.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les cotes de Marseille &#8211; Nice<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Samedi 14 septembre, 17h00<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Marseille<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/50955409?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 1.74<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/50955409?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 3.90<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Nice<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/50955409?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 4.40<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2024-2025 &#8211; Ce samedi, Marseille re\u00e7oit Nice dans le cadre de la 4\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.<\/p>\n","protected":false},"author":1,"featured_media":519914,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301,47045],"tags":[16878,17213,75,21872,21768,1554,446,460,8799],"class_list":["post-519911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-breve","tag-chaine","tag-football","tag-heure","tag-horaire","tag-ligue-1","tag-marseille","tag-nice","tag-programme-tv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marseille - Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2024-2025 - Ce samedi, Marseille re\u00e7oit Nice dans le cadre de la 4\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marseille - Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2024-2025 - Ce samedi, Marseille re\u00e7oit Nice dans le cadre de la 4\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-12T16:45:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-12T16:51:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Marseille - Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Marseille &#8211; Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1\",\"datePublished\":\"2024-09-12T16:45:12+00:00\",\"dateModified\":\"2024-09-12T16:51:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/\"},\"wordCount\":336,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png\",\"keywords\":[\"br\u00e8ve\",\"Cha\u00eene\",\"Football\",\"Heure\",\"Horaire\",\"Ligue 1\",\"Marseille\",\"Nice\",\"Programme TV\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/\",\"name\":\"Marseille - Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png\",\"datePublished\":\"2024-09-12T16:45:12+00:00\",\"dateModified\":\"2024-09-12T16:51:46+00:00\",\"description\":\"LIGUE 1 2024-2025 - Ce samedi, Marseille re\u00e7oit Nice dans le cadre de la 4\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marseille &#8211; Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marseille - Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1","description":"LIGUE 1 2024-2025 - Ce samedi, Marseille re\u00e7oit Nice dans le cadre de la 4\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/","og_locale":"fr_FR","og_type":"article","og_title":"Marseille - Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1","og_description":"LIGUE 1 2024-2025 - Ce samedi, Marseille re\u00e7oit Nice dans le cadre de la 4\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.","og_url":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-09-12T16:45:12+00:00","article_modified_time":"2024-09-12T16:51:46+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Marseille - Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Marseille &#8211; Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1","datePublished":"2024-09-12T16:45:12+00:00","dateModified":"2024-09-12T16:51:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/"},"wordCount":336,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png","keywords":["br\u00e8ve","Cha\u00eene","Football","Heure","Horaire","Ligue 1","Marseille","Nice","Programme TV"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/","url":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/","name":"Marseille - Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png","datePublished":"2024-09-12T16:45:12+00:00","dateModified":"2024-09-12T16:51:46+00:00","description":"LIGUE 1 2024-2025 - Ce samedi, Marseille re\u00e7oit Nice dans le cadre de la 4\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Marseille-Nice-Chaine-TV-Heure-et-Cotes-du-match-de-Ligue-1.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/marseille-nice-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Marseille &#8211; Nice : Cha\u00eene TV, Heure et Cotes du match de Ligue 1"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/519911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=519911"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/519911\/revisions"}],"predecessor-version":[{"id":519919,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/519911\/revisions\/519919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/519914"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=519911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=519911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=519911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}