{"id":520341,"date":"2024-09-14T17:28:06","date_gmt":"2024-09-14T15:28:06","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=520341&#038;preview=true&#038;preview_id=520341"},"modified":"2024-09-15T00:10:03","modified_gmt":"2024-09-14T22:10:03","slug":"video-resume-marseille-nice-4eme-journee-de-ligue-1","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/","title":{"rendered":"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille &#8211; Nice, 4\u00e8me journ\u00e9e de Ligue 1"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>LIGUE 1 2024-2025 &#8211; Ce samedi, Marseille recevait Nice lors de la 4\u00e8me journ\u00e9e de Ligue 1. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.<\/b><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a title=\"Classement Ligue 1 2024-2025\" href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2024-2025\/\" rel=\"\">Classement de la Ligue 1<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Ligue 1 : Le r\u00e9sum\u00e9 vid\u00e9o du match OM &#8211; Nice<\/h2>\n<p><span class=\"YM2x73XyQUsdFjJVZNwhEDzfLpGS4I6Cng\"><iframe loading=\"lazy\" title=\"L&#039;OM signe sa premi\u00e8re victoire au V\u00e9lodrome | J4 - OM vs. OGC Nice #OMOGCN\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/wKh4p6_0xNw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2024-2025 &#8211; Ce samedi, Marseille recevait Nice lors de la 4\u00e8me journ\u00e9e de Ligue 1. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.<\/p>\n","protected":false},"author":1,"featured_media":520344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301,47045],"tags":[16878,75,1554,446,460,4605],"class_list":["post-520341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-breve","tag-football","tag-ligue-1","tag-marseille","tag-nice","tag-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[Vid\u00e9o] R\u00e9sum\u00e9 Marseille - Nice, 4\u00e8me journ\u00e9e de Ligue 1<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2024-2025 - Ce samedi, Marseille recevait Nice lors de la 4\u00e8me journ\u00e9e de Ligue 1. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille - Nice, 4\u00e8me journ\u00e9e de Ligue 1\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2024-2025 - Ce samedi, Marseille recevait Nice lors de la 4\u00e8me journ\u00e9e de Ligue 1. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-14T15:28:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-14T22:10:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille - Nice, 4\u00e8me journ\u00e9e de Ligue 1\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille &#8211; Nice, 4\u00e8me journ\u00e9e de Ligue 1\",\"datePublished\":\"2024-09-14T15:28:06+00:00\",\"dateModified\":\"2024-09-14T22:10:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/\"},\"wordCount\":66,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Ligue 1\",\"Marseille\",\"Nice\",\"vid\u00e9o\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/\",\"name\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille - Nice, 4\u00e8me journ\u00e9e de Ligue 1\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png\",\"datePublished\":\"2024-09-14T15:28:06+00:00\",\"dateModified\":\"2024-09-14T22:10:03+00:00\",\"description\":\"LIGUE 1 2024-2025 - Ce samedi, Marseille recevait Nice lors de la 4\u00e8me journ\u00e9e de Ligue 1. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille &#8211; Nice, 4\u00e8me journ\u00e9e de Ligue 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille - Nice, 4\u00e8me journ\u00e9e de Ligue 1","description":"LIGUE 1 2024-2025 - Ce samedi, Marseille recevait Nice lors de la 4\u00e8me journ\u00e9e de Ligue 1. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/","og_locale":"fr_FR","og_type":"article","og_title":"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille - Nice, 4\u00e8me journ\u00e9e de Ligue 1","og_description":"LIGUE 1 2024-2025 - Ce samedi, Marseille recevait Nice lors de la 4\u00e8me journ\u00e9e de Ligue 1. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","og_url":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-09-14T15:28:06+00:00","article_modified_time":"2024-09-14T22:10:03+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille - Nice, 4\u00e8me journ\u00e9e de Ligue 1","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille &#8211; Nice, 4\u00e8me journ\u00e9e de Ligue 1","datePublished":"2024-09-14T15:28:06+00:00","dateModified":"2024-09-14T22:10:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/"},"wordCount":66,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png","keywords":["br\u00e8ve","Football","Ligue 1","Marseille","Nice","vid\u00e9o"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/","url":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/","name":"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille - Nice, 4\u00e8me journ\u00e9e de Ligue 1","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png","datePublished":"2024-09-14T15:28:06+00:00","dateModified":"2024-09-14T22:10:03+00:00","description":"LIGUE 1 2024-2025 - Ce samedi, Marseille recevait Nice lors de la 4\u00e8me journ\u00e9e de Ligue 1. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Video-Resume-Marseille-Nice-4eme-journee-de-Ligue-1.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-marseille-nice-4eme-journee-de-ligue-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"[Vid\u00e9o] R\u00e9sum\u00e9 Marseille &#8211; Nice, 4\u00e8me journ\u00e9e de Ligue 1"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/520341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=520341"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/520341\/revisions"}],"predecessor-version":[{"id":520501,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/520341\/revisions\/520501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/520344"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=520341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=520341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=520341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}