{"id":521024,"date":"2024-09-17T15:45:37","date_gmt":"2024-09-17T13:45:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=521024&#038;preview=true&#038;preview_id=521024"},"modified":"2024-09-17T15:45:37","modified_gmt":"2024-09-17T13:45:37","slug":"squash-baptiste-masotti-rend-les-armes-au-paris-squash","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/","title":{"rendered":"Squash : Baptiste Masotti rend les armes au Paris Squash"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>PARIS SQUASH 2024 &#8211; Dernier Fran\u00e7ais en lice, Baptiste Masotti a subi la loi de Tarek Momen, et ne verra pas les quarts de finale.\u00a0<\/em><\/h4>\n<p style=\"text-align: justify;\">Ils n&rsquo;\u00e9taient que deux Fran\u00e7ais sur 8 engag\u00e9s \u00e0 avoir franchi le premier tour du Paris Squash, et <strong>Gr\u00e9goire Marche<\/strong>, malgr\u00e9 une belle r\u00e9sistance, <a href=\"https:\/\/dicodusport.fr\/blog\/squash-gregoire-marche-cede-logiquement-en-8e-de-finale-du-paris-squash\/\">avait logiquement c\u00e9d\u00e9 contre le n\u00b01 mondial <strong>Ali Farag<\/strong> la veille<\/a>. <strong>Baptiste Masotti<\/strong> \u00e9tait donc le dernier Bleu en lice, mais lui aussi avait face \u00e0 lui un adversaire cors\u00e9, en la personne de <strong>Tarek Momen<\/strong>, ancien champion du monde, n\u00b07 mondial, et vainqueur des deux seules confrontations entre les deux joueurs.<\/p>\n<h2 style=\"text-align: justify;\">Rien \u00e0 faire<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;\u00c9gyptien attaque fort, menant 4-0 avant que le Fran\u00e7ais ne revienne \u00e0 hauteur&#8230; pour mieux encaisser les 5 points suivants ! <strong>Masotti<\/strong> est \u00e0 la merci de son adversaire, r\u00e9ussit \u00e0 revenir la tendance, mais un coup de magie de <strong>Momen<\/strong> lui offre trois balles de jeu, et une seule sera suffisante. Pourtant, le Tricolore est tout sauf ridicule, livrant notamment un deuxi\u00e8me jeu de haut niveau. Sauf que son rival garde le meilleur pour les derniers points cruciaux, baladant son rival aux quatre coins du court, et concluant sur un nouveau coup de folie.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83d\udd25 A stunning backhand kill from Masotti as the Frenchman begins his second-round match against Egypt&rsquo;s Momen<\/p>\n<p>Catch all the action live on <a href=\"https:\/\/twitter.com\/SquashTV?ref_src=twsrc%5Etfw\">@SquashTV<\/a> \ud83d\udcfa<a href=\"https:\/\/twitter.com\/hashtag\/ParisSquash?src=hash&amp;ref_src=twsrc%5Etfw\">#ParisSquash<\/a> <a href=\"https:\/\/t.co\/IFKB1xreJE\">pic.twitter.com\/IFKB1xreJE<\/a><\/p>\n<p>\u2014 PSA Squash Tour (@PSASquashTour) <a href=\"https:\/\/twitter.com\/PSASquashTour\/status\/1836030044734406965?ref_src=twsrc%5Etfw\">September 17, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\nMen\u00e9 deux manches \u00e0 rien, <strong>Baptiste Masotti<\/strong> jette toutes ses forces dans la bataille. Il r\u00e9ussit plus qu&rsquo;\u00e0 l&rsquo;accoutum\u00e9e \u00e0 provoquer la faute chez son rival, mais ce n&rsquo;est pas encore assez. <strong>Tarek Momen<\/strong> est le plus fort sur les points importants, et alors qu&rsquo;il est tenu en respect pendant la majeure partie du jeu, il acc\u00e9l\u00e8re une derni\u00e8re fois et rafle les quatre derniers points pour planter le dernier clou dans le cercueil tricolore. D\u00e9faite<strong> 11-7, 11-8, 11-7<\/strong> de <strong>Baptiste Masotti<\/strong>, battu par plus fort, non sans d\u00e9m\u00e9riter, mais le fait est qu&rsquo;il n&rsquo;y aura pas de Fran\u00e7ais en quart de finale du Paris Squash 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PARIS SQUASH 2024 &#8211; Dernier Fran\u00e7ais en lice, Baptiste Masotti a subi la loi de Tarek Momen, et ne verra pas les quarts de finale.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":521026,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9608],"tags":[16878,24081],"class_list":["post-521024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-squash","tag-breve","tag-squash-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Squash : Baptiste Masotti rend les armes au Paris Squash<\/title>\n<meta name=\"description\" content=\"PARIS SQUASH 2024 - Dernier Fran\u00e7ais en lice, Baptiste Masotti a subi la loi de Tarek Momen, et ne verra pas les quarts de finale.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Squash : Baptiste Masotti rend les armes au Paris Squash\" \/>\n<meta property=\"og:description\" content=\"PARIS SQUASH 2024 - Dernier Fran\u00e7ais en lice, Baptiste Masotti a subi la loi de Tarek Momen, et ne verra pas les quarts de finale.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T13:45:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Squash : Baptiste Masotti rend les armes au Paris Squash\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Squash : Baptiste Masotti rend les armes au Paris Squash\",\"datePublished\":\"2024-09-17T13:45:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/\"},\"wordCount\":362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png\",\"keywords\":[\"br\u00e8ve\",\"Squash fran\u00e7ais\"],\"articleSection\":[\"Squash\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/\",\"name\":\"Squash : Baptiste Masotti rend les armes au Paris Squash\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png\",\"datePublished\":\"2024-09-17T13:45:37+00:00\",\"description\":\"PARIS SQUASH 2024 - Dernier Fran\u00e7ais en lice, Baptiste Masotti a subi la loi de Tarek Momen, et ne verra pas les quarts de finale.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png\",\"width\":1200,\"height\":674,\"caption\":\"Squash Baptiste Masotti rend les armes au Paris Squash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Squash : Baptiste Masotti rend les armes au Paris Squash\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Squash : Baptiste Masotti rend les armes au Paris Squash","description":"PARIS SQUASH 2024 - Dernier Fran\u00e7ais en lice, Baptiste Masotti a subi la loi de Tarek Momen, et ne verra pas les quarts de finale.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/","og_locale":"fr_FR","og_type":"article","og_title":"Squash : Baptiste Masotti rend les armes au Paris Squash","og_description":"PARIS SQUASH 2024 - Dernier Fran\u00e7ais en lice, Baptiste Masotti a subi la loi de Tarek Momen, et ne verra pas les quarts de finale.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2024-09-17T13:45:37+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Squash : Baptiste Masotti rend les armes au Paris Squash","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Squash : Baptiste Masotti rend les armes au Paris Squash","datePublished":"2024-09-17T13:45:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/"},"wordCount":362,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png","keywords":["br\u00e8ve","Squash fran\u00e7ais"],"articleSection":["Squash"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/","url":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/","name":"Squash : Baptiste Masotti rend les armes au Paris Squash","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png","datePublished":"2024-09-17T13:45:37+00:00","description":"PARIS SQUASH 2024 - Dernier Fran\u00e7ais en lice, Baptiste Masotti a subi la loi de Tarek Momen, et ne verra pas les quarts de finale.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Squash-Baptiste-Masotti-rend-les-armes-au-Paris-Squash.png","width":1200,"height":674,"caption":"Squash Baptiste Masotti rend les armes au Paris Squash"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/squash-baptiste-masotti-rend-les-armes-au-paris-squash\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Squash : Baptiste Masotti rend les armes au Paris Squash"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/521024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=521024"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/521024\/revisions"}],"predecessor-version":[{"id":521027,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/521024\/revisions\/521027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/521026"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=521024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=521024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=521024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}