{"id":521878,"date":"2024-09-21T22:17:53","date_gmt":"2024-09-21T20:17:53","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=521878&#038;preview=true&#038;preview_id=521878"},"modified":"2024-09-21T23:26:36","modified_gmt":"2024-09-21T21:26:36","slug":"volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/","title":{"rendered":"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>SUPERCOUPE DE FRANCE FEMMES DE VOLLEYBALL 2024 &#8211; Plus fortes dans les moments importants, les Neptunes de Nantes n&rsquo;ont mis que trois sets \u00e0 prendre la mesure des Mariannes de Levallois Paris Saint-Cloud, pour aller chercher leur premi\u00e8re SuperCoupe.\u00a0<\/em><\/h4>\n<p style=\"text-align: justify;\">Apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/volleyball-montpellier-rafle-au-tiebreak-la-supercoupe-hommes-contre-saint-nazaire\/\">le sacre de justesse de Montpellier<\/a> chez les hommes, la finale de la SuperCoupe de France femmes de volley proposait une affiche totalement in\u00e9dite. Et qui plus est <a href=\"https:\/\/dicodusport.fr\/blog\/volley-les-mariannes-de-levallois-paris-saint-cloud-championnes-de-france\/\">une revanche de la finale de la Ligue A f\u00e9minine la saison derni\u00e8re<\/a>, remport\u00e9e par les Mariannes de Levallois Paris Saint-Cloud au d\u00e9pends des Neptunes de Nantes, laur\u00e9ates de la Coupe de France, et pr\u00eates pour une vengeance.<\/p>\n<h2 style=\"text-align: justify;\">Les Neptunes clutch<\/h2>\n<p style=\"text-align: justify;\">Et vengeance il y aura eu. Pourtant, on ne peut pas dire que les Neptunes se sont promen\u00e9es ce soir. Le match a \u00e9t\u00e9 atrocement serr\u00e9, notamment parce que<strong> Bianca Cugno<\/strong> envoyait la foudre en attaque, et parce que <strong>Natalia Murek<\/strong> n&rsquo;\u00e9tait clairement pas en reste dans ce secteur. La r\u00e9ception \u00e9tait de qualit\u00e9, les Mariannes tenaient en respect leurs rivales, tout y \u00e9tait&#8230;<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udc01\ud835\udc1a\ud835\udc25\ud835\udc25\ud835\udc1e \ud835\udc1d\ud835\udc1e \ud835\udc2c\ud835\udc1e\ud835\udc2d \ud83c\udfd0<a href=\"https:\/\/twitter.com\/lesmariannes75?ref_src=twsrc%5Etfw\">@lesmariannes75<\/a> \ud83d\udfe3 23 &#8211; 25 \ud83d\udd35 <a href=\"https:\/\/twitter.com\/neptunesnantes?ref_src=twsrc%5Etfw\">@neptunesnantes<\/a><\/p>\n<p>Le direct en exclusivit\u00e9 sur <a href=\"https:\/\/twitter.com\/beinsports_FR?ref_src=twsrc%5Etfw\">@beinsports_FR<\/a> 2 \ud83d\udcfa<a href=\"https:\/\/twitter.com\/hashtag\/Supercoupe?src=hash&amp;ref_src=twsrc%5Etfw\">#Supercoupe<\/a> <a href=\"https:\/\/t.co\/J9UMn4ejlj\">pic.twitter.com\/J9UMn4ejlj<\/a><\/p>\n<p>\u2014 LNV (@LNVofficiel) <a href=\"https:\/\/twitter.com\/LNVofficiel\/status\/1837580089946464482?ref_src=twsrc%5Etfw\">September 21, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">&#8230; sauf le plus important. Car sur les points cruciaux, sur les fins de sets, les Neptunes ont fait admirer une certaine forme de maestria. Les deux premi\u00e8res manches se sont jou\u00e9es sur des d\u00e9tails, mais c&rsquo;est ce qui a fait la diff\u00e9rence. Marqu\u00e9es par ces \u00e9checs, les Mariannes allaient craquer en fin de match et s&rsquo;incliner <strong>25-23, 25-23, 25-18<\/strong>. Une victoire logique des Neptunes de Nantes, battues en finale du Championnat et de la CEV Challenge Cup la saison pass\u00e9e, mais qui commencent cette fois par un titre, et possiblement pas le dernier.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SUPERCOUPE DE FRANCE FEMMES DE VOLLEYBALL 2024 &#8211; Plus fortes dans les moments importants, les Neptunes de Nantes n&rsquo;ont mis que trois sets \u00e0 prendre la mesure des Mariannes de Levallois Paris Saint-Cloud, pour aller chercher leur premi\u00e8re SuperCoupe.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":521933,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8369],"tags":[16878,38959,29824],"class_list":["post-521878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volley-ball","tag-breve","tag-levallois-paris-saint-cloud-volley","tag-neptunes-de-nantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes<\/title>\n<meta name=\"description\" content=\"SUPERCOUPE DE FRANCE FEMMES DE VOLLEYBALL 2024 - Les Neptunes de Nantes n&#039;ont mis que trois sets \u00e0 prendre la mesure des Mariannes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes\" \/>\n<meta property=\"og:description\" content=\"SUPERCOUPE DE FRANCE FEMMES DE VOLLEYBALL 2024 - Les Neptunes de Nantes n&#039;ont mis que trois sets \u00e0 prendre la mesure des Mariannes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-21T20:17:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-21T21:26:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes\",\"datePublished\":\"2024-09-21T20:17:53+00:00\",\"dateModified\":\"2024-09-21T21:26:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png\",\"keywords\":[\"br\u00e8ve\",\"Levallois Paris Saint-Cloud Volley\",\"Neptunes de Nantes\"],\"articleSection\":[\"Volley-Ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/\",\"name\":\"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png\",\"datePublished\":\"2024-09-21T20:17:53+00:00\",\"dateModified\":\"2024-09-21T21:26:36+00:00\",\"description\":\"SUPERCOUPE DE FRANCE FEMMES DE VOLLEYBALL 2024 - Les Neptunes de Nantes n'ont mis que trois sets \u00e0 prendre la mesure des Mariannes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Volleyball les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes","description":"SUPERCOUPE DE FRANCE FEMMES DE VOLLEYBALL 2024 - Les Neptunes de Nantes n'ont mis que trois sets \u00e0 prendre la mesure des Mariannes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/","og_locale":"fr_FR","og_type":"article","og_title":"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes","og_description":"SUPERCOUPE DE FRANCE FEMMES DE VOLLEYBALL 2024 - Les Neptunes de Nantes n'ont mis que trois sets \u00e0 prendre la mesure des Mariannes.","og_url":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2024-09-21T20:17:53+00:00","article_modified_time":"2024-09-21T21:26:36+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes","datePublished":"2024-09-21T20:17:53+00:00","dateModified":"2024-09-21T21:26:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png","keywords":["br\u00e8ve","Levallois Paris Saint-Cloud Volley","Neptunes de Nantes"],"articleSection":["Volley-Ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/","url":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/","name":"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png","datePublished":"2024-09-21T20:17:53+00:00","dateModified":"2024-09-21T21:26:36+00:00","description":"SUPERCOUPE DE FRANCE FEMMES DE VOLLEYBALL 2024 - Les Neptunes de Nantes n'ont mis que trois sets \u00e0 prendre la mesure des Mariannes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Volleyball-les-Neptunes-de-Nantes-maitrisent-Levallois-Paris-Saint-Cloud-et-raflent-la-SuperCoupe-femmes-1.png","width":1200,"height":674,"caption":"Volleyball les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/volleyball-les-neptunes-de-nantes-maitrisent-levallois-paris-saint-cloud-et-raflent-la-supercoupe-femmes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Volleyball : les Neptunes de Nantes ma\u00eetrisent Levallois Paris Saint-Cloud et raflent la SuperCoupe femmes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/521878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=521878"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/521878\/revisions"}],"predecessor-version":[{"id":521934,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/521878\/revisions\/521934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/521933"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=521878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=521878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=521878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}