{"id":523410,"date":"2024-09-29T10:46:23","date_gmt":"2024-09-29T08:46:23","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=523410&#038;preview=true&#038;preview_id=523410"},"modified":"2024-09-29T11:37:29","modified_gmt":"2024-09-29T09:37:29","slug":"championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/","title":{"rendered":"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s&rsquo;offrent deux m\u00e9dailles"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS DU MONDE GYMNASTIQUE A\u00c9ROBIC \u2013 Deuxi\u00e8me jour de comp\u00e9tition productif pour les Bleues, \u00e0 Pesaro ! Dans le sillage de Ma\u00eblys Lenclos, les filles ont d\u00e9croch\u00e9 les deux premi\u00e8res m\u00e9dailles fran\u00e7aises samedi.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Cela faisait tout simplement huit ans que la<strong> gymnastique a\u00e9robic<\/strong> attendait un tel \u00e9v\u00e8nement. Pour les Bleues, historiquement habitu\u00e9es \u00e0 briller aux <strong>championnats du monde<\/strong>, dont la premi\u00e8re \u00e9dition se d\u00e9roula en France, en 1995, la r\u00e9colte s&rsquo;\u00e9tait progressivement amincie pour devenir nulle lors des derni\u00e8res \u00e9ditions. Il fallait remonter \u00e0 2016 pour trouver trace d&rsquo;une derni\u00e8re m\u00e9daille de bronze, obtenue par <strong>Aur\u00e9lie Joly<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Ma\u00eblys Lenclos et le trio d\u00e9poussi\u00e8rent le palmar\u00e8s fran\u00e7ais<\/h2>\n<p style=\"text-align: justify;\">Huit ans plus tard, le collectif tricolore pr\u00e9sent \u00e0 <strong>Pesaro<\/strong> (Italie) pour l&rsquo;\u00e9dition 2024 a mis un terme \u00e0 cette disette historique. Et cela, elle le doit en grande partie \u00e0 celle qui rafle tout au niveau national depuis pr\u00e8s d&rsquo;une d\u00e9cennie : <strong>Ma\u00eblys Lenclos<\/strong>. Aux c\u00f4t\u00e9s de <strong>Clara Lestruhaut <\/strong>et <strong>Victoria Trosset<\/strong>, les trois filles ont livr\u00e9 une finale de haute vol\u00e9e en trio. Dans un v\u00e9ritable mano \u00e0 mano avec la Chine et la Bulgarie, les Bleues ont \u00e9chou\u00e9 \u00e0 0,003 point de Chinoises couronn\u00e9es. Mais elles ont en revanche surpass\u00e9 les Bulgares pour obtenir l&rsquo;argent.<\/p>\n<p style=\"text-align: justify;\">En prime, la journ\u00e9e s&rsquo;est termin\u00e9e en apoth\u00e9ose puisque sur l&rsquo;\u00e9preuve individuelle, <strong>Ma\u00eblys Lenclos<\/strong> a tout simplement doubl\u00e9 la mise. Port\u00e9e par l&rsquo;air <em>\u00ab\u00a0J&rsquo;irais o\u00f9 tu iras\u00a0\u00bb<\/em> de C\u00e9line Dion et Jean-Jacques Goldman, la pensionnaire du club d&rsquo;Arques a r\u00e9ussi \u00e0 se hisser sur la derni\u00e8re marche du podium, derri\u00e8re un intouchable duo <strong>Riri Kitazume <\/strong>&#8211; <strong>Anastasiia Kurashvili<\/strong>. En parall\u00e8le,<strong>\u00a0Clara Lestruhaut<\/strong> n&rsquo;a pu faire mieux qu&rsquo;une 9e place.<\/p>\n<p style=\"text-align: justify;\">Ce dimanche, quatre finales seront \u00e0 l&rsquo;affiche, et m\u00e8neront vers la fin de la comp\u00e9tition. La France disposera d&rsquo;une derni\u00e8re chance de monter sur un podium dans l&rsquo;\u00e9preuve de groupe, en s&rsquo;appuyant sur le trio Lenclos &#8211; Lastruhaut &#8211; Trossert, renforc\u00e9 par <strong>Margot Garcilazo Barrera <\/strong>et <strong>Aurore Cahuzac<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">[AER &#8211; Championnat du monde] &#8211; \ud83d\udccdPesaro (ITA) \ud83c\uddee\ud83c\uddf9<\/p>\n<p>Retour en images sur la premi\u00e8re journ\u00e9e de finales \ud83d\udcf8<\/p>\n<p>\ud83e\udd48Le trio compos\u00e9 de Clara Lestruhaut, Ma\u00eblys Lenclos &amp; Victoria Trosset, est vice-champion du monde avec 20.497 points ! \ud83d\ude0d\ud83d\udcaa<\/p>\n<p>Bravo \u00e0 elles \ud83d\udc4f<\/p>\n<p>\ud83d\udcf8 : @filippotomasiphoto <a href=\"https:\/\/t.co\/aL1JrGQDtv\">pic.twitter.com\/aL1JrGQDtv<\/a><\/p>\n<p>\u2014 F\u00e9d\u00e9ration Fran\u00e7aise de Gymnastique (@ffgymnastique) <a href=\"https:\/\/twitter.com\/ffgymnastique\/status\/1840102404278165558?ref_src=twsrc%5Etfw\">September 28, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS DU MONDE GYMNASTIQUE A\u00c9ROBIC \u2013 Deuxi\u00e8me jour de comp\u00e9tition productif pour les Bleues, \u00e0 Pesaro ! Dans le sillage de Ma\u00eblys Lenclos, les filles ont d\u00e9croch\u00e9 les deux premi\u00e8res m\u00e9dailles fran\u00e7aises samedi.<\/p>\n","protected":false},"author":55,"featured_media":523418,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10429],"tags":[16878],"class_list":["post-523410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gymnastique","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s&#039;offrent deux m\u00e9dailles<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS DU MONDE GYMNASTIQUE A\u00c9ROBIC \u2013 La France, port\u00e9e par Ma\u00eblys Lenclos, a d\u00e9croch\u00e9 deux m\u00e9dailles \u00e0 Pesaro samedi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s&#039;offrent deux m\u00e9dailles\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS DU MONDE GYMNASTIQUE A\u00c9ROBIC \u2013 La France, port\u00e9e par Ma\u00eblys Lenclos, a d\u00e9croch\u00e9 deux m\u00e9dailles \u00e0 Pesaro samedi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-29T08:46:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-29T09:37:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s&#039;offrent deux m\u00e9dailles\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s&rsquo;offrent deux m\u00e9dailles\",\"datePublished\":\"2024-09-29T08:46:23+00:00\",\"dateModified\":\"2024-09-29T09:37:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/\"},\"wordCount\":436,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png\",\"keywords\":[\"br\u00e8ve\"],\"articleSection\":[\"Gymnastique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/\",\"name\":\"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s'offrent deux m\u00e9dailles\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png\",\"datePublished\":\"2024-09-29T08:46:23+00:00\",\"dateModified\":\"2024-09-29T09:37:29+00:00\",\"description\":\"CHAMPIONNATS DU MONDE GYMNASTIQUE A\u00c9ROBIC \u2013 La France, port\u00e9e par Ma\u00eblys Lenclos, a d\u00e9croch\u00e9 deux m\u00e9dailles \u00e0 Pesaro samedi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png\",\"width\":1200,\"height\":674,\"caption\":\"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s'offrent deux m\u00e9dailles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s&#8217;offrent deux m\u00e9dailles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s'offrent deux m\u00e9dailles","description":"CHAMPIONNATS DU MONDE GYMNASTIQUE A\u00c9ROBIC \u2013 La France, port\u00e9e par Ma\u00eblys Lenclos, a d\u00e9croch\u00e9 deux m\u00e9dailles \u00e0 Pesaro samedi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/","og_locale":"fr_FR","og_type":"article","og_title":"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s'offrent deux m\u00e9dailles","og_description":"CHAMPIONNATS DU MONDE GYMNASTIQUE A\u00c9ROBIC \u2013 La France, port\u00e9e par Ma\u00eblys Lenclos, a d\u00e9croch\u00e9 deux m\u00e9dailles \u00e0 Pesaro samedi.","og_url":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-09-29T08:46:23+00:00","article_modified_time":"2024-09-29T09:37:29+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s'offrent deux m\u00e9dailles","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s&rsquo;offrent deux m\u00e9dailles","datePublished":"2024-09-29T08:46:23+00:00","dateModified":"2024-09-29T09:37:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/"},"wordCount":436,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png","keywords":["br\u00e8ve"],"articleSection":["Gymnastique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/","url":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/","name":"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s'offrent deux m\u00e9dailles","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png","datePublished":"2024-09-29T08:46:23+00:00","dateModified":"2024-09-29T09:37:29+00:00","description":"CHAMPIONNATS DU MONDE GYMNASTIQUE A\u00c9ROBIC \u2013 La France, port\u00e9e par Ma\u00eblys Lenclos, a d\u00e9croch\u00e9 deux m\u00e9dailles \u00e0 Pesaro samedi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/Championnats-du-monde-Gymnastique-aerobic-Maelys-Lenclos-et-les-Bleues-soffrent-deux-medailles.png","width":1200,"height":674,"caption":"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s'offrent deux m\u00e9dailles"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-gymnastique-aerobic-maelys-lenclos-et-les-bleues-soffrent-deux-medailles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Championnats du monde Gymnastique a\u00e9robic : Ma\u00eblys Lenclos et les Bleues s&#8217;offrent deux m\u00e9dailles"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/523410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=523410"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/523410\/revisions"}],"predecessor-version":[{"id":523441,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/523410\/revisions\/523441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/523418"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=523410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=523410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=523410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}