{"id":524601,"date":"2024-10-05T08:26:51","date_gmt":"2024-10-05T06:26:51","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=524601&#038;preview=true&#038;preview_id=524601"},"modified":"2024-10-05T08:28:29","modified_gmt":"2024-10-05T06:28:29","slug":"motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/","title":{"rendered":"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/motogp-gp-du-japon-2024-horaires-programme-tv-et-resultats\/\"><em><strong>MOTOGP &#8211; GRAND PRIX DU JAPON 2024<\/strong><\/em>\u00a0<\/a><em>&#8211; <strong>Francesco Bagnaia<\/strong><b> a remport\u00e9 la course sprint du Grand Prix du Japon, \u00e0 Motegi. L&rsquo;Italien a profit\u00e9 de la chute du leader, Pedro Acosta, pour rafler la mise. Enea Bastianini et Marc Marquez compl\u00e8tent le podium. Seulement 4e, Jorge Martin perd du terrain sur son rival dans la course au titre.<\/b><\/em><\/p>\n<div class=\"code-block code-block-1\">\n<div class=\"optidigital-wrapper-div\">\n<div class=\"optidigital-brand\">\n<div id=\"optidigital-adslot-Content_1\" class=\"Content_1\" data-google-query-id=\"COT9_4W9kocDFeRspAQdFgwBrg\">\n<div id=\"google_ads_iframe_\/21859823806\/dicodusport.fr\/blog-article_1__container__\">\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/motogp-japon-2024-classement-course-sprint\/\">MotoGP <\/a><\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/motogp-japon-2024-classement-course-sprint\/\"><strong>\u00a0Japon 2024 : Classement course sprint<\/strong><\/a><\/li>\n<li><strong>\u00c0 lire aussi &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/motogp-grille-de-depart-grand-prix-du-japon-2024\/\">Grille de d\u00e9part Grand Prix du Japon 2024<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L&rsquo;intense lutte pour le titre de champion du monde pilotes connaissait un nouvel \u00e9pisode ce samedi matin. Sur le circuit <strong>Twin Ring Motegi<\/strong>, <strong>Francesco Bagnaia<\/strong> (Ducati Lenovo Team) a fait une bonne op\u00e9ration en s&#8217;emparant de la 2e place sur la grille, derri\u00e8re <strong>Pedro Acosta<\/strong> (Red Bull GasGas Tech3), qui signait l\u00e0 sa premi\u00e8re pole en carri\u00e8re. Leader du g\u00e9n\u00e9ral, <strong>Jorge Martin (<\/strong>Prima Pramac Racing) \u00e9tait seulement 11e, et condamn\u00e9 \u00e0 une grosse remont\u00e9e pour ne pas perdre trop de points.<\/p>\n<h2 style=\"text-align: justify;\">Pedro Acosta laisse filer la victoire, Bagnaia en profite<\/h2>\n<p style=\"text-align: justify;\">Cela ne va pas poser trop de probl\u00e8mes puisqu&rsquo;apr\u00e8s deux virages, l&rsquo;Espagnol gratte six places pour se retrouver dans le Top 5, avant de se faire d\u00e9passer par un <strong>Marc Marquez<\/strong> (Gresini Racing) impressionnant. En t\u00eate, Bagnaia n&rsquo;est pas en reste, et s&#8217;empare de la t\u00eate du Grand Prix devant Acosta, et <strong>Enea Bastianini<\/strong> (Ducati Lenovo Team). Toutefois, le rookie a du culot, et le prouve en reprenant les commandes deux tours plus tard. 4e, <strong>Brad Binder<\/strong> (Red Bull KTM Factory Team) doit lui abandonner rapidement, ce qui permet \u00e0 Marquez et Martin de reprendre un rang, en \u00e9tant \u00e0 plus d&rsquo;une seconde d&rsquo;un trio de t\u00eate resserr\u00e9, et qui tient un rythme endiabl\u00e9.<\/p>\n<p style=\"text-align: justify;\">Marquez ne recolle pas, mais distance un Martin bien loin des standards de ses rivaux, et qui doit se contenter de la 5e place. La bataille pour la victoire est donc une lutte \u00e0 trois, men\u00e9e par un Pedro Acosta rapide, avec les deux Ducati dans le short de bout en bout. Alors qu&rsquo;il creuse l&rsquo;\u00e9cart et se dirige vers la victoire, l&rsquo;Espagnol va partir \u00e0 la faute, et perd tout sur une chute ! <strong>Francesco Bagnaia<\/strong> en profite alors pour reprendre la t\u00eate, et la conserve jusqu&rsquo;au bout avec une bonne marge.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">L&rsquo;ERREUR DE PEDRO ACOSTA \ud83e\udd2f<\/p>\n<p>Alors qu&rsquo;il menait la course, Pedro Acosta chute dans le 9e tour \u274c<a href=\"https:\/\/twitter.com\/hashtag\/JapaneseGP?src=hash&amp;ref_src=twsrc%5Etfw\">#JapaneseGP<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/MotoGP?src=hash&amp;ref_src=twsrc%5Etfw\">#MotoGP<\/a> <a href=\"https:\/\/t.co\/19uRo5b0O4\">pic.twitter.com\/19uRo5b0O4<\/a><\/p>\n<p>\u2014 CANAL+ MotoGP\u2122 (@CanalplusMotoGP) <a href=\"https:\/\/twitter.com\/CanalplusMotoGP\/status\/1842450192471044294?ref_src=twsrc%5Etfw\">October 5, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Jorge Martin perd du terrain, les Fran\u00e7ais hors du coup<\/h2>\n<p style=\"text-align: justify;\">Derri\u00e8re, la lutte fait rage entre <strong>Enea Bastianini <\/strong>et <strong>Marc Marquez<\/strong>. D\u00e9pass\u00e9, l&rsquo;Italien r\u00e9cup\u00e8re sa position et assure finalement la 2e place, devant son grand rival pour la 3e marche du podium au classement mondial. Seulement 4e, Jorge Martin perd six points sur Bagnaia, et voit son avance r\u00e9duite \u00e0 quinze unit\u00e9s. Ce dernier aura la pression dimanche.<\/p>\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 Fran\u00e7ais, <strong>Fabio Quartararo<\/strong> (Monster Energy Yamaha MotoGP) et <strong>Johann Zarco<\/strong> (LCR Honda) partaient d\u00e9j\u00e0 loin, et ont \u00e9t\u00e9 min\u00e9s par un premier tour rat\u00e9, qui les a r\u00e9trograd\u00e9 tous deux en fond de grille. Ce m\u00eame Zarco va m\u00eame \u00eatre impliqu\u00e9 directement sur les chutes de <strong>Joan Mir<\/strong> (Repsol Honda Team) et du local<strong> Takaaki Nakagami<\/strong> (LCR Honda), et sera p\u00e9nalis\u00e9 en cons\u00e9quence. Bref, le samedi est \u00e0 oublier, et un rebond sera attendu dimanche. Autre d\u00e9ception du jour, <strong>Maverick Vinales<\/strong> (Aprilia Racing) n&rsquo;a pas bonifi\u00e9 son excellente 3e place en qualifications, et termine hors des points.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MOTOGP &#8211; GRAND PRIX DU JAPON 2024\u00a0&#8211; Francesco Bagnaia a remport\u00e9 la course sprint du Grand Prix du Japon, \u00e0 Motegi. L&rsquo;Italien a profit\u00e9 de la chute du leader, Pedro Acosta, pour rafler la mise. Enea Bastianini et Marc Marquez compl\u00e8tent le podium. Seulement 4e, Jorge Martin perd du terrain sur son rival dans la course au titre.<\/p>\n","protected":false},"author":55,"featured_media":524616,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47087],"tags":[32415,16878,20390,6198,26788,10938],"class_list":["post-524601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-motogp","tag-actu","tag-breve","tag-francesco-bagnaia","tag-grand-prix-du-japon","tag-grand-prix-du-japon-motogp","tag-motogp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint<\/title>\n<meta name=\"description\" content=\"MOTOGP - GRAND PRIX DU JAPON 2024\u00a0- Francesco Bagnaia a d\u00e9croch\u00e9 la victoire sur la course sprint en profitant d&#039;une erreur de Pedro Acosta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint\" \/>\n<meta property=\"og:description\" content=\"MOTOGP - GRAND PRIX DU JAPON 2024\u00a0- Francesco Bagnaia a d\u00e9croch\u00e9 la victoire sur la course sprint en profitant d&#039;une erreur de Pedro Acosta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-05T06:26:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-05T06:28:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint\",\"datePublished\":\"2024-10-05T06:26:51+00:00\",\"dateModified\":\"2024-10-05T06:28:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/\"},\"wordCount\":616,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Francesco Bagnaia\",\"Grand Prix du Japon\",\"Grand Prix du Japon MotoGP\",\"MotoGP\"],\"articleSection\":[\"MotoGP\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/\",\"name\":\"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png\",\"datePublished\":\"2024-10-05T06:26:51+00:00\",\"dateModified\":\"2024-10-05T06:28:29+00:00\",\"description\":\"MOTOGP - GRAND PRIX DU JAPON 2024\u00a0- Francesco Bagnaia a d\u00e9croch\u00e9 la victoire sur la course sprint en profitant d'une erreur de Pedro Acosta.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png\",\"width\":1200,\"height\":674,\"caption\":\"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint","description":"MOTOGP - GRAND PRIX DU JAPON 2024\u00a0- Francesco Bagnaia a d\u00e9croch\u00e9 la victoire sur la course sprint en profitant d'une erreur de Pedro Acosta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/","og_locale":"fr_FR","og_type":"article","og_title":"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint","og_description":"MOTOGP - GRAND PRIX DU JAPON 2024\u00a0- Francesco Bagnaia a d\u00e9croch\u00e9 la victoire sur la course sprint en profitant d'une erreur de Pedro Acosta.","og_url":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-10-05T06:26:51+00:00","article_modified_time":"2024-10-05T06:28:29+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint","datePublished":"2024-10-05T06:26:51+00:00","dateModified":"2024-10-05T06:28:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/"},"wordCount":616,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png","keywords":["actu","br\u00e8ve","Francesco Bagnaia","Grand Prix du Japon","Grand Prix du Japon MotoGP","MotoGP"],"articleSection":["MotoGP"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/","url":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/","name":"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png","datePublished":"2024-10-05T06:26:51+00:00","dateModified":"2024-10-05T06:28:29+00:00","description":"MOTOGP - GRAND PRIX DU JAPON 2024\u00a0- Francesco Bagnaia a d\u00e9croch\u00e9 la victoire sur la course sprint en profitant d'une erreur de Pedro Acosta.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/moto.png","width":1200,"height":674,"caption":"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/motogp-gp-japon-2024-francesco-bagnaia-remporte-la-course-sprint\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"MotoGP GP Japon 2024 : Francesco Bagnaia remporte la course sprint"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/524601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=524601"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/524601\/revisions"}],"predecessor-version":[{"id":524617,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/524601\/revisions\/524617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/524616"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=524601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=524601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=524601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}