{"id":526502,"date":"2024-10-14T22:49:38","date_gmt":"2024-10-14T20:49:38","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=526502&#038;preview=true&#038;preview_id=526502"},"modified":"2024-10-14T23:15:15","modified_gmt":"2024-10-14T21:15:15","slug":"football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/","title":{"rendered":"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>LIGUE DES NATIONS (J4) &#8211; <strong>Pour la troisi\u00e8me fois de l\u2019ann\u00e9e, l\u2019\u00e9quipe de France s&rsquo;impose face \u00e0 la Belgique (1-2) apr\u00e8s ses victoires lors de l\u2019Euro 2024 et le 9 septembre dernier lors du match aller au Groupama Stadium de Lyon, dans cette Ligue des Nations.<\/strong><\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/belgique-france-les-notes-des-bleus\/\">Belgique &#8211; France : Les notes des Bleus<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Jamais deux sans trois pour la France face \u00e0 la Belgique. Un <strong>Belgique &#8211; France<\/strong> n\u2019est jamais une affiche banale. Et d\u00e9sormais, les trois confrontations opposant ces deux nations en 2024, ont \u00e9t\u00e9 toutes remport\u00e9es par l\u2019\u00e9quipe de France apr\u00e8s avoir remport\u00e9 son duel lors <a href=\"https:\/\/dicodusport.fr\/blog\/euro-2024-la-france-anticipe-la-sortie-de-la-belgique-des-les-huitiemes\/\">des huiti\u00e8mes de finales de l\u2019Euro 2024 (1-0)<\/a> et lors de <a href=\"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-les-bleus-se-reprennent-face-a-la-belgique\/\">la deuxi\u00e8me journ\u00e9e de la Ligue des Nations (2-0)<\/a>.\u00a0 Et cette quatri\u00e8me journ\u00e9e de Ligue des Nations reste une comp\u00e9tition o\u00f9 l\u2019enjeu pour l\u2019\u00e9quipe de France est de terminer \u00e0 la premi\u00e8re place de son groupe pour pr\u00e9tendre d&rsquo;int\u00e9grer le Final Four en mars 2025. <\/span><\/p>\n<h2>Des premi\u00e8res situations en faveur de la Belgique<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Les Bleus viennent au stade Stade Roi Baudouin dans l\u2019optique de r\u00e9aliser la passe de trois apr\u00e8s s\u2019\u00eatre impos\u00e9s face \u00e0 la Belgique au Stade de France le 9 septembre dernier. Puis face \u00e0 Isra\u00ebl quatre jours plus t\u00f4t. La rencontre d\u00e9bute plut\u00f4t en faveur des Diables Rouges o\u00f9 <strong>Youri Tielemans<\/strong> apporte un moment de frayeur d\u00e8s la premi\u00e8re minute de jeu avec un tir \u00e0 ras du sol au pied droit capt\u00e9 par<strong> Mike Maignan<\/strong> (1e). Sur coup franc, le milieu de terrain d\u2019Aston Villa adresse un ballon \u00e0 la t\u00eate de <strong>Lo\u00efs Openda<\/strong> qui manque le cadre (8e). La construction entre <strong>Youri Tielemans<\/strong> et <strong>Lo\u00efs Openda<\/strong> s\u2019op\u00e8re de nouveau sans que l\u2019attaquant de Leipzig ne parvienne \u00e0 cadrer (13e). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><strong>Mike Maignan<\/strong> est de nouveau mis \u00e0 contribution lorsque <strong>Leandro Trossard<\/strong> profite d\u2019une perte de ballon d&rsquo;<strong>Ibrahima\u00a0Konat\u00e9<\/strong> avant de d\u00e9livrer une frappe repouss\u00e9e par le portier fran\u00e7ais (18e). Un fauchage de <strong>William Saliba<\/strong> sur <strong>Lo\u00efs Openda<\/strong> conduit \u00e0 un p\u00e9nalty en faveur des Belges.<strong> Youri Tielemans<\/strong> prend les choses en main, mais se rate compl\u00e8tement en envoyant le ballon au-dessus du but (23e). Mais l\u2019offrande change de camp lorsque <strong>Wout Faes<\/strong> s\u2019\u00e9croule devant <strong>Bradley Barcola<\/strong> en touchant le cuir du coude dans la surface. Le p\u00e9nalty des Bleus est converti par <strong>Randal Kolo Muani<\/strong> d\u2019un contre-pied (0-1 ; 35e). L\u2019avance au score n\u2019aura dur\u00e9 que quatorze minutes en grignotant du temps additionnel favorable aux Belges qui reviennent dans la partie (45+4). Une \u00e9galisation sign\u00e9e de la t\u00eate de <strong>Lo\u00efs Openda<\/strong> (1-1).\u00a0<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u23f8\ufe0f Mi-temps \u00e0 Bruxelles. La Belgique \u00e9galise dans le temps additionnel.<\/p>\n<p>15 minutes pour souffler et on repart au combat \ud83d\udc4a<\/p>\n<p>\ud83c\udde7\ud83c\uddea1-1\ud83c\uddeb\ud83c\uddf7 | <a href=\"https:\/\/twitter.com\/hashtag\/BELFRA?src=hash&amp;ref_src=twsrc%5Etfw\">#BELFRA<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/FiersdetreBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#FiersdetreBleus<\/a> <a href=\"https:\/\/t.co\/7ntcpzaJNK\">pic.twitter.com\/7ntcpzaJNK<\/a><\/p>\n<p>\u2014 Equipe de France \u2b50\u2b50 (@equipedefrance) <a href=\"https:\/\/twitter.com\/equipedefrance\/status\/1845912076729880776?ref_src=twsrc%5Etfw\">October 14, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><strong>Premier doubl\u00e9 pour Randal Kolo Muani<\/strong><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Au retour des vestiaires, <strong>Kouadio Manu Kon\u00e9<\/strong> pense s\u2019offrir son premier but sous la tunique bleue. Sa r\u00e9alisation n\u2019est pas accord\u00e9e puisque <strong>Randal Kolo Muani<\/strong> a touch\u00e9 le ballon avec le bras en amont de l\u2019action (58e). Le buteur tricolore du premier acte retrouve la lumi\u00e8re dans le ciel belge en doublant la mise pour la premi\u00e8re fois en Bleus, quatre minutes plus tard (62e). Sur le c\u00f4t\u00e9 gauche, <strong>Bradley Barcola<\/strong> transmet le ballon \u00e0 <strong>Lucas Digne<\/strong>. Ce dernier effectue un centre de la patte gauche pour servir <strong>Randal Kolo Muani<\/strong> \u00e0 la conclusion d\u2019une t\u00eate d\u00e9crois\u00e9e (62e). Les Belges n\u2019ont pas dit leur dernier mot avec <strong>Zeno Debast<\/strong> qui tente sa chance de loin et force <strong>Mike Maignan<\/strong> \u00e0 la parade (65e). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Mais la France va terminer la f\u00eate des voisins en inf\u00e9riorit\u00e9 num\u00e9rique puisque <strong>Aur\u00e9lien Tchouam\u00e9ni<\/strong> commet une faute en position de dernier d\u00e9fenseur \u00e0 l\u2019entr\u00e9e de la surface sur <strong>Youri Tielemans<\/strong>. D\u00e9j\u00e0 averti au pr\u00e9alable, le milieu de terrain du Real Madrid \u00e9cope d\u2019un carton rouge (76e). Le dernier quart d\u2019heure aura apport\u00e9 son lot de frissons aux Bleus lorsque <strong>Leandro Trossard<\/strong> vient enrouler son ballon du pied droit pour solliciter une nouvelle fois les gants de <strong>Mike Maignan<\/strong> (90+2). Les Bleus s\u2019imposent face \u00e0 la Belgique pour la troisi\u00e8me fois de l\u2019ann\u00e9e. D&rsquo;ailleurs, la derni\u00e8re victoire des Belges face \u00e0 l\u2019\u00e9quipe de France dans un match officiel remonte \u00e0 1981. Deuxi\u00e8me de son groupe, la France va devoir rattraper son retard d&rsquo;un point sur l&rsquo;Italie. Prochain rendez-vous le 14 novembre face \u00e0 Isra\u00ebl, au Stade de France.\u00a0<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udde9\ud835\udddc\ud835\uddd6\ud835\udde7\ud835\udde2\ud835\udddc\ud835\udde5\ud835\uddd8 \ud835\uddd8\ud835\udde1 \ud835\uddd5\ud835\uddd8\ud835\udddf\ud835\uddda\ud835\udddc\ud835\udde4\ud835\udde8\ud835\uddd8 \ud83d\udd25<\/p>\n<p>Nos Bleus font coup double avec \ud835\udfee \ud835\ude03\ud835\uddf6\ud835\uddf0\ud835\ude01\ud835\uddfc\ud835\uddf6\ud835\uddff\ud835\uddf2\ud835\ude00 \ud835\uddf2\ud835\uddfb \ud835\udfee \ud835\uddfa\ud835\uddee\ud835\ude01\ud835\uddf0\ud835\uddf5\ud835\ude00 sur ce rassemblement \ud83d\udc4a\u2705<\/p>\n<p>\ud83c\udde7\ud83c\uddea1-2\ud83c\uddeb\ud83c\uddf7 | <a href=\"https:\/\/twitter.com\/hashtag\/BELFRA?src=hash&amp;ref_src=twsrc%5Etfw\">#BELFRA<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/FiersdetreBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#FiersdetreBleus<\/a> <a href=\"https:\/\/t.co\/9ETHdsguLQ\">pic.twitter.com\/9ETHdsguLQ<\/a><\/p>\n<p>\u2014 Equipe de France \u2b50\u2b50 (@equipedefrance) <a href=\"https:\/\/twitter.com\/equipedefrance\/status\/1845928466291569078?ref_src=twsrc%5Etfw\">October 14, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique<\/p>\n","protected":false},"author":62,"featured_media":526506,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301],"tags":[373,16878,75,30,3514,24],"class_list":["post-526502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-belgique","tag-breve","tag-football","tag-france","tag-ligue-des-nations","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique<\/title>\n<meta name=\"description\" content=\"LIGUE DES NATIONS (J4) - Pour la troisi\u00e8me fois de l\u2019ann\u00e9e, l\u2019Equipe de France s&#039;impose face \u00e0 la Belgique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique\" \/>\n<meta property=\"og:description\" content=\"LIGUE DES NATIONS (J4) - Pour la troisi\u00e8me fois de l\u2019ann\u00e9e, l\u2019Equipe de France s&#039;impose face \u00e0 la Belgique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-14T20:49:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T21:15:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andr\u00e9a Lamy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/\"},\"author\":{\"name\":\"Andr\u00e9a Lamy\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/5b73f4b55b8683f37e9f75d6dc039f31\"},\"headline\":\"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique\",\"datePublished\":\"2024-10-14T20:49:38+00:00\",\"dateModified\":\"2024-10-14T21:15:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/\"},\"wordCount\":816,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png\",\"keywords\":[\"Belgique\",\"br\u00e8ve\",\"Football\",\"France\",\"Ligue des nations\",\"sport\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/\",\"name\":\"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png\",\"datePublished\":\"2024-10-14T20:49:38+00:00\",\"dateModified\":\"2024-10-14T21:15:15+00:00\",\"description\":\"LIGUE DES NATIONS (J4) - Pour la troisi\u00e8me fois de l\u2019ann\u00e9e, l\u2019Equipe de France s'impose face \u00e0 la Belgique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png\",\"width\":1200,\"height\":674,\"caption\":\"Football Ligue des Nations Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/5b73f4b55b8683f37e9f75d6dc039f31\",\"name\":\"Andr\u00e9a Lamy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Andrea-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Andrea-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Andrea-150x150.jpg\",\"caption\":\"Andr\u00e9a Lamy\"},\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/andrea-lamy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique","description":"LIGUE DES NATIONS (J4) - Pour la troisi\u00e8me fois de l\u2019ann\u00e9e, l\u2019Equipe de France s'impose face \u00e0 la Belgique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/","og_locale":"fr_FR","og_type":"article","og_title":"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique","og_description":"LIGUE DES NATIONS (J4) - Pour la troisi\u00e8me fois de l\u2019ann\u00e9e, l\u2019Equipe de France s'impose face \u00e0 la Belgique.","og_url":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-10-14T20:49:38+00:00","article_modified_time":"2024-10-14T21:15:15+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png","type":"image\/png"}],"author":"Andr\u00e9a Lamy","twitter_card":"summary_large_image","twitter_title":"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/"},"author":{"name":"Andr\u00e9a Lamy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31"},"headline":"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique","datePublished":"2024-10-14T20:49:38+00:00","dateModified":"2024-10-14T21:15:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/"},"wordCount":816,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png","keywords":["Belgique","br\u00e8ve","Football","France","Ligue des nations","sport"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/","url":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/","name":"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png","datePublished":"2024-10-14T20:49:38+00:00","dateModified":"2024-10-14T21:15:15+00:00","description":"LIGUE DES NATIONS (J4) - Pour la troisi\u00e8me fois de l\u2019ann\u00e9e, l\u2019Equipe de France s'impose face \u00e0 la Belgique.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Football-Ligue-des-Nations-Troisieme-victoire-pour-les-Bleus-victorieux-en-Belgique.png","width":1200,"height":674,"caption":"Football Ligue des Nations Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-des-nations-troisieme-victoire-pour-les-bleus-victorieux-en-belgique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Football Ligue des Nations : Troisi\u00e8me victoire pour les Bleus, victorieux en Belgique"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31","name":"Andr\u00e9a Lamy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg","caption":"Andr\u00e9a Lamy"},"url":"https:\/\/dicodusport.fr\/blog\/author\/andrea-lamy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/526502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=526502"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/526502\/revisions"}],"predecessor-version":[{"id":526522,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/526502\/revisions\/526522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/526506"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=526502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=526502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=526502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}