{"id":527313,"date":"2024-10-18T17:24:05","date_gmt":"2024-10-18T15:24:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=527313&#038;preview=true&#038;preview_id=527313"},"modified":"2024-10-18T17:30:52","modified_gmt":"2024-10-18T15:30:52","slug":"pronostic-montpellier-marseille-cotes-analyse-et-conseil","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/","title":{"rendered":"Pronostic Montpellier &#8211; Marseille : Cotes, analyse et conseil"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>LIGUE 1 2024-2025<b> &#8211; <\/b><\/em><em><b>Montpellier re\u00e7oit Marseille lors de la 8\u00e8me journ\u00e9e de Ligue 1. Notre pronostic pour la rencontre.<\/b><\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211;\u00a0<\/strong><a title=\"Classement Ligue 1 2024-2025\" href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2024-2025\/\" rel=\"\"><strong>Le classement de la Ligue 1<\/strong><\/a><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Pronostic Montpellier &#8211; OM : Dimanche 20 octobre, 20h45<\/h2>\n<p style=\"text-align: justify;\"><strong>Montpellier<\/strong> est d\u00e9j\u00e0 au pied dur mur avant la r\u00e9ception de l&rsquo;<strong>Olympique de Marseille<\/strong>. Les H\u00e9raultais r\u00e9alisent un mauvais d\u00e9but de saison, et sont avant-derniers de Ligue 1 avant cette rencontre. Le <strong>MHSC<\/strong> a d\u00e9j\u00e0 encaiss\u00e9 21 buts cette saisons en seulement sept rencontres. C&rsquo;est \u00e9videmment beaucoup trop pour pr\u00e9tendre \u00e0 \u00eatre mieux class\u00e9.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/montpellier-marseille-chaine-tv-heure-et-cotes-du-match-de-ligue-1\/\" target=\"_blank\" rel=\"noopener\">Montpellier \u2013 Marseille : Cha\u00eene TV, Heure et Cotes du match de Ligue 1<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Olympique<\/strong> <strong>de<\/strong> <strong>Marseille<\/strong> vit une p\u00e9riode plus compliqu\u00e9e apr\u00e8s un d\u00e9but de saison canon. Alors que la victoire h\u00e9ro\u00efque face \u00e0 l&rsquo;<strong>Olympique Lyonnais<\/strong> aurait pu lancer d\u00e9finitivement la saison des <strong>Olympiens<\/strong>, ils ont au contraire montr\u00e9 un visage moins int\u00e9ressant ensuite. <strong>Adrien<\/strong> <strong>Rabiot<\/strong> n&rsquo;a pas encore retrouv\u00e9 son meilleur niveau, alors que <strong>Mason<\/strong> <strong>Greenwood<\/strong> a baiss\u00e9 un peu en r\u00e9gime.<\/p>\n<p style=\"text-align: justify;\">Les Marseillais sont favoris pour cette rencontre, mais attention \u00e0 <strong>Montpellier<\/strong> qui n&rsquo;aura rien \u00e0 perdre, et pourrait se sublimer dans un grand match \u00e0 la maison. On ne mise pas sur l&rsquo;issue de la rencontre, mais sur un but d&rsquo;<strong>Elye Wahi<\/strong>, l&rsquo;ancien Montpelli\u00e9rain.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 600px;\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Dimanche 20 octobre, 20h45<\/span><\/strong><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; text-align: center; width: 240px;\"><span style=\"font-size: 12px; color: #ffffff;\">Buteur<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; width: 600px;\"><strong>Elye Wahi<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 240px;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/50955475?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#ffffff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#ffffff;padding:0px 16px;font-size:13px;line-height:26px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 2.45<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2024-2025 &#8211; Montpellier re\u00e7oit Marseille lors de la 8\u00e8me journ\u00e9e de Ligue 1. Notre pronostic pour la rencontre.<\/p>\n","protected":false},"author":1,"featured_media":527368,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301,47045],"tags":[75,1554,446,1069,1889,4949],"class_list":["post-527313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-football","tag-ligue-1","tag-marseille","tag-montpellier","tag-om","tag-pronostics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pronostic Montpellier - Marseille : Cotes, analyse et conseil - Dicodusport<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2024-2025 - Montpellier re\u00e7oit Marseille lors de la 8\u00e8me journ\u00e9e de Ligue 1. Notre pronostic pour la rencontre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronostic Montpellier - Marseille : Cotes, analyse et conseil\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2024-2025 - Montpellier re\u00e7oit Marseille lors de la 8\u00e8me journ\u00e9e de Ligue 1. Notre pronostic pour la rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-18T15:24:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-18T15:30:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pronostic Montpellier - Marseille : Cotes, analyse et conseil\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Pronostic Montpellier &#8211; Marseille : Cotes, analyse et conseil\",\"datePublished\":\"2024-10-18T15:24:05+00:00\",\"dateModified\":\"2024-10-18T15:30:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/\"},\"wordCount\":282,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png\",\"keywords\":[\"Football\",\"Ligue 1\",\"Marseille\",\"Montpellier\",\"OM\",\"Pronostics\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/\",\"name\":\"Pronostic Montpellier - Marseille : Cotes, analyse et conseil - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png\",\"datePublished\":\"2024-10-18T15:24:05+00:00\",\"dateModified\":\"2024-10-18T15:30:52+00:00\",\"description\":\"LIGUE 1 2024-2025 - Montpellier re\u00e7oit Marseille lors de la 8\u00e8me journ\u00e9e de Ligue 1. Notre pronostic pour la rencontre.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronostic Montpellier &#8211; Marseille : Cotes, analyse et conseil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pronostic Montpellier - Marseille : Cotes, analyse et conseil - Dicodusport","description":"LIGUE 1 2024-2025 - Montpellier re\u00e7oit Marseille lors de la 8\u00e8me journ\u00e9e de Ligue 1. Notre pronostic pour la rencontre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/","og_locale":"fr_FR","og_type":"article","og_title":"Pronostic Montpellier - Marseille : Cotes, analyse et conseil","og_description":"LIGUE 1 2024-2025 - Montpellier re\u00e7oit Marseille lors de la 8\u00e8me journ\u00e9e de Ligue 1. Notre pronostic pour la rencontre.","og_url":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-10-18T15:24:05+00:00","article_modified_time":"2024-10-18T15:30:52+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Pronostic Montpellier - Marseille : Cotes, analyse et conseil","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Pronostic Montpellier &#8211; Marseille : Cotes, analyse et conseil","datePublished":"2024-10-18T15:24:05+00:00","dateModified":"2024-10-18T15:30:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/"},"wordCount":282,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png","keywords":["Football","Ligue 1","Marseille","Montpellier","OM","Pronostics"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/","url":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/","name":"Pronostic Montpellier - Marseille : Cotes, analyse et conseil - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png","datePublished":"2024-10-18T15:24:05+00:00","dateModified":"2024-10-18T15:30:52+00:00","description":"LIGUE 1 2024-2025 - Montpellier re\u00e7oit Marseille lors de la 8\u00e8me journ\u00e9e de Ligue 1. Notre pronostic pour la rencontre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Pronostic-Montpellier-Marseille-Cotes-analyse-et-conseil.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-montpellier-marseille-cotes-analyse-et-conseil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pronostic Montpellier &#8211; Marseille : Cotes, analyse et conseil"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/527313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=527313"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/527313\/revisions"}],"predecessor-version":[{"id":527386,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/527313\/revisions\/527386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/527368"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=527313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=527313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=527313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}