{"id":528682,"date":"2024-10-23T21:27:57","date_gmt":"2024-10-23T19:27:57","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=528682&#038;preview=true&#038;preview_id=528682"},"modified":"2025-09-16T08:52:06","modified_gmt":"2025-09-16T06:52:06","slug":"video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/","title":{"rendered":"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone &#8211; Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em><b>LIGUE DES CHAMPIONS 2024-2025 &#8211; Ce mercredi, Barcelone recevait le Bayern Munich lors de la 3\u00e8me journ\u00e9e de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.<\/b><\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a title=\"Classement Ligue des Champions 2024-2025 (PSG, Lille, Monaco et Brest)\" href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-des-champions-2024-2025-psg-lille-monaco-et-brest\/\" rel=\"\">Classement Ligue des Champions<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Ligue des champions : Le r\u00e9sum\u00e9 vid\u00e9o de Bar\u00e7a &#8211; Bayern Munich<\/h2>\n<p><span class=\"eS9TvDK2dGN3sOLtRCxMrb5Ai0cZ7Pf\"><iframe loading=\"lazy\" title=\"Le r\u00e9sum\u00e9 de Barcelone \/ Bayern Munich\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/Y9RkONyvHbA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barcelone recevait le Bayern Munich lors de la 3\u00e8me journ\u00e9e de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.<\/p>\n","protected":false},"author":2,"featured_media":528690,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47250],"tags":[912,2101,4484,16878,75,419,4605],"class_list":["post-528682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions-de-football","tag-barca","tag-barcelone","tag-bayern-munich","tag-breve","tag-football","tag-ligue-des-champions","tag-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions<\/title>\n<meta name=\"description\" content=\"Barcelone recevait le Bayern Munich lors de la 3\u00e8me journ\u00e9e de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions\" \/>\n<meta property=\"og:description\" content=\"Barcelone recevait le Bayern Munich lors de la 3\u00e8me journ\u00e9e de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-23T19:27:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T06:52:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Benjamin Cots\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/BenjaminCots\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/\"},\"author\":{\"name\":\"Benjamin Cots\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4\"},\"headline\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone &#8211; Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions\",\"datePublished\":\"2024-10-23T19:27:57+00:00\",\"dateModified\":\"2025-09-16T06:52:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/\"},\"wordCount\":74,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png\",\"keywords\":[\"bar\u00e7a\",\"barcelone\",\"Bayern Munich\",\"br\u00e8ve\",\"Football\",\"Ligue des champions\",\"vid\u00e9o\"],\"articleSection\":[\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/\",\"name\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png\",\"datePublished\":\"2024-10-23T19:27:57+00:00\",\"dateModified\":\"2025-09-16T06:52:06+00:00\",\"description\":\"Barcelone recevait le Bayern Munich lors de la 3\u00e8me journ\u00e9e de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png\",\"width\":1200,\"height\":674,\"caption\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone &#8211; Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4\",\"name\":\"Benjamin Cots\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png\",\"caption\":\"Benjamin Cots\"},\"description\":\"Footballeur et fan des Girondins de Bordeaux depuis mon plus jeune \u00e2ge, le foot et le sport en g\u00e9n\u00e9ral ont rythm\u00e9 ma vie. Apr\u00e8s des \u00e9tudes en informatique, la cr\u00e9ation de Dicodusport \u00e9tait le parfait m\u00e9lange pour allier mes deux passions.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/BenjaminCots\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions","description":"Barcelone recevait le Bayern Munich lors de la 3\u00e8me journ\u00e9e de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/","og_locale":"fr_FR","og_type":"article","og_title":"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions","og_description":"Barcelone recevait le Bayern Munich lors de la 3\u00e8me journ\u00e9e de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","og_url":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-10-23T19:27:57+00:00","article_modified_time":"2025-09-16T06:52:06+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png","type":"image\/png"}],"author":"Benjamin Cots","twitter_card":"summary_large_image","twitter_title":"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions","twitter_creator":"@https:\/\/twitter.com\/BenjaminCots","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/"},"author":{"name":"Benjamin Cots","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4"},"headline":"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone &#8211; Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions","datePublished":"2024-10-23T19:27:57+00:00","dateModified":"2025-09-16T06:52:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/"},"wordCount":74,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png","keywords":["bar\u00e7a","barcelone","Bayern Munich","br\u00e8ve","Football","Ligue des champions","vid\u00e9o"],"articleSection":["Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/","url":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/","name":"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png","datePublished":"2024-10-23T19:27:57+00:00","dateModified":"2025-09-16T06:52:06+00:00","description":"Barcelone recevait le Bayern Munich lors de la 3\u00e8me journ\u00e9e de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/10\/Video-Resume-Barcelone-Bayern-Munich-3eme-journee-de-Ligue-des-champions.png","width":1200,"height":674,"caption":"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone - Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-barcelone-bayern-munich-3eme-journee-de-ligue-des-champions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"[Vid\u00e9o] R\u00e9sum\u00e9 Barcelone &#8211; Bayern Munich, 3\u00e8me journ\u00e9e de Ligue des champions"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4","name":"Benjamin Cots","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png","caption":"Benjamin Cots"},"description":"Footballeur et fan des Girondins de Bordeaux depuis mon plus jeune \u00e2ge, le foot et le sport en g\u00e9n\u00e9ral ont rythm\u00e9 ma vie. Apr\u00e8s des \u00e9tudes en informatique, la cr\u00e9ation de Dicodusport \u00e9tait le parfait m\u00e9lange pour allier mes deux passions.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/BenjaminCots"],"url":"https:\/\/dicodusport.fr\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/528682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=528682"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/528682\/revisions"}],"predecessor-version":[{"id":528743,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/528682\/revisions\/528743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/528690"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=528682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=528682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=528682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}