{"id":531363,"date":"2024-11-06T15:54:16","date_gmt":"2024-11-06T14:54:16","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=531363&#038;preview=true&#038;preview_id=531363"},"modified":"2024-11-06T16:17:14","modified_gmt":"2024-11-06T15:17:14","slug":"transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/","title":{"rendered":"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>LIGUE 1 2024-2025 &#8211; Selon <a href=\"https:\/\/www.lequipe.fr\/Football\/Actualites\/En-quete-d-un-nouvel-entraineur-rennes-etudie-la-piste-jorge-sampaoli\/1518600\">L&rsquo;\u00c9quipe<\/a>, le Stade Rennais envisage de recruter Jorge Sampaoli pour remplacer Julien St\u00e9phan, en difficult\u00e9.\u00a0<\/em><\/h4>\n<p style=\"text-align: justify;\">Le <strong>Stade<\/strong> <strong>Rennais<\/strong> passe compl\u00e8tement \u00e0 c\u00f4t\u00e9 de son d\u00e9but de saison et pointe seulement au treizi\u00e8me rang du <a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2024-2025\/\">classement de la Ligue 1<\/a>, avec 11 points en 10 journ\u00e9es. <strong>Julien St\u00e9phan<\/strong>, de retour au club apr\u00e8s un passage \u00e0 Strasbourg, ne devrait pas rester en poste et donc faire les frais de cette entame rat\u00e9e. Plusieurs pistes ont \u00e9t\u00e9 \u00e9voqu\u00e9es ces derniers jours comme <strong>Habib<\/strong> <strong>Beye<\/strong>, <strong>Patrick<\/strong> <strong>Vieira<\/strong> ou encore <strong>S\u00e9rgio<\/strong> <strong>Concei\u00e7\u00e3o<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Jorge Sampaoli nouveau favori<\/h2>\n<p style=\"text-align: justify;\">Mais ces derni\u00e8res heures, une autre piste a pris de l&rsquo;\u00e9paisseur et pourrait se concr\u00e9tiser. <strong>Jorge<\/strong> <strong>Sampaoli<\/strong>, ancien entra\u00eeneur de l&rsquo;<strong>Olympique de Marseille<\/strong>, est le nouveau favori pour prendre les commandes du club breton. Pass\u00e9 par <strong>S\u00e9ville<\/strong> puis <strong>Flamengo<\/strong> depuis son d\u00e9part de la cit\u00e9 phoc\u00e9enne, il est sans club depuis la fin d&rsquo;ann\u00e9e 2023.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;Argentin avait fait du bon travail avec l&rsquo;<strong>OM<\/strong> avec notamment une deuxi\u00e8me place en <strong>Ligue<\/strong> <strong>1<\/strong> et une demi-finale de <strong>Ligue Europa Conf\u00e9rence<\/strong>. Si \u00e0 l&rsquo;heure actuelle, rien n&rsquo;est act\u00e9, <strong>Jorge<\/strong> <strong>Sampaoli<\/strong> est une vraie option pour le <strong>Stade<\/strong> <strong>Rennais<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">En qu\u00eate d&rsquo;un nouvel entra\u00eeneur, Rennes \u00e9tudie la piste Jorge Sampaoli <a href=\"https:\/\/t.co\/wYJN7GRlus\">https:\/\/t.co\/wYJN7GRlus<\/a> <a href=\"https:\/\/t.co\/Vo9VEayavO\">pic.twitter.com\/Vo9VEayavO<\/a><\/p>\n<p>\u2014 L&rsquo;\u00c9QUIPE (@lequipe) <a href=\"https:\/\/twitter.com\/lequipe\/status\/1854168412806676968?ref_src=twsrc%5Etfw\">November 6, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2024-2025 &#8211; Selon L&rsquo;\u00c9quipe, le Stade Rennais envisage de recruter Jorge Sampaoli pour remplacer Julien St\u00e9phan en difficult\u00e9.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":531367,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301,47045],"tags":[16878,75,1865],"class_list":["post-531363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-breve","tag-football","tag-stade-rennais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2024-2025 - Selon L&#039;\u00c9quipe, le Stade Rennais envisage de recruter Jorge Sampaoli pour remplacer Julien St\u00e9phan en difficult\u00e9.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2024-2025 - Selon L&#039;\u00c9quipe, le Stade Rennais envisage de recruter Jorge Sampaoli pour remplacer Julien St\u00e9phan en difficult\u00e9.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-06T14:54:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T15:17:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1\",\"datePublished\":\"2024-11-06T14:54:16+00:00\",\"dateModified\":\"2024-11-06T15:17:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/\"},\"wordCount\":249,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Stade rennais\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/\",\"name\":\"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png\",\"datePublished\":\"2024-11-06T14:54:16+00:00\",\"dateModified\":\"2024-11-06T15:17:14+00:00\",\"description\":\"LIGUE 1 2024-2025 - Selon L'\u00c9quipe, le Stade Rennais envisage de recruter Jorge Sampaoli pour remplacer Julien St\u00e9phan en difficult\u00e9.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1","description":"LIGUE 1 2024-2025 - Selon L'\u00c9quipe, le Stade Rennais envisage de recruter Jorge Sampaoli pour remplacer Julien St\u00e9phan en difficult\u00e9.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1","og_description":"LIGUE 1 2024-2025 - Selon L'\u00c9quipe, le Stade Rennais envisage de recruter Jorge Sampaoli pour remplacer Julien St\u00e9phan en difficult\u00e9.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-11-06T14:54:16+00:00","article_modified_time":"2024-11-06T15:17:14+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1","datePublished":"2024-11-06T14:54:16+00:00","dateModified":"2024-11-06T15:17:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/"},"wordCount":249,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png","keywords":["br\u00e8ve","Football","Stade rennais"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/","name":"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png","datePublished":"2024-11-06T14:54:16+00:00","dateModified":"2024-11-06T15:17:14+00:00","description":"LIGUE 1 2024-2025 - Selon L'\u00c9quipe, le Stade Rennais envisage de recruter Jorge Sampaoli pour remplacer Julien St\u00e9phan en difficult\u00e9.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-Jorge-Sampaoli-pourrait-faire-son-retour-en-Ligue-1.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-jorge-sampaoli-pourrait-faire-son-retour-en-ligue-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Jorge Sampaoli pourrait faire son retour en Ligue 1"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/531363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=531363"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/531363\/revisions"}],"predecessor-version":[{"id":531372,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/531363\/revisions\/531372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/531367"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=531363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=531363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=531363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}