{"id":533449,"date":"2024-11-17T13:12:53","date_gmt":"2024-11-17T12:12:53","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=533449&#038;preview=true&#038;preview_id=533449"},"modified":"2025-07-09T18:39:57","modified_gmt":"2025-07-09T16:39:57","slug":"sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/","title":{"rendered":"Sjusjoen Mass start femmes : Ingrid Tandrevold s&rsquo;impose d&rsquo;un souffle"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>BIATHLON SJUSJOEN &#8211; Ingrid Tandrevold remporte la mass start \u00e0 Sjusjoen (Norv\u00e8ge), en r\u00e9sistant aux assauts de sa compatriote <strong>Maren Kirkeeide. Les deux Norv\u00e9giennes se sont disput\u00e9es la victoire au sprint. Dorothea Wierer prend la 3e place \u00e0 30 secondes du duo.<\/strong><\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-sjusjoen-pre-saison-programme-complet-et-resultats\/\">Biathlon Sjusjoen Pr\u00e9-saison : Programme complet et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Ingrid Tandrevold<\/strong> vous salue bien. \u00c9videmment, la concurrence, aujourd&rsquo;hui, ne sera pas celle de la premi\u00e8re \u00e9preuve de Coupe du monde. Mais la 3e du classement g\u00e9n\u00e9ral de la saison pass\u00e9e, a frapp\u00e9 un tr\u00e8s joli coup ce week-end. <a href=\"https:\/\/dicodusport.fr\/blog\/sjusjoen-spint-femmes-ingrid-tandrevold-fait-le-plein-de-confiance-a-domicile\/\">Vainqueure du sprint ce samedi<\/a>, la Norv\u00e9gienne a doubl\u00e9 avec la mass start ce dimanche.<\/p>\n<h2 style=\"text-align: justify;\">Encore un debout chancelant pour Tandrevold<\/h2>\n<p style=\"text-align: justify;\"><strong>Ingrid Tandrevold<\/strong> a pu mesurer sa forme ce week-end, notamment face \u00e0 ses compatriotes, mais aussi son tir, qui l&rsquo;a parfois abandonn\u00e9e lors des championnats du monde et en fin de saison, la privant peut-\u00eatre du gros globe. Et particuli\u00e8rement sur le tir debout, qui lui avait pos\u00e9 tant de probl\u00e8mes la saison pass\u00e9e. Et les doutes vont toutefois perdurer. Avec un 7\/10 pas catastrophique, mais loin d&rsquo;\u00eatre imp\u00e9rial, dans des conditions de vent certes encore une fois bien d\u00e9licates. Pas de rat\u00e9 catastrophique, mais des r\u00e9glages \u00e0 trouver avant le d\u00e9but de saison. C&rsquo;est aussi \u00e0 cela que sert cette course.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-sjusjoen-2024-classement-mass-start-femmes\/\"><strong>Biathlon Sjusjoen Pr\u00e9-saison : Classement de la mass start femmes<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Mais d&rsquo;autres ont fait largement mieux qu&rsquo;elle. <strong>Dorothea Wierer<\/strong> et <strong>Maren Kirkeeide<\/strong> signant un 9\/10. Auparavant, elle avait creus\u00e9 des \u00e9carts. Un premier tir couch\u00e9 prudent et un second plus engag\u00e9. Pour s&rsquo;envoler. Mais c&rsquo;est sur les skis qu&rsquo;<strong>Ingrid Tandrevold<\/strong> a creus\u00e9 les \u00e9carts. Ressortie 2e apr\u00e8s le dernier tir debout, \u00e0 3,7 secondes de sa compatriote<strong> Maren Kirkeeide<\/strong>, l&rsquo;a\u00een\u00e9e des deux a renvers\u00e9 la table sur la partie purement physique. Apr\u00e8s avoir creus\u00e9 les \u00e9carts pr\u00e9c\u00e9demment, dans ce m\u00eame exercice. Elle signe d&rsquo;ailleurs le meilleur temps \u00e0 ski avec 44 secondes d&rsquo;avance sur la 2e. Un monde d&rsquo;\u00e9cart en l&rsquo;absence de beaucoup de grandes favorites.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u26f7\ufe0f Victoire d\u2019Ingrid Tandrevold apr\u00e8s une belle lutte contre Kirkeeide<a href=\"https:\/\/twitter.com\/hashtag\/lequipeBIATHLON?src=hash&amp;ref_src=twsrc%5Etfw\">#lequipeBIATHLON<\/a> <a href=\"https:\/\/t.co\/dkee7VIgkh\">pic.twitter.com\/dkee7VIgkh<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/1858121802775499123?ref_src=twsrc%5Etfw\">November 17, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Kirkeeide rebat les cartes en Norv\u00e8ge<\/h2>\n<p style=\"text-align: justify;\">Et pourtant, sa cadette a fait un dernier tour absolument remarquable, s&rsquo;accrochant comme une morte de faim. Port\u00e9e par son 19\/20 au tir, seule biathl\u00e8te ayant atteint ce taux de r\u00e9ussite, aujourd&rsquo;hui. Et avec sa deuxi\u00e8me place, elle va donner des n\u0153uds au cerveau des entra\u00eeneurs de sa s\u00e9lection. Pass\u00e9e \u00e0 c\u00f4t\u00e9 en sprint (36e), elle a montr\u00e9 qu&rsquo;elle avait le niveau Coupe du monde. M\u00eame si elle doit encore progresser \u00e0 ski. Car<strong> Karoline Knotten<\/strong> (4e) mais surtout <strong>Juni Arnekleiv<\/strong> (12e) ont connu des difficult\u00e9s ce dimanche midi. Le podium est compl\u00e9t\u00e9 par<strong> Dorothea Wierer,<\/strong> qui ne rassure pas vraiment sur les skis, malgr\u00e9 un 18\/20 solide au tir. L&rsquo;Italienne conc\u00e8de 31,2 secondes au duo. Place aux choses tr\u00e8s s\u00e9rieuses d\u00e9sormais.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingrid Tandrevold s&rsquo;impose d&rsquo;un souffle<\/p>\n","protected":false},"author":83,"featured_media":533466,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2426],"tags":[32415,2427,42924,16878,6848],"class_list":["post-533449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biathlon","tag-actu","tag-biathlon","tag-biathlon-pre-saison-sjusjoen","tag-breve","tag-sprint-hommes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sjusjoen Mass start femmes : Ingrid Tandrevold s&#039;impose d&#039;un souffle<\/title>\n<meta name=\"description\" content=\"BIATHLON SJUSJOEN - Ingrid Tandrevold remporte la mass start \u00e0 Sjusjoen (Norv\u00e8ge), en r\u00e9sistant aux assauts de sa compatriote Maren Kirkeeide.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sjusjoen Mass start femmes : Ingrid Tandrevold s&#039;impose d&#039;un souffle\" \/>\n<meta property=\"og:description\" content=\"BIATHLON SJUSJOEN - Ingrid Tandrevold remporte la mass start \u00e0 Sjusjoen (Norv\u00e8ge), en r\u00e9sistant aux assauts de sa compatriote Maren Kirkeeide.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-17T12:12:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T16:39:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sjusjoen Mass start femmes : Ingrid Tandrevold s&#039;impose d&#039;un souffle\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Sjusjoen Mass start femmes : Ingrid Tandrevold s&rsquo;impose d&rsquo;un souffle\",\"datePublished\":\"2024-11-17T12:12:53+00:00\",\"dateModified\":\"2025-07-09T16:39:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/\"},\"wordCount\":540,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png\",\"keywords\":[\"actu\",\"Biathlon\",\"Biathlon Pr\u00e9-saison Sjusjoen\",\"br\u00e8ve\",\"Sprint hommes\"],\"articleSection\":[\"Biathlon\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/\",\"name\":\"Sjusjoen Mass start femmes : Ingrid Tandrevold s'impose d'un souffle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png\",\"datePublished\":\"2024-11-17T12:12:53+00:00\",\"dateModified\":\"2025-07-09T16:39:57+00:00\",\"description\":\"BIATHLON SJUSJOEN - Ingrid Tandrevold remporte la mass start \u00e0 Sjusjoen (Norv\u00e8ge), en r\u00e9sistant aux assauts de sa compatriote Maren Kirkeeide.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png\",\"width\":1200,\"height\":674,\"caption\":\"Sjusjoen Mass start femmes Ingrid Tandrevold s'impose d'un souffle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sjusjoen Mass start femmes : Ingrid Tandrevold s&rsquo;impose d&rsquo;un souffle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/etienne-goursaud\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sjusjoen Mass start femmes : Ingrid Tandrevold s'impose d'un souffle","description":"BIATHLON SJUSJOEN - Ingrid Tandrevold remporte la mass start \u00e0 Sjusjoen (Norv\u00e8ge), en r\u00e9sistant aux assauts de sa compatriote Maren Kirkeeide.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/","og_locale":"fr_FR","og_type":"article","og_title":"Sjusjoen Mass start femmes : Ingrid Tandrevold s'impose d'un souffle","og_description":"BIATHLON SJUSJOEN - Ingrid Tandrevold remporte la mass start \u00e0 Sjusjoen (Norv\u00e8ge), en r\u00e9sistant aux assauts de sa compatriote Maren Kirkeeide.","og_url":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-11-17T12:12:53+00:00","article_modified_time":"2025-07-09T16:39:57+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Sjusjoen Mass start femmes : Ingrid Tandrevold s'impose d'un souffle","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Sjusjoen Mass start femmes : Ingrid Tandrevold s&rsquo;impose d&rsquo;un souffle","datePublished":"2024-11-17T12:12:53+00:00","dateModified":"2025-07-09T16:39:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/"},"wordCount":540,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png","keywords":["actu","Biathlon","Biathlon Pr\u00e9-saison Sjusjoen","br\u00e8ve","Sprint hommes"],"articleSection":["Biathlon"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/","url":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/","name":"Sjusjoen Mass start femmes : Ingrid Tandrevold s'impose d'un souffle","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png","datePublished":"2024-11-17T12:12:53+00:00","dateModified":"2025-07-09T16:39:57+00:00","description":"BIATHLON SJUSJOEN - Ingrid Tandrevold remporte la mass start \u00e0 Sjusjoen (Norv\u00e8ge), en r\u00e9sistant aux assauts de sa compatriote Maren Kirkeeide.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Sjusjoen-Mass-start-femmes-Ingrid-Tandrevold-simpose-dun-souffle.png","width":1200,"height":674,"caption":"Sjusjoen Mass start femmes Ingrid Tandrevold s'impose d'un souffle"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/sjusjoen-mass-start-femmes-ingrid-tandrevold-simpose-dun-souffle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Sjusjoen Mass start femmes : Ingrid Tandrevold s&rsquo;impose d&rsquo;un souffle"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/533449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=533449"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/533449\/revisions"}],"predecessor-version":[{"id":533478,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/533449\/revisions\/533478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/533466"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=533449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=533449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=533449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}