{"id":535815,"date":"2024-11-28T15:11:11","date_gmt":"2024-11-28T14:11:11","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=535815&#038;preview=true&#038;preview_id=535815"},"modified":"2025-07-09T18:39:43","modified_gmt":"2025-07-09T16:39:43","slug":"ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/","title":{"rendered":"IBU Cup Idre Fj\u00e4ll : Paula Botet s&rsquo;impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>IBU CUP 2024-2025 &#8211; C\u2019est une belle journ\u00e9e pour l\u2019\u00e9quipe de France de biathlon. Apr\u00e8s Antonin Guigonnat, troisi\u00e8me de sa course, Paula Botet s\u2019est impos\u00e9e en patronne sur le sprint f\u00e9minin, devan\u00e7ant sa compatriote Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore.<\/em><\/h4>\n<ul style=\"list-style-type: disc; text-align: justify;\">\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-coupe-du-monde-2024-2025-le-calendrier-complet\/\"><strong>\u00c0 voir aussi &#8211; Le calendrier complet de la Coupe du monde de biathlon 2024-2025<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Premi\u00e8re Tricolore \u00e0 s\u2019\u00e9lancer, <strong>Chlo\u00e9 Chevalier<\/strong> se montrait en forme sur les skis, prenant provisoirement la m\u00e8ne au 1<sup>er<\/sup> interm\u00e9diaire, au contact d\u2019<strong>Ida Lien<\/strong>. La Fran\u00e7aise et la Norv\u00e9gienne blanchissaient toutes deux les cinq premi\u00e8res cibles mais plus rapide \u00e0 d\u00e9gainer que son adversaire, Chevalier grappillait alors quelques secondes suppl\u00e9mentaires. Avec un nouveau 5\/5 sur la seconde salve, elle laissait m\u00eame loin derri\u00e8re elle la Scandinave, coupable de quatre (!) \u00e9checs. Plus pr\u00e9cise et plus rapide que tout le monde, ou presque, <strong>Chlo\u00e9 Chevalier<\/strong> ma\u00eetrisait les d\u00e9bats et tenait sa victoire. Jusqu\u2019\u00e0 l\u2019arriv\u00e9e de sa compatriote, <strong>Paula Botet<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Doubl\u00e9 tricolore men\u00e9 par Paula Botet<\/h2>\n<p style=\"text-align: justify;\">Car Paula Botet est all\u00e9e encore plus vite. Partie avec le dossard 41, la Vosgienne a laiss\u00e9 plan\u00e9 le suspense mais a litt\u00e9ralement survol\u00e9 la piste. Premier temps de skis sur ce sprint, la Fran\u00e7aise a \u00e9galement fait le plein sur l\u2019int\u00e9gralit\u00e9 des 10 cibles. Avec 13 secondes de marge sur Chevalier, elle se place sur la plus haute marche. La Su\u00e9doise<strong> Johanna Skottheim<\/strong> prend la troisi\u00e8me place. Dommage en revanche pour <strong>Camille Bened<\/strong>, auteure d\u2019une petite faute sur le debout. Sans \u00e7a, le podium et le tripl\u00e9 fran\u00e7ais \u00e9tait jouable. Mais c\u2019est n\u00e9anmoins une tr\u00e8s belle place d\u2019honneur qu\u2019elle a r\u00e9cup\u00e9r\u00e9e (6<sup>\u00e8me<\/sup>). Le staff des Bleues est pr\u00e9venu, la concurrence va \u00eatre toute aussi folle que l\u2019an pass\u00e9 pour esp\u00e9rer int\u00e9grer le groupe A. C&rsquo;est en tout cas une journ\u00e9e ensoleill\u00e9e pour l&rsquo;\u00e9quipe de France.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/ibu-cup-2024-2025-antonin-guigonnat-sur-le-podium-du-premier-sprint-de-la-saison\/\" class=\"vlp-link\" title=\"IBU Cup Idre Fj\u00e4ll : Antonin Guigonnat sur le podium du premier sprint de la saison\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Antonin-Guigonnat-sur-le-podium-du-premier-sprint-de-la-saison.png\" class=\"attachment-800x445 size-800x445\" alt=\"IBU Cup Idre Fj\u00e4ll Antonin Guigonnat sur le podium du premier sprint de la saison\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Antonin-Guigonnat-sur-le-podium-du-premier-sprint-de-la-saison.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Antonin-Guigonnat-sur-le-podium-du-premier-sprint-de-la-saison-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Antonin-Guigonnat-sur-le-podium-du-premier-sprint-de-la-saison-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Antonin-Guigonnat-sur-le-podium-du-premier-sprint-de-la-saison-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">IBU Cup Idre Fj\u00e4ll : Antonin Guigonnat sur le podium du premier sprint de la saison<\/div><div class=\"vlp-block-1 vlp-link-summary\">IBU CUP 2024-2025 - Pour le premier sprint de la saison, Antonin Guigonnat monte sur la troisi\u00e8me marche du podium. <\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>IBU CUP 2024-2025 &#8211; Paula Botet s\u2019est impos\u00e9e en patronne sur le sprint f\u00e9minin, devan\u00e7ant sa compatriote Chlo\u00e9 Chevalier.<\/p>\n","protected":false},"author":18,"featured_media":535869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2426],"tags":[2427,16878,2867,2696,12969,20988,6937],"class_list":["post-535815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biathlon","tag-biathlon","tag-breve","tag-chloe-chevalier","tag-ibu-cup","tag-idre-fjall","tag-paula-botet","tag-sprint-femmes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IBU Cup Idre Fj\u00e4ll : Paula Botet s&#039;impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint<\/title>\n<meta name=\"description\" content=\"IBU CUP 2024-2025 - Paula Botet s\u2019est impos\u00e9e en patronne sur le sprint f\u00e9minin, devan\u00e7ant sa compatriote Chlo\u00e9 Chevalier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IBU Cup Idre Fj\u00e4ll : Paula Botet s&#039;impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint\" \/>\n<meta property=\"og:description\" content=\"IBU CUP 2024-2025 - Paula Botet s\u2019est impos\u00e9e en patronne sur le sprint f\u00e9minin, devan\u00e7ant sa compatriote Chlo\u00e9 Chevalier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T14:11:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T16:39:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"IBU Cup Idre Fj\u00e4ll : Paula Botet s&#039;impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"IBU Cup Idre Fj\u00e4ll : Paula Botet s&rsquo;impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint\",\"datePublished\":\"2024-11-28T14:11:11+00:00\",\"dateModified\":\"2025-07-09T16:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/\"},\"wordCount\":440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png\",\"keywords\":[\"Biathlon\",\"br\u00e8ve\",\"Chlo\u00e9 Chevalier\",\"IBU Cup\",\"Idre Fj\u00e4ll\",\"Paula Botet\",\"Sprint femmes\"],\"articleSection\":[\"Biathlon\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/\",\"name\":\"IBU Cup Idre Fj\u00e4ll : Paula Botet s'impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png\",\"datePublished\":\"2024-11-28T14:11:11+00:00\",\"dateModified\":\"2025-07-09T16:39:43+00:00\",\"description\":\"IBU CUP 2024-2025 - Paula Botet s\u2019est impos\u00e9e en patronne sur le sprint f\u00e9minin, devan\u00e7ant sa compatriote Chlo\u00e9 Chevalier.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png\",\"width\":1200,\"height\":674,\"caption\":\"IBU Cup Idre Fj\u00e4ll Paula Botet s'impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IBU Cup Idre Fj\u00e4ll : Paula Botet s&rsquo;impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IBU Cup Idre Fj\u00e4ll : Paula Botet s'impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint","description":"IBU CUP 2024-2025 - Paula Botet s\u2019est impos\u00e9e en patronne sur le sprint f\u00e9minin, devan\u00e7ant sa compatriote Chlo\u00e9 Chevalier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/","og_locale":"fr_FR","og_type":"article","og_title":"IBU Cup Idre Fj\u00e4ll : Paula Botet s'impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint","og_description":"IBU CUP 2024-2025 - Paula Botet s\u2019est impos\u00e9e en patronne sur le sprint f\u00e9minin, devan\u00e7ant sa compatriote Chlo\u00e9 Chevalier.","og_url":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2024-11-28T14:11:11+00:00","article_modified_time":"2025-07-09T16:39:43+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"IBU Cup Idre Fj\u00e4ll : Paula Botet s'impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"IBU Cup Idre Fj\u00e4ll : Paula Botet s&rsquo;impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint","datePublished":"2024-11-28T14:11:11+00:00","dateModified":"2025-07-09T16:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/"},"wordCount":440,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png","keywords":["Biathlon","br\u00e8ve","Chlo\u00e9 Chevalier","IBU Cup","Idre Fj\u00e4ll","Paula Botet","Sprint femmes"],"articleSection":["Biathlon"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/","url":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/","name":"IBU Cup Idre Fj\u00e4ll : Paula Botet s'impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png","datePublished":"2024-11-28T14:11:11+00:00","dateModified":"2025-07-09T16:39:43+00:00","description":"IBU CUP 2024-2025 - Paula Botet s\u2019est impos\u00e9e en patronne sur le sprint f\u00e9minin, devan\u00e7ant sa compatriote Chlo\u00e9 Chevalier.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/IBU-Cup-Idre-Fjall-Paula-Botet-simpose-devant-Chloe-Chevalier-pour-un-double-tricolore-sur-le-sprint-1.png","width":1200,"height":674,"caption":"IBU Cup Idre Fj\u00e4ll Paula Botet s'impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ibu-cup-idre-fjall-paula-botet-s-simpose-devant-chloe-chevalier-pour-un-double-tricolore-sur-le-sprint\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"IBU Cup Idre Fj\u00e4ll : Paula Botet s&rsquo;impose devant Chlo\u00e9 Chevalier pour un doubl\u00e9 tricolore sur le sprint"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/535815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=535815"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/535815\/revisions"}],"predecessor-version":[{"id":536031,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/535815\/revisions\/536031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/535869"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=535815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=535815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=535815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}